{"id":356,"count":5,"description":"","link":"https:\/\/acninternational.org\/pt-pt\/country\/rwanda\/","name":"Rwanda","slug":"rwanda","taxonomy":"country","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rwanda Archives | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/pt-pt\/country\/rwanda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rwanda Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/pt-pt\/country\/rwanda\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/07\/ACN-20140929-13926-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/country\\\/rwanda\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/country\\\/rwanda\\\/\",\"name\":\"Rwanda Archives | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/country\\\/rwanda\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/country\\\/rwanda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rwanda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rwanda Archives | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/pt-pt\/country\/rwanda\/","og_locale":"pt_PT","og_type":"article","og_title":"Rwanda Archives","og_url":"https:\/\/acninternational.org\/pt-pt\/country\/rwanda\/","og_site_name":"ACN International","og_image":[{"width":200,"height":200,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/07\/ACN-20140929-13926-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@acn_int","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/acninternational.org\/pt-pt\/country\/rwanda\/","url":"https:\/\/acninternational.org\/pt-pt\/country\/rwanda\/","name":"Rwanda Archives | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/pt-pt\/#website"},"breadcrumb":{"@id":"https:\/\/acninternational.org\/pt-pt\/country\/rwanda\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/pt-pt\/country\/rwanda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Rwanda"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/pt-pt\/#website","url":"https:\/\/acninternational.org\/pt-pt\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/pt-pt\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/acninternational.org\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/pt-pt\/wp-json\/wp\/v2\/country\/356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/pt-pt\/wp-json\/wp\/v2\/country"}],"about":[{"href":"https:\/\/acninternational.org\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/country"}],"wp:post_type":[{"href":"https:\/\/acninternational.org\/pt-pt\/wp-json\/wp\/v2\/posts?country=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}