{"id":124577,"date":"2019-10-04T12:08:36","date_gmt":"2019-10-04T10:08:36","guid":{"rendered":"https:\/\/acninternational.org\/le-nostre-attivita-regionali\/"},"modified":"2020-02-14T11:35:57","modified_gmt":"2020-02-14T10:35:57","slug":"le-nostre-attivita-regionali","status":"publish","type":"page","link":"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/","title":{"rendered":"Le nostre attivit\u00e0 regionali"},"content":{"rendered":"<h1>\u00bb Le nostre iniziative di aiuto  partono da un serrato dialogo  con le Chiese locali \u00ab<\/h1>\n<p>Il Medio Oriente e l\u2019Africa sono stati le prio- rit\u00e0 regionali dei nostri progetti d\u2019aiuto nel 2018. In tutte le nostre attivit\u00e0 di progetto \u00e8 particolarmente importante per noi il dialogo con la Chiesa locale poich\u00e9 i vescovi e i religiosi sanno meglio di tutti dove la sofferenza \u00e8 pi\u00f9 profonda e quali misure d\u2019aiuto \u00e8 necessario intraprendere.<\/p>\n<p>Riteniamo che il nostro compito sia quello di sostenere la Chiesa soprattutto laddove i cristiani soffrono a causa della guerra, dell\u2019oppressione, della persecuzio- ne e della violenza.<\/p>\n<p>UAnche nel 2018, il Medio Oriente \u00e8 stato purtroppo un focolaio di violenza in cui i fedeli si trovano quotidianamente, e in molti posti, alla merc\u00e9 dell\u2019ISIS e di altri gruppi islamisti dovendone subire la violenza. Per questo motivo, i progetti d\u2019aiuto per la Siria e l\u2019Iraq continueranno ad avere la priorit\u00e0.<\/p>\n<p>Ma anche in diversi paesi dell\u2019Africa i cri- stiani soffrono per la persecuzione e la violenza dell\u2019islamismo radicale. Allo stesso tempo questo continente \u00e8 quello in cui i credenti sono aumentati maggiormente. I nostri finanziamenti per l\u2019Africa tengono in considerazione questi sviluppi, tanto che nel 2018 pi\u00f9 di un quarto del budget per i nostri progetti \u00e8 andato alle Chiese locali dei Paesi africani.<\/p>\n<p>[mapsvg id=&#8221;61512&#8243;]<\/p>\n<p>In Asia, invece, la nostra priorit\u00e0 sono regioni come il Pakistan e le Filippine, Paesi anche questi dove l\u2019islamismo radicale sta avanzando.<\/p>\n<p>Naturalmente, siamo attivi anche in India, dove in molti luoghi un induismo sempre pi\u00f9 radicale perseguita la minoranza cristia- na e la opprime con la violenza.<\/p>\n<p>Ma anche la Cina, il Vietnam o il Laos, che da decenni soffrono sotto le strutture del potere comunista, fanno ancora parte della nostra lista per gli aiuti.<\/p>\n<p>\t\t\t.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container{max-width:480px;min-height:275px;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container:after{content:&#8221;&#8221;;min-height:inherit;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container &gt; .elementor-row &gt; .elementor-column &gt; .elementor-column-wrap &gt; .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-95eaab5{overflow:hidden;transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-bc-flex-widget .elementor-52611 .elementor-element.elementor-element-14939d0.elementor-column .elementor-column-wrap{align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-14939d0.elementor-column.elementor-element[data-element_type=&#8221;column&#8221;] &gt; .elementor-column-wrap.elementor-element-populated &gt; .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-14939d0 &gt; .elementor-element-populated{padding:0px 15px 0px 15px;}.elementor-52611 .elementor-element.elementor-element-39a867f &gt; .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;padding:0px 0px 0px 0px;}.elementor-52611 .elementor-element.elementor-element-39a867f &gt; .elementor-element-populated &gt; .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-52611 .elementor-element.elementor-element-5b56fcc &gt; .elementor-widget-container{margin:-8px 0px -24px 0px;padding:6px 10px 10px 015px;background-color:rgba(255,255,255,0.8);}.elementor-52611 .elementor-element.elementor-element-95eaab5:not(.elementor-motion-effects-element-type-background), .elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-motion-effects-container &gt; .elementor-motion-effects-layer{background-color:#c6c6c6;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-52611 .elementor-element.elementor-element-eb4abd6 &gt; .elementor-element-populated{padding:19px 20px 20px 20px;}.elementor-52611 .elementor-element.elementor-element-af0fafa &gt; .elementor-widget-container{padding:0px 0px 0px 10px;}.jet-listing-item.single-jet-engine .elementor{width:364px;margin-left:auto;margin-right:auto;}\t\t<\/p>\n<section data-id=\"95eaab5\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n<section data-id=\"013e1e2\">\n<p>.a-56256-color a, .a-56256-color h2, .a-56256-color svg {<br \/>\n    color:#8A3A8E !important;<br \/>\n    fill:#8A3A8E !important;<br \/>\n}<br \/>\n.a-56256-color h2 {<br \/>\nline-height: 1.4;<br \/>\n}<\/p>\n<p><a href=\"https:\/\/acninternational.org\/regional-activity\/latin-%e2%80%8damerica\/\"><\/p>\n<h2>Latin \u200dAmerica<br \/>\n<\/h2>\n<p><\/a><br \/>\n\t\t<\/section>\n<\/section>\n<section data-id=\"439f1c7\">\n<ul>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/latin-%e2%80%8damerica\/argentina-chile\/\">Argentina &amp; Chile<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/latin-%e2%80%8damerica\/brazil\/\">Brazil<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/latin-%e2%80%8damerica\/cuba\/\">Cuba<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/latin-%e2%80%8damerica\/ecuador\/\">Ecuador<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/latin-%e2%80%8damerica\/guatemala-el-salvador-honduras\/\">Guatemala, El Salvador &amp; Honduras<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/latin-%e2%80%8damerica\/haiti\/\">Haiti<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/latin-%e2%80%8damerica\/nicaragua\/\">Nicaragua<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/latin-%e2%80%8damerica\/peru\/\">Peru<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/latin-%e2%80%8damerica\/uruguay\/\">Uruguay<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/latin-%e2%80%8damerica\/venezuela\/\">Venezuela<\/a><\/li>\n<\/ul>\n<\/section>\n<p>\t\t.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container{max-width:480px;min-height:275px;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container:after{content:&#8221;&#8221;;min-height:inherit;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container &gt; .elementor-row &gt; .elementor-column &gt; .elementor-column-wrap &gt; .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-95eaab5{overflow:hidden;transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-bc-flex-widget .elementor-52611 .elementor-element.elementor-element-14939d0.elementor-column .elementor-column-wrap{align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-14939d0.elementor-column.elementor-element[data-element_type=&#8221;column&#8221;] &gt; .elementor-column-wrap.elementor-element-populated &gt; .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-14939d0 &gt; .elementor-element-populated{padding:0px 15px 0px 15px;}.elementor-52611 .elementor-element.elementor-element-39a867f &gt; .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;padding:0px 0px 0px 0px;}.elementor-52611 .elementor-element.elementor-element-39a867f &gt; .elementor-element-populated &gt; .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-52611 .elementor-element.elementor-element-5b56fcc &gt; .elementor-widget-container{margin:-8px 0px -24px 0px;padding:6px 10px 10px 015px;background-color:rgba(255,255,255,0.8);}.elementor-52611 .elementor-element.elementor-element-95eaab5:not(.elementor-motion-effects-element-type-background), .elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-motion-effects-container &gt; .elementor-motion-effects-layer{background-color:#c6c6c6;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-52611 .elementor-element.elementor-element-eb4abd6 &gt; .elementor-element-populated{padding:19px 20px 20px 20px;}.elementor-52611 .elementor-element.elementor-element-af0fafa &gt; .elementor-widget-container{padding:0px 0px 0px 10px;}.jet-listing-item.single-jet-engine .elementor{width:364px;margin-left:auto;margin-right:auto;}\t\t<\/p>\n<section data-id=\"95eaab5\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n<section data-id=\"013e1e2\">\n<p>.a-52881-color a, .a-52881-color h2, .a-52881-color svg {<br \/>\n    color:#B91324 !important;<br \/>\n    fill:#B91324 !important;<br \/>\n}<br \/>\n.a-52881-color h2 {<br \/>\nline-height: 1.4;<br \/>\n}<\/p>\n<p><a href=\"https:\/\/acninternational.org\/regional-activity\/middle-east\/\"><\/p>\n<h2>Middle East<br \/>\n<\/h2>\n<p><\/a><br \/>\n\t\t<\/section>\n<\/section>\n<section data-id=\"439f1c7\">\n<ul>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/middle-east\/iraq\/\">Iraq<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/middle-east\/syria\/\">Syria<\/a><\/li>\n<\/ul>\n<\/section>\n<p>\t\t.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container{max-width:480px;min-height:275px;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container:after{content:&#8221;&#8221;;min-height:inherit;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container &gt; .elementor-row &gt; .elementor-column &gt; .elementor-column-wrap &gt; .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-95eaab5{overflow:hidden;transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-bc-flex-widget .elementor-52611 .elementor-element.elementor-element-14939d0.elementor-column .elementor-column-wrap{align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-14939d0.elementor-column.elementor-element[data-element_type=&#8221;column&#8221;] &gt; .elementor-column-wrap.elementor-element-populated &gt; .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-14939d0 &gt; .elementor-element-populated{padding:0px 15px 0px 15px;}.elementor-52611 .elementor-element.elementor-element-39a867f &gt; .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;padding:0px 0px 0px 0px;}.elementor-52611 .elementor-element.elementor-element-39a867f &gt; .elementor-element-populated &gt; .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-52611 .elementor-element.elementor-element-5b56fcc &gt; .elementor-widget-container{margin:-8px 0px -24px 0px;padding:6px 10px 10px 015px;background-color:rgba(255,255,255,0.8);}.elementor-52611 .elementor-element.elementor-element-95eaab5:not(.elementor-motion-effects-element-type-background), .elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-motion-effects-container &gt; .elementor-motion-effects-layer{background-color:#c6c6c6;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-52611 .elementor-element.elementor-element-eb4abd6 &gt; .elementor-element-populated{padding:19px 20px 20px 20px;}.elementor-52611 .elementor-element.elementor-element-af0fafa &gt; .elementor-widget-container{padding:0px 0px 0px 10px;}.jet-listing-item.single-jet-engine .elementor{width:364px;margin-left:auto;margin-right:auto;}\t\t<\/p>\n<section data-id=\"95eaab5\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n<section data-id=\"013e1e2\">\n<p>.a-56260-color a, .a-56260-color h2, .a-56260-color svg {<br \/>\n    color:#0F3A56 !important;<br \/>\n    fill:#0F3A56 !important;<br \/>\n}<br \/>\n.a-56260-color h2 {<br \/>\nline-height: 1.4;<br \/>\n}<\/p>\n<p><a href=\"https:\/\/acninternational.org\/regional-activity\/western-%e2%80%8d-%e2%80%8d-eastern-%e2%80%8deurope\/\"><\/p>\n<h2>Western \u200d\/ \u200dEastern \u200dEurope<br \/>\n<\/h2>\n<p><\/a><br \/>\n\t\t<\/section>\n<\/section>\n<section data-id=\"439f1c7\">\n<ul>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/western-%e2%80%8d-%e2%80%8d-eastern-%e2%80%8deurope\/albania\/\">Albania<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/western-%e2%80%8d-%e2%80%8d-eastern-%e2%80%8deurope\/belarus\/\">Belarus<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/western-%e2%80%8d-%e2%80%8d-eastern-%e2%80%8deurope\/bosnia-and-herzegovina\/\">Bosnia and Herzegovina<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/western-%e2%80%8d-%e2%80%8d-eastern-%e2%80%8deurope\/bulgaria\/\">Bulgaria<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/western-%e2%80%8d-%e2%80%8d-eastern-%e2%80%8deurope\/czech-republic\/\">Czech Republic<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/western-%e2%80%8d-%e2%80%8d-eastern-%e2%80%8deurope\/refugees-in-western-europe\/\">Refugees in Western Europe<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/western-%e2%80%8d-%e2%80%8d-eastern-%e2%80%8deurope\/romania\/\">Romania<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/western-%e2%80%8d-%e2%80%8d-eastern-%e2%80%8deurope\/russia\/\">Russia<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/western-%e2%80%8d-%e2%80%8d-eastern-%e2%80%8deurope\/ukraine\/\">Ukraine<\/a><\/li>\n<\/ul>\n<\/section>\n<p>\t\t.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container{max-width:480px;min-height:275px;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container:after{content:&#8221;&#8221;;min-height:inherit;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container &gt; .elementor-row &gt; .elementor-column &gt; .elementor-column-wrap &gt; .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-95eaab5{overflow:hidden;transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-bc-flex-widget .elementor-52611 .elementor-element.elementor-element-14939d0.elementor-column .elementor-column-wrap{align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-14939d0.elementor-column.elementor-element[data-element_type=&#8221;column&#8221;] &gt; .elementor-column-wrap.elementor-element-populated &gt; .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-14939d0 &gt; .elementor-element-populated{padding:0px 15px 0px 15px;}.elementor-52611 .elementor-element.elementor-element-39a867f &gt; .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;padding:0px 0px 0px 0px;}.elementor-52611 .elementor-element.elementor-element-39a867f &gt; .elementor-element-populated &gt; .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-52611 .elementor-element.elementor-element-5b56fcc &gt; .elementor-widget-container{margin:-8px 0px -24px 0px;padding:6px 10px 10px 015px;background-color:rgba(255,255,255,0.8);}.elementor-52611 .elementor-element.elementor-element-95eaab5:not(.elementor-motion-effects-element-type-background), .elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-motion-effects-container &gt; .elementor-motion-effects-layer{background-color:#c6c6c6;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-52611 .elementor-element.elementor-element-eb4abd6 &gt; .elementor-element-populated{padding:19px 20px 20px 20px;}.elementor-52611 .elementor-element.elementor-element-af0fafa &gt; .elementor-widget-container{padding:0px 0px 0px 10px;}.jet-listing-item.single-jet-engine .elementor{width:364px;margin-left:auto;margin-right:auto;}\t\t<\/p>\n<section data-id=\"95eaab5\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n<section data-id=\"013e1e2\">\n<p>.a-56262-color a, .a-56262-color h2, .a-56262-color svg {<br \/>\n    color:#689037 !important;<br \/>\n    fill:#689037 !important;<br \/>\n}<br \/>\n.a-56262-color h2 {<br \/>\nline-height: 1.4;<br \/>\n}<\/p>\n<p><a href=\"https:\/\/acninternational.org\/regional-activity\/asia-%e2%80%8d-%e2%80%8doceania\/\"><\/p>\n<h2>Asia \u200d\/ \u200dOceania<br \/>\n<\/h2>\n<p><\/a><br \/>\n\t\t<\/section>\n<\/section>\n<section data-id=\"439f1c7\">\n<ul>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/asia-%e2%80%8d-%e2%80%8doceania\/bangladesh\/\">Bangladesh<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/asia-%e2%80%8d-%e2%80%8doceania\/china\/\">China<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/asia-%e2%80%8d-%e2%80%8doceania\/india\/\">India<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/asia-%e2%80%8d-%e2%80%8doceania\/kazakhstan\/\">Kazakhstan<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/asia-%e2%80%8d-%e2%80%8doceania\/pakistan\/\">Pakistan<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/asia-%e2%80%8d-%e2%80%8doceania\/papua-new-guinea\/\">Papua New Guinea<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/asia-%e2%80%8d-%e2%80%8doceania\/philippines\/\">Philippines<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/asia-%e2%80%8d-%e2%80%8doceania\/sri-lanka\/\">Sri Lanka<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/asia-%e2%80%8d-%e2%80%8doceania\/vietnam\/\">Vietnam<\/a><\/li>\n<\/ul>\n<\/section>\n<p>\t\t.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container{max-width:480px;min-height:275px;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container:after{content:&#8221;&#8221;;min-height:inherit;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-container &gt; .elementor-row &gt; .elementor-column &gt; .elementor-column-wrap &gt; .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-95eaab5{overflow:hidden;transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;}.elementor-bc-flex-widget .elementor-52611 .elementor-element.elementor-element-14939d0.elementor-column .elementor-column-wrap{align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-14939d0.elementor-column.elementor-element[data-element_type=&#8221;column&#8221;] &gt; .elementor-column-wrap.elementor-element-populated &gt; .elementor-widget-wrap{align-content:flex-end;align-items:flex-end;}.elementor-52611 .elementor-element.elementor-element-14939d0 &gt; .elementor-element-populated{padding:0px 15px 0px 15px;}.elementor-52611 .elementor-element.elementor-element-39a867f &gt; .elementor-element-populated{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;padding:0px 0px 0px 0px;}.elementor-52611 .elementor-element.elementor-element-39a867f &gt; .elementor-element-populated &gt; .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-52611 .elementor-element.elementor-element-5b56fcc &gt; .elementor-widget-container{margin:-8px 0px -24px 0px;padding:6px 10px 10px 015px;background-color:rgba(255,255,255,0.8);}.elementor-52611 .elementor-element.elementor-element-95eaab5:not(.elementor-motion-effects-element-type-background), .elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-motion-effects-container &gt; .elementor-motion-effects-layer{background-color:#c6c6c6;}.elementor-52611 .elementor-element.elementor-element-95eaab5 &gt; .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-52611 .elementor-element.elementor-element-eb4abd6 &gt; .elementor-element-populated{padding:19px 20px 20px 20px;}.elementor-52611 .elementor-element.elementor-element-af0fafa &gt; .elementor-widget-container{padding:0px 0px 0px 10px;}.jet-listing-item.single-jet-engine .elementor{width:364px;margin-left:auto;margin-right:auto;}\t\t<\/p>\n<section data-id=\"95eaab5\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n<section data-id=\"013e1e2\">\n<p>.a-56258-color a, .a-56258-color h2, .a-56258-color svg {<br \/>\n    color:#E0AC00 !important;<br \/>\n    fill:#E0AC00 !important;<br \/>\n}<br \/>\n.a-56258-color h2 {<br \/>\nline-height: 1.4;<br \/>\n}<\/p>\n<p><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/\"><\/p>\n<h2>Africa<br \/>\n<\/h2>\n<p><\/a><br \/>\n\t\t<\/section>\n<\/section>\n<section data-id=\"439f1c7\">\n<ul>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/algeria\/\">Algeria<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/angola\/\">Angola<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/benin\/\">Benin<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/burkina-faso\/\">Burkina Faso<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/cameroon\/\">Cameroon<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/central-african-republic\/\">Central African Republic<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/democratic-republic-of-the-congo\/\">Democratic Republic of the Congo<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/ethiopia\/\">Ethiopia<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/guinea-conakry\/\">Guinea-Conakry<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/kenya\/\">Kenya<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/liberia\/\">Liberia<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/libya\/\">Libya<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/madagascar\/\">Madagascar<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/mali\/\">Mali<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/mozambique\/\">Mozambique<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/niger\/\">Niger<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/nigeria\/\">Nigeria<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/rwanda\/\">Rwanda<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/sierra-leone\/\">Sierra Leone<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/south-sudan\/\">South Sudan<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/sudan\/\">Sudan<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/tanzania\/\">Tanzania<\/a><\/li>\n<li><a href=\"https:\/\/acninternational.org\/regional-activity\/africa\/uganda\/\">Uganda<\/a><\/li>\n<\/ul>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>\u00bb Le nostre iniziative di aiuto partono da un serrato dialogo con le Chiese locali \u00ab Il Medio Oriente e l\u2019Africa sono stati le prio- rit\u00e0 regionali dei nostri progetti d\u2019aiuto nel 2018. In tutte le nostre attivit\u00e0 di progetto \u00e8 particolarmente importante per noi il dialogo con la Chiesa locale poich\u00e9 i vescovi e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":124578,"parent":124568,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-124577","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le nostre attivit\u00e0 regionali | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le nostre attivit\u00e0 regionali\" \/>\n<meta property=\"og:description\" content=\"\u00bb Le nostre iniziative di aiuto partono da un serrato dialogo con le Chiese locali \u00ab Il Medio Oriente e l\u2019Africa sono stati le prio- rit\u00e0 regionali dei nostri progetti d\u2019aiuto nel 2018. In tutte le nostre attivit\u00e0 di progetto \u00e8 particolarmente importante per noi il dialogo con la Chiesa locale poich\u00e9 i vescovi e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-14T10:35:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/09\/ACN-20160218-36673-featured-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/le-nostre-aree-prioritarie\\\/le-nostre-attivita-regionali\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/it\\\/le-nostre-aree-prioritarie\\\/le-nostre-attivita-regionali\\\/\",\"name\":\"Le nostre attivit\u00e0 regionali | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/le-nostre-aree-prioritarie\\\/le-nostre-attivita-regionali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/le-nostre-aree-prioritarie\\\/le-nostre-attivita-regionali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ACN-20160218-36673-featured-image.jpg\",\"datePublished\":\"2019-10-04T10:08:36+00:00\",\"dateModified\":\"2020-02-14T10:35:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/le-nostre-aree-prioritarie\\\/le-nostre-attivita-regionali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/it\\\/le-nostre-aree-prioritarie\\\/le-nostre-attivita-regionali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/le-nostre-aree-prioritarie\\\/le-nostre-attivita-regionali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ACN-20160218-36673-featured-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ACN-20160218-36673-featured-image.jpg\",\"width\":2000,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/le-nostre-aree-prioritarie\\\/le-nostre-attivita-regionali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le nostre aree prioritarie\",\"item\":\"https:\\\/\\\/acninternational.org\\\/it\\\/le-nostre-aree-prioritarie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le nostre attivit\u00e0 regionali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/it\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le nostre attivit\u00e0 regionali | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/","og_locale":"it_IT","og_type":"article","og_title":"Le nostre attivit\u00e0 regionali","og_description":"\u00bb Le nostre iniziative di aiuto partono da un serrato dialogo con le Chiese locali \u00ab Il Medio Oriente e l\u2019Africa sono stati le prio- rit\u00e0 regionali dei nostri progetti d\u2019aiuto nel 2018. In tutte le nostre attivit\u00e0 di progetto \u00e8 particolarmente importante per noi il dialogo con la Chiesa locale poich\u00e9 i vescovi e [&hellip;]","og_url":"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_modified_time":"2020-02-14T10:35:57+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/09\/ACN-20160218-36673-featured-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@acn_int","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/","url":"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/","name":"Le nostre attivit\u00e0 regionali | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/09\/ACN-20160218-36673-featured-image.jpg","datePublished":"2019-10-04T10:08:36+00:00","dateModified":"2020-02-14T10:35:57+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/09\/ACN-20160218-36673-featured-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/09\/ACN-20160218-36673-featured-image.jpg","width":2000,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/le-nostre-attivita-regionali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/it\/"},{"@type":"ListItem","position":2,"name":"Le nostre aree prioritarie","item":"https:\/\/acninternational.org\/it\/le-nostre-aree-prioritarie\/"},{"@type":"ListItem","position":3,"name":"Le nostre attivit\u00e0 regionali"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/it\/#website","url":"https:\/\/acninternational.org\/it\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/it\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/acninternational.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/it\/wp-json\/wp\/v2\/pages\/124577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/acninternational.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/it\/wp-json\/wp\/v2\/comments?post=124577"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/it\/wp-json\/wp\/v2\/pages\/124577\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/acninternational.org\/it\/wp-json\/wp\/v2\/pages\/124568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/it\/wp-json\/wp\/v2\/media\/124578"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/it\/wp-json\/wp\/v2\/media?parent=124577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}