{"id":260789,"date":"2025-12-10T07:22:02","date_gmt":"2025-12-10T06:22:02","guid":{"rendered":"https:\/\/acninternational.org\/?p=260789"},"modified":"2025-12-10T07:22:11","modified_gmt":"2025-12-10T06:22:11","slug":"nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/","title":{"rendered":"Nigeria\u00a0: un cat\u00e9chiste pardonne \u00e0 l\u2019homme qui a tent\u00e9 de le tuer en raison de son minist\u00e8re"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Malgr\u00e9 plusieurs attaques et une tentative d\u2019assassinat, Tobias Yahaya a d\u00e9cid\u00e9 de rester \u00e0 Sokoto pour poursuivre son minist\u00e8re au service de l\u2019Eglise.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le 19 avril 2023, vers 3 heures du matin, trois hommes arm\u00e9s ont franchi la cl\u00f4ture de s\u00e9curit\u00e9 entourant le domicile de Tobias Yahaya, pr\u00e8s de la cath\u00e9drale de la Sainte-Famille de Sokoto. Tobias, cat\u00e9chiste de 26 ans, a \u00e9t\u00e9 r\u00e9veill\u00e9 par l\u2019intrusion.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198951-1024x768.jpg\" alt=\"\" class=\"wp-image-260779\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198951-1024x768.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198951-300x225.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198951-768x576.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198951.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Tobias Yahaya recevant le prix \u00ab Courage to be Christian \u00bb (Le courage d&rsquo;\u00eatre chr\u00e9tien) d\u00e9cern\u00e9 par ACN UK lors du Red Wednesday, cath\u00e9drale Saint-Georges, Southwark, Londres.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Beaucoup de choses vous viennent \u00e0 l\u2019esprit dans un moment comme celui-l\u00e0, car s\u2019ils \u00e9taient entr\u00e9s et m\u2019avaient trouv\u00e9 avec ma femme et mes quatre enfants, Dieu seul sait ce qui aurait pu arriver&nbsp;\u00bb, raconte-t-il lors d\u2019une interview avec Aid to the Church in Need (ACN). \u00ab&nbsp;J\u2019ai d\u00e9cid\u00e9 de sortir.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ibrahim, le chef du petit groupe, a sorti un couteau et poignard\u00e9 le cat\u00e9chiste \u00e0 la poitrine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Je suis tomb\u00e9 au sol en saignant&nbsp;\u00bb, se souvient Tobias. \u00ab&nbsp;Et les deux autres se sont enfuis, en estimant que leur mission \u00e9tait accomplie.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ibrahim, cependant, est rest\u00e9, et a tent\u00e9 de le poignarder \u00e0 nouveau lorsqu\u2019il a essay\u00e9 de se relever. \u00ab&nbsp;Mais cette fois, j\u2019ai pris le couteau avec mes mains&nbsp;\u00bb, explique Tobias, \u00ab&nbsp;alors il l\u2019a tordu, me blessant gravement les paumes. J\u2019ai d\u00fb le l\u00e2cher mais j\u2019ai r\u00e9ussi \u00e0 le maintenir pr\u00e8s de moi, de sorte qu\u2019il n\u2019a pas pu l\u2019utiliser \u00e0 nouveau contre moi.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A ce moment-l\u00e0, l\u2019\u00e9pouse de Tobias a commenc\u00e9 \u00e0 crier et \u00e0 alerter les voisins qui ont r\u00e9ussi \u00e0 attraper Ibrahim. Tobias perdait tant de sang qu\u2019il a perdu connaissance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsqu\u2019il s\u2019est r\u00e9veill\u00e9 environ 24 heures plus tard, il \u00e9tait allong\u00e9 dans un lit d\u2019h\u00f4pital \u00e0 c\u00f4t\u00e9 d\u2019Ibrahim, qui \u00e9tait \u00e9galement soign\u00e9 pour ses blessures.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Je lui ai demand\u00e9&nbsp;: \u201cPourquoi voulez-vous me tuer&nbsp;?\u201d, se souvient Tobias. \u00ab&nbsp;Ibrahim n\u2019a pas pu r\u00e9pondre. Il \u00e9tait en larmes. Les gens autour de moi m\u2019ont demand\u00e9&nbsp;: \u201cPourquoi parlez-vous \u00e0 cette personne&nbsp;? Concentrez-vous sur votre sant\u00e9.\u201d J\u2019ai r\u00e9pondu que je voulais conna\u00eetre la raison pour laquelle il avait tent\u00e9 de me prendre la vie.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalement, il a appris qu\u2019Ibrahim et ses compagnons, qui n\u2019avaient pas \u00e9t\u00e9 appr\u00e9hend\u00e9s, craignaient l\u2019influence du cat\u00e9chiste sur les jeunes de la r\u00e9gion, qui est \u00e0 90% musulmane. Ce n\u2019\u00e9tait pas la premi\u00e8re fois que Tobias avait des probl\u00e8mes en raison de son minist\u00e8re chr\u00e9tien.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-enseigner-par-l-exemple\"><strong>Enseigner par l\u2019exemple<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Au Nigeria, le minist\u00e8re de cat\u00e9chiste est beaucoup plus qu\u2019\u00eatre volontaire pour enseigner le cat\u00e9chisme le dimanche. Les cat\u00e9chistes suivent une longue formation et sont officiellement envoy\u00e9s en mission. Tobias a \u00e9t\u00e9 envoy\u00e9 en mission il y a neuf ans par l\u2019\u00e9v\u00eaque \u00e9m\u00e9rite de Sokoto, Mgr Kevin Aje. Les cat\u00e9chistes organisent les bapt\u00eames, distribuent la communion et c\u00e9l\u00e8brent les offices lorsque les pr\u00eatres ne sont pas disponibles. Le travail de Tobias contribue \u00e0 la croissance de l\u2019Eglise \u00e0 Sokoto. \u00ab&nbsp;A P\u00e2ques, l\u2019an dernier, 100 enfants de notre paroisse ont \u00e9t\u00e9 confirm\u00e9s&nbsp;\u00bb, raconte-t-il.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais probablement la plus grande le\u00e7on qu&rsquo;il a transmise \u00e0 ses ouailles pendant cette \u00e9preuve, &nbsp;c\u2019est ce qui s\u2019est pass\u00e9 lors du proc\u00e8s. Quand le juge a impos\u00e9 une sentence d\u2019un an de prison pour Ibrahim, Tobias a pris la parole&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;J\u2019ai demand\u00e9 au juge musulman&nbsp;: \u201cPuis-je prendre dans mes bras Ibrahim&nbsp;?\u201d et tout le monde dans la salle d&rsquo;audience a manifest\u00e9 son incr\u00e9dulit\u00e9 et sa surprise. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le juge a indiqu\u00e9 qu\u2019il \u00e9tait d\u2019accord. \u00ab&nbsp;Je l\u2019ai pris dans mes bras, lui ai serr\u00e9 les mains et lui ai dit&nbsp;: \u201cJe vous ai pardonn\u00e9\u201d&nbsp;\u00bb, se rappelle le cat\u00e9chiste. \u00ab&nbsp;Il n\u2019\u00e9tait pas en mesure de me parler, mais j\u2019ai vu des larmes qui coulaient sur ses joues. Je lui ai r\u00e9p\u00e9t\u00e9&nbsp;: \u201cJe vous ai pardonn\u00e9\u201d&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tobias et sa famille sont rentr\u00e9s chez eux. Ils \u00e9taient pleins de questions sur ce qu\u2019ils devaient faire ensuite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Qu\u2019est-ce que Dieu veut nous communiquer dans ce genre de situations&nbsp;? Car ce n\u2019\u00e9tait pas la premi\u00e8re attaque&nbsp;\u00bb, poursuit-il. \u00ab&nbsp;Je d\u00e9sire continuer mon travail de cat\u00e9chiste. Ma femme me soutient. Ma m\u00e8re me soutient. Il y a eu des pri\u00e8res, des conseils de mon \u00e9v\u00eaque, de pr\u00eatres, et d\u2019autres personnes&nbsp;\u00bb, se souvient-il.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Au milieu de tous ces conseils, ma m\u00e8re, qui n\u2019est jamais all\u00e9e \u00e0 l\u2019\u00e9cole, a dit quelque chose qui est rest\u00e9 dans mon esprit. \u201cL\u2019endroit o\u00f9 Dieu veut que nous soyons peut n\u2019\u00eatre pas confortable, ou pas \u00e0 notre go\u00fbt, mais c\u2019est l\u00e0 que nous trouvons le vrai bonheur\u201d. Et je pense qu\u2019elle a raison.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est ainsi que Tobias poursuit sa mission, soutenu par les paroles de Saint Paul dans sa deuxi\u00e8me lettre aux Corinthiens&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;En toute circonstance, nous sommes dans la d\u00e9tresse, mais sans \u00eatre angoiss\u00e9s&nbsp;; nous sommes d\u00e9concert\u00e9s, mais non d\u00e9sempar\u00e9s&nbsp;; nous sommes pourchass\u00e9s, mais non pas abandonn\u00e9s&nbsp;; terrass\u00e9s, mais non pas an\u00e9antis. Toujours nous portons, dans notre corps, la mort de J\u00e9sus, afin que la vie de J\u00e9sus, elle aussi, soit manifest\u00e9e dans notre corps. En effet, nous, les vivants, nous sommes continuellement livr\u00e9s \u00e0 la mort \u00e0 cause de J\u00e9sus, afin que la vie de J\u00e9sus, elle aussi, soit manifest\u00e9e dans notre condition charnelle vou\u00e9e \u00e0 la mort. Ainsi la mort fait son \u0153uvre en nous, et la vie en vous.&nbsp;\u00bb (2 Corinthiens 4 : 8-12)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;<\/strong><strong>En 2025, Aid to the Church in Need (ACN) consacre sa campagne de No\u00ebl aux cat\u00e9chistes, v\u00e9ritables piliers de la foi dans les endroits les plus difficiles pour maintenir l&rsquo;esp\u00e9rance dans le monde.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malgr\u00e9 plusieurs attaques et une tentative d\u2019assassinat, Tobias Yahaya a d\u00e9cid\u00e9 de rester \u00e0 Sokoto pour poursuivre son minist\u00e8re au service de l\u2019Eglise. Le 19 avril 2023, vers 3 heures du matin, trois hommes arm\u00e9s ont franchi la cl\u00f4ture de s\u00e9curit\u00e9 entourant le domicile de Tobias Yahaya, pr\u00e8s de la cath\u00e9drale de la Sainte-Famille de [&hellip;]<\/p>\n","protected":false},"author":4258341461,"featured_media":260774,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[1276],"tags":[],"country":[1454],"class_list":["post-260789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured-fr","country-nigeria-fr-2"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nigeria\u00a0: un cat\u00e9chiste pardonne \u00e0 l\u2019homme qui a tent\u00e9 de le tuer en raison de son minist\u00e8re | ACN International<\/title>\n<meta name=\"description\" content=\"L\u2019endroit o\u00f9 Dieu veut que nous soyons peut n\u2019\u00eatre pas confortable, ou pas \u00e0 notre go\u00fbt, mais c\u2019est l\u00e0 que nous trouvons le vrai bonheu\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nigeria\u00a0: un cat\u00e9chiste pardonne \u00e0 l\u2019homme qui a tent\u00e9 de le tuer en raison de son minist\u00e8re\" \/>\n<meta property=\"og:description\" content=\"L\u2019endroit o\u00f9 Dieu veut que nous soyons peut n\u2019\u00eatre pas confortable, ou pas \u00e0 notre go\u00fbt, mais c\u2019est l\u00e0 que nous trouvons le vrai bonheu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-10T06:22:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T06:22:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"John Burger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/JohnBurger\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"John Burger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/\"},\"author\":{\"name\":\"John Burger\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/b42b8684e5819123b6699ed3f377ac93\"},\"headline\":\"Nigeria\u00a0: un cat\u00e9chiste pardonne \u00e0 l\u2019homme qui a tent\u00e9 de le tuer en raison de son minist\u00e8re\",\"datePublished\":\"2025-12-10T06:22:02+00:00\",\"dateModified\":\"2025-12-10T06:22:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/\"},\"wordCount\":1080,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ACN-20251209-198950.jpg\",\"articleSection\":[\"FEATURED\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/\",\"name\":\"Nigeria\u00a0: un cat\u00e9chiste pardonne \u00e0 l\u2019homme qui a tent\u00e9 de le tuer en raison de son minist\u00e8re | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ACN-20251209-198950.jpg\",\"datePublished\":\"2025-12-10T06:22:02+00:00\",\"dateModified\":\"2025-12-10T06:22:11+00:00\",\"description\":\"L\u2019endroit o\u00f9 Dieu veut que nous soyons peut n\u2019\u00eatre pas confortable, ou pas \u00e0 notre go\u00fbt, mais c\u2019est l\u00e0 que nous trouvons le vrai bonheu\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ACN-20251209-198950.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ACN-20251209-198950.jpg\",\"width\":1980,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FEATURED\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/featured-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nigeria\u00a0: un cat\u00e9chiste pardonne \u00e0 l\u2019homme qui a tent\u00e9 de le tuer en raison de son minist\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/b42b8684e5819123b6699ed3f377ac93\",\"name\":\"John Burger\",\"description\":\"John Burger is communications consultant to Aid to the Church in Need-USA. A native of New York, he spent several years teaching internationally, and the next 32 years in Catholic journalism in the United States. He is author of the 2023 book At the Foot of the Cross: Lessons from Ukraine.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/JohnBurger\"],\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/john-burger\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nigeria\u00a0: un cat\u00e9chiste pardonne \u00e0 l\u2019homme qui a tent\u00e9 de le tuer en raison de son minist\u00e8re | ACN International","description":"L\u2019endroit o\u00f9 Dieu veut que nous soyons peut n\u2019\u00eatre pas confortable, ou pas \u00e0 notre go\u00fbt, mais c\u2019est l\u00e0 que nous trouvons le vrai bonheu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/","og_locale":"fr_FR","og_type":"article","og_title":"Nigeria\u00a0: un cat\u00e9chiste pardonne \u00e0 l\u2019homme qui a tent\u00e9 de le tuer en raison de son minist\u00e8re","og_description":"L\u2019endroit o\u00f9 Dieu veut que nous soyons peut n\u2019\u00eatre pas confortable, ou pas \u00e0 notre go\u00fbt, mais c\u2019est l\u00e0 que nous trouvons le vrai bonheu","og_url":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2025-12-10T06:22:02+00:00","article_modified_time":"2025-12-10T06:22:11+00:00","og_image":[{"width":1980,"height":800,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg","type":"image\/jpeg"}],"author":"John Burger","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/JohnBurger","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"John Burger","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/"},"author":{"name":"John Burger","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/b42b8684e5819123b6699ed3f377ac93"},"headline":"Nigeria\u00a0: un cat\u00e9chiste pardonne \u00e0 l\u2019homme qui a tent\u00e9 de le tuer en raison de son minist\u00e8re","datePublished":"2025-12-10T06:22:02+00:00","dateModified":"2025-12-10T06:22:11+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/"},"wordCount":1080,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg","articleSection":["FEATURED"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/","url":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/","name":"Nigeria\u00a0: un cat\u00e9chiste pardonne \u00e0 l\u2019homme qui a tent\u00e9 de le tuer en raison de son minist\u00e8re | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg","datePublished":"2025-12-10T06:22:02+00:00","dateModified":"2025-12-10T06:22:11+00:00","description":"L\u2019endroit o\u00f9 Dieu veut que nous soyons peut n\u2019\u00eatre pas confortable, ou pas \u00e0 notre go\u00fbt, mais c\u2019est l\u00e0 que nous trouvons le vrai bonheu","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg","width":1980,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/nigeria-un-catechiste-pardonne-a-lhomme-qui-a-tente-de-le-tuer-en-raison-de-son-ministere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"FEATURED","item":"https:\/\/acninternational.org\/fr\/category\/featured-fr\/"},{"@type":"ListItem","position":3,"name":"Nigeria\u00a0: un cat\u00e9chiste pardonne \u00e0 l\u2019homme qui a tent\u00e9 de le tuer en raison de son minist\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/b42b8684e5819123b6699ed3f377ac93","name":"John Burger","description":"John Burger is communications consultant to Aid to the Church in Need-USA. A native of New York, he spent several years teaching internationally, and the next 32 years in Catholic journalism in the United States. He is author of the 2023 book At the Foot of the Cross: Lessons from Ukraine.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/JohnBurger"],"url":"https:\/\/acninternational.org\/fr\/author\/john-burger\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/260789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/4258341461"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=260789"}],"version-history":[{"count":1,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/260789\/revisions"}],"predecessor-version":[{"id":260790,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/260789\/revisions\/260790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/260774"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=260789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=260789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=260789"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=260789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}