{"id":259552,"date":"2025-10-31T14:42:06","date_gmt":"2025-10-31T13:42:06","guid":{"rendered":"https:\/\/acninternational.org\/?p=259552"},"modified":"2025-10-31T15:57:57","modified_gmt":"2025-10-31T14:57:57","slug":"burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/","title":{"rendered":"Burkina Faso : deux dioc\u00e8ses frapp\u00e9s par une nouvelle vague d\u2019attaques"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>La fondation pontificale Aid to the Church in Need (ACN) exprime sa vive inqui\u00e9tude et sa profonde tristesse face \u00e0 la recrudescence du terrorisme dans les dioc\u00e8ses de Nouna (nord-ouest) et de Fada N&rsquo;Gourma (sud-est), au Burkina Faso. Ces trois derni\u00e8res semaines, les violences ont \u00e0 nouveau touch\u00e9 des civils et des membres de l\u2019\u00c9glise. Elles interviennent apr\u00e8s plusieurs mois d\u2019espoir pour la population et les personnes d\u00e9plac\u00e9es, qui commen\u00e7aient \u00e0 retourner dans leurs villages. Les sources locales d\u2019ACN, tenues anonymes pour leur s\u00e9curit\u00e9, font \u00e9tat d\u2019une situation d\u00e9grad\u00e9e malgr\u00e9 les efforts des forces de d\u00e9fense et des Volontaires pour la D\u00e9fense de la Patrie (VDP).<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20211012-117966-1024x683.jpg\" alt=\"\" class=\"wp-image-259537\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20211012-117966-1024x683.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20211012-117966-300x200.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20211012-117966-768x512.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20211012-117966.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Apr\u00e8s plusieurs mois de paix relative, le terrorisme a refait surface au Burkina Faso<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Le 6 octobre 2025, le dioc\u00e8se de Nouna a \u00e9t\u00e9 victime de deux assauts meurtriers. Sur la paroisse de Djibasso, dans la commune frontali\u00e8re de Madouba, trois adolescents de retour du Mali pour <a href=\"https:\/\/acninternational.org\/fr\/a-lest-du-burkina-faso-la-rentree-scolaire-reste-marquee-par-de-grandes-difficultes\/\">la rentr\u00e9e scolaire<\/a>, ont \u00e9t\u00e9 sortis d\u2019un bus et ex\u00e9cut\u00e9s. Des rumeurs persistantes planaient dans ce sens et certains villages de la zone avaient \u00e9t\u00e9 inqui\u00e9t\u00e9s ces derni\u00e8res semaines par des menaces terroristes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelques heures plus tard, sur l\u2019axe Nouna\u2013D\u00e9dougou, un bus de passagers, pour la plupart originaires de la paroisse de Solenzo, et d\u2019autres personnes circulant sur la voie, ont \u00e9t\u00e9 la cible de tirs, faisant au moins 15 morts.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le m\u00eame jour, dans le dioc\u00e8se de Fada N&rsquo;Gourma, un cat\u00e9chiste du village de Kouala a \u00e9t\u00e9 enlev\u00e9 en pleine messe dominicale. \u00ab Il a \u00e9t\u00e9 sp\u00e9cifiquement vis\u00e9 par les terroristes. L\u2019intention est de semer la peur chez les chr\u00e9tiens, qui tant\u00f4t se voient autoris\u00e9s \u00e0 prier, tant\u00f4t subissent des exactions pour les faire fuir \u00bb, confie une des sources locales d\u2019ACN. Selon les informations re\u00e7ues par la fondation, il a \u00e9t\u00e9 lib\u00e9r\u00e9 par la suite.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20250819-193345-1024x768.jpg\" alt=\"\" class=\"wp-image-259543\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20250819-193345-1024x768.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20250819-193345-300x225.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20250819-193345-768x576.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20250819-193345.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Les chr\u00e9tiens sont minoritaires dans le pays et souvent victimes d&rsquo;agressions terroristes<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Quelques jours plus t\u00f4t, le 21 septembre, dans ce m\u00eame dioc\u00e8se, un autre cat\u00e9chiste de Saatenga a \u00e9t\u00e9 assassin\u00e9 dans une embuscade alors qu\u2019il rentrait d\u2019une r\u00e9union pastorale \u00e0 Diabo. Selon les informations recueillies par ACN, les routes de cette r\u00e9gion demeurent dangereuses et les groupes arm\u00e9s circulent d\u00e9sormais en effectifs r\u00e9duits pour des raisons qui restent \u00e0 \u00e9lucider. \u00ab De nombreux chr\u00e9tiens choisissent de prendre le risque de rester malgr\u00e9 des menaces de plus en plus pesantes dans certaines parties de ce dioc\u00e8se \u00bb, confie la source locale, \u00ab mais la peur s\u2019est install\u00e9e de mani\u00e8re durable au sein de la population civile \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fondation invite tous ses bienfaiteurs et amis \u00e0 prier pour les victimes, leurs familles, la population, et pour le retour de la paix et de la s\u00e9curit\u00e9 au Burkina Faso. ACN r\u00e9affirme son engagement \u00e0 soutenir l\u2019\u00c9glise et ses communaut\u00e9s chr\u00e9tiennes dans le maintien de l\u2019esp\u00e9rance et de la solidarit\u00e9, apportant secours mat\u00e9riel et spirituel face aux d\u00e9fis pos\u00e9s par le terrorisme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans son <a href=\"https:\/\/acninternational.org\/fr\/religiousfreedomreport\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rapport sur la libert\u00e9 religieuse dans le monde<\/a> publi\u00e9 le 21 octobre 2025, ACN alerte sur la situation au Burkina Faso, o\u00f9, depuis 2015, les attaques djihadistes d\u2019Al-Qa\u00efda et de l\u2019\u00c9tat islamique ont caus\u00e9 plus de 20 000 morts et fait plus de 2 millions de d\u00e9plac\u00e9s internes. En 2024, le pays repr\u00e9sentait un cinqui\u00e8me des d\u00e9c\u00e8s li\u00e9s au terrorisme mondial, avec 1 532 morts recens\u00e9s. Ces violences ont aussi entra\u00een\u00e9 la mort ou l\u2018enl\u00e8vement de dizaines de chefs religieux, ainsi que la fermeture d\u2019une trentaine de paroisses. Pr\u00e8s de la moiti\u00e9 du territoire est d\u00e9sormais contr\u00f4l\u00e9e par des groupes arm\u00e9s. Chr\u00e9tiens et musulmans sont menac\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fondation pontificale Aid to the Church in Need (ACN) exprime sa vive inqui\u00e9tude et sa profonde tristesse face \u00e0 la recrudescence du terrorisme dans les dioc\u00e8ses de Nouna (nord-ouest) et de Fada N&rsquo;Gourma (sud-est), au Burkina Faso. Ces trois derni\u00e8res semaines, les violences ont \u00e0 nouveau touch\u00e9 des civils et des membres de l\u2019\u00c9glise. [&hellip;]<\/p>\n","protected":false},"author":4258341481,"featured_media":259532,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[919,962],"tags":[],"country":[1476],"class_list":["post-259552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelle","category-news-fr","country-burkina-faso-fr"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Burkina Faso : deux dioc\u00e8ses frapp\u00e9s par une nouvelle vague d\u2019attaques | ACN International<\/title>\n<meta name=\"description\" content=\"Ces trois derni\u00e8res semaines, les violences ont \u00e0 nouveau touch\u00e9 des civils et des membres de l\u2019\u00c9glise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Burkina Faso : deux dioc\u00e8ses frapp\u00e9s par une nouvelle vague d\u2019attaques\" \/>\n<meta property=\"og:description\" content=\"Ces trois derni\u00e8res semaines, les violences ont \u00e0 nouveau touch\u00e9 des civils et des membres de l\u2019\u00c9glise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-31T13:42:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T14:57:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20250819-193376.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christophe Lafontaine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christophe Lafontaine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/\"},\"author\":{\"name\":\"Christophe Lafontaine\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/987b44dfb14eab5a1068181b3c28d42f\"},\"headline\":\"Burkina Faso : deux dioc\u00e8ses frapp\u00e9s par une nouvelle vague d\u2019attaques\",\"datePublished\":\"2025-10-31T13:42:06+00:00\",\"dateModified\":\"2025-10-31T14:57:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/\"},\"wordCount\":668,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ACN-20250819-193376.jpg\",\"articleSection\":[\"Nouvelle\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/\",\"name\":\"Burkina Faso : deux dioc\u00e8ses frapp\u00e9s par une nouvelle vague d\u2019attaques | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ACN-20250819-193376.jpg\",\"datePublished\":\"2025-10-31T13:42:06+00:00\",\"dateModified\":\"2025-10-31T14:57:57+00:00\",\"description\":\"Ces trois derni\u00e8res semaines, les violences ont \u00e0 nouveau touch\u00e9 des civils et des membres de l\u2019\u00c9glise.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ACN-20250819-193376.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ACN-20250819-193376.jpg\",\"width\":1980,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/news-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Burkina Faso : deux dioc\u00e8ses frapp\u00e9s par une nouvelle vague d\u2019attaques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/987b44dfb14eab5a1068181b3c28d42f\",\"name\":\"Christophe Lafontaine\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/christophe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Burkina Faso : deux dioc\u00e8ses frapp\u00e9s par une nouvelle vague d\u2019attaques | ACN International","description":"Ces trois derni\u00e8res semaines, les violences ont \u00e0 nouveau touch\u00e9 des civils et des membres de l\u2019\u00c9glise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/","og_locale":"fr_FR","og_type":"article","og_title":"Burkina Faso : deux dioc\u00e8ses frapp\u00e9s par une nouvelle vague d\u2019attaques","og_description":"Ces trois derni\u00e8res semaines, les violences ont \u00e0 nouveau touch\u00e9 des civils et des membres de l\u2019\u00c9glise.","og_url":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2025-10-31T13:42:06+00:00","article_modified_time":"2025-10-31T14:57:57+00:00","og_image":[{"width":1980,"height":800,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20250819-193376.jpg","type":"image\/jpeg"}],"author":"Christophe Lafontaine","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"Christophe Lafontaine","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/"},"author":{"name":"Christophe Lafontaine","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/987b44dfb14eab5a1068181b3c28d42f"},"headline":"Burkina Faso : deux dioc\u00e8ses frapp\u00e9s par une nouvelle vague d\u2019attaques","datePublished":"2025-10-31T13:42:06+00:00","dateModified":"2025-10-31T14:57:57+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/"},"wordCount":668,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20250819-193376.jpg","articleSection":["Nouvelle","Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/","url":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/","name":"Burkina Faso : deux dioc\u00e8ses frapp\u00e9s par une nouvelle vague d\u2019attaques | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20250819-193376.jpg","datePublished":"2025-10-31T13:42:06+00:00","dateModified":"2025-10-31T14:57:57+00:00","description":"Ces trois derni\u00e8res semaines, les violences ont \u00e0 nouveau touch\u00e9 des civils et des membres de l\u2019\u00c9glise.","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20250819-193376.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/10\/ACN-20250819-193376.jpg","width":1980,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/burkina-faso-deux-dioceses-frappes-par-une-nouvelle-vague-dattaques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/acninternational.org\/fr\/category\/news-fr\/"},{"@type":"ListItem","position":3,"name":"Burkina Faso : deux dioc\u00e8ses frapp\u00e9s par une nouvelle vague d\u2019attaques"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/987b44dfb14eab5a1068181b3c28d42f","name":"Christophe Lafontaine","url":"https:\/\/acninternational.org\/fr\/author\/christophe\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/259552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/4258341481"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=259552"}],"version-history":[{"count":2,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/259552\/revisions"}],"predecessor-version":[{"id":259561,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/259552\/revisions\/259561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/259532"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=259552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=259552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=259552"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=259552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}