{"id":255264,"date":"2025-09-11T08:07:30","date_gmt":"2025-09-11T06:07:30","guid":{"rendered":"https:\/\/acninternational.org\/?p=255264"},"modified":"2025-09-11T13:15:13","modified_gmt":"2025-09-11T11:15:13","slug":"irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/","title":{"rendered":"Irak\u00a0: un festival \u0153cum\u00e9nique montre la voie \u00e0 suivre pour l&rsquo;\u00c9glise pers\u00e9cut\u00e9e"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u00ab&nbsp;Ce que l&rsquo;on voulait autrefois r\u00e9duire au silence est devenu une proclamation. La foi a surv\u00e9cu et l\u2019esp\u00e9rance est plus forte que la mort.&nbsp;\u00bb<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Les chr\u00e9tiens qui ont surv\u00e9cu aux attaques djihadistes dans le Nord de l\u2019Irak sont r\u00e9unis pour un important festival, qui montre que la foi est toujours vivante dans la r\u00e9gion.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194227-1024x682.jpg\" alt=\"\" class=\"wp-image-255237\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194227-1024x682.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194227-300x200.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194227-768x511.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194227.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Les responsables des diff\u00e9rentes confessions chr\u00e9tiennes se r\u00e9unissent pour marquer l&rsquo;Exaltation de la Croix<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Du 9 au 13 septembre 2025, des chr\u00e9tiens des diff\u00e9rentes traditions pr\u00e9sentes dans la r\u00e9gion \u2013 Eglise assyrienne d\u2019Orient, chald\u00e9ens, syriaques catholiques et syriaques orthodoxes \u2013 se r\u00e9unissent pour une c\u00e9l\u00e9bration prolong\u00e9e de la f\u00eate de l\u2019Exaltation de la Sainte Croix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mgr Bashar Warda, archev\u00eaque chald\u00e9en, a travaill\u00e9 avec les leaders des autres \u00c9glises pour organiser cet \u00e9v\u00e9nement. Il a d\u00e9clar\u00e9 \u00e0 la fondation pontificale Aid to the Church in Need (ACN) \u2013 qui a contribu\u00e9 \u00e0 soutenir les c\u00e9l\u00e9brations \u2013 que c\u2019\u00e9tait un signe montrant que la foi est toujours vivante. Il a notamment d\u00e9clar\u00e9&nbsp;: \u00ab&nbsp;Le moment choisi pour ce festival est profond\u00e9ment symbolique. Il y a dix ans, Daesh a cherch\u00e9 \u00e0 effacer le christianisme de cette terre. Aujourd\u2019hui, ces m\u00eames communaut\u00e9s brandissent haut la croix sur les places publiques, dans les \u00e9glises et lors de processions joyeuses. Ce que l&rsquo;on voulait autrefois r\u00e9duire au silence est devenu une proclamation : la foi a surv\u00e9cu et l\u2019esp\u00e9rance est plus forte que la mort.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194226-1024x682.jpg\" alt=\"\" class=\"wp-image-255243\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194226-1024x682.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194226-300x200.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194226-768x511.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194226.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00a0Cette c\u00e9l\u00e9bration commune est un signe de r\u00e9silience dans une r\u00e9gion marqu\u00e9e par de grandes pers\u00e9cutions dans le pass\u00e9<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Le groupe islamiste extr\u00e9miste Daesh (ISIS) a contr\u00f4l\u00e9 certaines parties de la plaine de Ninive, au Nord de l\u2019Irak, de 2014 \u00e0 2017. Plus de 120.000 chr\u00e9tiens ont trouv\u00e9 refuge \u00e0 Erbil, dans la r\u00e9gion semi-autonome du Kurdistan irakien, apr\u00e8s avoir fui leurs maisons en ao\u00fbt 2014. ACN a soutenu les r\u00e9fugi\u00e9s chr\u00e9tiens qui ont fui en 2014 et, apr\u00e8s la d\u00e9faite de Daesh, a aid\u00e9 \u00e0 reconstruire les villes et villages chr\u00e9tiens pour permettre aux communaut\u00e9s de retourner chez elles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les festivit\u00e9s doivent commencer aujourd\u2019hui 9 septembre par une procession aux flambeaux de 2 km \u00e0 Ankawa, en banlieue d\u2019Erbil, depuis le sanctuaire chald\u00e9en de Saint-Elie jusqu\u2019\u00e0 la cath\u00e9drale assyrienne Saint-Jean-Baptiste, o\u00f9 les pri\u00e8res et l\u2019hom\u00e9lie donn\u00e9e par le patriarche de l\u2019Eglise assyrienne d\u2019Orient Mar Awa III seront suivies d\u2019un repas. Le programme charg\u00e9 comprend des pri\u00e8res, de la musique, des \u00e9v\u00e9nements culturels, des activit\u00e9s et comp\u00e9titions sportives, jusqu&rsquo;\u00e0 la veill\u00e9e de l&rsquo;Exaltation de la Sainte Croix, le 13 septembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce festival de cinq jours est d\u00e9sormais inscrit au calendrier annuel des \u00c9glises, faisant suite aux c\u00e9l\u00e9brations \u0153cum\u00e9niques de 2024. L\u2019\u00e9dition 2025 s\u2019appuie sur les activit\u00e9s de l\u2019ann\u00e9e derni\u00e8re \u00ab&nbsp;en cherchant non seulement \u00e0 r\u00e9it\u00e9rer leur succ\u00e8s, mais aussi \u00e0 \u00e9largir leur port\u00e9e, \u00e0 approfondir leur contenu et \u00e0 y impliquer plus de jeunes et de familles issus des diff\u00e9rentes \u00c9glises.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mgr Warda a rendu hommage au Comit\u00e9 des jeunes, compos\u00e9 de 20 b\u00e9n\u00e9voles des quatre \u00c9glises, qui ont jou\u00e9 un r\u00f4le de premier plan. Il a affirm\u00e9&nbsp;: \u00ab&nbsp;Les jeunes de toutes les \u00c9glises ont pr\u00e9par\u00e9 ensemble ce festival, organisant des pri\u00e8res, des activit\u00e9s sportives, des marathons, des concerts, des jeux pour les enfants et des \u00e9v\u00e9nements culturels. Leur collaboration est devenue un signe visible d\u2019un nouvel avenir. Les g\u00e9n\u00e9rations plus \u00e2g\u00e9es ont observ\u00e9 avec admiration comment ces jeunes ont d\u00e9couvert que ce qui les unit \u2013 leur foi en Christ \u2013 est bien plus grand que ce qui les divise. Entre leurs mains, le r\u00eave de l\u2019unit\u00e9 chr\u00e9tienne en Irak est d\u00e9j\u00e0 en train de devenir une r\u00e9alit\u00e9 v\u00e9cue.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le festival est consid\u00e9r\u00e9 comme fondamental pour l\u2019avenir du christianisme dans le pays. Le dernier recensement, r\u00e9alis\u00e9 par Saddam Hussein, chiffrait les croyants \u00e0 1,4 million, mais leur nombre est aujourd\u2019hui tomb\u00e9 bien en dessous d\u2019un quart de million.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194228-1024x682.jpg\" alt=\"\" class=\"wp-image-255249\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194228-1024x682.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194228-300x200.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194228-768x511.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194228.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Des milliers de fid\u00e8les, de diff\u00e9rentes confessions, se r\u00e9unissent pour partager des repas et c\u00e9l\u00e9brer<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Selon Mgr Bashar Warda, \u00ab&nbsp;le Festival de la Croix 2025 est plus qu\u2019une c\u00e9l\u00e9bration locale. C\u2019est un message adress\u00e9 \u00e0 toute l\u2019\u00c9glise. De la terre d\u2019Abraham, o\u00f9 les chr\u00e9tiens ont souffert l\u2019exil et la pers\u00e9cution, s\u2019\u00e9l\u00e8ve une parole d\u2019esp\u00e9rance&nbsp;: nous sommes toujours l\u00e0. Nous sommes unis dans le Christ. La Croix n\u2019a pas \u00e9t\u00e9 r\u00e9duite au silence et, en Irak, une \u00c9glise petite et meurtrie a montr\u00e9 au monde la puissance de l\u2019unit\u00e9, le courage de la foi et la joie de la vie ressuscit\u00e9e.&nbsp;\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd\u2019hui, ces m\u00eames communaut\u00e9s brandissent haut la croix sur les places publiques, dans les \u00e9glises et lors de processions joyeuses<\/p>\n","protected":false},"author":4258341477,"featured_media":255232,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[919,962],"tags":[],"country":[1446],"class_list":["post-255264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelle","category-news-fr","country-iraq-fr"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Irak\u00a0: un festival \u0153cum\u00e9nique montre la voie \u00e0 suivre pour l&#039;\u00c9glise pers\u00e9cut\u00e9e | ACN International<\/title>\n<meta name=\"description\" content=\"Aujourd\u2019hui, ces m\u00eames communaut\u00e9s brandissent haut la croix sur les places publiques, dans les \u00e9glises et lors de processions joyeuses.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Irak\u00a0: un festival \u0153cum\u00e9nique montre la voie \u00e0 suivre pour l&#039;\u00c9glise pers\u00e9cut\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Aujourd\u2019hui, ces m\u00eames communaut\u00e9s brandissent haut la croix sur les places publiques, dans les \u00e9glises et lors de processions joyeuses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-11T06:07:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T11:15:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"John Newton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"John Newton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/\"},\"author\":{\"name\":\"John Newton\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/5243e12a4e135672e43bcc5c2157627d\"},\"headline\":\"Irak\u00a0: un festival \u0153cum\u00e9nique montre la voie \u00e0 suivre pour l&rsquo;\u00c9glise pers\u00e9cut\u00e9e\",\"datePublished\":\"2025-09-11T06:07:30+00:00\",\"dateModified\":\"2025-09-11T11:15:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/\"},\"wordCount\":865,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ACN-20250909-194223-1.jpg\",\"articleSection\":[\"Nouvelle\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/\",\"name\":\"Irak\u00a0: un festival \u0153cum\u00e9nique montre la voie \u00e0 suivre pour l'\u00c9glise pers\u00e9cut\u00e9e | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ACN-20250909-194223-1.jpg\",\"datePublished\":\"2025-09-11T06:07:30+00:00\",\"dateModified\":\"2025-09-11T11:15:13+00:00\",\"description\":\"Aujourd\u2019hui, ces m\u00eames communaut\u00e9s brandissent haut la croix sur les places publiques, dans les \u00e9glises et lors de processions joyeuses.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ACN-20250909-194223-1.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ACN-20250909-194223-1.jpg\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/news-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Irak\u00a0: un festival \u0153cum\u00e9nique montre la voie \u00e0 suivre pour l&rsquo;\u00c9glise pers\u00e9cut\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/5243e12a4e135672e43bcc5c2157627d\",\"name\":\"John Newton\",\"description\":\"John Newton has worked in Aid to the Church in Need (UK)\u2019s Press and Public Affairs Department, which oversees various areas of the charity\u2019s work including PR, research and parliamentary outreach, for almost two decades. Dr Newton is the co-author of the charity\u2019s keynote Persecuted and Forgotten? report on the oppression of Christians, and a contributor to its comprehensive Religious Freedom in the World report. He has also authored Religious Freedom Today: The Catholic View and The Eastern Catholic Churches: A Short Introduction.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/john-newton\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Irak\u00a0: un festival \u0153cum\u00e9nique montre la voie \u00e0 suivre pour l'\u00c9glise pers\u00e9cut\u00e9e | ACN International","description":"Aujourd\u2019hui, ces m\u00eames communaut\u00e9s brandissent haut la croix sur les places publiques, dans les \u00e9glises et lors de processions joyeuses.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/","og_locale":"fr_FR","og_type":"article","og_title":"Irak\u00a0: un festival \u0153cum\u00e9nique montre la voie \u00e0 suivre pour l'\u00c9glise pers\u00e9cut\u00e9e","og_description":"Aujourd\u2019hui, ces m\u00eames communaut\u00e9s brandissent haut la croix sur les places publiques, dans les \u00e9glises et lors de processions joyeuses.","og_url":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2025-09-11T06:07:30+00:00","article_modified_time":"2025-09-11T11:15:13+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg","type":"image\/jpeg"}],"author":"John Newton","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"John Newton","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/"},"author":{"name":"John Newton","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/5243e12a4e135672e43bcc5c2157627d"},"headline":"Irak\u00a0: un festival \u0153cum\u00e9nique montre la voie \u00e0 suivre pour l&rsquo;\u00c9glise pers\u00e9cut\u00e9e","datePublished":"2025-09-11T06:07:30+00:00","dateModified":"2025-09-11T11:15:13+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/"},"wordCount":865,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg","articleSection":["Nouvelle","Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/","url":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/","name":"Irak\u00a0: un festival \u0153cum\u00e9nique montre la voie \u00e0 suivre pour l'\u00c9glise pers\u00e9cut\u00e9e | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg","datePublished":"2025-09-11T06:07:30+00:00","dateModified":"2025-09-11T11:15:13+00:00","description":"Aujourd\u2019hui, ces m\u00eames communaut\u00e9s brandissent haut la croix sur les places publiques, dans les \u00e9glises et lors de processions joyeuses.","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/irak-un-festival-oecumenique-montre-la-voie-a-suivre-pour-leglise-persecutee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/acninternational.org\/fr\/category\/news-fr\/"},{"@type":"ListItem","position":3,"name":"Irak\u00a0: un festival \u0153cum\u00e9nique montre la voie \u00e0 suivre pour l&rsquo;\u00c9glise pers\u00e9cut\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/5243e12a4e135672e43bcc5c2157627d","name":"John Newton","description":"John Newton has worked in Aid to the Church in Need (UK)\u2019s Press and Public Affairs Department, which oversees various areas of the charity\u2019s work including PR, research and parliamentary outreach, for almost two decades. Dr Newton is the co-author of the charity\u2019s keynote Persecuted and Forgotten? report on the oppression of Christians, and a contributor to its comprehensive Religious Freedom in the World report. He has also authored Religious Freedom Today: The Catholic View and The Eastern Catholic Churches: A Short Introduction.","url":"https:\/\/acninternational.org\/fr\/author\/john-newton\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/255264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/4258341477"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=255264"}],"version-history":[{"count":2,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/255264\/revisions"}],"predecessor-version":[{"id":255345,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/255264\/revisions\/255345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/255232"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=255264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=255264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=255264"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=255264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}