{"id":231502,"date":"2024-11-04T16:55:40","date_gmt":"2024-11-04T15:55:40","guid":{"rendered":"https:\/\/acninternational.org\/?p=231502"},"modified":"2025-08-12T10:28:30","modified_gmt":"2025-08-12T08:28:30","slug":"burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/","title":{"rendered":"Burkina Faso : un pr\u00eatre appelle \u00e0 prier apr\u00e8s trois nouvelles attaques terroristes dans l\u2019est du pays"},"content":{"rendered":"<p><em>Le dioc\u00e8se de Fada N\u2019Gourma a \u00e9t\u00e9 secou\u00e9 par de nouvelles attaques terroristes dans les paroisses de Piela et de Saatenga, causant la mort de plusieurs personnes et d&rsquo;importants d\u00e9g\u00e2ts mat\u00e9riels. Ces attaques s\u2019inscrivent dans un contexte de violence terroriste persistante dans le pays depuis 2015.<\/em><\/p>\n<p>\u00ab\u00a0Les attaques se multiplient. Nous nous recommandons \u00e0 vos ferventes pri\u00e8res. Priez pour les victimes et pour les survivants qui sont apeur\u00e9s\u00a0\u00bb, a demand\u00e9 un pr\u00eatre du dioc\u00e8se de Fada N\u2019Gourma dans l\u2019est du Burkina Faso \u00e0 la fondation internationale Aid to the Church in Need (ACN).<\/p>\n<p>D\u00e9but octobre, au moins <a href=\"https:\/\/acninternational.org\/fr\/burkina-faso-des-terroristes-se-livrent-a-un-massacre-brutal-sur-trois-jours\/\" target=\"_blank\" rel=\"noopener\">150 personnes ont \u00e9t\u00e9 tu\u00e9es par des terroristes \u00e0 Manni<\/a>, dans le m\u00eame dioc\u00e8se. \u00a0Le 20 octobre, Zi\u00e9la et Kombembgo, deux villages de la paroisse de Saatenga dans le sud-ouest de Fada N\u2019Gourma, ont \u00e9t\u00e9 attaqu\u00e9s par une centaine de terroristes.<\/p>\n<p>\u00c0 Zi\u00e9la, des terroristes ont surgi vers 10h du matin. Alors que les habitants vaquaient \u00e0 leurs occupations apr\u00e8s la pri\u00e8re dominicale, des coups de feu ont \u00e9t\u00e9 tir\u00e9s. Les hommes ont imm\u00e9diatement tent\u00e9 de fuir et de se cacher, car, comme l\u2019explique une source locale \u00e0 ACN, les terroristes \u00ab\u00a0s&rsquo;attaquent principalement aux hommes en \u00e2ge de combattre, et non aux femmes, aux enfants ou aux personnes \u00e2g\u00e9es\u00a0\u00bb. Cependant, \u00ab une jeune fille chr\u00e9tienne qui a voulu fuir sa maison, a tragiquement perdu la vie, abattue par erreur, les terroristes croyants qu&rsquo;il s&rsquo;agissait d\u2019un adulte\u00a0\u00bb a d\u00e9clar\u00e9 la source, qui pr\u00e9f\u00e8re garder l&rsquo;anonymat par crainte de repr\u00e9sailles.<\/p>\n<figure id=\"attachment_231486\" aria-describedby=\"caption-attachment-231486\" style=\"width: 720px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-231486 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241104-174675.jpg\" alt=\"Destruction du village de Kouri apr\u00e8s l'attaque terroriste du 19 octobre 2024\" width=\"720\" height=\"960\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241104-174675.jpg 720w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241104-174675-225x300.jpg 225w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption id=\"caption-attachment-231486\" class=\"wp-caption-text\">Destruction du village de Kouri apr\u00e8s l&rsquo;attaque terroriste du 19 octobre 2024<\/figcaption><\/figure>\n<p>Toujours selon la m\u00eame source, les terroristes ont mis le feu \u00e0 de nombreuses maisons appartenant aussi bien \u00e0 des familles chr\u00e9tiennes que musulmanes. Parmi les maisons prises pour cible figurait celle du cat\u00e9chiste, qui se trouvait \u00e0 l\u2019ext\u00e9rieur du village au moment de l&rsquo;attaque. Sa femme, rest\u00e9e sur place avec trois de leurs jeunes enfants, a \u00e9t\u00e9 malmen\u00e9e et leur maison pill\u00e9e puis incendi\u00e9e. \u00ab\u00a0La famille est saine et sauve, et le fait que le mari \u00e9tait absent lui a sauv\u00e9 la vie \u00bb, a rapport\u00e9 la source locale \u00e0 ACN.<\/p>\n<p>Les cat\u00e9chistes sont actuellement en premi\u00e8re ligne des violences dans le pays, car ce sont eux qui sont charg\u00e9s de l\u2019encadrement pastoral des fid\u00e8les dans de nombreux villages. Et tous n\u2019ont pas la m\u00eame chance que le cat\u00e9chiste de Zi\u00e9la\u00a0: \u00ab Il y a six mois \u00e0 peine, <a href=\"https:\/\/acninternational.org\/breaking-news-catechist-kidnapped-and-killed-in-burkina-faso\/\" target=\"_blank\" rel=\"noopener\">\u00c9douard Yougbar\u00e9, cat\u00e9chiste \u00e0 Pouargoguin<\/a>, \u00e0 7 km de Saatenga, a \u00e9t\u00e9 sauvagement \u00e9gorg\u00e9, laissant derri\u00e8re lui une veuve et huit enfants. Ses derniers mots ont \u00e9t\u00e9 : \u2018Seigneur J\u00e9sus, viens me sauver ! Seigneur J\u00e9sus, viens me sauver !\u2019 \u00bb, se souvient l\u2019interlocuteur d\u2019ACN.<\/p>\n<p>Ce m\u00eame dimanche 20 octobre, Kombembgo, un village situ\u00e9 \u00e0 12 km de Saatenga, a \u00e9galement \u00e9t\u00e9 cibl\u00e9 par les terroristes. Selon les informations recueillies par ACN, trois Volontaires pour la D\u00e9fense de la Patrie (VDP) et un civil ont perdu la vie lors de cet assaut.<\/p>\n<p>Les VDP, des civils qui collaborent avec les forces de s\u00e9curit\u00e9 de l\u2019\u00c9tat, jouent un r\u00f4le crucial dans la d\u00e9fense des communaut\u00e9s rurales non prot\u00e9g\u00e9es, l\u00e0 o\u00f9 l&rsquo;arm\u00e9e burkinab\u00e9e a du mal \u00e0 intervenir. \u00ab Gr\u00e2ce \u00e0 la r\u00e9action rapide des VDP qui ont pu \u00e9liminer quelques terroristes, ceux-ci n\u2019ont pas eu le temps d\u2019incendier les maisons \u00e0 Kombembgo \u00bb, a expliqu\u00e9 la source.<\/p>\n<p>Cependant, l&rsquo;engagement des VDP contre les terroristes comporte de grands risques, comme l\u2019a d\u00e9montr\u00e9 l\u2019attaque de Kouri, dans la paroisse de Piela, \u00e0 environ 150 km de Saatenga, dans le nord de Fada N\u2019Gourma, seulement un jour plus t\u00f4t, le 19 octobre. Le village a \u00e9t\u00e9 attaqu\u00e9 par plus de 100 terroristes qui ont tu\u00e9 environ 13 personnes, dont deux VDP et une femme catholique.<\/p>\n<figure id=\"attachment_231492\" aria-describedby=\"caption-attachment-231492\" style=\"width: 720px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-231492 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241028-174234.jpg\" alt=\"Plus de 100 assaillants ont frapp\u00e9 le village de Kouri, pr\u00e8s de Piela, tuant 13 personnes et d\u00e9truisant des maisons, le dispensaire, la pharmacie et le poste VDP.\" width=\"720\" height=\"961\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241028-174234.jpg 720w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241028-174234-225x300.jpg 225w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption id=\"caption-attachment-231492\" class=\"wp-caption-text\">Plus de 100 assaillants ont frapp\u00e9 le village de Kouri, pr\u00e8s de Piela, tuant 13 personnes et d\u00e9truisant des maisons, le dispensaire, la pharmacie et le poste VDP.<\/figcaption><\/figure>\n<p>Ce raid semble avoir \u00e9t\u00e9 men\u00e9 en repr\u00e9sailles au soutien apport\u00e9 par la population aux VDP. \u00a0\u00ab Les femmes avaient offert une moto aux VDP pour leur lutte en faveur de la paix, un geste qui a d\u00e9plu aux terroristes\u00a0\u00bb, a expliqu\u00e9 une source locale \u00e0 ACN. \u00ab\u00a0Les assaillants ont \u00e9galement mis le feu \u00e0 16 maisons, malheureusement situ\u00e9es sur une colline qui a permis aux terroristes de se rapprocher de Kouri sans \u00eatre d\u00e9tect\u00e9s \u00e0 temps, toutes appartenant \u00e0 des familles catholiques \u00bb a-t-il ajout\u00e9. Des infrastructures essentielles comme le dispensaire, la pharmacie et le poste des VDP auraient \u00e9galement \u00e9t\u00e9 d\u00e9truites. Les deux cat\u00e9chistes du village ont pu s\u2019\u00e9chapper devenant des d\u00e9plac\u00e9s internes.<\/p>\n<p>Kouri avait d\u00e9j\u00e0 \u00e9t\u00e9 la cible d&rsquo;une autre attaque terroriste le 1er juin 2024, au cours de laquelle des personnes ont perdu la vie et des maisons ont \u00e9t\u00e9 incendi\u00e9es, ce qui avait conduit \u00e0 l\u2019installation de VDP pour renforcer la s\u00e9curit\u00e9 locale.<\/p>\n<p>L&rsquo;un des pr\u00eatres locaux a appel\u00e9 \u00e0 prier pour les victimes et pour la paix : \u00ab\u00a0Implorons le Seigneur pour que la paix revienne dans notre pays, ainsi que dans tous les pays frapp\u00e9s chaque jour par des attaques meurtri\u00e8res, comme le Mali et le Niger, et dans les nations en guerre comme l&rsquo;Ukraine, Isra\u00ebl et le Liban. Que la pri\u00e8re de saint Fran\u00e7ois d\u2019Assise nous guide\u00a0: \u00ab Seigneur, fais de moi un instrument de ta paix. L\u00e0 o\u00f9 est la haine, que je mette l\u2019amour. \u00bb<\/p>\n<p>Ces trag\u00e9dies soulignent l&rsquo;urgence de la situation s\u00e9curitaire au Burkina Faso, o\u00f9 les attaques terroristes qui ont d\u00e9but\u00e9 en 2015, continuent de ravager les communaut\u00e9s, laissant dans leur sillage plus de deux millions de d\u00e9plac\u00e9s internes.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le dioc\u00e8se de Fada N\u2019Gourma a \u00e9t\u00e9 secou\u00e9 par de nouvelles attaques terroristes dans les paroisses de Piela et de<\/p>\n","protected":false},"author":4258341405,"featured_media":231481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[919,962],"tags":[],"country":[315],"class_list":["post-231502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelle","category-news-fr","country-burkina-faso"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Burkina Faso : un pr\u00eatre appelle \u00e0 prier apr\u00e8s trois nouvelles attaques terroristes dans l\u2019est du pays | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Burkina Faso : un pr\u00eatre appelle \u00e0 prier apr\u00e8s trois nouvelles attaques terroristes dans l\u2019est du pays\" \/>\n<meta property=\"og:description\" content=\"Le dioc\u00e8se de Fada N\u2019Gourma a \u00e9t\u00e9 secou\u00e9 par de nouvelles attaques terroristes dans les paroisses de Piela et de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-04T15:55:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T08:28:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241029-174316.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sina Hartert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sina Hartert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/\"},\"author\":{\"name\":\"Sina Hartert\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/333738ed03abe11491094c5c30cf3133\"},\"headline\":\"Burkina Faso : un pr\u00eatre appelle \u00e0 prier apr\u00e8s trois nouvelles attaques terroristes dans l\u2019est du pays\",\"datePublished\":\"2024-11-04T15:55:40+00:00\",\"dateModified\":\"2025-08-12T08:28:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/\"},\"wordCount\":1025,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/ACN-20241029-174316.jpg\",\"articleSection\":[\"Nouvelle\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/\",\"name\":\"Burkina Faso : un pr\u00eatre appelle \u00e0 prier apr\u00e8s trois nouvelles attaques terroristes dans l\u2019est du pays | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/ACN-20241029-174316.jpg\",\"datePublished\":\"2024-11-04T15:55:40+00:00\",\"dateModified\":\"2025-08-12T08:28:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/ACN-20241029-174316.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/ACN-20241029-174316.jpg\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/news-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Burkina Faso : un pr\u00eatre appelle \u00e0 prier apr\u00e8s trois nouvelles attaques terroristes dans l\u2019est du pays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/333738ed03abe11491094c5c30cf3133\",\"name\":\"Sina Hartert\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/sina-hartert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Burkina Faso : un pr\u00eatre appelle \u00e0 prier apr\u00e8s trois nouvelles attaques terroristes dans l\u2019est du pays | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/","og_locale":"fr_FR","og_type":"article","og_title":"Burkina Faso : un pr\u00eatre appelle \u00e0 prier apr\u00e8s trois nouvelles attaques terroristes dans l\u2019est du pays","og_description":"Le dioc\u00e8se de Fada N\u2019Gourma a \u00e9t\u00e9 secou\u00e9 par de nouvelles attaques terroristes dans les paroisses de Piela et de","og_url":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2024-11-04T15:55:40+00:00","article_modified_time":"2025-08-12T08:28:30+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241029-174316.jpg","type":"image\/jpeg"}],"author":"Sina Hartert","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"Sina Hartert","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/"},"author":{"name":"Sina Hartert","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/333738ed03abe11491094c5c30cf3133"},"headline":"Burkina Faso : un pr\u00eatre appelle \u00e0 prier apr\u00e8s trois nouvelles attaques terroristes dans l\u2019est du pays","datePublished":"2024-11-04T15:55:40+00:00","dateModified":"2025-08-12T08:28:30+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/"},"wordCount":1025,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241029-174316.jpg","articleSection":["Nouvelle","Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/","url":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/","name":"Burkina Faso : un pr\u00eatre appelle \u00e0 prier apr\u00e8s trois nouvelles attaques terroristes dans l\u2019est du pays | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241029-174316.jpg","datePublished":"2024-11-04T15:55:40+00:00","dateModified":"2025-08-12T08:28:30+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241029-174316.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/11\/ACN-20241029-174316.jpg","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/burkina-faso-un-pretre-appelle-a-prier-apres-trois-nouvelles-attaques-terroristes-dans-lest-du-pays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/acninternational.org\/fr\/category\/news-fr\/"},{"@type":"ListItem","position":3,"name":"Burkina Faso : un pr\u00eatre appelle \u00e0 prier apr\u00e8s trois nouvelles attaques terroristes dans l\u2019est du pays"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/333738ed03abe11491094c5c30cf3133","name":"Sina Hartert","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/fr\/author\/sina-hartert\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/231502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/4258341405"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=231502"}],"version-history":[{"count":1,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/231502\/revisions"}],"predecessor-version":[{"id":245366,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/231502\/revisions\/245366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/231481"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=231502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=231502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=231502"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=231502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}