{"id":185516,"date":"2023-10-02T12:32:25","date_gmt":"2023-10-02T10:32:25","guid":{"rendered":"https:\/\/acninternational.org\/?p=185516"},"modified":"2023-10-02T12:32:33","modified_gmt":"2023-10-02T10:32:33","slug":"acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/","title":{"rendered":"ACN approuve 500.000 $ pour un second programme d\u2019aide destin\u00e9 aux r\u00e9gions de Syrie touch\u00e9es par le tremblement de terre"},"content":{"rendered":"<p><em>L\u2019argent envoy\u00e9 en Syrie aidera \u00e0 restaurer les infrastructures essentielles de l\u2019\u00c9glise et \u00e0 continuer \u00e0 fournir de l\u2019aide \u00e0 ceux qui en ont besoin.<\/em><\/p>\n<p>La fondation Aid to the Church in Need (ACN) a approuv\u00e9 un second programme d\u2019aide de pr\u00e8s d\u2019un demi-million de dollars pour aider l\u2019\u00c9glise locale \u00e0 se remettre du <a href=\"https:\/\/acninternational.org\/earthquake-in-syria-absolute-despair\/\" target=\"_blank\" rel=\"noopener\">tremblement de terre d\u00e9vastateur de f\u00e9vrier<\/a>.<\/p>\n<figure id=\"attachment_185502\" aria-describedby=\"caption-attachment-185502\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-185502 size-large\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230227-141803-1024x683.jpeg\" alt=\"Xavier Bisits \u00e0 Latakia avec des victimes du tremblement de terre le 6 f\u00e9vrier 2023\" width=\"800\" height=\"534\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230227-141803-1024x683.jpeg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230227-141803-300x200.jpeg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230227-141803-768x512.jpeg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230227-141803.jpeg 1080w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-185502\" class=\"wp-caption-text\">Xavier Bisits \u00e0 Latakia avec des victimes du tremblement de terre le 6 f\u00e9vrier 2023<\/figcaption><\/figure>\n<p>ACN a \u00e9t\u00e9 l&rsquo;une des premi\u00e8res organisations internationales \u00e0 envoyer de l&rsquo;aide en Syrie apr\u00e8s le tremblement de terre, car elle \u00e9tait d\u00e9j\u00e0 pr\u00e9sente sur le terrain et disposait de partenaires locaux de confiance. L\u2019\u0153uvre catholique de bienfaisance a fourni une assistance mat\u00e9rielle, psychologique et \u00e9ducative. Le nouveau programme d\u2019aide servira \u00e0 pr\u00e9server et \u00e0 restaurer les infrastructures essentielles de l\u2019\u00c9glise, b\u00e9n\u00e9ficiant directement \u00e0 environ 30.000 personnes de huit rites diff\u00e9rents au sein des quatre gouvernorats les plus touch\u00e9s par le tremblement de terre.<\/p>\n<p>\u00ab\u00a0ACN est reconnaissante envers ses bienfaiteurs de soutenir ce nouveau programme d\u2019intervention apr\u00e8s le tremblement de terre. Ce programme couvre les r\u00e9parations de neuf \u00e9glises et monast\u00e8res, de deux \u00e9coles, d\u2019un jardin d\u2019enfants, d\u2019un centre communautaire et d\u2019un centre pour la jeunesse. Il couvre \u00e9galement l\u2019achat d\u2019un nouveau v\u00e9hicule pour un pr\u00eatre missionnaire dont la camionnette a \u00e9t\u00e9 \u00e9cras\u00e9e par les d\u00e9combres pendant le s\u00e9isme \u00bb, a d\u00e9clar\u00e9 Xavier Stephen Bisits, repr\u00e9sentant de la fondation ACN en Syrie, au Liban et en \u00c9gypte.<\/p>\n<p>\u00ab\u00a0Ce soutien aidera l\u2019\u00c9glise \u00e0 se remettre sur pied, \u00e0 continuer \u00e0 servir les plus vuln\u00e9rables et \u00e0 poursuivre son travail pastoral le plus essentiel, dans un pays qui est toujours en \u00e9tat de crise\u00a0\u00bb, a ajout\u00e9 Bisits, qui s\u2019est rendu dans la r\u00e9gion touch\u00e9e pour superviser les efforts de secours imm\u00e9diatement apr\u00e8s le s\u00e9isme de f\u00e9vrier et qui s\u2019y rend r\u00e9guli\u00e8rement depuis lors.<\/p>\n<h4><strong>Alep, Lattaqui\u00e9 et Hama<\/strong><\/h4>\n<p>Plus de la moiti\u00e9 de l\u2019aide (62%), ira \u00e0 Alep et comprendra la restauration d\u2019un centre caritatif d\u2019assistance aux pauvres, ainsi que deux \u00e9coles. En contribuant \u00e0 la restauration de l\u2019\u00e9cole Mekhtarist et de l\u2019\u00e9cole Karen Geppe Gemaran dans cette ville, ACN contribue \u00e0 ce que les enfants puissent continuer \u00e0 recevoir une \u00e9ducation dans un environnement s\u00fbr, garantissant ainsi une plus grande stabilit\u00e9 sociale et familiale.<\/p>\n<figure id=\"attachment_185508\" aria-describedby=\"caption-attachment-185508\" style=\"width: 720px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-185508 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230323-143085.jpg\" alt=\"Dommages dans l'archidioc\u00e8se orthodoxe syriaque d'Alep apr\u00e8s le tremblement de terre\" width=\"720\" height=\"960\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230323-143085.jpg 720w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230323-143085-225x300.jpg 225w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption id=\"caption-attachment-185508\" class=\"wp-caption-text\">Dommages dans l&rsquo;archidioc\u00e8se orthodoxe syriaque d&rsquo;Alep apr\u00e8s le tremblement de terre<\/figcaption><\/figure>\n<p>Pr\u00e8s de 25% de l\u2019aide ira \u00e0 Lattaqui\u00e9, o\u00f9 ACN financera la restauration de trois \u00e9glises, dont la cath\u00e9drale grecque orthodoxe Saint-Georges, le monast\u00e8re catholique melkite Notre-Dame-de-la-Joie et l\u2019\u00e9glise orthodoxe arm\u00e9nienne Sainte-Marie.<\/p>\n<h4><strong>Les b\u00e9n\u00e9ficiaires remercient ACN<\/strong><\/h4>\n<p>Le tremblement de terre du 6 f\u00e9vrier qui a frapp\u00e9 la Turquie et la Syrie, d\u2019une magnitude de 7,8 sur l\u2019\u00e9chelle de Richter, est le plus important qu\u2019ait connu la r\u00e9gion depuis plus de 80 ans. Le bilan total de morts confirm\u00e9s s\u2019\u00e9l\u00e8ve \u00e0 pr\u00e8s de 60.000 personnes, principalement en Turquie. Environ 8.500 personnes sont mortes en Syrie.<\/p>\n<p>Depuis lors, dans quatre diff\u00e9rents gouvernorats, ACN a aid\u00e9 \u00e0 r\u00e9parer les maisons des chr\u00e9tiens, \u00e0 payer les loyers des familles d\u00e9plac\u00e9es et a fourni une aide d\u2019urgence \u00e0 un total de 2.800 familles. Dans le m\u00eame temps, ACN a financ\u00e9 des activit\u00e9s estivales ainsi qu\u2019un soutien pastoral aux enfants et aux familles, en particulier \u00e0 Alep. L\u2019aide a \u00e9galement permis de distribuer des m\u00e9dicaments aux chr\u00e9tiens affect\u00e9s.<\/p>\n<figure id=\"attachment_185496\" aria-describedby=\"caption-attachment-185496\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-185496 size-large\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230731-150524-1024x928.jpg\" alt=\"P\u00e8re Fadi Azar lors de la distribution de mat\u00e9riel d'urgence aux familles dans le besoin\" width=\"800\" height=\"725\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230731-150524-1024x928.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230731-150524-300x272.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230731-150524-768x696.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230731-150524.jpg 1080w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-185496\" class=\"wp-caption-text\">P\u00e8re Fadi Azar lors de la distribution de mat\u00e9riel d&rsquo;urgence aux familles dans le besoin<\/figcaption><\/figure>\n<p>\u00ab\u00a0Le soutien d\u2019ACN a \u00e9t\u00e9 fondamental pour la mise en \u0153uvre de l\u2019aide d\u2019urgence \u00e0 Lattaqui\u00e9, o\u00f9 440 familles ont \u00e9t\u00e9 aid\u00e9es \u00e0 travers diverses activit\u00e9s, notamment la distribution de paniers de nourriture et de produits d\u2019hygi\u00e8ne, ainsi que la r\u00e9habilitation de quatre maisons \u00bb, remercie le P\u00e8re Fadi Azar, cur\u00e9 de la paroisse de Lattaqui\u00e9, en r\u00e9ponse au r\u00e9cent soutien de ACN.<\/p>\n<p>Michlen Mukel est une autre b\u00e9n\u00e9ficiaire <a href=\"https:\/\/acninternational.org\/syria-acn-begins-project-to-help-pay-rent-of-victims-who-cannot-return-to-their-homes\/\" target=\"_blank\" rel=\"noopener\">du premier plan d\u2019aide<\/a> d\u2019ACN. Elle et sa famille ont refus\u00e9 de quitter Alep malgr\u00e9 12 ans de guerre, une crise financi\u00e8re paralysante et le tremblement de terre qui a litt\u00e9ralement \u00e9branl\u00e9 les fondements de leur existence. Le b\u00e2timent dans lequel elle vit a \u00e9t\u00e9 gravement endommag\u00e9.<\/p>\n<p>\u00ab\u00a0Nous avons demand\u00e9 de l\u2019aide \u00e0 plusieurs organisations et nous avons eu la chance de recevoir le soutien de l\u2019\u00c9glise et de la fondation ACN. Ils ont commenc\u00e9 \u00e0 renforcer la toiture et le quatri\u00e8me \u00e9tage et ont \u00e9galement travaill\u00e9 sur le sous-sol et les fondations. Je suis tr\u00e8s reconnaissante envers tous ceux qui ont contribu\u00e9 \u00e0 cet important projet, en particulier les bienfaiteurs. Gr\u00e2ce \u00e0 leurs efforts, nos maisons sont s\u00fbres et pr\u00eates pour l\u2019hiver \u00bb, a-t-elle d\u00e9clar\u00e9 \u00e0 ACN.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019argent envoy\u00e9 en Syrie aidera \u00e0 restaurer les infrastructures essentielles de l\u2019\u00c9glise et \u00e0 continuer \u00e0 fournir de l\u2019aide \u00e0<\/p>\n","protected":false},"author":4258341447,"featured_media":185490,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[233,919,962],"tags":[],"country":[819],"class_list":["post-185516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","category-nouvelle","category-news-fr","country-syrie"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ACN approuve 500.000 $ pour un second programme d\u2019aide destin\u00e9 aux r\u00e9gions de Syrie touch\u00e9es par le tremblement de terre | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACN approuve 500.000 $ pour un second programme d\u2019aide destin\u00e9 aux r\u00e9gions de Syrie touch\u00e9es par le tremblement de terre\" \/>\n<meta property=\"og:description\" content=\"L\u2019argent envoy\u00e9 en Syrie aidera \u00e0 restaurer les infrastructures essentielles de l\u2019\u00c9glise et \u00e0 continuer \u00e0 fournir de l\u2019aide \u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-02T10:32:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-02T10:32:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230209-140445.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"ACN approuve 500.000 $ pour un second programme d\u2019aide destin\u00e9 aux r\u00e9gions de Syrie touch\u00e9es par le tremblement de terre\",\"datePublished\":\"2023-10-02T10:32:25+00:00\",\"dateModified\":\"2023-10-02T10:32:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/\"},\"wordCount\":881,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ACN-20230209-140445.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\",\"Nouvelle\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/\",\"name\":\"ACN approuve 500.000 $ pour un second programme d\u2019aide destin\u00e9 aux r\u00e9gions de Syrie touch\u00e9es par le tremblement de terre | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ACN-20230209-140445.jpg\",\"datePublished\":\"2023-10-02T10:32:25+00:00\",\"dateModified\":\"2023-10-02T10:32:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ACN-20230209-140445.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ACN-20230209-140445.jpg\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non classifi\u00e9(e)\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/non-classifiee\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ACN approuve 500.000 $ pour un second programme d\u2019aide destin\u00e9 aux r\u00e9gions de Syrie touch\u00e9es par le tremblement de terre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ACN approuve 500.000 $ pour un second programme d\u2019aide destin\u00e9 aux r\u00e9gions de Syrie touch\u00e9es par le tremblement de terre | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/","og_locale":"fr_FR","og_type":"article","og_title":"ACN approuve 500.000 $ pour un second programme d\u2019aide destin\u00e9 aux r\u00e9gions de Syrie touch\u00e9es par le tremblement de terre","og_description":"L\u2019argent envoy\u00e9 en Syrie aidera \u00e0 restaurer les infrastructures essentielles de l\u2019\u00c9glise et \u00e0 continuer \u00e0 fournir de l\u2019aide \u00e0","og_url":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2023-10-02T10:32:25+00:00","article_modified_time":"2023-10-02T10:32:33+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230209-140445.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"ACN Press Team","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"ACN approuve 500.000 $ pour un second programme d\u2019aide destin\u00e9 aux r\u00e9gions de Syrie touch\u00e9es par le tremblement de terre","datePublished":"2023-10-02T10:32:25+00:00","dateModified":"2023-10-02T10:32:33+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/"},"wordCount":881,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230209-140445.jpg","articleSection":["Non classifi\u00e9(e)","Nouvelle","Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/","url":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/","name":"ACN approuve 500.000 $ pour un second programme d\u2019aide destin\u00e9 aux r\u00e9gions de Syrie touch\u00e9es par le tremblement de terre | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230209-140445.jpg","datePublished":"2023-10-02T10:32:25+00:00","dateModified":"2023-10-02T10:32:33+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230209-140445.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/10\/ACN-20230209-140445.jpg","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/acn-approuve-500-000-pour-un-second-programme-daide-destine-aux-regions-de-syrie-touchees-par-le-tremblement-de-terre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Non classifi\u00e9(e)","item":"https:\/\/acninternational.org\/fr\/category\/non-classifiee\/"},{"@type":"ListItem","position":3,"name":"ACN approuve 500.000 $ pour un second programme d\u2019aide destin\u00e9 aux r\u00e9gions de Syrie touch\u00e9es par le tremblement de terre"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/fr\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/185516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=185516"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/185516\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/185490"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=185516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=185516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=185516"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=185516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}