{"id":177109,"date":"2022-12-21T12:51:42","date_gmt":"2022-12-21T11:51:42","guid":{"rendered":"https:\/\/acninternational.org\/?p=177109"},"modified":"2022-12-21T13:08:12","modified_gmt":"2022-12-21T12:08:12","slug":"syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/","title":{"rendered":"Syrie : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb"},"content":{"rendered":"<h4>Marie, m\u00e8re de la r\u00e9conciliation, exemple pour les chr\u00e9tiens syriens.<\/h4>\n<p>\u00ab \u201cPardonne-leur, Seigneur\u201d, combien de fois avons-nous d\u00fb r\u00e9p\u00e9ter ces paroles, surtout ces derni\u00e8res ann\u00e9es ! \u00bb d\u00e9clare S\u0153ur Jihanne Attalah, religieuse des S\u0153urs de la Charit\u00e9 de Sainte-Jeanne-Antide-Thouret \u00e0 Damas, \u00e0 la veille de la c\u00e9l\u00e9bration de No\u00ebl, dans cette atmosph\u00e8re de guerre qui dure depuis plus de dix ans en Syrie.<\/p>\n<p>\u00ab Du jour au lendemain, nous \u00e9tions forc\u00e9s de ne plus avoir un regard sur notre belle et immense \u00e9cole, nouvellement b\u00e2tie sur la route de l\u2019a\u00e9roport de Damas \u00bb, se souvient S\u0153ur Jihane avec une certaine tristesse. L\u2019\u00e9cole Al-Riaya que la congr\u00e9gation poss\u00e8de dans la banlieue de Damas est devenue un th\u00e9\u00e2tre de guerre. Elles ont perdu non seulement leur \u00e9cole, mais aussi des \u00eatres chers. \u00ab Nous avons perdu une jeune enseignante et une jeune \u00e9tudiante, sans parler des personnes bless\u00e9es \u00bb, a-t-elle d\u00e9clar\u00e9 \u00e0 la Fondation internationale Aid to the Church in Need (ACN).<\/p>\n<figure id=\"attachment_177094\" aria-describedby=\"caption-attachment-177094\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-177094 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-16-1.png\" alt=\"chr\u00e9tiens syrie guerre\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-16-1.png 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-16-1-300x179.png 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-177094\" class=\"wp-caption-text\">S. Jihanne<\/figcaption><\/figure>\n<p>L\u2019une des \u00e9l\u00e8ves de l\u2019\u00e9cole, Christine (15 ans), rentrait de l\u2019\u00e9cole avec une camarade de classe. \u00c0 cause d\u2019une bombe qui a explos\u00e9 sur sa route, elle a perdu un pied et sa meilleure amie. S\u0153ur Jihane explique qu\u2019alors que Christine \u00e9tait \u00e0 l\u2019h\u00f4pital et \u00e9tait interview\u00e9e par une cha\u00eene de t\u00e9l\u00e9vision, la jeune fille a r\u00e9pondu d\u2019une voix calme : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb.<\/p>\n<p>Soudain, un jour, les \u00e9l\u00e8ves n\u2019avaient plus le droit de venir chercher leurs affaires rest\u00e9es dans leurs pupitres, et les enseignants devaient \u00e9galement abandonner toutes leurs affaires. La direction de l\u2019\u00e9cole a \u00e9t\u00e9 oblig\u00e9e de trouver des salles de classe pour les \u00e9l\u00e8ves et de se charger de leur s\u00e9curit\u00e9 en plus de leur \u00e9ducation.<\/p>\n<figure id=\"attachment_177100\" aria-describedby=\"caption-attachment-177100\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-177100 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-15-1.png\" alt=\"chr\u00e9tiens syrie guerre\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-15-1.png 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-15-1-300x179.png 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-177100\" class=\"wp-caption-text\">S. Jihanne avec des petits \u00e9l\u00e8ves de l&rsquo;\u00e9cole Al-Riaya<\/figcaption><\/figure>\n<p>Malgr\u00e9 tant d\u2019ann\u00e9es de souffrance, de guerre et de douleur dans ce pays, S\u0153ur Jihane raconte combien la foi a \u00e9t\u00e9 et est importante pour maintenir la paix int\u00e9rieure, et comment Marie, m\u00e8re de la r\u00e9conciliation, est un exemple pour les chr\u00e9tiens syriens : \u00ab Au milieu de toutes ces t\u00e9n\u00e8bres, il y avait toujours une place pour l\u2019esp\u00e9rance qui nous guidait et nous aidait \u00e0 \u00e9lever notre regard, \u00e0 d\u00e9passer notre d\u00e9sir de vengeance et \u00e0 nous transcender. Oui, c\u2019est gr\u00e2ce \u00e0 notre foi en Dieu et \u00e0 la pr\u00e9sence de la Vierge Marie, rest\u00e9e au pied de la croix. Elle est rest\u00e9e debout, puisant sa force dans son Fils \u00bb, ajoute s\u0153ur Jihane.<\/p>\n<p>Apr\u00e8s la fin de la guerre \u00e0 Damas, les religieuses sont revenues pour reconstruire l\u2019\u00e9cole et rouvrir ses portes. La Fondation internationale Aid to the Church in Need (ACN) a soutenu l\u2019installation d\u2019un syst\u00e8me de dessalement \u00e0 l\u2019\u00e9cole Al-Riaya, g\u00e9r\u00e9e par la communaut\u00e9\u00a0des S\u0153urs de la Charit\u00e9 de Sainte-Jeanne-Antide-Thouret et le mobilier pour l&rsquo;\u00e9cole en 2021.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malgr\u00e9 toutes ces ann\u00e9es de souffrance, guerre et douleur dans Syrie, le plus important a \u00e9t\u00e9 de garder la foi pour avoir paix int\u00e9rieure.<\/p>\n","protected":false},"author":4258341447,"featured_media":177089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[1276],"tags":[],"country":[819],"class_list":["post-177109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured-fr","country-syrie"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Syrie : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb<\/title>\n<meta name=\"description\" content=\"Malgr\u00e9 toutes ces ann\u00e9es de souffrance, guerre et douleur dans Syrie, le plus important a \u00e9t\u00e9 de garder la foi pour avoir paix int\u00e9rieure.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Syrie : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb\" \/>\n<meta property=\"og:description\" content=\"Malgr\u00e9 toutes ces ann\u00e9es de souffrance, guerre et douleur dans Syrie, le plus important a \u00e9t\u00e9 de garder la foi pour avoir paix int\u00e9rieure.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-21T11:51:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T12:08:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/grande-9-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Syrie : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb\",\"datePublished\":\"2022-12-21T11:51:42+00:00\",\"dateModified\":\"2022-12-21T12:08:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/\"},\"wordCount\":553,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/grande-9-2.png\",\"articleSection\":[\"FEATURED\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/\",\"name\":\"Syrie : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/grande-9-2.png\",\"datePublished\":\"2022-12-21T11:51:42+00:00\",\"dateModified\":\"2022-12-21T12:08:12+00:00\",\"description\":\"Malgr\u00e9 toutes ces ann\u00e9es de souffrance, guerre et douleur dans Syrie, le plus important a \u00e9t\u00e9 de garder la foi pour avoir paix int\u00e9rieure.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/grande-9-2.png\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/grande-9-2.png\",\"width\":2000,\"height\":625,\"caption\":\"chr\u00e9tiens syrie guerre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FEATURED\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/featured-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Syrie : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Syrie : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb","description":"Malgr\u00e9 toutes ces ann\u00e9es de souffrance, guerre et douleur dans Syrie, le plus important a \u00e9t\u00e9 de garder la foi pour avoir paix int\u00e9rieure.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/","og_locale":"fr_FR","og_type":"article","og_title":"Syrie : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb","og_description":"Malgr\u00e9 toutes ces ann\u00e9es de souffrance, guerre et douleur dans Syrie, le plus important a \u00e9t\u00e9 de garder la foi pour avoir paix int\u00e9rieure.","og_url":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2022-12-21T11:51:42+00:00","article_modified_time":"2022-12-21T12:08:12+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/grande-9-2.png","type":"image\/png"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"ACN Press Team","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Syrie : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb","datePublished":"2022-12-21T11:51:42+00:00","dateModified":"2022-12-21T12:08:12+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/"},"wordCount":553,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/grande-9-2.png","articleSection":["FEATURED"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/","url":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/","name":"Syrie : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/grande-9-2.png","datePublished":"2022-12-21T11:51:42+00:00","dateModified":"2022-12-21T12:08:12+00:00","description":"Malgr\u00e9 toutes ces ann\u00e9es de souffrance, guerre et douleur dans Syrie, le plus important a \u00e9t\u00e9 de garder la foi pour avoir paix int\u00e9rieure.","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/grande-9-2.png","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/grande-9-2.png","width":2000,"height":625,"caption":"chr\u00e9tiens syrie guerre"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/syrie-que-le-seigneur-leur-pardonne-cest-tout-ce-que-je-peux-dire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"FEATURED","item":"https:\/\/acninternational.org\/fr\/category\/featured-fr\/"},{"@type":"ListItem","position":3,"name":"Syrie : \u00ab Que le Seigneur leur pardonne, c\u2019est tout ce que je peux dire \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/fr\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/177109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=177109"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/177109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/177089"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=177109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=177109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=177109"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=177109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}