{"id":155371,"date":"2021-07-07T10:21:02","date_gmt":"2021-07-07T08:21:02","guid":{"rendered":"https:\/\/acninternational.org\/?p=155371"},"modified":"2021-07-07T10:46:51","modified_gmt":"2021-07-07T08:46:51","slug":"alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/","title":{"rendered":"Alors que la COVID-19 frappe \u00e0 nouveau durement le Zimbabwe, l\u2019AED s&rsquo;efforce d&rsquo;att\u00e9nuer les difficult\u00e9s des agents pastoraux"},"content":{"rendered":"<p>L\u2019imposition d\u2019un nouveau confinement au Zimbabwe, en raison de la pand\u00e9mie de COVID-19, a une nouvelle fois attir\u00e9 l\u2019attention du monde entier sur ce pays en d\u00e9tresse. Le besoin d\u2019aide est \u00e9norme et le nombre d\u2019infections a grimp\u00e9 en fl\u00e8che pour atteindre 596 nouveaux cas et 26 morts rien qu\u2019en une semaine, comme l\u2019a d\u00e9clar\u00e9 le vice-pr\u00e9sident Constantino Chiwenga \u00e0 la mi-juin. Ces derniers mois, la fondation pontificale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse (AED) a pu y apporter une aide continue pour lutter contre la pand\u00e9mie.<\/p>\n<p>Des fonds ont \u00e9t\u00e9 vers\u00e9s pour fournir des \u00e9quipements de protection individuelle, tels que des masques, des \u00e9crans faciaux, des gants en latex, des combinaisons de protection, des bottes en caoutchouc et du d\u00e9sinfectant. Tous ces \u00e9quipements permettent \u00e0 plus de 1.200 agents pastoraux \u2013 pr\u00eatres, diacres, religieuses et religieux \u2013 d\u2019accomplir leur travail. Leur d\u00e9fi est de couvrir l&rsquo;\u00e9norme territoire des huit dioc\u00e8ses du pays, dans lesquels beaucoup d\u2019entre eux sont souvent en premi\u00e8re ligne pour offrir une assistance m\u00e9dicale et sociale.<\/p>\n<figure id=\"attachment_155348\" aria-describedby=\"caption-attachment-155348\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-155348 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe2.jpg\" alt=\"L\u2019imposition d\u2019un nouveau confinement au Zimbabwe, en raison de la pand\u00e9mie de COVID-19, a une nouvelle fois attir\u00e9 l\u2019attention du monde entier sur ce pays en d\u00e9tresse.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe2.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe2-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-155348\" class=\"wp-caption-text\">L\u2019imposition d\u2019un nouveau confinement au Zimbabwe, en raison de la pand\u00e9mie de COVID-19, a une nouvelle fois attir\u00e9 l\u2019attention du monde entier sur ce pays en d\u00e9tresse.<\/figcaption><\/figure>\n<p>En raison de sa situation g\u00e9ographique, le Zimbabwe est une porte d\u2019entr\u00e9e vers le Botswana, la Zambie, l\u2019Afrique du Sud et le Mozambique. C\u2019est un probl\u00e8me, par exemple, pour le dioc\u00e8se de Chinhoyi qui s\u2019\u00e9tend sur un vaste territoire de 56.000 kilom\u00e8tres carr\u00e9s, avec un total de 142 agents pastoraux (pr\u00eatres, diacres permanents, religieuses et religieux) qui travaillent dans les \u00e9coles, les h\u00f4pitaux, les centres pastoraux, les paroisses et les missions. Ce dioc\u00e8se est vuln\u00e9rable aux infections provenant de Chirundu, le principal poste fronti\u00e8re avec la Zambie. Il y a aussi de nombreuses personnes qui circulent \u00e0 travers des points de passage non autoris\u00e9s entre le Zimbabwe et le Mozambique ou la Zambie. Dans le dioc\u00e8se de Masvingo, les agents pastoraux doivent \u00e9galement couvrir une vaste superficie, qui fait environ 70.000 kilom\u00e8tres carr\u00e9s, soit deux fois la taille de la Belgique. Ils ne sont que 66 pr\u00eatres, 83 religieuses et 2 religieux, tous impliqu\u00e9s dans le travail pastoral et \u00e9ducatif, mais aussi dans les soins infirmiers et le travail social, en lien avec 3 h\u00f4pitaux et 5 cliniques.<\/p>\n<p>Un autre d\u00e9fi est d\u00fb au fait que la majeure partie du pays est rurale et habit\u00e9e par des paysans. Sur les 21 paroisses du dioc\u00e8se de Chinhoyi, 6 sont urbaines et les autres sont des paroisses et des missions rurales. Les h\u00f4pitaux sont donc \u00e9loign\u00e9s, ce qui rend difficile le transfert des cas graves. Des infections graves surviennent \u00e9galement en raison de l\u2019incapacit\u00e9 \u00e0 s\u00e9parer les cas de COVID-19 des autres. Le dioc\u00e8se de Gokwe est encore plus rural. Sa population se compose essentiellement de paysans qui n\u2019ont personne pour les aider en cas d\u2019urgence. Les pr\u00e9cipitations \u00e9tant tr\u00e8s irr\u00e9guli\u00e8res, la r\u00e9colte est insuffisante et de nombreuses personnes ont du mal \u00e0 se nourrir. La famine expose les gens \u00e0 diverses maladies comme le paludisme, car la r\u00e9gion est infest\u00e9e de mouches ts\u00e9-ts\u00e9 et de moustiques qui ont fait plusieurs victimes. La situation s\u2019est aggrav\u00e9e avec l\u2019arriv\u00e9e de la COVID-19 qui pr\u00e9sente des sympt\u00f4mes similaires. En outre, le confinement impos\u00e9 par le gouvernement, a laiss\u00e9 de nombreuses personnes sans aucune ressource. Les agents pastoraux ont du mal \u00e0 obtenir de la nourriture parce qu\u2019ils ne peuvent pas rendre visite aux paroissiens qui les aidaient \u00e0 s&rsquo;approvisionner en nourriture avant la crise. Il y a des probl\u00e8mes similaires dans trois autres dioc\u00e8ses\u00a0: Bulawayo, Gweru et Mutare.<\/p>\n<figure id=\"attachment_155342\" aria-describedby=\"caption-attachment-155342\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-155342 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe3.jpg\" alt=\"Ces derniers mois, la fondation pontificale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse (AED) a pu y apporter une aide continue pour lutter contre la pand\u00e9mie.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe3.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe3-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-155342\" class=\"wp-caption-text\">Ces derniers mois, la fondation pontificale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse (AED) a pu y apporter une aide continue pour lutter contre la pand\u00e9mie.<\/figcaption><\/figure>\n<p>L\u2019\u00e9picentre actuel de la pand\u00e9mie est Harare, la capitale du Zimbabwe. Quelque 136 religieuses, religieux et pr\u00eatres y servent actuellement les malades\u00a0: ils prient avec eux, leur donnent les derniers sacrements, enterrent les morts et accompagnent les familles endeuill\u00e9es. Ils sont en premi\u00e8re ligne, interagissant chaque jour entre eux et avec les communaut\u00e9s de croyants qu&rsquo;ils servent, ce qui les rend vuln\u00e9rables \u00e0 ce dangereux virus.<\/p>\n<p>\u00ab\u00a0Comme nous en a r\u00e9cemment inform\u00e9 l&rsquo;archev\u00eaque de Bulawayo, notre aide est arriv\u00e9e juste \u00e0 temps avant la troisi\u00e8me vague \u00bb, explique Ulrich Kny, responsable des projets pour le Zimbabwe au sein de l\u2019AED. Ulrich Kny poursuit : \u00ab\u00a0Dans de nombreux pays africains, les soins m\u00e9dicaux sont totalement insuffisants. Le paludisme, le sida, le chol\u00e9ra et d\u2019autres maladies sont tr\u00e8s r\u00e9pandus. Si une pand\u00e9mie comme la Covid-19 vient s\u2019y ajouter, la catastrophe est in\u00e9vitable. Et une telle catastrophe se profilait dans certains pays d\u2019Afrique australe au d\u00e9but de l\u2019ann\u00e9e lorsque la deuxi\u00e8me vague de la pand\u00e9mie, due \u00e0 la propagation du mutant sud-africain du virus, a pris des proportions de plus en plus d\u00e9vastatrices, tuant un nombre croissant de personnes \u2013 dont des \u00e9v\u00eaques, des pr\u00eatres, des religieuses, des cat\u00e9chistes et d\u2019autres travailleurs pastoraux la\u00efcs\u00a0\u00bb.<\/p>\n<p>La crise humanitaire au Zimbabwe n\u2019a cess\u00e9 de s\u2019amplifier ces derni\u00e8res ann\u00e9es, en particulier depuis le cyclone Idai en 2019. Le pays a connu un taux d\u2019inflation record de 786%. En 2020, plus d\u2019un tiers de la population totale \u2013 pr\u00e8s de 15 millions de personnes &#8211; d\u00e9pendait encore de l\u2019aide alimentaire. L\u2019\u00c9glise, par l\u2019interm\u00e9diaire de ses agents pastoraux, s&rsquo;efforce constamment d&rsquo;apporter du r\u00e9confort aux personnes qui souffrent.<\/p>\n<p>Ulrich Kny conclut\u00a0: \u00ab\u00a0C\u2019\u00e9tait clair pour moi : pour que les \u00e9glises locales puissent continuer leur travail pastoral, nous devions apporter notre aide. Normalement, dans de nombreux dioc\u00e8ses, nous fournissons une \u00ab\u00a0aide \u00e0 la subsistance\u00a0\u00bb aux religieuses et transmettons des intentions de messe aux pr\u00eatres afin de leur fournir une source de revenus pour qu\u2019ils puissent mener une vie digne. Mais aujourd\u2019hui, nous allons devoir fournir non seulement une aide \u00e0 la subsistance, mais aussi une aide \u00e0 la survie\u00a0! Les pr\u00eatres et les religieuses ne peuvent continuer \u00e0 rendre visite aux malades, aux mourants et aux n\u00e9cessiteux, \u00e0 ceux qui ont particuli\u00e8rement besoin d\u2019une assistance spirituelle dans la solitude de leur confinement, que s\u2019ils sont eux-m\u00eames prot\u00e9g\u00e9s de mani\u00e8re ad\u00e9quate. Nous avons donc offert notre aide \u00e0 tous les dioc\u00e8ses de plusieurs pays pour l\u2019achat d\u2019\u00e9quipements de protection individuelle \u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019imposition d\u2019un nouveau confinement au Zimbabwe, en raison de la pand\u00e9mie de COVID-19, a une nouvelle fois attir\u00e9 l\u2019attention du<\/p>\n","protected":false},"author":4258341447,"featured_media":155354,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[920,921],"tags":[],"country":[937,933],"class_list":["post-155371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projekt","category-projet","country-simbabwe","country-zimbabwe"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alors que la COVID-19 frappe \u00e0 nouveau durement le Zimbabwe, l\u2019AED s&#039;efforce d&#039;att\u00e9nuer les difficult\u00e9s des agents pastoraux | ACN International<\/title>\n<meta name=\"description\" content=\"L\u2019imposition d\u2019un nouveau confinement au Zimbabwe, en raison de la pand\u00e9mie de COVID-19, a une nouvelle fois attir\u00e9 l\u2019attention du monde entier sur ce pays en d\u00e9tresse. Le besoin d\u2019aide est \u00e9norme et le nombre d\u2019infections a grimp\u00e9 en fl\u00e8che pour atteindre 596 nouveaux cas et 26 morts rien qu\u2019en une semaine, comme l\u2019a d\u00e9clar\u00e9 le vice-pr\u00e9sident Constantino Chiwenga \u00e0 la mi-juin. Ces derniers mois, la fondation pontificale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse (AED) a pu y apporter une aide continue pour lutter contre la pand\u00e9mie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alors que la COVID-19 frappe \u00e0 nouveau durement le Zimbabwe, l\u2019AED s&#039;efforce d&#039;att\u00e9nuer les difficult\u00e9s des agents pastoraux\" \/>\n<meta property=\"og:description\" content=\"L\u2019imposition d\u2019un nouveau confinement au Zimbabwe, en raison de la pand\u00e9mie de COVID-19, a une nouvelle fois attir\u00e9 l\u2019attention du monde entier sur ce pays en d\u00e9tresse. Le besoin d\u2019aide est \u00e9norme et le nombre d\u2019infections a grimp\u00e9 en fl\u00e8che pour atteindre 596 nouveaux cas et 26 morts rien qu\u2019en une semaine, comme l\u2019a d\u00e9clar\u00e9 le vice-pr\u00e9sident Constantino Chiwenga \u00e0 la mi-juin. Ces derniers mois, la fondation pontificale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse (AED) a pu y apporter une aide continue pour lutter contre la pand\u00e9mie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-07T08:21:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-07T08:46:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Alors que la COVID-19 frappe \u00e0 nouveau durement le Zimbabwe, l\u2019AED s&rsquo;efforce d&rsquo;att\u00e9nuer les difficult\u00e9s des agents pastoraux\",\"datePublished\":\"2021-07-07T08:21:02+00:00\",\"dateModified\":\"2021-07-07T08:46:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/\"},\"wordCount\":1165,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Zimbabwe.jpg\",\"articleSection\":[\"Projekt\",\"Projet\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/\",\"name\":\"Alors que la COVID-19 frappe \u00e0 nouveau durement le Zimbabwe, l\u2019AED s'efforce d'att\u00e9nuer les difficult\u00e9s des agents pastoraux | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Zimbabwe.jpg\",\"datePublished\":\"2021-07-07T08:21:02+00:00\",\"dateModified\":\"2021-07-07T08:46:51+00:00\",\"description\":\"L\u2019imposition d\u2019un nouveau confinement au Zimbabwe, en raison de la pand\u00e9mie de COVID-19, a une nouvelle fois attir\u00e9 l\u2019attention du monde entier sur ce pays en d\u00e9tresse. Le besoin d\u2019aide est \u00e9norme et le nombre d\u2019infections a grimp\u00e9 en fl\u00e8che pour atteindre 596 nouveaux cas et 26 morts rien qu\u2019en une semaine, comme l\u2019a d\u00e9clar\u00e9 le vice-pr\u00e9sident Constantino Chiwenga \u00e0 la mi-juin. Ces derniers mois, la fondation pontificale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse (AED) a pu y apporter une aide continue pour lutter contre la pand\u00e9mie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Zimbabwe.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Zimbabwe.jpg\",\"width\":1400,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROJECTS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/projects-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alors que la COVID-19 frappe \u00e0 nouveau durement le Zimbabwe, l\u2019AED s&rsquo;efforce d&rsquo;att\u00e9nuer les difficult\u00e9s des agents pastoraux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alors que la COVID-19 frappe \u00e0 nouveau durement le Zimbabwe, l\u2019AED s'efforce d'att\u00e9nuer les difficult\u00e9s des agents pastoraux | ACN International","description":"L\u2019imposition d\u2019un nouveau confinement au Zimbabwe, en raison de la pand\u00e9mie de COVID-19, a une nouvelle fois attir\u00e9 l\u2019attention du monde entier sur ce pays en d\u00e9tresse. Le besoin d\u2019aide est \u00e9norme et le nombre d\u2019infections a grimp\u00e9 en fl\u00e8che pour atteindre 596 nouveaux cas et 26 morts rien qu\u2019en une semaine, comme l\u2019a d\u00e9clar\u00e9 le vice-pr\u00e9sident Constantino Chiwenga \u00e0 la mi-juin. Ces derniers mois, la fondation pontificale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse (AED) a pu y apporter une aide continue pour lutter contre la pand\u00e9mie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/","og_locale":"fr_FR","og_type":"article","og_title":"Alors que la COVID-19 frappe \u00e0 nouveau durement le Zimbabwe, l\u2019AED s'efforce d'att\u00e9nuer les difficult\u00e9s des agents pastoraux","og_description":"L\u2019imposition d\u2019un nouveau confinement au Zimbabwe, en raison de la pand\u00e9mie de COVID-19, a une nouvelle fois attir\u00e9 l\u2019attention du monde entier sur ce pays en d\u00e9tresse. Le besoin d\u2019aide est \u00e9norme et le nombre d\u2019infections a grimp\u00e9 en fl\u00e8che pour atteindre 596 nouveaux cas et 26 morts rien qu\u2019en une semaine, comme l\u2019a d\u00e9clar\u00e9 le vice-pr\u00e9sident Constantino Chiwenga \u00e0 la mi-juin. Ces derniers mois, la fondation pontificale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse (AED) a pu y apporter une aide continue pour lutter contre la pand\u00e9mie.","og_url":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2021-07-07T08:21:02+00:00","article_modified_time":"2021-07-07T08:46:51+00:00","og_image":[{"width":1400,"height":438,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"ACN Press Team","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Alors que la COVID-19 frappe \u00e0 nouveau durement le Zimbabwe, l\u2019AED s&rsquo;efforce d&rsquo;att\u00e9nuer les difficult\u00e9s des agents pastoraux","datePublished":"2021-07-07T08:21:02+00:00","dateModified":"2021-07-07T08:46:51+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/"},"wordCount":1165,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe.jpg","articleSection":["Projekt","Projet"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/","url":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/","name":"Alors que la COVID-19 frappe \u00e0 nouveau durement le Zimbabwe, l\u2019AED s'efforce d'att\u00e9nuer les difficult\u00e9s des agents pastoraux | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe.jpg","datePublished":"2021-07-07T08:21:02+00:00","dateModified":"2021-07-07T08:46:51+00:00","description":"L\u2019imposition d\u2019un nouveau confinement au Zimbabwe, en raison de la pand\u00e9mie de COVID-19, a une nouvelle fois attir\u00e9 l\u2019attention du monde entier sur ce pays en d\u00e9tresse. Le besoin d\u2019aide est \u00e9norme et le nombre d\u2019infections a grimp\u00e9 en fl\u00e8che pour atteindre 596 nouveaux cas et 26 morts rien qu\u2019en une semaine, comme l\u2019a d\u00e9clar\u00e9 le vice-pr\u00e9sident Constantino Chiwenga \u00e0 la mi-juin. Ces derniers mois, la fondation pontificale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse (AED) a pu y apporter une aide continue pour lutter contre la pand\u00e9mie.","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Zimbabwe.jpg","width":1400,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/alors-que-la-covid-19-frappe-a-nouveau-durement-le-zimbabwe-laed-sefforce-dattenuer-les-difficultes-des-agents-pastoraux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"PROJECTS","item":"https:\/\/acninternational.org\/fr\/category\/projects-fr\/"},{"@type":"ListItem","position":3,"name":"Alors que la COVID-19 frappe \u00e0 nouveau durement le Zimbabwe, l\u2019AED s&rsquo;efforce d&rsquo;att\u00e9nuer les difficult\u00e9s des agents pastoraux"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/fr\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/155371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=155371"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/155371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/155354"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=155371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=155371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=155371"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=155371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}