{"id":151747,"date":"2021-05-27T16:57:34","date_gmt":"2021-05-27T14:57:34","guid":{"rendered":"https:\/\/acninternational.org\/?p=151747"},"modified":"2026-06-07T16:27:52","modified_gmt":"2026-06-07T14:27:52","slug":"rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/","title":{"rendered":"RDCongo : la population doit choisir entre le danger du volcan et les assauts possibles des groupes arm\u00e9s"},"content":{"rendered":"<p><strong>Demande de pri\u00e8res pour la population de Goma <\/strong><\/p>\n<p>La situation dans la ville de Goma, dans l&rsquo;Est de la R\u00e9publique D\u00e9mocratique du Congo, est alarmante. Apr\u00e8s la premi\u00e8re \u00e9ruption du volcan Nyirangongo dans la nuit de samedi \u00e0 dimanche, la situation semblait s&rsquo;\u00eatre calm\u00e9e, mais de forts mouvements de terrain et le risque d&rsquo;une nouvelle \u00e9ruption, obligent la population \u00e0 \u00e9vacuer la ville, qui compte environ deux millions d&rsquo;habitants.<\/p>\n<p>\u00ab\u00a0<em>Je demande des pri\u00e8res pour la population de Goma et pour nos s\u00e9minaristes. Nous ne savons toujours pas si nous devrons \u00e9vacuer le s\u00e9minaire<\/em>\u00ab\u00a0, d\u00e9clare le P\u00e8re Ars\u00e8ne Masumbuko, recteur du S\u00e9minaire Saint Jean Paul II de Buhimba \u00e0 l&rsquo;organisation caritative internationale ACN, qui soutient la formation des 29 s\u00e9minaristes et des six pr\u00eatres formateurs.<\/p>\n<p>\u00ab\u00a0<em>Le grave danger est qu&rsquo;il y ait une explosion dans le lac, o\u00f9 se trouve du gaz, qui mettrait tout en danger dans une zone de 20 kilom\u00e8tres. C&rsquo;est pourquoi nous attendons de recevoir plus d&rsquo;informations et de pouvoir prendre une d\u00e9cision<\/em>\u00ab\u00a0, explique le p\u00e8re Masumbuko, qui avait quitt\u00e9 Goma vendredi en raison d&rsquo;une urgence familiale, avant que le volcan ne commence \u00e0 cracher de la lave. Il ne pouvait plus revenir. \u00ab\u00a0<em>Je suis en contact permanent avec le vice-recteur pour d\u00e9cider de ce qu&rsquo;il faut faire<\/em>\u00ab\u00a0.<\/p>\n<p>La d\u00e9cision est tr\u00e8s difficile \u00e0 prendre en raison de la situation dans la r\u00e9gion du Nord-Kivu, o\u00f9 se trouve Goma. La population a augment\u00e9 de fa\u00e7on spectaculaire ces derni\u00e8res ann\u00e9es en raison des r\u00e9fugi\u00e9s de la guerre civile et de la situation de violence et d&rsquo;ins\u00e9curit\u00e9 caus\u00e9es par les groupes arm\u00e9s actifs dans les zones. <em>\u00ab\u00a0Le premier dilemme est de savoir s&rsquo;il faut \u00e9vacuer ou non, mais si on \u00e9vacue, la question suivante est de savoir o\u00f9 aller et surtout comment s&rsquo;y rendre, car la s\u00e9curit\u00e9 en dehors de Goma est tr\u00e8s fragile. Il y a des groupes arm\u00e9s qui profitent de cette situation pour attaquer et agresser les gens<\/em>\u00ab\u00a0, d\u00e9clare le pr\u00eatre a ACN par t\u00e9l\u00e9phone ce matin (jeudi 27 Mai) .<\/p>\n<p>\u00ab\u00a0<em>La situation est chaotique. La MONUSCO est d\u00e9j\u00e0 partie et nous a laiss\u00e9s seuls. Il n&rsquo;y a pas d&rsquo;indications pr\u00e9cises, les gens sont inform\u00e9s par les r\u00e9seaux sociaux, Facebook ou WhatsApp et des messages contradictoires sont \u00e9chang\u00e9s. C&rsquo;est vraiment un drame. Je vous demande de nous soutenir par vos pri\u00e8res.<\/em> \u00ab\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Demande de pri\u00e8res pour la population de Goma  La situation dans la ville de Goma, dans l&rsquo;Est de la<\/p>\n","protected":false},"author":4258341447,"featured_media":150545,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[959,919],"tags":[],"country":[322,838],"class_list":["post-151747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-fr","category-nouvelle","country-democratic-republic-of-the-congo","country-republique-democratique-du-congo"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>RDCongo : la population doit choisir entre le danger du volcan et les assauts possibles des groupes arm\u00e9s | ACN International<\/title>\n<meta name=\"description\" content=\"La situation dans la ville de Goma, dans l&#039;Est de la R\u00e9publique D\u00e9mocratique du Congo, est alarmante. Apr\u00e8s la premi\u00e8re \u00e9ruption du volcan Nyirangongo dans la nuit de samedi \u00e0 dimanche, la situation semblait s&#039;\u00eatre calm\u00e9e, mais de forts mouvements de terrain et le risque d&#039;une nouvelle \u00e9ruption, obligent la population \u00e0 \u00e9vacuer la ville, qui compte environ deux millions d&#039;habitants.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RDCongo : la population doit choisir entre le danger du volcan et les assauts possibles des groupes arm\u00e9s\" \/>\n<meta property=\"og:description\" content=\"La situation dans la ville de Goma, dans l&#039;Est de la R\u00e9publique D\u00e9mocratique du Congo, est alarmante. Apr\u00e8s la premi\u00e8re \u00e9ruption du volcan Nyirangongo dans la nuit de samedi \u00e0 dimanche, la situation semblait s&#039;\u00eatre calm\u00e9e, mais de forts mouvements de terrain et le risque d&#039;une nouvelle \u00e9ruption, obligent la population \u00e0 \u00e9vacuer la ville, qui compte environ deux millions d&#039;habitants.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-27T14:57:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-07T14:27:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/04\/drc_news_Bishops-warn-of-threat-of-Islamism-in-East-Congo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"RDCongo : la population doit choisir entre le danger du volcan et les assauts possibles des groupes arm\u00e9s\",\"datePublished\":\"2021-05-27T14:57:34+00:00\",\"dateModified\":\"2026-06-07T14:27:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/\"},\"wordCount\":454,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/drc_news_Bishops-warn-of-threat-of-Islamism-in-East-Congo.jpg\",\"articleSection\":[\"NOTICIAS\",\"Nouvelle\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/\",\"name\":\"RDCongo : la population doit choisir entre le danger du volcan et les assauts possibles des groupes arm\u00e9s | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/drc_news_Bishops-warn-of-threat-of-Islamism-in-East-Congo.jpg\",\"datePublished\":\"2021-05-27T14:57:34+00:00\",\"dateModified\":\"2026-06-07T14:27:52+00:00\",\"description\":\"La situation dans la ville de Goma, dans l'Est de la R\u00e9publique D\u00e9mocratique du Congo, est alarmante. Apr\u00e8s la premi\u00e8re \u00e9ruption du volcan Nyirangongo dans la nuit de samedi \u00e0 dimanche, la situation semblait s'\u00eatre calm\u00e9e, mais de forts mouvements de terrain et le risque d'une nouvelle \u00e9ruption, obligent la population \u00e0 \u00e9vacuer la ville, qui compte environ deux millions d'habitants.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/drc_news_Bishops-warn-of-threat-of-Islamism-in-East-Congo.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/drc_news_Bishops-warn-of-threat-of-Islamism-in-East-Congo.jpg\",\"width\":2000,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/news-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RDCongo : la population doit choisir entre le danger du volcan et les assauts possibles des groupes arm\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"RDCongo : la population doit choisir entre le danger du volcan et les assauts possibles des groupes arm\u00e9s | ACN International","description":"La situation dans la ville de Goma, dans l'Est de la R\u00e9publique D\u00e9mocratique du Congo, est alarmante. Apr\u00e8s la premi\u00e8re \u00e9ruption du volcan Nyirangongo dans la nuit de samedi \u00e0 dimanche, la situation semblait s'\u00eatre calm\u00e9e, mais de forts mouvements de terrain et le risque d'une nouvelle \u00e9ruption, obligent la population \u00e0 \u00e9vacuer la ville, qui compte environ deux millions d'habitants.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/","og_locale":"fr_FR","og_type":"article","og_title":"RDCongo : la population doit choisir entre le danger du volcan et les assauts possibles des groupes arm\u00e9s","og_description":"La situation dans la ville de Goma, dans l'Est de la R\u00e9publique D\u00e9mocratique du Congo, est alarmante. Apr\u00e8s la premi\u00e8re \u00e9ruption du volcan Nyirangongo dans la nuit de samedi \u00e0 dimanche, la situation semblait s'\u00eatre calm\u00e9e, mais de forts mouvements de terrain et le risque d'une nouvelle \u00e9ruption, obligent la population \u00e0 \u00e9vacuer la ville, qui compte environ deux millions d'habitants.","og_url":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2021-05-27T14:57:34+00:00","article_modified_time":"2026-06-07T14:27:52+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/04\/drc_news_Bishops-warn-of-threat-of-Islamism-in-East-Congo.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"ACN Press Team","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"RDCongo : la population doit choisir entre le danger du volcan et les assauts possibles des groupes arm\u00e9s","datePublished":"2021-05-27T14:57:34+00:00","dateModified":"2026-06-07T14:27:52+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/"},"wordCount":454,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/04\/drc_news_Bishops-warn-of-threat-of-Islamism-in-East-Congo.jpg","articleSection":["NOTICIAS","Nouvelle"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/","url":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/","name":"RDCongo : la population doit choisir entre le danger du volcan et les assauts possibles des groupes arm\u00e9s | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/04\/drc_news_Bishops-warn-of-threat-of-Islamism-in-East-Congo.jpg","datePublished":"2021-05-27T14:57:34+00:00","dateModified":"2026-06-07T14:27:52+00:00","description":"La situation dans la ville de Goma, dans l'Est de la R\u00e9publique D\u00e9mocratique du Congo, est alarmante. Apr\u00e8s la premi\u00e8re \u00e9ruption du volcan Nyirangongo dans la nuit de samedi \u00e0 dimanche, la situation semblait s'\u00eatre calm\u00e9e, mais de forts mouvements de terrain et le risque d'une nouvelle \u00e9ruption, obligent la population \u00e0 \u00e9vacuer la ville, qui compte environ deux millions d'habitants.","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/04\/drc_news_Bishops-warn-of-threat-of-Islamism-in-East-Congo.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/04\/drc_news_Bishops-warn-of-threat-of-Islamism-in-East-Congo.jpg","width":2000,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/rdcongo-la-population-doit-choisir-entre-le-danger-du-volcan-et-les-assauts-possibles-des-groupes-armes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/acninternational.org\/fr\/category\/news-fr\/"},{"@type":"ListItem","position":3,"name":"RDCongo : la population doit choisir entre le danger du volcan et les assauts possibles des groupes arm\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/fr\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/151747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=151747"}],"version-history":[{"count":1,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/151747\/revisions"}],"predecessor-version":[{"id":265041,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/151747\/revisions\/265041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/150545"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=151747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=151747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=151747"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=151747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}