{"id":145854,"date":"2020-12-15T14:02:32","date_gmt":"2020-12-15T13:02:32","guid":{"rendered":"https:\/\/acninternational.org\/?p=145854"},"modified":"2020-12-15T14:12:54","modified_gmt":"2020-12-15T13:12:54","slug":"ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/","title":{"rendered":"Ghana: une machine \u00e0 cuire les hosties pour des religieuses"},"content":{"rendered":"<p>La \u00ab\u00a0Congr\u00e9gation des s\u0153urs du Saint Enfant J\u00e9sus\u00a0\u00bb (Handmaids of the Holy Child Jesus) est une congr\u00e9gation de religieuses fond\u00e9e au Nigeria. Elles travaillent dans l\u2019\u00e9ducation ou comme infirmi\u00e8res, elles s\u2019occupent des pauvres et des d\u00e9favoris\u00e9s, en particulier des femmes et des jeunes filles, et accomplissent diverses autres missions sociales et pastorales.<\/p>\n<p>C\u2019est surtout au Ghana que cette Congr\u00e9gation b\u00e9n\u00e9ficie d\u2019un grand nombre de vocations, si bien qu\u2019une maison de novices a \u00e9t\u00e9 fond\u00e9e en 1983 dans le dioc\u00e8se de Sunyani. C\u2019est l\u00e0 que les jeunes s\u0153urs qui n\u2019ont pas encore fait leurs v\u0153ux sont form\u00e9es. Ces jeunes femmes doivent recevoir une \u00e9ducation aussi bonne que possible, mais compte tenu de la mauvaise situation \u00e9conomique, il n\u2019est pas facile pour une jeune congr\u00e9gation autochtone de r\u00e9unir les moyens mat\u00e9riels n\u00e9cessaires \u00e0 cela. Pour couvrir les frais de formation, les s\u0153urs cuisent des hosties pour de nombreux dioc\u00e8ses du pays. Il s\u2019agit l\u00e0 \u00e9galement d\u2019un service rendu \u00e0 l\u2019Eglise et d\u2019une partie de leur apostolat, car sans hosties, il n\u2019y a pas d\u2019Eucharistie.<\/p>\n<figure id=\"attachment_145838\" aria-describedby=\"caption-attachment-145838\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-145838 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/12\/Ghana2.jpg\" alt=\"Ghana: une machine \u00e0 cuire les hosties pour des religieuses.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/12\/Ghana2.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/12\/Ghana2-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-145838\" class=\"wp-caption-text\">Ghana: une machine \u00e0 cuire les hosties pour des religieuses.<\/figcaption><\/figure>\n<p>La demande est forte, car le nombre de catholiques augmente et beaucoup d\u2019entre eux assistent aussi \u00e0 la messe en semaine. En fait, il faudrait 1,5 million d\u2019hosties chaque mois pour les fid\u00e8les et 15.000 grandes hosties pour les c\u00e9l\u00e9brants. Mais avec leur machine vieille de 25 ans et d\u00e9j\u00e0 d\u00e9fectueuse, les s\u0153urs ne pouvaient r\u00e9pondre qu\u2019\u00e0 15 pourcents de la demande, vu que la fabrication de la p\u00e2te, le processus de cuisson et la d\u00e9coupe des hosties \u00e9taient laborieux. En outre, le travail \u00e9tait peu \u00e0 peu devenu dangereux, \u00e9tant donn\u00e9 qu\u2019il y avait en permanence un risque d\u2019\u00e9lectrocution en raison de la d\u00e9fectuosit\u00e9 des c\u00e2bles \u00e9lectriques.<\/p>\n<p>Les s\u0153urs nous ont donc demand\u00e9 de l\u2019aide et nos bienfaiteurs ne les ont pas abandonn\u00e9es: 21.000 euros ont \u00e9t\u00e9 offerts aux s\u0153urs, ce qui leur a permis d\u2019augmenter consid\u00e9rablement leur production. Du fait de l\u2019augmentation des ressources financi\u00e8res disponibles, la formation des jeunes s\u0153urs a ainsi pu \u00eatre am\u00e9lior\u00e9e. S\u0153ur Christina, la ma\u00eetresse des novices, remercie de tout c\u0153ur tous les bienfaiteurs et \u00e9crit\u00a0: \u00ab\u00a0Nous demandons \u00e0 Dieu de vous b\u00e9nir !\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u00ab\u00a0Congr\u00e9gation des s\u0153urs du Saint Enfant J\u00e9sus\u00a0\u00bb (Handmaids of the Holy Child Jesus) est une congr\u00e9gation de religieuses fond\u00e9e<\/p>\n","protected":false},"author":4258341447,"featured_media":145844,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[233],"tags":[],"country":[399],"class_list":["post-145854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","country-ghana-es"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ghana: une machine \u00e0 cuire les hosties pour des religieuses<\/title>\n<meta name=\"description\" content=\"Les s\u0153urs nous ont donc demand\u00e9 de l\u2019aide et nos bienfaiteurs ne les ont pas abandonn\u00e9es: 21.000 euros ont \u00e9t\u00e9 offerts aux s\u0153urs, ce qui leur a permis d\u2019augmenter consid\u00e9rablement leur production. Du fait de l\u2019augmentation des ressources financi\u00e8res disponibles, la formation des jeunes s\u0153urs a ainsi pu \u00eatre am\u00e9lior\u00e9e. S\u0153ur Christina, la ma\u00eetresse des novices, remercie de tout c\u0153ur tous les bienfaiteurs et \u00e9crit\u00a0: \u00ab\u00a0Nous demandons \u00e0 Dieu de vous b\u00e9nir !\u00a0\u00bb\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ghana: une machine \u00e0 cuire les hosties pour des religieuses\" \/>\n<meta property=\"og:description\" content=\"Les s\u0153urs nous ont donc demand\u00e9 de l\u2019aide et nos bienfaiteurs ne les ont pas abandonn\u00e9es: 21.000 euros ont \u00e9t\u00e9 offerts aux s\u0153urs, ce qui leur a permis d\u2019augmenter consid\u00e9rablement leur production. Du fait de l\u2019augmentation des ressources financi\u00e8res disponibles, la formation des jeunes s\u0153urs a ainsi pu \u00eatre am\u00e9lior\u00e9e. S\u0153ur Christina, la ma\u00eetresse des novices, remercie de tout c\u0153ur tous les bienfaiteurs et \u00e9crit\u00a0: \u00ab\u00a0Nous demandons \u00e0 Dieu de vous b\u00e9nir !\u00a0\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-15T13:02:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-15T13:12:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/12\/Ghana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Ghana: une machine \u00e0 cuire les hosties pour des religieuses\",\"datePublished\":\"2020-12-15T13:02:32+00:00\",\"dateModified\":\"2020-12-15T13:12:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/\"},\"wordCount\":432,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Ghana.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/\",\"name\":\"Ghana: une machine \u00e0 cuire les hosties pour des religieuses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Ghana.jpg\",\"datePublished\":\"2020-12-15T13:02:32+00:00\",\"dateModified\":\"2020-12-15T13:12:54+00:00\",\"description\":\"Les s\u0153urs nous ont donc demand\u00e9 de l\u2019aide et nos bienfaiteurs ne les ont pas abandonn\u00e9es: 21.000 euros ont \u00e9t\u00e9 offerts aux s\u0153urs, ce qui leur a permis d\u2019augmenter consid\u00e9rablement leur production. Du fait de l\u2019augmentation des ressources financi\u00e8res disponibles, la formation des jeunes s\u0153urs a ainsi pu \u00eatre am\u00e9lior\u00e9e. S\u0153ur Christina, la ma\u00eetresse des novices, remercie de tout c\u0153ur tous les bienfaiteurs et \u00e9crit\u00a0: \u00ab\u00a0Nous demandons \u00e0 Dieu de vous b\u00e9nir !\u00a0\u00bb\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Ghana.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Ghana.jpg\",\"width\":1400,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/news-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ghana: une machine \u00e0 cuire les hosties pour des religieuses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ghana: une machine \u00e0 cuire les hosties pour des religieuses","description":"Les s\u0153urs nous ont donc demand\u00e9 de l\u2019aide et nos bienfaiteurs ne les ont pas abandonn\u00e9es: 21.000 euros ont \u00e9t\u00e9 offerts aux s\u0153urs, ce qui leur a permis d\u2019augmenter consid\u00e9rablement leur production. Du fait de l\u2019augmentation des ressources financi\u00e8res disponibles, la formation des jeunes s\u0153urs a ainsi pu \u00eatre am\u00e9lior\u00e9e. S\u0153ur Christina, la ma\u00eetresse des novices, remercie de tout c\u0153ur tous les bienfaiteurs et \u00e9crit\u00a0: \u00ab\u00a0Nous demandons \u00e0 Dieu de vous b\u00e9nir !\u00a0\u00bb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/","og_locale":"fr_FR","og_type":"article","og_title":"Ghana: une machine \u00e0 cuire les hosties pour des religieuses","og_description":"Les s\u0153urs nous ont donc demand\u00e9 de l\u2019aide et nos bienfaiteurs ne les ont pas abandonn\u00e9es: 21.000 euros ont \u00e9t\u00e9 offerts aux s\u0153urs, ce qui leur a permis d\u2019augmenter consid\u00e9rablement leur production. Du fait de l\u2019augmentation des ressources financi\u00e8res disponibles, la formation des jeunes s\u0153urs a ainsi pu \u00eatre am\u00e9lior\u00e9e. S\u0153ur Christina, la ma\u00eetresse des novices, remercie de tout c\u0153ur tous les bienfaiteurs et \u00e9crit\u00a0: \u00ab\u00a0Nous demandons \u00e0 Dieu de vous b\u00e9nir !\u00a0\u00bb","og_url":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2020-12-15T13:02:32+00:00","article_modified_time":"2020-12-15T13:12:54+00:00","og_image":[{"width":1400,"height":438,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/12\/Ghana.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"ACN Press Team","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Ghana: une machine \u00e0 cuire les hosties pour des religieuses","datePublished":"2020-12-15T13:02:32+00:00","dateModified":"2020-12-15T13:12:54+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/"},"wordCount":432,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/12\/Ghana.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/","url":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/","name":"Ghana: une machine \u00e0 cuire les hosties pour des religieuses","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/12\/Ghana.jpg","datePublished":"2020-12-15T13:02:32+00:00","dateModified":"2020-12-15T13:12:54+00:00","description":"Les s\u0153urs nous ont donc demand\u00e9 de l\u2019aide et nos bienfaiteurs ne les ont pas abandonn\u00e9es: 21.000 euros ont \u00e9t\u00e9 offerts aux s\u0153urs, ce qui leur a permis d\u2019augmenter consid\u00e9rablement leur production. Du fait de l\u2019augmentation des ressources financi\u00e8res disponibles, la formation des jeunes s\u0153urs a ainsi pu \u00eatre am\u00e9lior\u00e9e. S\u0153ur Christina, la ma\u00eetresse des novices, remercie de tout c\u0153ur tous les bienfaiteurs et \u00e9crit\u00a0: \u00ab\u00a0Nous demandons \u00e0 Dieu de vous b\u00e9nir !\u00a0\u00bb","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/12\/Ghana.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/12\/Ghana.jpg","width":1400,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/ghana-une-machine-a-cuire-les-hosties-pour-des-religieuses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/acninternational.org\/fr\/category\/news-fr\/"},{"@type":"ListItem","position":3,"name":"Ghana: une machine \u00e0 cuire les hosties pour des religieuses"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/fr\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/145854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=145854"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/145854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/145844"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=145854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=145854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=145854"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=145854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}