{"id":143475,"date":"2020-09-25T10:54:27","date_gmt":"2020-09-25T08:54:27","guid":{"rendered":"https:\/\/acninternational.org\/?p=143475"},"modified":"2020-09-25T11:01:46","modified_gmt":"2020-09-25T09:01:46","slug":"une-lueur-despoir-a-beyrouth","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/","title":{"rendered":"Une lueur d\u2019espoir \u00e0 Beyrouth"},"content":{"rendered":"<p>La perspective que les placards de cuisine allaient bient\u00f4t se remplir a suscit\u00e9 une vague d\u2019enthousiasme au dispensaire socio-m\u00e9dical intercommunautaire de Nabaa, quartier pauvre de Beyrouth.<\/p>\n<p>Les b\u00e9n\u00e9ficiaires du centre s\u2019y sont r\u00e9unis pour recevoir des colis alimentaires, gr\u00e2ce au soutien de la Fondation pontificale internationale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse.<\/p>\n<p>Avant m\u00eame la grave crise \u00e9conomique qui a secou\u00e9 le Liban, Bassima d\u00e9clarait que sa famille \u00ab vivait au bord du gouffre \u00bb survivant \u00e0 peine avec les revenus de son mari chauffeur de taxi. \u00ab Maintenant, je peux \u00e0 peine nourrir mes trois enfants \u00bb, d\u00e9clare cette m\u00e8re \u00e2g\u00e9e de 41 ans.<\/p>\n<p>Plus de la moiti\u00e9 de la population libanaise vit actuellement en dessous du seuil de pauvret\u00e9, et le pouvoir d\u2019achat de la monnaie nationale a diminu\u00e9 de 80 % en moins d\u2019un an.<\/p>\n<p>Accompagn\u00e9e de son plus jeune enfant Charbel, trois ans, qui porte le nom de ce saint libanais tant aim\u00e9, Bassima explique\u00a0: \u00ab Si j&rsquo;allais au supermarch\u00e9 et achetais le plus petit de ces produits, il ne me resterait pas assez d&rsquo;argent pour survivre le reste du mois. Aujourd&rsquo;hui, je ne peux presque rien acheter\u00bb.<\/p>\n<p>Chaque colis alimentaire familial \u2013 divis\u00e9 en deux bo\u00eetes \u2013 contient des produits de base tels que des lentilles et des haricots, des conserves et de l\u2019huile de cuisson.<\/p>\n<p>\u00ab Je suis tr\u00e8s reconnaissante au dispensaire\u00a0\u00bb, a d\u00e9clar\u00e9 Bassima avec le petit Charbel \u00e0 ses c\u00f4t\u00e9s, empilant ses bo\u00eetes dans une poussette pour les transporter chez elle.\u00a0 \u00ab\u00a0L\u2019assistante sociale et les s\u0153urs sont toujours l\u00e0 pour m\u2019\u00e9couter et m\u2019aider. \u00bb<\/p>\n<p>Au total, 786 familles ont b\u00e9n\u00e9fici\u00e9 de la distribution des colis alimentaires au dispensaire de Nabaa. Au total, plus de 5.800 familles dans le besoin sont aid\u00e9es dans le cadre de l\u2019initiative financ\u00e9e par l\u2019AED, en coop\u00e9ration avec la CNEWA [Association catholique d\u2019aide \u00e0 l\u2019Orient] et Caritas. Les distributions ont lieu dans plusieurs centres des zones de Beyrouth qui ont \u00e9t\u00e9 touch\u00e9es par la double explosion catastrophique du 4 ao\u00fbt.<\/p>\n<figure id=\"attachment_143459\" aria-describedby=\"caption-attachment-143459\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-143459 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut2.jpg\" alt=\"&quot;Une lueur d\u2019espoir \u00e0 Beyrouth&quot;.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut2.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut2-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-143459\" class=\"wp-caption-text\">\u00ab\u00a0Une lueur d\u2019espoir \u00e0 Beyrouth\u00a0\u00bb.<\/figcaption><\/figure>\n<p>\u00ab\u00a0Il y a tellement de pauvres dans la r\u00e9gion de Nabaa, tant de besoins \u00bb, souligne S\u0153ur Marie Justine el Osta, des S\u0153urs maronites de la Sainte Famille, directrice du dispensaire. \u00ab\u00a0Depuis l\u2019explosion, les besoins ont augment\u00e9. Les gens se battent pour vivre au jour le jour et chaque jour tout devient plus cher \u00bb, dit-elle \u00e0 propos de la situation d\u00e9sastreuse du pays qui plonge la classe moyenne dans la pauvret\u00e9.<\/p>\n<p>\u00ab\u00a0Je remercie Dieu d\u2019avoir envoy\u00e9 l\u2019AED pour nous aider. C&rsquo;est un signe que l&rsquo;\u00c9glise est proche de notre peuple dans sa souffrance. J\u2019esp\u00e8re qu\u2019\u00e0 l\u2019avenir, il y aura d\u2019autres collaborations et de nouveaux projets\u00a0\u00bb, d\u00e9clare S\u0153ur Marie Justine.<\/p>\n<p>Quand Abeer, 33 ans, a appris que l\u2019AED \u2013 et sa partenaire CNEWA \u2013 \u00e9taient toutes deux des \u0153uvres pontificales, elle a fait remarquer avec enthousiasme\u00a0: \u00ab\u00a0Je veux que le Pape Fran\u00e7ois le sache, je l\u2019aime tellement ! \u00a0Un de mes r\u00eaves, c\u2019est d\u2019aller au Vatican pour le rencontrer\u00a0\u00bb.<\/p>\n<p>Apr\u00e8s avoir \u00e9t\u00e9 au ch\u00f4mage pendant pr\u00e8s d\u2019un an, sans espoir en raison du confinement caus\u00e9s par le coronavirus, le mari d\u2019Abeer a enfin trouv\u00e9 du travail aux \u00c9mirats Arabes Unis. La s\u00e9paration est difficile pour la famille d\u2019Abeer, car elle s\u2019occupe de leur fils de quatre ans au Liban.<\/p>\n<p>\u00ab\u00a0Dieu merci, il a du travail maintenant\u00a0\u00bb, dit Abeer. Auparavant, Abeer travaillait comme femme de m\u00e9nage dans une \u00e9cole. C\u2019\u00e9tait sa fa\u00e7on d\u2019aider \u00e0 subvenir aux besoins de sa famille. Dipl\u00f4m\u00e9e en gestion h\u00f4teli\u00e8re, elle n\u2019avait pas r\u00e9ussi \u00e0 trouver un emploi dans son domaine. \u00ab\u00a0Parfois, il faut traverser des moments difficiles pour appr\u00e9cier ce que l\u2019on a\u00a0\u00bb, dit Abeer.<\/p>\n<p>\u00ab\u00a0J\u00e9sus est tr\u00e8s mis\u00e9ricordieux, il nous aide. Notre seule aide provient de ce centre. Je me sens tr\u00e8s bien ici. Mon fils y fait ses examens m\u00e9dicaux, se fait vacciner, etc. Ici, les s\u0153urs sont comme une lueur d\u2019espoir, car c\u2019est une p\u00e9riode tr\u00e8s, tr\u00e8s difficile que nous vivons maintenant, au Liban\u00a0\u00bb.<\/p>\n<p>Malgr\u00e9 ses difficult\u00e9s, Abeer dit avec conviction : \u00ab\u00a0Dieu ne nous quittera jamais. Ma foi est grande. C\u2019est pour cela que je peux me lever. Et j\u2019enseignerai ma foi \u00e0 mon fils \u00bb.<\/p>\n<p>\u00ab\u00a0Le Liban est d\u00e9vast\u00e9. Nous traversons la p\u00e9riode la plus difficile de son histoire \u00bb, souligne S\u0153ur Marie Justine.<\/p>\n<p>\u00ab\u00a0Nous demandons \u2013 pour le bien de l\u2019humanit\u00e9 \u2013 la solidarit\u00e9 avec le Liban. Nous demandons au monde entier de s\u2019unir et de nous aider\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La perspective que les placards de cuisine allaient bient\u00f4t se remplir a suscit\u00e9 une vague d\u2019enthousiasme au dispensaire socio-m\u00e9dical intercommunautaire<\/p>\n","protected":false},"author":4258341447,"featured_media":143465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[233],"tags":[],"country":[847],"class_list":["post-143475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","country-liban"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Une lueur d\u2019espoir \u00e0 Beyrouth<\/title>\n<meta name=\"description\" content=\"La perspective que les placards de cuisine allaient bient\u00f4t se remplir a suscit\u00e9 une vague d\u2019enthousiasme au dispensaire socio-m\u00e9dical intercommunautaire de Nabaa, quartier pauvre de Beyrouth.Les b\u00e9n\u00e9ficiaires du centre s\u2019y sont r\u00e9unis pour recevoir des colis alimentaires, gr\u00e2ce au soutien de la Fondation pontificale internationale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une lueur d\u2019espoir \u00e0 Beyrouth\" \/>\n<meta property=\"og:description\" content=\"La perspective que les placards de cuisine allaient bient\u00f4t se remplir a suscit\u00e9 une vague d\u2019enthousiasme au dispensaire socio-m\u00e9dical intercommunautaire de Nabaa, quartier pauvre de Beyrouth.Les b\u00e9n\u00e9ficiaires du centre s\u2019y sont r\u00e9unis pour recevoir des colis alimentaires, gr\u00e2ce au soutien de la Fondation pontificale internationale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-25T08:54:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-25T09:01:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Une lueur d\u2019espoir \u00e0 Beyrouth\",\"datePublished\":\"2020-09-25T08:54:27+00:00\",\"dateModified\":\"2020-09-25T09:01:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/\"},\"wordCount\":815,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Lebanon_Beirut.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/\",\"name\":\"Une lueur d\u2019espoir \u00e0 Beyrouth\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Lebanon_Beirut.jpg\",\"datePublished\":\"2020-09-25T08:54:27+00:00\",\"dateModified\":\"2020-09-25T09:01:46+00:00\",\"description\":\"La perspective que les placards de cuisine allaient bient\u00f4t se remplir a suscit\u00e9 une vague d\u2019enthousiasme au dispensaire socio-m\u00e9dical intercommunautaire de Nabaa, quartier pauvre de Beyrouth.Les b\u00e9n\u00e9ficiaires du centre s\u2019y sont r\u00e9unis pour recevoir des colis alimentaires, gr\u00e2ce au soutien de la Fondation pontificale internationale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Lebanon_Beirut.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Lebanon_Beirut.jpg\",\"width\":1400,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/une-lueur-despoir-a-beyrouth\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/news-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Une lueur d\u2019espoir \u00e0 Beyrouth\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Une lueur d\u2019espoir \u00e0 Beyrouth","description":"La perspective que les placards de cuisine allaient bient\u00f4t se remplir a suscit\u00e9 une vague d\u2019enthousiasme au dispensaire socio-m\u00e9dical intercommunautaire de Nabaa, quartier pauvre de Beyrouth.Les b\u00e9n\u00e9ficiaires du centre s\u2019y sont r\u00e9unis pour recevoir des colis alimentaires, gr\u00e2ce au soutien de la Fondation pontificale internationale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/","og_locale":"fr_FR","og_type":"article","og_title":"Une lueur d\u2019espoir \u00e0 Beyrouth","og_description":"La perspective que les placards de cuisine allaient bient\u00f4t se remplir a suscit\u00e9 une vague d\u2019enthousiasme au dispensaire socio-m\u00e9dical intercommunautaire de Nabaa, quartier pauvre de Beyrouth.Les b\u00e9n\u00e9ficiaires du centre s\u2019y sont r\u00e9unis pour recevoir des colis alimentaires, gr\u00e2ce au soutien de la Fondation pontificale internationale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse.\u00a0","og_url":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2020-09-25T08:54:27+00:00","article_modified_time":"2020-09-25T09:01:46+00:00","og_image":[{"width":1400,"height":438,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"ACN Press Team","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Une lueur d\u2019espoir \u00e0 Beyrouth","datePublished":"2020-09-25T08:54:27+00:00","dateModified":"2020-09-25T09:01:46+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/"},"wordCount":815,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/","url":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/","name":"Une lueur d\u2019espoir \u00e0 Beyrouth","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut.jpg","datePublished":"2020-09-25T08:54:27+00:00","dateModified":"2020-09-25T09:01:46+00:00","description":"La perspective que les placards de cuisine allaient bient\u00f4t se remplir a suscit\u00e9 une vague d\u2019enthousiasme au dispensaire socio-m\u00e9dical intercommunautaire de Nabaa, quartier pauvre de Beyrouth.Les b\u00e9n\u00e9ficiaires du centre s\u2019y sont r\u00e9unis pour recevoir des colis alimentaires, gr\u00e2ce au soutien de la Fondation pontificale internationale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse.\u00a0","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut.jpg","width":1400,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/une-lueur-despoir-a-beyrouth\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/acninternational.org\/fr\/category\/news-fr\/"},{"@type":"ListItem","position":3,"name":"Une lueur d\u2019espoir \u00e0 Beyrouth"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/fr\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/143475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=143475"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/143475\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/143465"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=143475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=143475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=143475"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=143475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}