{"id":142761,"date":"2020-09-09T10:31:59","date_gmt":"2020-09-09T08:31:59","guid":{"rendered":"https:\/\/acninternational.org\/?p=142761"},"modified":"2022-08-01T13:57:08","modified_gmt":"2022-08-01T11:57:08","slug":"liban-beyrouth-nous-ne-vous-abandonnerons-pas","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/","title":{"rendered":"Beyrouth, nous ne vous abandonnerons pas"},"content":{"rendered":"<p><strong><em>L\u2019AED pr\u00e9pare un deuxi\u00e8me envoi d&rsquo;aide \u00e0 Beyrouth, alors que l\u2019explosion du mois dernier fait craindre un exode des chr\u00e9tiens du Liban<\/em><\/strong><\/p>\n<p>On sait que plus de 100 \u00e9glises, couvents, \u00e9coles confessionnelles chr\u00e9tiennes et autres institutions ont besoin de r\u00e9parations \u00e0 la suite de l&rsquo;explosion du 4 ao\u00fbt. Une \u00e9quipe de la fondation pontificale Aide \u00e0 l&rsquo;\u00c9glise en D\u00e9tresse (AED) se rendra bient\u00f4t dans la capitale libanaise pour \u00e9valuer les d\u00e9g\u00e2ts et pr\u00e9parer des projets en vue d&rsquo;\u00e9tablir un plan d&rsquo;aide pastoral avant l&rsquo;arriv\u00e9e de l&rsquo;hiver.<\/p>\n<p>Cette aide viendrait s\u2019ajouter \u00e0 l\u2019aide d\u2019urgence de 250.000 euros fournie par la fondation dans les jours qui ont suivi l\u2019explosion pour des colis alimentaires et autres articles de premi\u00e8re n\u00e9cessit\u00e9, pour pr\u00e8s de 6.000 familles particuli\u00e8rement affect\u00e9es par la catastrophe.<\/p>\n<p>Regina Lynch, directrice des projets de l\u2019AED, a d\u00e9clar\u00e9\u00a0: \u00ab\u00a0Il existe une v\u00e9ritable crainte d\u2019un exode des chr\u00e9tiens. Soulignant que c\u2019est le quartier chr\u00e9tien de Beyrouth qui avait fait les frais de l\u2019explosion, Mme Lynch a d\u00e9clar\u00e9 que la communaut\u00e9 chr\u00e9tienne avait besoin d\u2019\u00eatre rassur\u00e9e, en ce qui concerne la r\u00e9paration de ses structures, afin de permettre aux fid\u00e8les de poursuivre ce qu\u2019elle a appel\u00e9 son \u00ab\u00a0r\u00f4le vital de b\u00e2tisseur de ponts\u00a0\u00bb, entre les musulmans sunnites et chiites.<\/p>\n<figure id=\"attachment_142749\" aria-describedby=\"caption-attachment-142749\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-142749 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Regina-Lynch.jpg\" alt=\"Regina Lynch, directrice des projets de l\u2019AED.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Regina-Lynch.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Regina-Lynch-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-142749\" class=\"wp-caption-text\">Regina Lynch, directrice des projets de l\u2019AED.<\/figcaption><\/figure>\n<p>Elle a soulign\u00e9 la n\u00e9cessit\u00e9 de soutenir les nombreux couvents et autres institutions religieuses qui ont \u00e9t\u00e9 endommag\u00e9s et qui g\u00e8rent des \u00e9coles, des h\u00f4pitaux, des cliniques et d\u2019autres centres de protection sociale \u00e0 Beyrouth et dans le reste du Liban. Mme Lynch a d\u00e9clar\u00e9\u00a0: \u00ab\u00a0Ce qui s\u2019est pass\u00e9 le 4 ao\u00fbt pourrait \u00eatre la goutte d\u2019eau qui fait d\u00e9border le vase, aboutissant \u00e0 ce que les chr\u00e9tiens, inquiets de la d\u00e9t\u00e9rioration de la situation \u00e9conomique et politique, perdent patience et estiment que la seule fa\u00e7on d\u2019assurer un avenir meilleur \u00e0 leurs familles est de commencer une nouvelle vie ailleurs. Nous voulons leur montrer que, gr\u00e2ce \u00e0 notre aide, il y a de l\u2019avenir pour eux dans un pays qui a si longtemps \u00e9t\u00e9 un phare du Christianisme pour le Proche-Orient et au-del\u00e0\u00a0\u00bb.<\/p>\n<p>L\u2019AED coordonne son aide \u00e0 Beyrouth avec d\u2019autres organisations catholiques, chacune d\u2019entre elles prenant en charge certains domaines d&rsquo;aide : la reconstruction des maisons, l\u2019\u00e9ducation, les soins m\u00e9dicaux et les infrastructures. Pas moins de 300.000 familles \u00e0 Beyrouth ont \u00e9t\u00e9 d\u00e9plac\u00e9es \u00e0 la suite de l\u2019explosion et Mme Lynch a soulign\u00e9 la n\u00e9cessit\u00e9 d\u2019une aide d\u2019urgence constante, affirmant qu\u2019il faudrait du temps avant que leurs maisons ne soient r\u00e9par\u00e9es.<\/p>\n<p>Remerciant les bienfaiteurs de l\u2019AED pour leur soutien, elle a d\u00e9clar\u00e9\u00a0: \u00ab Nous sommes vraiment impressionn\u00e9s par la g\u00e9n\u00e9rosit\u00e9 des nombreuses personnes qui ont r\u00e9pondu avec tant de compassion en faveur de ceux qui souffrent \u00e0 Beyrouth. Les messages que nous avons re\u00e7us de ceux que nous aidons \u00e0 Beyrouth font clairement part de leur gratitude envers tous ceux qui ont r\u00e9pondu \u00e0 leur appel \u00e0 l\u2019aide. Le message est clair : ceux qui souffrent ne sont pas seuls\u00a0\u00bb.<\/p>\n<p>Vendredi dernier, le 4 septembre, le pape Fran\u00e7ois a appel\u00e9 \u00e0 une journ\u00e9e de pri\u00e8re et de je\u00fbne pour le Liban.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019AED pr\u00e9pare un deuxi\u00e8me envoi d&rsquo;aide \u00e0 Beyrouth, alors que l\u2019explosion du mois dernier fait craindre un exode des chr\u00e9tiens<\/p>\n","protected":false},"author":4258341447,"featured_media":143477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[233,962],"tags":[],"country":[847],"class_list":["post-142761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","category-news-fr","country-liban"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Liban: Beyrouth, nous ne vous abandonnerons pas<\/title>\n<meta name=\"description\" content=\"L\u2019AED pr\u00e9pare un deuxi\u00e8me envoi d&#039;aide \u00e0 Beyrouth, alors que l\u2019explosion du mois dernier fait craindre un exode des chr\u00e9tiens du LibanOn sait que plus de 100 \u00e9glises, couvents, \u00e9coles confessionnelles chr\u00e9tiennes et autres institutions ont besoin de r\u00e9parations \u00e0 la suite de l&#039;explosion du 4 ao\u00fbt. Une \u00e9quipe de la fondation pontificale Aide \u00e0 l&#039;\u00c9glise en D\u00e9tresse (AED) se rendra bient\u00f4t dans la capitale libanaise pour \u00e9valuer les d\u00e9g\u00e2ts et pr\u00e9parer des projets en vue d&#039;\u00e9tablir un plan d&#039;aide pastoral avant l&#039;arriv\u00e9e de l&#039;hiver.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beyrouth, nous ne vous abandonnerons pas\" \/>\n<meta property=\"og:description\" content=\"L\u2019AED pr\u00e9pare un deuxi\u00e8me envoi d&#039;aide \u00e0 Beyrouth, alors que l\u2019explosion du mois dernier fait craindre un exode des chr\u00e9tiens du LibanOn sait que plus de 100 \u00e9glises, couvents, \u00e9coles confessionnelles chr\u00e9tiennes et autres institutions ont besoin de r\u00e9parations \u00e0 la suite de l&#039;explosion du 4 ao\u00fbt. Une \u00e9quipe de la fondation pontificale Aide \u00e0 l&#039;\u00c9glise en D\u00e9tresse (AED) se rendra bient\u00f4t dans la capitale libanaise pour \u00e9valuer les d\u00e9g\u00e2ts et pr\u00e9parer des projets en vue d&#039;\u00e9tablir un plan d&#039;aide pastoral avant l&#039;arriv\u00e9e de l&#039;hiver.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-09T08:31:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-01T11:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Beyrouth, nous ne vous abandonnerons pas\",\"datePublished\":\"2020-09-09T08:31:59+00:00\",\"dateModified\":\"2022-08-01T11:57:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/\"},\"wordCount\":594,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Lebanon_Beirut_3.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/\",\"name\":\"Liban: Beyrouth, nous ne vous abandonnerons pas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Lebanon_Beirut_3.jpg\",\"datePublished\":\"2020-09-09T08:31:59+00:00\",\"dateModified\":\"2022-08-01T11:57:08+00:00\",\"description\":\"L\u2019AED pr\u00e9pare un deuxi\u00e8me envoi d'aide \u00e0 Beyrouth, alors que l\u2019explosion du mois dernier fait craindre un exode des chr\u00e9tiens du LibanOn sait que plus de 100 \u00e9glises, couvents, \u00e9coles confessionnelles chr\u00e9tiennes et autres institutions ont besoin de r\u00e9parations \u00e0 la suite de l'explosion du 4 ao\u00fbt. Une \u00e9quipe de la fondation pontificale Aide \u00e0 l'\u00c9glise en D\u00e9tresse (AED) se rendra bient\u00f4t dans la capitale libanaise pour \u00e9valuer les d\u00e9g\u00e2ts et pr\u00e9parer des projets en vue d'\u00e9tablir un plan d'aide pastoral avant l'arriv\u00e9e de l'hiver.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Lebanon_Beirut_3.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Lebanon_Beirut_3.jpg\",\"width\":1400,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/news-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beyrouth, nous ne vous abandonnerons pas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Liban: Beyrouth, nous ne vous abandonnerons pas","description":"L\u2019AED pr\u00e9pare un deuxi\u00e8me envoi d'aide \u00e0 Beyrouth, alors que l\u2019explosion du mois dernier fait craindre un exode des chr\u00e9tiens du LibanOn sait que plus de 100 \u00e9glises, couvents, \u00e9coles confessionnelles chr\u00e9tiennes et autres institutions ont besoin de r\u00e9parations \u00e0 la suite de l'explosion du 4 ao\u00fbt. Une \u00e9quipe de la fondation pontificale Aide \u00e0 l'\u00c9glise en D\u00e9tresse (AED) se rendra bient\u00f4t dans la capitale libanaise pour \u00e9valuer les d\u00e9g\u00e2ts et pr\u00e9parer des projets en vue d'\u00e9tablir un plan d'aide pastoral avant l'arriv\u00e9e de l'hiver.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/","og_locale":"fr_FR","og_type":"article","og_title":"Beyrouth, nous ne vous abandonnerons pas","og_description":"L\u2019AED pr\u00e9pare un deuxi\u00e8me envoi d'aide \u00e0 Beyrouth, alors que l\u2019explosion du mois dernier fait craindre un exode des chr\u00e9tiens du LibanOn sait que plus de 100 \u00e9glises, couvents, \u00e9coles confessionnelles chr\u00e9tiennes et autres institutions ont besoin de r\u00e9parations \u00e0 la suite de l'explosion du 4 ao\u00fbt. Une \u00e9quipe de la fondation pontificale Aide \u00e0 l'\u00c9glise en D\u00e9tresse (AED) se rendra bient\u00f4t dans la capitale libanaise pour \u00e9valuer les d\u00e9g\u00e2ts et pr\u00e9parer des projets en vue d'\u00e9tablir un plan d'aide pastoral avant l'arriv\u00e9e de l'hiver.","og_url":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2020-09-09T08:31:59+00:00","article_modified_time":"2022-08-01T11:57:08+00:00","og_image":[{"width":1400,"height":438,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut_3.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"ACN Press Team","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Beyrouth, nous ne vous abandonnerons pas","datePublished":"2020-09-09T08:31:59+00:00","dateModified":"2022-08-01T11:57:08+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/"},"wordCount":594,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut_3.jpg","articleSection":["Non classifi\u00e9(e)","Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/","url":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/","name":"Liban: Beyrouth, nous ne vous abandonnerons pas","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut_3.jpg","datePublished":"2020-09-09T08:31:59+00:00","dateModified":"2022-08-01T11:57:08+00:00","description":"L\u2019AED pr\u00e9pare un deuxi\u00e8me envoi d'aide \u00e0 Beyrouth, alors que l\u2019explosion du mois dernier fait craindre un exode des chr\u00e9tiens du LibanOn sait que plus de 100 \u00e9glises, couvents, \u00e9coles confessionnelles chr\u00e9tiennes et autres institutions ont besoin de r\u00e9parations \u00e0 la suite de l'explosion du 4 ao\u00fbt. Une \u00e9quipe de la fondation pontificale Aide \u00e0 l'\u00c9glise en D\u00e9tresse (AED) se rendra bient\u00f4t dans la capitale libanaise pour \u00e9valuer les d\u00e9g\u00e2ts et pr\u00e9parer des projets en vue d'\u00e9tablir un plan d'aide pastoral avant l'arriv\u00e9e de l'hiver.","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut_3.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Lebanon_Beirut_3.jpg","width":1400,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/liban-beyrouth-nous-ne-vous-abandonnerons-pas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/acninternational.org\/fr\/category\/news-fr\/"},{"@type":"ListItem","position":3,"name":"Beyrouth, nous ne vous abandonnerons pas"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/fr\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/142761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=142761"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/142761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/143477"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=142761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=142761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=142761"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=142761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}