{"id":140888,"date":"2020-07-30T16:43:41","date_gmt":"2020-07-30T14:43:41","guid":{"rendered":"https:\/\/acninternational.org\/?p=140888"},"modified":"2020-07-30T17:00:49","modified_gmt":"2020-07-30T15:00:49","slug":"la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute","status":"publish","type":"post","link":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/","title":{"rendered":"\u00ab La communaut\u00e9 internationale ne prend pas conscience du probl\u00e8me de Cabo Delgado \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9"},"content":{"rendered":"<p>Le monde ne voit pas, ou ne veut pas voir, ce qui se passe dans la province de Cabo Delgado. C&rsquo;est le point de vue exprim\u00e9 par Paulo Rangel, membre du Parlement europ\u00e9en et vice-pr\u00e9sident du Parti Populaire Europ\u00e9en, sur la situation qui se d\u00e9roule actuellement dans le nord-est du Mozambique, o\u00f9 de violentes attaques de groupes arm\u00e9s ont d\u00e9j\u00e0 caus\u00e9 des centaines de morts et laiss\u00e9 plus de 200 000 personnes sans abri. Cela devrait \u00eatre une priorit\u00e9 absolue pour la communaut\u00e9 internationale. Pourtant, ce n\u2019est pas le cas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-140863\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere-3.jpg\" alt=\"\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere-3.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere-3-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><\/p>\n<p>\u00ab\u00a0Il est d\u00e9j\u00e0 tard pour intervenir, mais mieux vaut tard que jamais. Nous sommes confront\u00e9s depuis 2017 \u00e0 ces attaques qui se sont multipli\u00e9es, et la communaut\u00e9 internationale n\u2019a pas du tout pris conscience de ce probl\u00e8me\u00a0\u00bb. Dans un entretien accord\u00e9 \u00e0 la Fondation pontificale Aide \u00e0 l\u2019\u00c9glise en D\u00e9tresse (AED), Paulo Rangel d\u00e9crit comme une \u00ab\u00a0poudri\u00e8re\u00a0\u00bb la province de Cabo Delgado, et demande de l\u2019aide pour la population touch\u00e9e par la violence, en particulier pour les personnes d\u00e9plac\u00e9es qui ont perdu tout ce qu\u2019elles avaient \u00e0 cause des attaques de groupes arm\u00e9s affirmant faire partie de l\u2019\u00c9tat Islamique (Daesh).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-140857\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere-2.jpg\" alt=\"\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere-2.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere-2-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><\/p>\n<p>\u00ab Ce qui se passe actuellement \u00e0 Cabo Delgado, c&rsquo;est que les gens fuient vers les villes, o\u00f9 ils pensent que les attaques seront moins probables, parce qu&rsquo;ils ont vu ce qui se passe dans les villages&#8230; En d\u2019autres termes, ces d\u00e9placements de population ne sont pas seulement la cons\u00e9quence directe des attaques contre les villages, mais c\u2019est aussi une r\u00e9action de panique totalement justifi\u00e9e. Les gens s\u2019enfuient pour se prot\u00e9ger, avant d\u2019\u00eatre attaqu\u00e9s\u00a0\u00bb.<\/p>\n<figure id=\"attachment_140875\" aria-describedby=\"caption-attachment-140875\" style=\"width: 205px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-140875 size-medium\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/ACN-20200707-102949-205x300.jpg\" alt=\"\" width=\"205\" height=\"300\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/ACN-20200707-102949-205x300.jpg 205w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/ACN-20200707-102949-701x1024.jpg 701w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/ACN-20200707-102949-768x1122.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/ACN-20200707-102949-1051x1536.jpg 1051w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/ACN-20200707-102949-1401x2048.jpg 1401w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/ACN-20200707-102949-scaled.jpg 1752w\" sizes=\"auto, (max-width: 205px) 100vw, 205px\" \/><figcaption id=\"caption-attachment-140875\" class=\"wp-caption-text\">Paulo Rangel &#8211; eurodeputado (Portugal)<\/figcaption><\/figure>\n<p>Pour l\u2019eurod\u00e9put\u00e9, il est important de faire observer qu\u2019il ne s\u2019agit pas d\u2019une guerre de religion car les victimes de la haine de ces groupes extr\u00e9mistes sont tant chr\u00e9tiennes que musulmanes. Il souligne \u00e9galement la position de l\u2019\u00e9v\u00eaque de Pemba, Mgr Luiz Fernando Lisboa, quant \u00e0 cette question. \u00ab L\u2019\u00e9v\u00eaque de Pemba a \u00e9t\u00e9 tr\u00e8s clair dans toutes ses interventions proph\u00e9tiques. Dans les appels qu\u2019il a lanc\u00e9s (il a \u00e9t\u00e9 le grand ap\u00f4tre de cette cause), il a soulign\u00e9 que les musulmans souffraient aussi beaucoup. Les dirigeants musulmans sont \u00e9galement extr\u00eamement pr\u00e9occup\u00e9s\u00a0\u00bb.<\/p>\n<p>Tout le monde souffre de cette violence, tous sont victimes de la destruction brutale qui a frapp\u00e9 cette r\u00e9gion d\u00e9j\u00e0 si pauvre. C\u2019est \u00e9galement pour cette raison que l\u2019aide de la communaut\u00e9 internationale est urgente. \u00ab\u00a0Nous parlons de l\u2019une des r\u00e9gions les plus pauvres du monde \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9. \u00ab\u00a0Ces personnes vivaient d\u00e9j\u00e0 dans une extr\u00eame pauvret\u00e9, avec de grandes difficult\u00e9s. Le probl\u00e8me est qu\u2019\u00e0 l\u2019heure actuelle, ces gens risquent de mourir, de perdre leur maison, d\u2019\u00eatre d\u00e9plac\u00e9s&#8230;\u00a0\u00bb.<\/p>\n<p>Paulo Rangel d\u00e9crit \u00e0 la Fondation pontificale AED l\u2019atmosph\u00e8re de peur et de violence extr\u00eame qui s\u2019abat sur la r\u00e9gion. \u00ab\u00a0\u00c0 l\u2019heure actuelle, nous savons qu\u2019il y a des jeunes filles qui sont enlev\u00e9es, r\u00e9duites en esclavage, qui deviennent des esclaves sexuelles de certains de ces gu\u00e9rilleros, de ces insurg\u00e9s, de ces terroristes&#8230; Nous savons que des milices djihadistes recrutent des jeunes, dont certains tr\u00e8s jeunes \u00e2g\u00e9s de 14, 15, 16 ans. Il est clair que ces jeunes gar\u00e7ons sont sous la contrainte. S&rsquo;ils refusent de rejoindre le groupe, ils pourraient \u00eatre tu\u00e9s&#8230;\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The world does not see, or does not wish to see, what is happening in the province of Cabo Delgado<\/p>\n","protected":false},"author":66,"featured_media":140870,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[233],"tags":[],"country":[418],"class_list":["post-140888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","country-mozambique-es"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00ab La communaut\u00e9 internationale ne prend pas conscience du probl\u00e8me de Cabo Delgado \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9 | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab La communaut\u00e9 internationale ne prend pas conscience du probl\u00e8me de Cabo Delgado \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9\" \/>\n<meta property=\"og:description\" content=\"The world does not see, or does not wish to see, what is happening in the province of Cabo Delgado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-30T14:43:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-30T15:00:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milena\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milena\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/\"},\"author\":{\"name\":\"Milena\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/5a2b2930ad4475e0aa0dade4e51d9474\"},\"headline\":\"\u00ab La communaut\u00e9 internationale ne prend pas conscience du probl\u00e8me de Cabo Delgado \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9\",\"datePublished\":\"2020-07-30T14:43:41+00:00\",\"dateModified\":\"2020-07-30T15:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/\"},\"wordCount\":629,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/acnnews_Mozambique_The-international-community-is-nowhere.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/\",\"name\":\"\u00ab La communaut\u00e9 internationale ne prend pas conscience du probl\u00e8me de Cabo Delgado \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9 | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/acnnews_Mozambique_The-international-community-is-nowhere.jpg\",\"datePublished\":\"2020-07-30T14:43:41+00:00\",\"dateModified\":\"2020-07-30T15:00:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/acnnews_Mozambique_The-international-community-is-nowhere.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/acnnews_Mozambique_The-international-community-is-nowhere.jpg\",\"width\":2000,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/category\\\/news-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00ab La communaut\u00e9 internationale ne prend pas conscience du probl\u00e8me de Cabo Delgado \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/#\\\/schema\\\/person\\\/5a2b2930ad4475e0aa0dade4e51d9474\",\"name\":\"Milena\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/fr\\\/author\\\/milena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00ab La communaut\u00e9 internationale ne prend pas conscience du probl\u00e8me de Cabo Delgado \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9 | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00ab La communaut\u00e9 internationale ne prend pas conscience du probl\u00e8me de Cabo Delgado \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9","og_description":"The world does not see, or does not wish to see, what is happening in the province of Cabo Delgado","og_url":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2020-07-30T14:43:41+00:00","article_modified_time":"2020-07-30T15:00:49+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere.jpg","type":"image\/jpeg"}],"author":"Milena","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"\u00c9crit par":"Milena","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/"},"author":{"name":"Milena","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/5a2b2930ad4475e0aa0dade4e51d9474"},"headline":"\u00ab La communaut\u00e9 internationale ne prend pas conscience du probl\u00e8me de Cabo Delgado \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9","datePublished":"2020-07-30T14:43:41+00:00","dateModified":"2020-07-30T15:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/"},"wordCount":629,"publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/","url":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/","name":"\u00ab La communaut\u00e9 internationale ne prend pas conscience du probl\u00e8me de Cabo Delgado \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9 | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere.jpg","datePublished":"2020-07-30T14:43:41+00:00","dateModified":"2020-07-30T15:00:49+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/07\/acnnews_Mozambique_The-international-community-is-nowhere.jpg","width":2000,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/fr\/la-communaute-internationale-ne-prend-pas-conscience-du-probleme-de-cabo-delgado-declare-leurodepute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/acninternational.org\/fr\/category\/news-fr\/"},{"@type":"ListItem","position":3,"name":"\u00ab La communaut\u00e9 internationale ne prend pas conscience du probl\u00e8me de Cabo Delgado \u00bb, d\u00e9clare l\u2019eurod\u00e9put\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/fr\/#website","url":"https:\/\/acninternational.org\/fr\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/fr\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/fr\/#\/schema\/person\/5a2b2930ad4475e0aa0dade4e51d9474","name":"Milena","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/fr\/author\/milena\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/140888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/comments?post=140888"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/posts\/140888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media\/140870"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/media?parent=140888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/categories?post=140888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/tags?post=140888"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/fr\/wp-json\/wp\/v2\/country?post=140888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}