{"id":267677,"date":"2026-07-15T16:00:57","date_gmt":"2026-07-15T14:00:57","guid":{"rendered":"https:\/\/acninternational.org\/?p=267677"},"modified":"2026-07-15T16:01:04","modified_gmt":"2026-07-15T14:01:04","slug":"teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/","title":{"rendered":"\u201cTeolog\u00eda vivida\u201d entre los escombros: seminaristas venezolanos ayudan a los damnificados"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>\u201cQue la gente nos abrace y busque consuelo en nosotros es un signo de que la misi\u00f3n de la Iglesia es estar con las personas\u201d, dice seminarista venezolano.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El seminarista venezolano Germ\u00e1n Jim\u00e9nez de la di\u00f3cesis de Petare se encuentra ya en la \u00faltima etapa de formaci\u00f3n antes de la ordenaci\u00f3n sacerdotal. Desde el primer momento despu\u00e9s del doble terremoto del 24 de junio, que ha dejado hasta ahora m\u00e1s de 4.400 fallecidos en Venezuela, se ha movilizado para llevar ayuda material y espiritual a miles de damnificados en La Guaira.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"911\" height=\"1024\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260715-208310-911x1024.jpg\" alt=\"\" class=\"wp-image-267658\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260715-208310-911x1024.jpg 911w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260715-208310-267x300.jpg 267w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260715-208310-768x863.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260715-208310.jpg 1027w\" sizes=\"auto, (max-width: 911px) 100vw, 911px\" \/><figcaption class=\"wp-element-caption\">Germ\u00e1n Jim\u00e9nez<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el seminarista, la tragedia ha dejado lecciones para el futuro sacerdocio de todos los seminaristas que no olvidar\u00e1n jam\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cVivimos el terremoto con mucha angustia, nervios y miedo\u201d, explica. Dice que \u00e9l estaba estudiando en su habitaci\u00f3n del Seminario de santa Rita en Caracas cuando son\u00f3 la alerta en el tel\u00e9fono y escuch\u00f3 \u201cla bulla y el nerviosismo de mis compa\u00f1eros\u201d. \u201cEntonces, salimos corriendo del edificio, preocupados por lo que estaba pasando\u201d, narra a la fundaci\u00f3n pontificia Aid to the Church in Need (ACN).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuenta que horas m\u00e1s tarde, los seminaristas vieron \u201ciglesias, edificaciones civiles y viviendas derrumbadas\u201d tanto en Caracas como en La Guaira. Sin dudarlo, optaron por ayudar a trav\u00e9s de las C\u00e1ritas diocesanas y las parroquias a las personas que hab\u00edan perdido sus hogares y que estaban buscando a sus seres queridos bajo los escombros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHe podido bajar a La Guaira en tres ocasiones para ver la realidad en mis propias carnes: personas que a\u00fan tienen esperanza de encontrar con vida a un ser querido, otras que esperan sencillamente localizar sus restos\u201d, a\u00f1ade.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208307.jpg\" alt=\"\" class=\"wp-image-267664\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208307.jpg 1920w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208307-300x169.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208307-1024x576.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208307-768x432.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208307-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Junto a sus compa\u00f1eros de seminario de santa Rita ha distribuido alimentos, colchonetas, ropa y medicinas. Pero su prioridad ha sido \u201cque las personas sientan que la Iglesia est\u00e1 con ellos\u201d, que la Iglesia se detenga a \u201cescuchar, dar un abrazo, una sonrisa\u201d. Como seminarista de la di\u00f3cesis de Petare, est\u00e1 experimentando que \u201cDios se hace presente en medio de esta circunstancia\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAunque no somos sacerdotes, llevamos el alzacuellos y nos ven como representaci\u00f3n de la Iglesia y de Cristo. Que la gente nos abrace y busque consuelo en nosotros es un signo de que la Iglesia debe estar presente sin hacer publicidad ni esperar nada a cambio. Tambi\u00e9n debe recordarles que hay un Dios que los ama, un Dios que los quiere. La misi\u00f3n no es tanto el hacer, sino el estar. El trabajo ha sido ese, estar presente en medio del pueblo y hacer presente a la iglesia en medio de \u00e9l\u201d, dice a la fundaci\u00f3n ACN.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de tanto dolor, Germ\u00e1n se refugia en el Evangelio. Dice que le inspira el episodio en el que Jes\u00fas calma la tempestad y pregunta a sus disc\u00edpulos \u2018\u00bfPor qu\u00e9 ten\u00e9is miedo?\u2019. \u201c\u00c9l est\u00e1 en medio de la tormenta con nosotros\u201d, reflexiona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, dice que est\u00e1 aprendiendo mucho de su pa\u00eds pues \u201cesta tragedia nos ha permitido ver que los venezolanos formamos una sola familia\u201d. Por ejemplo, \u201clos primeros que salieron en ayuda de la gente fueron los mismos vecinos, las personas de a pie. Esa solidaridad espont\u00e1nea es un signo de esperanza para nuestro pa\u00eds\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208309.jpg\" alt=\"\" class=\"wp-image-267670\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208309.jpg 1920w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208309-300x169.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208309-1024x576.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208309-768x432.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260714-208309-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La historia de Germ\u00e1n refleja el papel que muchos seminaristas de Venezuela est\u00e1n protagonizando en la respuesta de la Iglesia a la tragedia. Mientras atienden a los damnificados y les llevan consuelo, esperanza y ayudas materiales, estos futuros sacerdotes reciben lecciones que tendr\u00e1n una enorme repercusi\u00f3n en la vida de la Iglesia cat\u00f3lica en muchas di\u00f3cesis de Venezuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El domingo, 12 de junio, el arzobispo de Caracas, monse\u00f1or Ra\u00fal Biord, celebr\u00f3 una misa de env\u00edo para los seminaristas que habiendo acabado el a\u00f1o acad\u00e9mico, se desplazar\u00e1n a las zonas afectadas por el terremoto, donde realizar\u00e1n su experiencia pastoral ayudando a los damnificados. El prelado destac\u00f3 que \u201cesta labor va a ser dura, pero es parte crucial de una \u2018teolog\u00eda vivida\u2019\u201d. La formaci\u00f3n acad\u00e9mica es importante, pero tambi\u00e9n lo es el contacto directo con el sufrimiento y la realidad de las personas, una experiencia que prepara a los futuros sacerdotes para su misi\u00f3n de servir a los m\u00e1s necesitados\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Germ\u00e1n concluye con una petici\u00f3n a los benefactores de ACN: \u201cQuiero pedirle al Se\u00f1or que nos conceda misericordia en medio de estos momentos de dificultades. Realmente Venezuela ha sufrido durante mucho tiempo por tantas cosas, pero especialmente hoy quiero pedir para que en Venezuela pueda reinar la paz, la tranquilidad y pueda reinar tambi\u00e9n su presencia en medio de todo este proceso que estamos viviendo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ACN ha aprobado una ayuda de emergencia de 100.000 euros para las di\u00f3cesis de La Guaira y Caracas, destinada a las necesidades m\u00e1s urgentes y a sostener a los seminaristas y sacerdotes que, como \u00e9l, acompa\u00f1an a los damnificados. Esta semana, una delegaci\u00f3n de la Fundaci\u00f3n Pontificia ACN ha visitado las zonas golpeadas por el se\u00edsmo como se\u00f1al de comuni\u00f3n y para evaluar sobre el terreno nuevas formas de apoyo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cQue la gente nos abrace y busque consuelo en nosotros es un signo de que la misi\u00f3n de la Iglesia es estar con las personas\u201d, dice seminarista venezolano. El seminarista venezolano Germ\u00e1n Jim\u00e9nez de la di\u00f3cesis de Petare se encuentra ya en la \u00faltima etapa de formaci\u00f3n antes de la ordenaci\u00f3n sacerdotal. Desde el primer [&hellip;]<\/p>\n","protected":false},"author":4258341486,"featured_media":267657,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[4258341378],"_acn_featured_article":false,"footnotes":""},"categories":[1254],"tags":[],"country":[391],"class_list":["post-267677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-es","country-venezuela-es"],"acn_coauthors":[{"id":4258341378,"name":"Maria Lozano","url":"https:\/\/acninternational.org\/es\/author\/maria\/"}],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u201cTeolog\u00eda vivida\u201d entre los escombros: seminaristas venezolanos ayudan a los damnificados | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cTeolog\u00eda vivida\u201d entre los escombros: seminaristas venezolanos ayudan a los damnificados\" \/>\n<meta property=\"og:description\" content=\"\u201cQue la gente nos abrace y busque consuelo en nosotros es un signo de que la misi\u00f3n de la Iglesia es estar con las personas\u201d, dice seminarista venezolano. El seminarista venezolano Germ\u00e1n Jim\u00e9nez de la di\u00f3cesis de Petare se encuentra ya en la \u00faltima etapa de formaci\u00f3n antes de la ordenaci\u00f3n sacerdotal. Desde el primer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T14:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T14:01:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260630-207855.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Javier Mart\u00ednez-Brocal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Mart\u00ednez-Brocal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/\"},\"author\":{\"name\":\"Javier Mart\u00ednez-Brocal\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/44d4edf255c7adbb6b1b26bf36edf8b5\"},\"headline\":\"\u201cTeolog\u00eda vivida\u201d entre los escombros: seminaristas venezolanos ayudan a los damnificados\",\"datePublished\":\"2026-07-15T14:00:57+00:00\",\"dateModified\":\"2026-07-15T14:01:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/\"},\"wordCount\":896,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/ACN-20260630-207855.jpg\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/\",\"name\":\"\u201cTeolog\u00eda vivida\u201d entre los escombros: seminaristas venezolanos ayudan a los damnificados | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/ACN-20260630-207855.jpg\",\"datePublished\":\"2026-07-15T14:00:57+00:00\",\"dateModified\":\"2026-07-15T14:01:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/ACN-20260630-207855.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/ACN-20260630-207855.jpg\",\"width\":1980,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTICIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/news-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u201cTeolog\u00eda vivida\u201d entre los escombros: seminaristas venezolanos ayudan a los damnificados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/44d4edf255c7adbb6b1b26bf36edf8b5\",\"name\":\"Javier Mart\u00ednez-Brocal\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/javier\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u201cTeolog\u00eda vivida\u201d entre los escombros: seminaristas venezolanos ayudan a los damnificados | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cTeolog\u00eda vivida\u201d entre los escombros: seminaristas venezolanos ayudan a los damnificados","og_description":"\u201cQue la gente nos abrace y busque consuelo en nosotros es un signo de que la misi\u00f3n de la Iglesia es estar con las personas\u201d, dice seminarista venezolano. El seminarista venezolano Germ\u00e1n Jim\u00e9nez de la di\u00f3cesis de Petare se encuentra ya en la \u00faltima etapa de formaci\u00f3n antes de la ordenaci\u00f3n sacerdotal. Desde el primer [&hellip;]","og_url":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2026-07-15T14:00:57+00:00","article_modified_time":"2026-07-15T14:01:04+00:00","og_image":[{"width":1980,"height":800,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260630-207855.jpg","type":"image\/jpeg"}],"author":"Javier Mart\u00ednez-Brocal","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"Javier Mart\u00ednez-Brocal","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/"},"author":{"name":"Javier Mart\u00ednez-Brocal","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/44d4edf255c7adbb6b1b26bf36edf8b5"},"headline":"\u201cTeolog\u00eda vivida\u201d entre los escombros: seminaristas venezolanos ayudan a los damnificados","datePublished":"2026-07-15T14:00:57+00:00","dateModified":"2026-07-15T14:01:04+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/"},"wordCount":896,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260630-207855.jpg","articleSection":["NOTICIAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/","url":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/","name":"\u201cTeolog\u00eda vivida\u201d entre los escombros: seminaristas venezolanos ayudan a los damnificados | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260630-207855.jpg","datePublished":"2026-07-15T14:00:57+00:00","dateModified":"2026-07-15T14:01:04+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260630-207855.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/07\/ACN-20260630-207855.jpg","width":1980,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/teologia-vivida-entre-los-escombros-seminaristas-venezolanos-ayudan-a-los-damnificados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"NOTICIAS","item":"https:\/\/acninternational.org\/es\/category\/news-es\/"},{"@type":"ListItem","position":3,"name":"\u201cTeolog\u00eda vivida\u201d entre los escombros: seminaristas venezolanos ayudan a los damnificados"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/44d4edf255c7adbb6b1b26bf36edf8b5","name":"Javier Mart\u00ednez-Brocal","url":"https:\/\/acninternational.org\/es\/author\/javier\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/267677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341486"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=267677"}],"version-history":[{"count":1,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/267677\/revisions"}],"predecessor-version":[{"id":267678,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/267677\/revisions\/267678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/267657"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=267677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=267677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=267677"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=267677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}