{"id":263297,"date":"2026-04-14T08:09:17","date_gmt":"2026-04-14T06:09:17","guid":{"rendered":"https:\/\/acninternational.org\/?p=263297"},"modified":"2026-04-14T11:39:03","modified_gmt":"2026-04-14T09:39:03","slug":"el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/","title":{"rendered":"El L\u00edbano se derrumba bajo los bombardeos: \u201cla gente se siente deshumanizada\u201d"},"content":{"rendered":"\n<p>Entre las prioridades est\u00e1n la reapertura de las escuelas y el pago de los salarios de los maestros, ya que estos desempe\u00f1an un papel crucial en la difusi\u00f3n de los valores cristianos en la regi\u00f3n.<\/p>\n\n\n\n<p>La gente est\u00e1 \u201casustada, enojada y triste\u201d despu\u00e9s de que m\u00e1s de 100 bombas cayeran en Beirut en una sola noche, y destrozara cualquier sensaci\u00f3n de seguridad que quedaba para aquellos que a\u00fan viven en sus hogares, explic\u00f3 a ACN un trabajador humanitario.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/03\/ACN-20250604-190124-768x1024.jpg\" alt=\"\" class=\"wp-image-262932\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/03\/ACN-20250604-190124-768x1024.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/03\/ACN-20250604-190124-225x300.jpg 225w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/03\/ACN-20250604-190124.jpg 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Los ataques a\u00e9reos israel\u00edes causaron cientos de v\u00edctimas mortales en todo el L\u00edbano en un solo d\u00eda<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Las Fuerzas de Defensa de Israel (FDI) lanzaron una ola masiva de ataques en Beirut el 8 de abril, matando al menos a 254 personas e hiriendo a m\u00e1s de 1000<\/p>\n\n\n\n<p>Tras el anuncio del presidente estadounidense Donald Trump de un alto el fuego con Ir\u00e1n el 7 de abril, el primer ministro israel\u00ed Benjamin Netanyahu anunci\u00f3 que \u00abno hay alto el fuego en el L\u00edbano\u00bb y que su pa\u00eds continuar\u00eda \u00abatacando a Hezbol\u00e1 con toda su fuerza\u00bb.<\/p>\n\n\n\n<p>Marielle Boutros, coordinadora de proyectos de la organizaci\u00f3n ben\u00e9fica cat\u00f3lica Ayuda a la Iglesia Necesitada (ACN), que vive y trabaja en el este de Beirut, dijo que la gente cre\u00eda estar a salvo en sus casas cuando explotaron las bombas.<\/p>\n\n\n\n<p>\u00abHace dos d\u00edas cayeron m\u00e1s de 100 bombas sobre Beirut. Fue aqu\u00ed y all\u00e1, no solo en el sur de la capital, fue alrededor de toda la ciudad; se pod\u00edan o\u00edr las bombas desde nuestra oficina\u00bb.<\/p>\n\n\n\n<p>\u00abAlgunas zonas no hab\u00edan sido atacadas previamente, as\u00ed que la gente pens\u00f3 que estaban a salvo, pero no\u2026 Fue aterrador, caus\u00f3 ira, caus\u00f3 tristeza, especialmente cuando uno oye que hay un alto el fuego en otros lugares. Fue realmente tr\u00e1gico\u00bb.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"760\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/01\/ACN-20231030-155096-1024x760.jpg\" alt=\"\" class=\"wp-image-238508\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/01\/ACN-20231030-155096-1024x760.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/01\/ACN-20231030-155096-300x223.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/01\/ACN-20231030-155096-768x570.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/01\/ACN-20231030-155096.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Marielle Boutros<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Un fr\u00e1gil alto el fuego entre Hezbol\u00e1 e Israel, establecido en 2024, colaps\u00f3 el 28 de febrero despu\u00e9s de que un ataque estadounidense-israel\u00ed contra Ir\u00e1n matara a su l\u00edder supremo, el ayatol\u00e1 Ali Khamenei.<\/p>\n\n\n\n<p>Desde entonces, m\u00e1s de 1800 personas han muerto, incluidos 120 ni\u00f1os, y otras 3000 han resultado heridas.<\/p>\n\n\n\n<p>Las tropas israel\u00edes han evacuado grandes territorios en aldeas del sur mientras intentan tomar el control de las fronteras.<\/p>\n\n\n\n<p>El 31 de marzo, el ej\u00e9rcito liban\u00e9s se retir\u00f3 de Rmeich y Ein Ebel, las dos aldeas cristianas del sur del L\u00edbano que ahora estar\u00e1n en la zona de amortiguaci\u00f3n de Israel.<\/p>\n\n\n\n<p>Marielle Boutros cuenta que cada d\u00eda trae una mezcla de alivio y dolor. \u00abSientes que te est\u00e1n deshumanizando. Llamas a tus familiares y te alivia saber que est\u00e1n bien, pero luego tienes 200 muertos y casi 2000 heridos. No te sientes seguro. Algunas de las v\u00edctimas estaban en sus casas, en un lugar seguro y reconfortante, y fueron bombardeadas.\u00bb<\/p>\n\n\n\n<p>\u00abTener que lidiar con la ansiedad, los miedos y la culpa que se acrecientan en los \u00faltimos a\u00f1os. Para m\u00ed, esto es lo peor: cuando te sientes aliviado de que no sea tu familia, pero ves que otras familias s\u00ed sufren perdidas. Tenemos esta presi\u00f3n para continuar con nuestra vida diaria porque no podemos permitirnos no hacerlo debido a la crisis econ\u00f3mica.\u00bb<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/04\/ACN-20250604-190115-1024x575.jpg\" alt=\"\" class=\"wp-image-263290\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/04\/ACN-20250604-190115-1024x575.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/04\/ACN-20250604-190115-300x168.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/04\/ACN-20250604-190115-768x431.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/04\/ACN-20250604-190115.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Las zonas cristianas del pa\u00eds tambi\u00e9n se est\u00e1n viendo afectadas por los atentados<\/figcaption><\/figure>\n<\/div>\n\n\n<p>\u00abNo estamos bien. Estamos sobreviviendo, pero en el coraz\u00f3n de cada uno de nosotros queremos que esta pesadilla termine de alguna manera\u00bb, confiesa a ACN.<\/p>\n\n\n\n<p>ACN tiene varios proyectos en el L\u00edbano, incluyendo apoyo en el sur del pa\u00eds con paquetes de alimentos y asistencia m\u00e9dica. La organizaci\u00f3n ben\u00e9fica puede llevar combustible a las familias desplazadas que viven en centros de iglesias y tambi\u00e9n apoyo psicol\u00f3gico y sanaci\u00f3n de traumas para ni\u00f1os.<\/p>\n\n\n\n<p>Seg\u00fan Marielle Boutros, los programas escolares de la organizaci\u00f3n ben\u00e9fica y el apoyo a las iglesias son fundamentales. \u00abEn este momento, las escuelas en el sur del L\u00edbano no est\u00e1n funcionando. Algunas de ellas est\u00e1n funcionando en l\u00ednea y hay que pagar a los maestros. Esta es una verdadera emergencia. No podemos permitirnos detener la educaci\u00f3n de nuevo. Las escuelas cerraron en 2019, y durante el Covid, y luego durante una crisis econ\u00f3mica.\u00bb<\/p>\n\n\n\n<p>\u00abEl sistema escolar en el L\u00edbano es muy importante para la poblaci\u00f3n, ya que es una fortaleza para los libaneses. Despu\u00e9s de graduarse, salen del pa\u00eds para continuar sus estudios antes de regresar. No pueden permitirse cerrar.\u00bb<\/p>\n\n\n\n<p>\u00abPara la Iglesia tambi\u00e9n es muy importante, ya que es donde se imparte el catecismo. Es un lugar para las misiones, para la predicaci\u00f3n, para transmitir los valores cristianos y vivir esos valores. Estos son elementos clave para la sociedad aqu\u00ed.\u00bb<\/p>\n\n\n\n<p>&nbsp;Boutros pide oraciones: \u00abLa situaci\u00f3n se est\u00e1 volviendo desesperante d\u00eda tras d\u00eda, pero se pueden sentir las oraciones. Despu\u00e9s de todo, nuestro Dios es un Dios que resucit\u00f3. \u00c9l venci\u00f3 a la muerte. Podemos confiar en un Dios as\u00ed.\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre las prioridades est\u00e1n la reapertura de las escuelas y el pago de los salarios de los maestros, ya que estos desempe\u00f1an un papel crucial en la difusi\u00f3n de los valores cristianos en la regi\u00f3n. La gente est\u00e1 \u201casustada, enojada y triste\u201d despu\u00e9s de que m\u00e1s de 100 bombas cayeran en Beirut en una sola [&hellip;]<\/p>\n","protected":false},"author":4258341473,"featured_media":263289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[1254],"tags":[],"country":[521],"class_list":["post-263297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-es","country-libano"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El L\u00edbano se derrumba bajo los bombardeos: \u201cla gente se siente deshumanizada\u201d | ACN International<\/title>\n<meta name=\"description\" content=\"Entre las prioridades est\u00e1n la reapertura de las escuelas y el pago de los salarios de los maestros, ya que estos desempe\u00f1an un papel crucial en la difusi\u00f3n de los valores cristianos en la regi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El L\u00edbano se derrumba bajo los bombardeos: \u201cla gente se siente deshumanizada\u201d\" \/>\n<meta property=\"og:description\" content=\"Entre las prioridades est\u00e1n la reapertura de las escuelas y el pago de los salarios de los maestros, ya que estos desempe\u00f1an un papel crucial en la difusi\u00f3n de los valores cristianos en la regi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T06:09:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T09:39:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/04\/ACN-20250604-190113.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie Raffray\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie Raffray\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/\"},\"author\":{\"name\":\"Nathalie Raffray\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/35ec54402072e28b3317109624ff0897\"},\"headline\":\"El L\u00edbano se derrumba bajo los bombardeos: \u201cla gente se siente deshumanizada\u201d\",\"datePublished\":\"2026-04-14T06:09:17+00:00\",\"dateModified\":\"2026-04-14T09:39:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/\"},\"wordCount\":867,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ACN-20250604-190113.jpg\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/\",\"name\":\"El L\u00edbano se derrumba bajo los bombardeos: \u201cla gente se siente deshumanizada\u201d | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ACN-20250604-190113.jpg\",\"datePublished\":\"2026-04-14T06:09:17+00:00\",\"dateModified\":\"2026-04-14T09:39:03+00:00\",\"description\":\"Entre las prioridades est\u00e1n la reapertura de las escuelas y el pago de los salarios de los maestros, ya que estos desempe\u00f1an un papel crucial en la difusi\u00f3n de los valores cristianos en la regi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ACN-20250604-190113.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ACN-20250604-190113.jpg\",\"width\":1980,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTICIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/news-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El L\u00edbano se derrumba bajo los bombardeos: \u201cla gente se siente deshumanizada\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/35ec54402072e28b3317109624ff0897\",\"name\":\"Nathalie Raffray\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/nathalie-raffray\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El L\u00edbano se derrumba bajo los bombardeos: \u201cla gente se siente deshumanizada\u201d | ACN International","description":"Entre las prioridades est\u00e1n la reapertura de las escuelas y el pago de los salarios de los maestros, ya que estos desempe\u00f1an un papel crucial en la difusi\u00f3n de los valores cristianos en la regi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/","og_locale":"es_ES","og_type":"article","og_title":"El L\u00edbano se derrumba bajo los bombardeos: \u201cla gente se siente deshumanizada\u201d","og_description":"Entre las prioridades est\u00e1n la reapertura de las escuelas y el pago de los salarios de los maestros, ya que estos desempe\u00f1an un papel crucial en la difusi\u00f3n de los valores cristianos en la regi\u00f3n.","og_url":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2026-04-14T06:09:17+00:00","article_modified_time":"2026-04-14T09:39:03+00:00","og_image":[{"width":1980,"height":800,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/04\/ACN-20250604-190113.jpg","type":"image\/jpeg"}],"author":"Nathalie Raffray","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"Nathalie Raffray","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/"},"author":{"name":"Nathalie Raffray","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/35ec54402072e28b3317109624ff0897"},"headline":"El L\u00edbano se derrumba bajo los bombardeos: \u201cla gente se siente deshumanizada\u201d","datePublished":"2026-04-14T06:09:17+00:00","dateModified":"2026-04-14T09:39:03+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/"},"wordCount":867,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/04\/ACN-20250604-190113.jpg","articleSection":["NOTICIAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/","url":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/","name":"El L\u00edbano se derrumba bajo los bombardeos: \u201cla gente se siente deshumanizada\u201d | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/04\/ACN-20250604-190113.jpg","datePublished":"2026-04-14T06:09:17+00:00","dateModified":"2026-04-14T09:39:03+00:00","description":"Entre las prioridades est\u00e1n la reapertura de las escuelas y el pago de los salarios de los maestros, ya que estos desempe\u00f1an un papel crucial en la difusi\u00f3n de los valores cristianos en la regi\u00f3n.","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/04\/ACN-20250604-190113.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2026\/04\/ACN-20250604-190113.jpg","width":1980,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/el-libano-se-derrumba-bajo-los-bombardeos-la-gente-se-siente-deshumanizada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"NOTICIAS","item":"https:\/\/acninternational.org\/es\/category\/news-es\/"},{"@type":"ListItem","position":3,"name":"El L\u00edbano se derrumba bajo los bombardeos: \u201cla gente se siente deshumanizada\u201d"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/35ec54402072e28b3317109624ff0897","name":"Nathalie Raffray","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/es\/author\/nathalie-raffray\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/263297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341473"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=263297"}],"version-history":[{"count":2,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/263297\/revisions"}],"predecessor-version":[{"id":263323,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/263297\/revisions\/263323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/263289"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=263297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=263297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=263297"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=263297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}