{"id":260791,"date":"2025-12-10T07:22:02","date_gmt":"2025-12-10T06:22:02","guid":{"rendered":"https:\/\/acninternational.org\/?p=260791"},"modified":"2025-12-10T07:22:13","modified_gmt":"2025-12-10T06:22:13","slug":"nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/","title":{"rendered":"Nigeria: Catequista perdona al hombre que intent\u00f3 matarlo por ejercer su ministerio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>A pesar de varias agresiones y un intento de asesinato, Tob\u00edas Yahaya y su familia decidieron quedarse en Sokoto para continuar con su ministerio al servicio de la Iglesia.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alrededor de las 3 de la madrugada del 19 de abril de 2023, tres hombres armados tumbaron la valla de seguridad que rodea la casa de Tob\u00edas Yahaya, catequista de 26 a\u00f1os, cerca de la catedral de la Sagrada Familia de Sokoto, en el nortoeste de Nigeria. Yahaya se despert\u00f3 por el ruido.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198951-1024x768.jpg\" alt=\"\" class=\"wp-image-260779\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198951-1024x768.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198951-300x225.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198951-768x576.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198951.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Tobias Yahaya recibe el premio \u00abValor para ser cristiano\u00bb del Mi\u00e9rcoles Rojo de ACN Reino Unido, en la catedral de San Jorge, Southwark, Londres.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u201cEn ese momento piensas en muchas cosas, porque si hubieran entrado en mi casa y me hubieran encontrado con mi esposa y mis cuatro hijos, solo Dios sabe lo que podr\u00eda haber pasado\u201d, dice en una entrevista con la fundaci\u00f3n Aid to the Church in Need (ACN). \u201cPor eso decid\u00ed salir\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un hombre llamado Ibrahim, que lideraba a los intrusos, sac\u00f3 un cuchillo y apu\u00f1al\u00f3 al catequista en el pecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCa\u00ed al suelo sangrando\u201d, recuerda Yahaya. \u201cLos otros dos huyeron, pensando que hab\u00edan cumplido su misi\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cambio, Ibrahim se qued\u00f3 e intent\u00f3 apu\u00f1alar al catequista de nuevo cuando trat\u00f3 de levantarse. \u201cPero esta vez agarr\u00e9 la hoja del cuchillo con mis manos\u201d, explica Yahaya, \u201centonces gir\u00f3 el cuchillo, hiri\u00e9ndome gravemente las palmas. Tuve que soltar el cuchillo, pero logr\u00e9 asir a Ibrahim para que no pudiera volver a apu\u00f1alarme\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para entonces, la esposa de Tob\u00edas hab\u00eda empezado a gritar, alertando a los vecinos, que lograron apresar a Ibrahim. Tob\u00edas hab\u00eda perdido tanta sangre que perdi\u00f3 el conocimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando despert\u00f3, unas 24 horas despu\u00e9s, estaba tumbado en una cama de hospital junto a su agresor, al que tambi\u00e9n estaban atendiendo por sus heridas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEntonces le pregunt\u00e9: \u00bfPor qu\u00e9 quieres matarme?\u201d, recuerda Tob\u00edas Yahaya. \u201cIbrahim no pudo responder. Estaba llorando. La gente a mi alrededor me preguntaba: \u00bfPor qu\u00e9 hablas con \u00e9l? Conc\u00e9ntrate en tu salud\u201d. Yo les dije que quer\u00eda saber la raz\u00f3n por la que intent\u00f3 quitarme la vida\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente supo que Ibrahim y sus compinches, que no fueron detenidos, tem\u00edan la influencia del catequista sobre los j\u00f3venes de la zona, que es musulmana en un 90%. Esa no fue la primera vez que Yahaya sufr\u00eda problemas por su ministerio cristiano.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-ensenar-con-el-ejemplo\"><strong>Ense\u00f1ar con el ejemplo<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">En Nigeria, el ministerio del catequista supone mucho m\u00e1s que ofrecerse como voluntario para ense\u00f1ar en la escuela parroquial. Los catequistas reciben una larga formaci\u00f3n y son nombrados oficialmente por la Iglesia. Yahaya fue nombrado hace nueve a\u00f1os por el entonces obispo em\u00e9rito de Sokoto, Mons. Kevin Aje. Los catequistas organizan bautizos, distribuyen la comuni\u00f3n y dirigen liturgias cuando no hay sacerdotes disponibles. La labor de Yahaya contribuye al crecimiento de la Iglesia en Sokoto: \u201cLa pasada Pascua confirmamos a 100 ni\u00f1os en nuestra parroquia\u201d, afirma en su entrevista con ACN.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero quiz\u00e1s la mayor lecci\u00f3n que Tob\u00edas imparti\u00f3 a su comunidad a ra\u00edz de esa dura prueba tuvo lugar durante el juicio. Cuando el juez impuso una sentencia de un a\u00f1o de prisi\u00f3n a Ibrahim, Yahaya tom\u00f3 la palabra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLe pregunt\u00e9 al juez musulm\u00e1n: \u00bfPuedo abrazar a Ibrahim?, a lo que todos los presentes en la sala reaccionaron con incredulidad y sorpresa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El juez dijo que no hab\u00eda problema. \u201cEntonces lo abrac\u00e9, le estrech\u00e9 la mano y le dije: Te perdono\u201d, recuerda el catequista. \u201cNo fue capaz de hablarme, pero vi l\u00e1grimas corriendo por sus mejillas. Y yo repet\u00ed: Te perdono\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tob\u00edas y su familia se fueron a casa, con toda clase de preguntas sobre qu\u00e9 hacer a continuaci\u00f3n asaltando su mente: \u201c\u00bfQu\u00e9 quiere comunicarnos Dios a trav\u00e9s de este tipo de situaciones? Porque esa no fue la primera agresi\u00f3n que sufr\u00ed\u201d, se\u00f1ala en sus declaraciones a ACN. \u201cYo segu\u00eda deseando cumplir con mi trabajo como catequista. Mi esposa me apoy\u00f3 y mi madre, tambi\u00e9n. Tambi\u00e9n hubo oraciones y orientaci\u00f3n y apoyo por parte de mi obispo, los sacerdotes y otras personas\u201d, recuerda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMientras recib\u00eda consejos de todos ellos, mi madre, que nunca fue a la escuela, dijo algo que se me qued\u00f3 grabado en la mente: \u2018Puede que el lugar donde Dios quiere que estemos no sea c\u00f3modo o no sea de nuestro agrado, pero es all\u00ed donde encontramos la verdadera felicidad\u2019. Y yo creo que tiene raz\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y as\u00ed, Tob\u00edas Yahaya contin\u00faa con su misi\u00f3n, sostenido por las palabras de San Pablo en su Segunda Carta a los Corintios: \u201cAtribulados en todo, mas no aplastados; apurados, mas no desesperados;\u00a0perseguidos, pero no abandonados; derribados, mas no aniquilados,\u00a0llevando siempre y en todas partes en el cuerpo la muerte de Jes\u00fas, para que tambi\u00e9n la vida de Jes\u00fas se manifieste en nuestro cuerpo.\u00a0Pues, mientras vivimos, continuamente nos est\u00e1n entregando a la muerte por causa de Jes\u00fas; para que tambi\u00e9n la vida de Jes\u00fas se manifieste en nuestra carne mortal.\u00a0De este modo, la muerte act\u00faa en nosotros, y la vida en vosotros\u201d.<br><br><em><strong>En 2025, Aid to the Church in Need (ACN) dedica su campa\u00f1a de Navidad a los catequistas, verdaderos pilares de la fe en los lugares m\u00e1s dif\u00edciles para mantener la esperanza en el mundo<\/strong>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesar de varias agresiones y un intento de asesinato, Tob\u00edas Yahaya y su familia decidieron quedarse en Sokoto para continuar con su ministerio al servicio de la Iglesia. Alrededor de las 3 de la madrugada del 19 de abril de 2023, tres hombres armados tumbaron la valla de seguridad que rodea la casa de [&hellip;]<\/p>\n","protected":false},"author":4258341461,"featured_media":260778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[760],"tags":[],"country":[408],"class_list":["post-260791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","country-nigeria-es"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nigeria: Catequista perdona al hombre que intent\u00f3 matarlo por ejercer su ministerio | ACN International<\/title>\n<meta name=\"description\" content=\"Puede que el lugar donde Dios quiere que estemos no sea c\u00f3modo o no sea de nuestro agrado, pero es all\u00ed donde encontramos la verdadera felicidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nigeria: Catequista perdona al hombre que intent\u00f3 matarlo por ejercer su ministerio\" \/>\n<meta property=\"og:description\" content=\"Puede que el lugar donde Dios quiere que estemos no sea c\u00f3modo o no sea de nuestro agrado, pero es all\u00ed donde encontramos la verdadera felicidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-10T06:22:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T06:22:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"John Burger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/JohnBurger\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"John Burger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/\"},\"author\":{\"name\":\"John Burger\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/b42b8684e5819123b6699ed3f377ac93\"},\"headline\":\"Nigeria: Catequista perdona al hombre que intent\u00f3 matarlo por ejercer su ministerio\",\"datePublished\":\"2025-12-10T06:22:02+00:00\",\"dateModified\":\"2025-12-10T06:22:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/\"},\"wordCount\":933,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ACN-20251209-198950.jpg\",\"articleSection\":[\"DESTACADO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/\",\"name\":\"Nigeria: Catequista perdona al hombre que intent\u00f3 matarlo por ejercer su ministerio | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ACN-20251209-198950.jpg\",\"datePublished\":\"2025-12-10T06:22:02+00:00\",\"dateModified\":\"2025-12-10T06:22:13+00:00\",\"description\":\"Puede que el lugar donde Dios quiere que estemos no sea c\u00f3modo o no sea de nuestro agrado, pero es all\u00ed donde encontramos la verdadera felicidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ACN-20251209-198950.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ACN-20251209-198950.jpg\",\"width\":1980,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DESTACADO\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/destacado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nigeria: Catequista perdona al hombre que intent\u00f3 matarlo por ejercer su ministerio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/b42b8684e5819123b6699ed3f377ac93\",\"name\":\"John Burger\",\"description\":\"John Burger is communications consultant to Aid to the Church in Need-USA. A native of New York, he spent several years teaching internationally, and the next 32 years in Catholic journalism in the United States. He is author of the 2023 book At the Foot of the Cross: Lessons from Ukraine.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/JohnBurger\"],\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/john-burger\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nigeria: Catequista perdona al hombre que intent\u00f3 matarlo por ejercer su ministerio | ACN International","description":"Puede que el lugar donde Dios quiere que estemos no sea c\u00f3modo o no sea de nuestro agrado, pero es all\u00ed donde encontramos la verdadera felicidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/","og_locale":"es_ES","og_type":"article","og_title":"Nigeria: Catequista perdona al hombre que intent\u00f3 matarlo por ejercer su ministerio","og_description":"Puede que el lugar donde Dios quiere que estemos no sea c\u00f3modo o no sea de nuestro agrado, pero es all\u00ed donde encontramos la verdadera felicidad.","og_url":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2025-12-10T06:22:02+00:00","article_modified_time":"2025-12-10T06:22:13+00:00","og_image":[{"width":1980,"height":800,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg","type":"image\/jpeg"}],"author":"John Burger","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/JohnBurger","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"John Burger","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/"},"author":{"name":"John Burger","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/b42b8684e5819123b6699ed3f377ac93"},"headline":"Nigeria: Catequista perdona al hombre que intent\u00f3 matarlo por ejercer su ministerio","datePublished":"2025-12-10T06:22:02+00:00","dateModified":"2025-12-10T06:22:13+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/"},"wordCount":933,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg","articleSection":["DESTACADO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/","url":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/","name":"Nigeria: Catequista perdona al hombre que intent\u00f3 matarlo por ejercer su ministerio | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg","datePublished":"2025-12-10T06:22:02+00:00","dateModified":"2025-12-10T06:22:13+00:00","description":"Puede que el lugar donde Dios quiere que estemos no sea c\u00f3modo o no sea de nuestro agrado, pero es all\u00ed donde encontramos la verdadera felicidad.","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/12\/ACN-20251209-198950.jpg","width":1980,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/nigeria-catequista-perdona-al-hombre-que-intento-matarlo-por-ejercer-su-ministerio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"DESTACADO","item":"https:\/\/acninternational.org\/es\/category\/destacado\/"},{"@type":"ListItem","position":3,"name":"Nigeria: Catequista perdona al hombre que intent\u00f3 matarlo por ejercer su ministerio"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/b42b8684e5819123b6699ed3f377ac93","name":"John Burger","description":"John Burger is communications consultant to Aid to the Church in Need-USA. A native of New York, he spent several years teaching internationally, and the next 32 years in Catholic journalism in the United States. He is author of the 2023 book At the Foot of the Cross: Lessons from Ukraine.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/JohnBurger"],"url":"https:\/\/acninternational.org\/es\/author\/john-burger\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/260791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341461"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=260791"}],"version-history":[{"count":1,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/260791\/revisions"}],"predecessor-version":[{"id":260792,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/260791\/revisions\/260792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/260778"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=260791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=260791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=260791"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=260791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}