{"id":255268,"date":"2025-09-11T08:07:30","date_gmt":"2025-09-11T06:07:30","guid":{"rendered":"https:\/\/acninternational.org\/?p=255268"},"modified":"2025-09-11T13:12:36","modified_gmt":"2025-09-11T11:12:36","slug":"iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/","title":{"rendered":"Iraq: Un festival ecum\u00e9nico muestra futuro para la Iglesia perseguida"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u201cLo que antes se pretend\u00eda silenciar se ha convertido en una proclamaci\u00f3n: La fe ha sobrevivido y la esperanza es m\u00e1s fuerte que la muerte\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Los cristianos que sobrevivieron a los ataques yihadistas en el norte de Iraq se reunen para celebrar un gran festival que proclamar\u00e1 que la fe sigue viva en la regi\u00f3n.<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194227-1024x682.jpg\" alt=\"\" class=\"wp-image-255237\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194227-1024x682.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194227-300x200.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194227-768x511.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194227.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Los l\u00edderes de las distintas confesiones cristianas se re\u00fanen con motivo de la Exaltaci\u00f3n de la Cruz<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Del 9 al 13 de septiembre de 2025, cristianos de diferentes tradiciones de la regi\u00f3n -la Iglesia asiria de Oriente, la Iglesia caldea, la Iglesia siro-cat\u00f3lica y la Iglesia siro-ortodoxa- se unen para celebrar juntos la fiesta de la Exaltaci\u00f3n de la Santa Cruz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El arzobispo caldeo Bashar Warda, que ha colaborado con l\u00edderes de otras Iglesias en la planificaci\u00f3n de los eventos, explica a la fundaci\u00f3n pontificia Aid to the Church in Need (ACN) -que ha contribuido a financiar la celebraci\u00f3n- que esto es se\u00f1al de que la fe sigue viva: \u201cLa fecha de la fiesta es profundamente simb\u00f3lica. Hace una d\u00e9cada, el Estado Isl\u00e1mico intent\u00f3 borrar el cristianismo de estas tierras. Hoy, esas mismas comunidades levantar\u00e1n la cruz en las plazas p\u00fablicas, en las iglesias y en alegres procesiones. Lo que antes se pretend\u00eda silenciar se ha convertido en una proclamaci\u00f3n: La fe ha sobrevivido y la esperanza es m\u00e1s fuerte que la muerte\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194226-1024x682.jpg\" alt=\"\" class=\"wp-image-255243\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194226-1024x682.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194226-300x200.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194226-768x511.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194226.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La celebraci\u00f3n conjunta es un signo de resistencia en una regi\u00f3n marcada por grandes persecuciones en el pasado<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El grupo extremista Estado Isl\u00e1mico control\u00f3 partes de la llanura de N\u00ednive, en el norte de Iraq, desde 2014 hasta 2017. M\u00e1s de 120.000 cristianos buscaron refugio en Erbil, en la regi\u00f3n semiaut\u00f3noma del Kurdist\u00e1n iraqu\u00ed, tras huir de sus hogares en agosto de 2014. ACN apoy\u00f3 a los refugiados cristianos que huyeron en 2014 y, tras la derrota del Estado Isl\u00e1mico, ayud\u00f3 a reconstruir las ciudades y pueblos cristianos, para que las comunidades pudieran retornar a sus hogares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los actos comenzar\u00e1n hoy (9 de septiembre) con una procesi\u00f3n de antorchas de 2 kil\u00f3metros en Ankawa, un suburbio de Erbil, desde el santuario caldeo de San El\u00edas hasta la catedral asiria de San Juan Bautista, donde &#8211; tras las oraciones y la homil\u00eda del patriarca Mar Awa III de la Iglesia asiria de Oriente &#8211; se celebrar\u00e1 una comida. El apretado programa incluye oraciones, m\u00fasica, eventos culturales y actividades y competiciones deportivas hasta el 13 de septiembre, vigilia de la fiesta de la Exaltaci\u00f3n de la Santa Cruz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El festival de cinco d\u00edas pasar\u00e1 a ser un evento anual en el calendario de estas Iglesias, como continuaci\u00f3n de las celebraciones ecum\u00e9nicas de 2024. El festival de 2025 parte de las actividades del a\u00f1o pasado \u201ccon el objetivo no solo de repetir su \u00e9xito, sino tambi\u00e9n de ampliar su alcance, profundizar en su contenido e involucrar a m\u00e1s j\u00f3venes y familias de las diferentes Iglesias\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El arzobispo Warda ha elogiado al Comit\u00e9 Juvenil, compuesto por 20 voluntarios de las cuatro Iglesias, que han desempe\u00f1ado un papel protagonista: \u201cJ\u00f3venes de todas las Iglesias han planificado juntos el festival organizando oraciones, deportes, maratones, conciertos, juegos infantiles y eventos culturales. Su colaboraci\u00f3n se ha convertido en un signo visible de un nuevo futuro. Las generaciones mayores han presenciado con admiraci\u00f3n c\u00f3mo estos j\u00f3venes han descubierto que lo que los une -su fe en Cristo- es mucho mayor que lo que los divide. En sus manos, el sue\u00f1o de la unidad cristiana en Iraq ya se est\u00e1 convirtiendo en una realidad vivida\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El festival se considera vital para el futuro del cristianismo en el pa\u00eds. Seg\u00fan el \u00faltimo censo, realizado bajo Sadam Husein, en Iraq hab\u00eda 1,4 millones de creyentes, mientras que actualmente su n\u00famero supone menos de un cuarto de mill\u00f3n.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194228-1024x682.jpg\" alt=\"\" class=\"wp-image-255249\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194228-1024x682.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194228-300x200.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194228-768x511.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194228.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Miles de fieles, de distintas confesiones, se re\u00fanen para compartir comidas y celebrar<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El arzobispo Bashar Warda ha declarado: \u201cEl Festival de la Cruz 2025 es m\u00e1s que una celebraci\u00f3n local. Es un mensaje a la Iglesia Universal. Desde la tierra de Abraham, donde los cristianos sufrieron el exilio y la persecuci\u00f3n, llega una palabra de esperanza: seguimos aqu\u00ed. Somos uno en Cristo. La Cruz no ha sido silenciada y, en Iraq, una Iglesia peque\u00f1a y lastimada ha mostrado al mundo el poder de la unidad, el valor de la fe y la alegr\u00eda de la vida resucitada\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy, esas mismas comunidades levantar\u00e1n la cruz en las plazas p\u00fablicas, en las iglesias y en alegres procesiones<\/p>\n","protected":false},"author":4258341477,"featured_media":255236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[746,1254],"tags":[],"country":[386],"class_list":["post-255268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-news-es","country-irak"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Iraq: Un festival ecum\u00e9nico muestra futuro para la Iglesia perseguida | ACN International<\/title>\n<meta name=\"description\" content=\"Hoy, esas mismas comunidades levantar\u00e1n la cruz en las plazas p\u00fablicas, en las iglesias y en alegres procesiones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iraq: Un festival ecum\u00e9nico muestra futuro para la Iglesia perseguida\" \/>\n<meta property=\"og:description\" content=\"Hoy, esas mismas comunidades levantar\u00e1n la cruz en las plazas p\u00fablicas, en las iglesias y en alegres procesiones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-11T06:07:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T11:12:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"John Newton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"John Newton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/\"},\"author\":{\"name\":\"John Newton\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5243e12a4e135672e43bcc5c2157627d\"},\"headline\":\"Iraq: Un festival ecum\u00e9nico muestra futuro para la Iglesia perseguida\",\"datePublished\":\"2025-09-11T06:07:30+00:00\",\"dateModified\":\"2025-09-11T11:12:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/\"},\"wordCount\":780,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ACN-20250909-194223-1.jpg\",\"articleSection\":[\"NOTICIAS\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/\",\"name\":\"Iraq: Un festival ecum\u00e9nico muestra futuro para la Iglesia perseguida | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ACN-20250909-194223-1.jpg\",\"datePublished\":\"2025-09-11T06:07:30+00:00\",\"dateModified\":\"2025-09-11T11:12:36+00:00\",\"description\":\"Hoy, esas mismas comunidades levantar\u00e1n la cruz en las plazas p\u00fablicas, en las iglesias y en alegres procesiones.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ACN-20250909-194223-1.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ACN-20250909-194223-1.jpg\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTICIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/news-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Iraq: Un festival ecum\u00e9nico muestra futuro para la Iglesia perseguida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5243e12a4e135672e43bcc5c2157627d\",\"name\":\"John Newton\",\"description\":\"John Newton has worked in Aid to the Church in Need (UK)\u2019s Press and Public Affairs Department, which oversees various areas of the charity\u2019s work including PR, research and parliamentary outreach, for almost two decades. Dr Newton is the co-author of the charity\u2019s keynote Persecuted and Forgotten? report on the oppression of Christians, and a contributor to its comprehensive Religious Freedom in the World report. He has also authored Religious Freedom Today: The Catholic View and The Eastern Catholic Churches: A Short Introduction.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/john-newton\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Iraq: Un festival ecum\u00e9nico muestra futuro para la Iglesia perseguida | ACN International","description":"Hoy, esas mismas comunidades levantar\u00e1n la cruz en las plazas p\u00fablicas, en las iglesias y en alegres procesiones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/","og_locale":"es_ES","og_type":"article","og_title":"Iraq: Un festival ecum\u00e9nico muestra futuro para la Iglesia perseguida","og_description":"Hoy, esas mismas comunidades levantar\u00e1n la cruz en las plazas p\u00fablicas, en las iglesias y en alegres procesiones.","og_url":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2025-09-11T06:07:30+00:00","article_modified_time":"2025-09-11T11:12:36+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg","type":"image\/jpeg"}],"author":"John Newton","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"John Newton","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/"},"author":{"name":"John Newton","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5243e12a4e135672e43bcc5c2157627d"},"headline":"Iraq: Un festival ecum\u00e9nico muestra futuro para la Iglesia perseguida","datePublished":"2025-09-11T06:07:30+00:00","dateModified":"2025-09-11T11:12:36+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/"},"wordCount":780,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg","articleSection":["NOTICIAS","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/","url":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/","name":"Iraq: Un festival ecum\u00e9nico muestra futuro para la Iglesia perseguida | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg","datePublished":"2025-09-11T06:07:30+00:00","dateModified":"2025-09-11T11:12:36+00:00","description":"Hoy, esas mismas comunidades levantar\u00e1n la cruz en las plazas p\u00fablicas, en las iglesias y en alegres procesiones.","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/09\/ACN-20250909-194223-1.jpg","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/iraq-un-festival-ecumenico-muestra-futuro-para-la-iglesia-perseguida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"NOTICIAS","item":"https:\/\/acninternational.org\/es\/category\/news-es\/"},{"@type":"ListItem","position":3,"name":"Iraq: Un festival ecum\u00e9nico muestra futuro para la Iglesia perseguida"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5243e12a4e135672e43bcc5c2157627d","name":"John Newton","description":"John Newton has worked in Aid to the Church in Need (UK)\u2019s Press and Public Affairs Department, which oversees various areas of the charity\u2019s work including PR, research and parliamentary outreach, for almost two decades. Dr Newton is the co-author of the charity\u2019s keynote Persecuted and Forgotten? report on the oppression of Christians, and a contributor to its comprehensive Religious Freedom in the World report. He has also authored Religious Freedom Today: The Catholic View and The Eastern Catholic Churches: A Short Introduction.","url":"https:\/\/acninternational.org\/es\/author\/john-newton\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/255268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341477"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=255268"}],"version-history":[{"count":2,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/255268\/revisions"}],"predecessor-version":[{"id":255342,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/255268\/revisions\/255342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/255236"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=255268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=255268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=255268"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=255268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}