{"id":253169,"date":"2025-08-28T15:46:45","date_gmt":"2025-08-28T13:46:45","guid":{"rendered":"https:\/\/acninternational.org\/?p=252196"},"modified":"2025-09-07T10:25:09","modified_gmt":"2025-09-07T08:25:09","slug":"la-joven-que-huyo-de-irak-y-conocio-al-papa","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/","title":{"rendered":"La joven que huy\u00f3 de Irak y conoci\u00f3 al Papa"},"content":{"rendered":"<p><em>Perseguida con dureza por su fe, Sof\u00eda ha encontrado en Dios consuelo y la fuerza para perdonar a quienes la expulsaron de su pa\u00eds y casi la mataron en varias ocasiones. <\/em><\/p>\n<p>El 6 de agosto de 2014, cientos de miles de cristianos iraqu\u00edes tuvieron que dejarlo todo y huir de su patria, cuando los terroristas del Estado Isl\u00e1mico invadieron sus pueblos y ciudades en la llanura de N\u00ednive.<\/p>\n<p>Entre ellos se encontraba Sof\u00eda, una ni\u00f1a que entonces ten\u00eda 12 a\u00f1os. Presa del miedo y la incertidumbre, no sab\u00eda ad\u00f3nde la llevar\u00eda finalmente ese viaje.<\/p>\n<figure id=\"attachment_252189\" aria-describedby=\"caption-attachment-252189\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-252189 size-large\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/04\/ACN-20181107-79080.jpg\" alt=\"De izquierda a derecha: Sara Isabel (productora) y Sof\u00eda Butrus, en el documental universitario Su Fidelidad.\" width=\"800\" height=\"517\" \/><figcaption id=\"caption-attachment-252189\" class=\"wp-caption-text\">De izquierda a derecha: Sara Isabel (productora) y Sof\u00eda Butrus, en el documental universitario Su Fidelidad.<\/figcaption><\/figure>\n<p>\u201cNo nos llevamos nada por falta de tiempo y porque no sab\u00edamos lo que iba a ocurrir. Solo nos llevamos nuestros pasaportes. Algunos de los que hu\u00edamos fueron capturados por el camino y secuestrados, en su mayor\u00eda mujeres y ni\u00f1os. Por la gracia de Dios, mi familia y yo escapamos sanos y salvos, pero quemaron nuestra casa y todas nuestras pertenencias. Yo ten\u00eda 12 a\u00f1os\u201d, explica en un breve documental dirigido por Sara Isabel, quien ha producido <em>Tu fidelidad<\/em> como proyecto universitario en Portugal.<\/p>\n<p>La familia se traslad\u00f3 a Siria, pero tambi\u00e9n all\u00ed sufrieron persecuci\u00f3n. \u201cBombardeaban las iglesias porque sab\u00edan que los cristianos van a misa todos los domingos\u201d, recuerda.<\/p>\n<p>\u201cUn domingo iba de camino a misa cuando, de repente, una mujer que sali\u00f3 de la nada nos grit\u00f3 que nos escondi\u00e9ramos dentro de la iglesia, y luego desapareci\u00f3. Hab\u00eda visto que iban a caer misiles en la zona, pero ya era demasiado tarde. Entramos en la iglesia, pero no tuvimos tiempo de escondernos. Yo estaba delante de la puerta y un misil cay\u00f3 justo all\u00ed. Todo explot\u00f3. No pod\u00eda o\u00edr ni ver nada. No sab\u00eda si estaba viva o muerta. Cuando abr\u00ed los ojos, vi que fragmentos de vidrios de colores hab\u00edan pasado a mi lado sin llegar a tocarme\u201d.<\/p>\n<p>\u201cSab\u00eda que era un milagro, f\u00edsicamente era imposible. Mi muerte era segura. Ten\u00eda a mis dos hermanos a mi lado, pero el polvo era tan denso que no pod\u00eda verlos. Por un instante sent\u00ed terror por no saber si estaban vivos. Cuando todo se calm\u00f3, pude comprobar que estaban completamente ilesos. El milagro que me ocurri\u00f3 a m\u00ed tambi\u00e9n les ocurri\u00f3 a ellos\u201d, cuenta la joven mirando a la c\u00e1mara.<\/p>\n<p>Finalmente, su familia lleg\u00f3 a Inglaterra y all\u00ed encontr\u00f3 paz. La fe sigui\u00f3 siendo un refugio seguro para ellos, pero Sof\u00eda no pod\u00eda imaginar lo que Dios a\u00fan le ten\u00eda reservado. Al acercarse la Jornada Mundial de la Juventud de 2023, solicit\u00f3 un puesto en el Ensemble 23, un grupo de j\u00f3venes bailarines que actuar\u00eda en algunos de los eventos m\u00e1s importantes del encuentro. Para su gran sorpresa, fue aceptada.<\/p>\n<p>\u201cPara m\u00ed fue el regalo m\u00e1s maravilloso que Dios pod\u00eda hacerme. Conoc\u00ed a gente nueva, a personas de diferentes or\u00edgenes. Nos vieron cat\u00f3licos de todo el mundo y pude ser mensajera de la Palabra de Dios. Representamos un v\u00eda crucis y al final percibimos c\u00f3mo hab\u00edamos tocado el coraz\u00f3n del p\u00fablico: pudimos ver la emoci\u00f3n en sus rostros\u201d.<\/p>\n<p>\u201cEl Papa nos mir\u00f3 y nos hizo una se\u00f1al para que nos acerc\u00e1ramos. Fue entonces cuando, frente a \u00e9l, romp\u00ed a llorar y entonces \u00e9l me puso la mano en la cabeza. Despu\u00e9s de todo lo que hab\u00eda vivido, su mano me pareci\u00f3 m\u00e1s suave que cualquier otra cosa de este mundo. Mi confianza en Dios me hizo darme cuenta de c\u00f3mo \u00c9l hab\u00eda estado a mi lado durante tanto tiempo, c\u00f3mo me hab\u00eda protegido de la muerte, de ser violada, de recibir disparos, de ser secuestrada y de todas las cosas terribles que nos hicieron a los cristianos\u201d, dice Sof\u00eda en el documental, <a href=\"https:\/\/www.youtube.com\/watch?v=JpAlPfL8YxQ\" target=\"_blank\" rel=\"noopener\">que se puede ver aqu\u00ed<\/a>.<\/p>\n<p>El testimonio de esta joven iraqu\u00ed termina con una declaraci\u00f3n profundamente conmovedora: \u201cLos perdono, perdono a todos los que me han hecho da\u00f1o en el pasado. El amor de Dios es m\u00e1s grande que cualquier maldad humana. Si Jes\u00fas baj\u00f3 a la Tierra, muri\u00f3 en la cruz y perdon\u00f3, \u00bfqui\u00e9n soy yo para no perdonar?\u201d.<\/p>\n<p><em>Cuando los terroristas islamistas obligaron a cristianos como Sof\u00eda a huir de sus lugares de origen, Aid to the Church in Need (ACN) dio un paso adelante, ayudando a proporcionar soluciones y ayuda inmediata. La fundaci\u00f3n pontificia tambi\u00e9n contribuy\u00f3 a reconstruir hogares en pueblos cristianos para que la poblaci\u00f3n pudiera regresar y actualmente sigue colaborando estrechamente con las Iglesias locales para hacer posible una presencia cristiana duradera en la regi\u00f3n.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sof\u00eda ha encontrado en Dios consuelo y la fuerza para perdonar a quienes la expulsaron de su pa\u00eds y casi la mataron en varias ocasiones<\/p>\n","protected":false},"author":4258341382,"featured_media":253238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[745],"tags":[],"country":[386],"class_list":["post-253169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas","country-irak"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La joven que huy\u00f3 de Irak y conoci\u00f3 al Papa | ACN International<\/title>\n<meta name=\"description\" content=\"Sof\u00eda ha encontrado en Dios consuelo y la fuerza para perdonar a quienes la expulsaron de su pa\u00eds y casi la mataron en varias ocasiones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La joven que huy\u00f3 de Irak y conoci\u00f3 al Papa\" \/>\n<meta property=\"og:description\" content=\"Sof\u00eda ha encontrado en Dios consuelo y la fuerza para perdonar a quienes la expulsaron de su pa\u00eds y casi la mataron en varias ocasiones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-28T13:46:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-07T08:25:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acninternational.org\/wp-content\/uploads\/2025\/08\/ACN-20250826-193655.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paulo Aido\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paulo Aido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/\"},\"author\":{\"name\":\"Paulo Aido\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/74d18921c1d8be9ca663e4035d1fce84\"},\"headline\":\"La joven que huy\u00f3 de Irak y conoci\u00f3 al Papa\",\"datePublished\":\"2025-08-28T13:46:45+00:00\",\"dateModified\":\"2025-09-07T08:25:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/\"},\"wordCount\":836,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/ACN-20250826-193655.jpg\",\"articleSection\":[\"ENTREVISTAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/\",\"name\":\"La joven que huy\u00f3 de Irak y conoci\u00f3 al Papa | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/ACN-20250826-193655.jpg\",\"datePublished\":\"2025-08-28T13:46:45+00:00\",\"dateModified\":\"2025-09-07T08:25:09+00:00\",\"description\":\"Sof\u00eda ha encontrado en Dios consuelo y la fuerza para perdonar a quienes la expulsaron de su pa\u00eds y casi la mataron en varias ocasiones.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/ACN-20250826-193655.jpg\",\"contentUrl\":\"https:\\\/\\\/acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/ACN-20250826-193655.jpg\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/la-joven-que-huyo-de-irak-y-conocio-al-papa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DESTACADO\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/destacado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La joven que huy\u00f3 de Irak y conoci\u00f3 al Papa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/74d18921c1d8be9ca663e4035d1fce84\",\"name\":\"Paulo Aido\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/paulo-aido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La joven que huy\u00f3 de Irak y conoci\u00f3 al Papa | ACN International","description":"Sof\u00eda ha encontrado en Dios consuelo y la fuerza para perdonar a quienes la expulsaron de su pa\u00eds y casi la mataron en varias ocasiones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/","og_locale":"es_ES","og_type":"article","og_title":"La joven que huy\u00f3 de Irak y conoci\u00f3 al Papa","og_description":"Sof\u00eda ha encontrado en Dios consuelo y la fuerza para perdonar a quienes la expulsaron de su pa\u00eds y casi la mataron en varias ocasiones.","og_url":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2025-08-28T13:46:45+00:00","article_modified_time":"2025-09-07T08:25:09+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/acninternational.org\/wp-content\/uploads\/2025\/08\/ACN-20250826-193655.jpg","type":"image\/jpeg"}],"author":"Paulo Aido","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"Paulo Aido","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/"},"author":{"name":"Paulo Aido","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/74d18921c1d8be9ca663e4035d1fce84"},"headline":"La joven que huy\u00f3 de Irak y conoci\u00f3 al Papa","datePublished":"2025-08-28T13:46:45+00:00","dateModified":"2025-09-07T08:25:09+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/"},"wordCount":836,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/#primaryimage"},"thumbnailUrl":"https:\/\/acninternational.org\/wp-content\/uploads\/2025\/08\/ACN-20250826-193655.jpg","articleSection":["ENTREVISTAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/","url":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/","name":"La joven que huy\u00f3 de Irak y conoci\u00f3 al Papa | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/#primaryimage"},"thumbnailUrl":"https:\/\/acninternational.org\/wp-content\/uploads\/2025\/08\/ACN-20250826-193655.jpg","datePublished":"2025-08-28T13:46:45+00:00","dateModified":"2025-09-07T08:25:09+00:00","description":"Sof\u00eda ha encontrado en Dios consuelo y la fuerza para perdonar a quienes la expulsaron de su pa\u00eds y casi la mataron en varias ocasiones.","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/#primaryimage","url":"https:\/\/acninternational.org\/wp-content\/uploads\/2025\/08\/ACN-20250826-193655.jpg","contentUrl":"https:\/\/acninternational.org\/wp-content\/uploads\/2025\/08\/ACN-20250826-193655.jpg","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/la-joven-que-huyo-de-irak-y-conocio-al-papa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"DESTACADO","item":"https:\/\/acninternational.org\/es\/category\/destacado\/"},{"@type":"ListItem","position":3,"name":"La joven que huy\u00f3 de Irak y conoci\u00f3 al Papa"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/74d18921c1d8be9ca663e4035d1fce84","name":"Paulo Aido","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/es\/author\/paulo-aido\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/253169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341382"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=253169"}],"version-history":[{"count":1,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/253169\/revisions"}],"predecessor-version":[{"id":253206,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/253169\/revisions\/253206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/253238"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=253169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=253169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=253169"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=253169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}