{"id":249382,"date":"2025-06-26T18:26:29","date_gmt":"2025-06-26T16:26:29","guid":{"rendered":"https:\/\/acninternational.org\/?p=249382"},"modified":"2025-08-19T15:56:28","modified_gmt":"2025-08-19T13:56:28","slug":"tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/","title":{"rendered":"El padre Fadi Azar, sacerdote sirio, habla sobre la situaci\u00f3n de los cristianos: \u201cTenemos derecho a ir a la iglesia a rezar en paz\u201d"},"content":{"rendered":"<p><em>\u201cSentimos que estamos solos\u201d: el sacerdote se hace eco del dolor de la comunidad cristiana tras el atentado de Damasco el pasado domingo<\/em><\/p>\n<p>\u201cLos cristianos de Siria est\u00e1n sintiendo un dolor muy grande. La comunidad cristiana en toda Siria est\u00e1 viviendo un momento de mucha tristeza: la p\u00e9rdida de 30 cristianos que murieron en este ataque. Hasta ahora hay 54 heridos\u201d. As\u00ed lo ha afirmado el padre Fadi Azar, sacerdote franciscano en Siria, durante una entrevista concedida a Aid to the Church in Need (ACN).<\/p>\n<figure id=\"attachment_249363\" aria-describedby=\"caption-attachment-249363\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-249363 size-large\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20240410-163012-1024x771.jpg\" alt=\"El padre Fadi Azar, franciscano sirio que pas\u00f3 muchos a\u00f1os en Damasco\" width=\"800\" height=\"602\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20240410-163012-1024x771.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20240410-163012-300x226.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20240410-163012-768x578.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20240410-163012.jpg 1080w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-249363\" class=\"wp-caption-text\">El padre Fadi Azar, franciscano sirio que pas\u00f3 muchos a\u00f1os en Damasco<\/figcaption><\/figure>\n<p>El sacerdote sirio ha afirmado que la situaci\u00f3n se complica por momentos para algunos grupos religiosos. Cada vez que la Iglesia habla con el gobierno dicen que es algo puntual. Hasta que ha llegado este momento grave que ha \u201ctocado\u201d a toda Siria\u201d.<\/p>\n<p>El padre Fadi ha hecho un llamamiento para que se defiendan los derechos humanos en Siria: \u201cTenemos la fe, no tenemos miedo. La persecuci\u00f3n a los cristianos en Medio Oriente, en Tierra Santa, siempre ha sido la persecuci\u00f3n. Desde hace 2000 a\u00f1os hay persecuci\u00f3n. Pero estamos en este mundo civil, donde se defienden los derechos humanos. Queremos solamente justicia, justicia, nada m\u00e1s. Los cristianos tienen derecho a vivir en un pa\u00eds donde haya seguridad, para que puedan ir a la iglesia a rezar en paz\u201d.<\/p>\n<p>El sacerdote, que vive en Latakia pero ha pasado muchos a\u00f1os en Damasco, ha hablado del momento de incertidumbre que atraviesa Siria y del sufrimiento de los cristianos, despu\u00e9s del atentado del pasado domingo. Sobre esto, ha incidido en la repetici\u00f3n de las agresiones: \u201cpor ejemplo disparos en frente de las iglesias de Homs y Hama, as\u00ed como secuestros. Muchos cristianos est\u00e1n perdiendo el trabajo\u201d, ha dicho a ACN.<\/p>\n<figure id=\"attachment_249369\" aria-describedby=\"caption-attachment-249369\" style=\"width: 720px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-249369 size-full\" src=\"http:\/\/dev.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20230731-150524.jpg\" alt=\"El P. Fadi es socio de un proyecto de AIN y vive actualmente en Latakia\" width=\"720\" height=\"960\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20230731-150524.jpg 720w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20230731-150524-225x300.jpg 225w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption id=\"caption-attachment-249369\" class=\"wp-caption-text\">El P. Fadi es socio de un proyecto de AIN y vive actualmente en Latakia<\/figcaption><\/figure>\n<p>En este sentido, sobre la situaci\u00f3n de inestabilidad que vive el pa\u00eds desde el cambio de gobierno, el sacerdote ha recordado lo que pas\u00f3 en marzo. \u201cEn marzo, aqu\u00ed en Latakia, mataron a muchos alauitas\u201d refiri\u00e9ndose a las aldeas al este de Latakia, en la regi\u00f3n costera del pa\u00eds, violento escenario de masacres contra la comunidad alauita. \u201cY ahora -contin\u00faa- por primera vez en la historia de Siria, desde 1860, pasa un ataque as\u00ed: entran dentro de la iglesia y se mata a mucha gente durante la hora de la Misa, durante la oraci\u00f3n, el domingo a las seis de la tarde\u201d.<\/p>\n<p>El sacerdote sirio ha insistido en que, en este escenario, los cristianos no son los \u00fanicos que tienen miedo: \u201clos alauitas, los drusos\u2026 es una persecuci\u00f3n\u201d. En cuanto a los presuntos autores del ataque del pasado domingo contra la iglesia de Dweila en Damasco, existen diferentes versiones en torno a su identidad. El padre Fadi dijo: \u00abAlguien afirma que fue el grupo Ansar al-Sunna, que lleva la bandera de Daesh. Antes, todos estaban en Idlib\u00bb. Adem\u00e1s, subray\u00f3: \u00abEs un peligro, no solo para los cristianos, sino tambi\u00e9n para los drusos o alauitas, e incluso para los musulmanes moderados&#8230; Son muy peligrosos (&#8230;). No quieren un gobierno civil; quieren un gobierno terrorista islamista fan\u00e1tico\u00bb.<\/p>\n<p>Respecto a si este atentado ha sido inesperado para la poblaci\u00f3n, el sacerdote ha dicho que en cierto modo esperaban que ocurriera algo as\u00ed desde hac\u00eda meses: \u201cHab\u00eda amenazas, muchas amenazas. Se esperaba, pero no se sab\u00eda cu\u00e1ndo (&#8230;). La semana pasada ya atacaron una iglesia en Homs, la iglesia sirio-ortodoxa, donde un muchacho dispar\u00f3 a la puerta de la iglesia\u201d.<\/p>\n<figure id=\"attachment_249375\" aria-describedby=\"caption-attachment-249375\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-249375 size-large\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20250623-190843-1024x576.jpg\" alt=\"La iglesia ortodoxa de San El\u00edas result\u00f3 gravemente da\u00f1ada en el atentado en el que murieron decenas de personas\" width=\"800\" height=\"450\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20250623-190843-1024x576.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20250623-190843-300x169.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20250623-190843-768x432.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20250623-190843.jpg 1080w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-249375\" class=\"wp-caption-text\">La iglesia ortodoxa de San El\u00edas result\u00f3 gravemente da\u00f1ada en el atentado en el que murieron decenas de personas<\/figcaption><\/figure>\n<p>Seg\u00fan las redes sociales locales, hoy, 26 de junio, se ha producido otra agresi\u00f3n cuando individuos en motocicletas abrieron fuego frente a la iglesia de Latakia y, tr\u00e1gicamente, una persona muri\u00f3. La di\u00f3cesis ortodoxa griega de Latakia neg\u00f3 las noticias sobre la muerte del guardia de la iglesia, confirmando que la v\u00edctima no tiene relaciones directa con la iglesia y que el ataque tuvo lugar fuera de la iglesia.<\/p>\n<h4><strong>Protecci\u00f3n internacional<\/strong><\/h4>\n<p>Acerca de c\u00f3mo se encuentra la comunidad cristiana de la zona en este momento, el sacerdote sirio ha relatado que \u201ctodos los cristianos sienten un dolor muy grande. Nos sentimos\u00a0 solos ahora. Pedimos la intervenci\u00f3n del Vaticano, de la Comunidad Europea\u2026\u201d y contin\u00faa: \u201cLa gente ahora nos dice: <em>\u2018Padre, no queremos ayudas, no queremos alimentos, medicamentos, nada. Ay\u00fadenos a escapar. No podemos vivir aqu\u00ed. Tenemos miedo por nuestra vida, tenemos miedo por el futuro de nuestros hijos\u2019<\/em>\u201d.<\/p>\n<p>En este contexto, el n\u00famero de cristianos en Siria sigue disminuyendo: \u201csomos una minor\u00eda ahora. En todos estos a\u00f1os, antes de la guerra, hab\u00eda un 10% de cristianos, ahora somos el 3%. Y, probablemente, en este verano, muchos cristianos se van a marchar\u201d, ha dicho en sus declaraciones a ACN.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No podemos vivir aqu\u00ed. Tenemos miedo por nuestra vida, tenemos miedo por el futuro de nuestros hijos<\/p>\n","protected":false},"author":4258341471,"featured_media":249357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[745,798],"tags":[],"country":[390],"class_list":["post-249382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas","category-interviews-es","country-siria"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El padre Fadi Azar, sacerdote sirio, habla sobre la situaci\u00f3n de los cristianos: \u201cTenemos derecho a ir a la iglesia a rezar en paz\u201d | ACN International<\/title>\n<meta name=\"description\" content=\"No podemos vivir aqu\u00ed. Tenemos miedo por nuestra vida, tenemos miedo por el futuro de nuestros hijos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El padre Fadi Azar, sacerdote sirio, habla sobre la situaci\u00f3n de los cristianos: \u201cTenemos derecho a ir a la iglesia a rezar en paz\u201d\" \/>\n<meta property=\"og:description\" content=\"No podemos vivir aqu\u00ed. Tenemos miedo por nuestra vida, tenemos miedo por el futuro de nuestros hijos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-26T16:26:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T13:56:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20230213-140528.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blanca Tortosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blanca Tortosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/\"},\"author\":{\"name\":\"Blanca Tortosa\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/4b7f68ff83f4357a4e56af66d98d43f2\"},\"headline\":\"El padre Fadi Azar, sacerdote sirio, habla sobre la situaci\u00f3n de los cristianos: \u201cTenemos derecho a ir a la iglesia a rezar en paz\u201d\",\"datePublished\":\"2025-06-26T16:26:29+00:00\",\"dateModified\":\"2025-08-19T13:56:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/\"},\"wordCount\":886,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ACN-20230213-140528.jpeg\",\"articleSection\":[\"ENTREVISTAS\",\"INTERVIEWS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/\",\"name\":\"El padre Fadi Azar, sacerdote sirio, habla sobre la situaci\u00f3n de los cristianos: \u201cTenemos derecho a ir a la iglesia a rezar en paz\u201d | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ACN-20230213-140528.jpeg\",\"datePublished\":\"2025-06-26T16:26:29+00:00\",\"dateModified\":\"2025-08-19T13:56:28+00:00\",\"description\":\"No podemos vivir aqu\u00ed. Tenemos miedo por nuestra vida, tenemos miedo por el futuro de nuestros hijos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ACN-20230213-140528.jpeg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ACN-20230213-140528.jpeg\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INTERVIEWS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/interviews-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El padre Fadi Azar, sacerdote sirio, habla sobre la situaci\u00f3n de los cristianos: \u201cTenemos derecho a ir a la iglesia a rezar en paz\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/4b7f68ff83f4357a4e56af66d98d43f2\",\"name\":\"Blanca Tortosa\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/blanca-tortosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El padre Fadi Azar, sacerdote sirio, habla sobre la situaci\u00f3n de los cristianos: \u201cTenemos derecho a ir a la iglesia a rezar en paz\u201d | ACN International","description":"No podemos vivir aqu\u00ed. Tenemos miedo por nuestra vida, tenemos miedo por el futuro de nuestros hijos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/","og_locale":"es_ES","og_type":"article","og_title":"El padre Fadi Azar, sacerdote sirio, habla sobre la situaci\u00f3n de los cristianos: \u201cTenemos derecho a ir a la iglesia a rezar en paz\u201d","og_description":"No podemos vivir aqu\u00ed. Tenemos miedo por nuestra vida, tenemos miedo por el futuro de nuestros hijos.","og_url":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2025-06-26T16:26:29+00:00","article_modified_time":"2025-08-19T13:56:28+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20230213-140528.jpeg","type":"image\/jpeg"}],"author":"Blanca Tortosa","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"Blanca Tortosa","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/"},"author":{"name":"Blanca Tortosa","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/4b7f68ff83f4357a4e56af66d98d43f2"},"headline":"El padre Fadi Azar, sacerdote sirio, habla sobre la situaci\u00f3n de los cristianos: \u201cTenemos derecho a ir a la iglesia a rezar en paz\u201d","datePublished":"2025-06-26T16:26:29+00:00","dateModified":"2025-08-19T13:56:28+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/"},"wordCount":886,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20230213-140528.jpeg","articleSection":["ENTREVISTAS","INTERVIEWS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/","url":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/","name":"El padre Fadi Azar, sacerdote sirio, habla sobre la situaci\u00f3n de los cristianos: \u201cTenemos derecho a ir a la iglesia a rezar en paz\u201d | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20230213-140528.jpeg","datePublished":"2025-06-26T16:26:29+00:00","dateModified":"2025-08-19T13:56:28+00:00","description":"No podemos vivir aqu\u00ed. Tenemos miedo por nuestra vida, tenemos miedo por el futuro de nuestros hijos.","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20230213-140528.jpeg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/06\/ACN-20230213-140528.jpeg","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/tenemos-derecho-a-ir-a-la-iglesia-a-rezar-en-paz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"INTERVIEWS","item":"https:\/\/acninternational.org\/es\/category\/interviews-es\/"},{"@type":"ListItem","position":3,"name":"El padre Fadi Azar, sacerdote sirio, habla sobre la situaci\u00f3n de los cristianos: \u201cTenemos derecho a ir a la iglesia a rezar en paz\u201d"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/4b7f68ff83f4357a4e56af66d98d43f2","name":"Blanca Tortosa","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/es\/author\/blanca-tortosa\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/249382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341471"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=249382"}],"version-history":[{"count":1,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/249382\/revisions"}],"predecessor-version":[{"id":252034,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/249382\/revisions\/252034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/249357"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=249382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=249382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=249382"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=249382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}