{"id":188012,"date":"2024-01-16T01:20:40","date_gmt":"2024-01-16T00:20:40","guid":{"rendered":"https:\/\/acninternational.org\/?p=188012"},"modified":"2024-04-11T11:48:19","modified_gmt":"2024-04-11T09:48:19","slug":"acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/","title":{"rendered":"ACN se alegra por la liberaci\u00f3n de sacerdotes en Nicaragua, pero persiste  la preocupaci\u00f3n por la falta de libertad religiosa"},"content":{"rendered":"<p><em>Diecinueve cl\u00e9rigos han sido liberados y expulsados del pa\u00eds, sum\u00e1ndose a las ya decenas de exiliados de los \u00faltimos a\u00f1os. Las restricciones a la libertad religiosa contin\u00faan en un pa\u00eds donde cuatro de las nueve di\u00f3cesis actuales tienen obispos exiliados en el extranjero, ha se\u00f1alado Regina Lynch, presidenta ejecutiva de Aid to the Church in Need. <\/em><\/p>\n<figure id=\"attachment_187976\" aria-describedby=\"caption-attachment-187976\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-187976 size-large\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/ACN-20190410-86495-1024x683.jpg\" alt=\"Estatua de Cristo con corona de espinas portando la cruz\" width=\"800\" height=\"534\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/ACN-20190410-86495-1024x683.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/ACN-20190410-86495-300x200.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/ACN-20190410-86495-768x512.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/ACN-20190410-86495.jpg 1080w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-187976\" class=\"wp-caption-text\">Estatua de Cristo con corona de espinas portando la cruz<\/figcaption><\/figure>\n<p>La fundaci\u00f3n pontificia internacional Aid to the Church in Need (ACN) ha acogido con satisfacci\u00f3n la noticia de la liberaci\u00f3n de 19 cl\u00e9rigos que estaban <a href=\"https:\/\/acninternational.org\/es\/decenas-de-sacerdotes-detenidos-en-2023-mientras-regimenes-autoritarios-reprimen-cada-vez-mas-a-la-iglesia\/\" target=\"_blank\" rel=\"noopener\">encarcelados en Nicaragua<\/a> por denunciar injusticias y violaciones de los derechos humanos, o simplemente por intentar actuar con libertad. No obstante, ACN tambi\u00e9n se muestra preocupada por el hecho de que se hayan visto obligados a abandonar el pa\u00eds y por la continua represi\u00f3n de la libertad religiosa en este estado iberoamericano.<\/p>\n<p>La liberaci\u00f3n fue anunciada por el gobierno nicarag\u00fcense mediante un comunicado oficial, acompa\u00f1ado de una lista con los nombres de los liberados y desterrados: dos obispos, 15 sacerdotes y dos seminaristas. El grupo fue puesto en libertad el domingo, 14 de enero, y lleg\u00f3 a Roma ese mismo d\u00eda &#8211; con la excepci\u00f3n de uno de ellos, que permaneci\u00f3 en Venezuela por problemas de salud.<\/p>\n<p>Entre los liberados se encuentran el obispo de Matagalpa, Mons. Rolando \u00c1lvarez -detenido en agosto de 2022 que, tras haberse negado en \u00a02023 a exiliarse a EE.UU, hab\u00eda sido condenado a <a href=\"https:\/\/acninternational.org\/es\/nicaragua-acn-expresa-su-gran-preocupacion-por-la-situacion-de-la-iglesia-y-la-condena-a-26-anos-de-prision-del-obispo-rolando-alvarez\/\" target=\"_blank\" rel=\"noopener\">\u00a026 a\u00f1os de prisi\u00f3n<\/a>, y el obispo de Siuna, Isidoro de Carmen Mora Ortega, detenido por mencionar a \u00c1lvarez en una homil\u00eda durante una fuerte represi\u00f3n en diciembre.<\/p>\n<figure id=\"attachment_186855\" aria-describedby=\"caption-attachment-186855\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-186855 size-large\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/12\/ACN-20230825-151827-1024x683.jpg\" alt=\"Regina Lynch (Presidenta Ejecutiva de AIN Internacional)\" width=\"800\" height=\"534\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/12\/ACN-20230825-151827-1024x683.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/12\/ACN-20230825-151827-300x200.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/12\/ACN-20230825-151827-768x512.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/12\/ACN-20230825-151827.jpg 1080w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-186855\" class=\"wp-caption-text\">Regina Lynch (Presidenta Ejecutiva de AIN Internacional)<\/figcaption><\/figure>\n<p>La presidenta ejecutiva de ACN, Regina Lynch, ha acogido con cierta cautela la liberaci\u00f3n de los cl\u00e9rigos, se\u00f1alando su alegr\u00eda pero tambi\u00e9n la preocupaci\u00f3n por la falta de libertad religiosa en Nicaragua a\u00fan permanece: \u201cEs una buena noticia que el obispo Rolando \u00c1lvarez ya no est\u00e9 en prisi\u00f3n, pero no hay que olvidar que ha estado encerrado durante 16 meses.\u00a0 Esperemos que reciba el apoyo necesario para recuperarse despu\u00e9s de su largo periodo de detenci\u00f3n. ACN tambi\u00e9n celebra la liberaci\u00f3n del otro obispo, de los 15 sacerdotes y los dos seminaristas que permanecieron en prisi\u00f3n durante un periodo m\u00e1s breve, pero tambi\u00e9n debemos destacar lo tremendamente injusto que es que se hayan visto obligados a vivir separados de sus feligreses y sus familias. \u00a0Hay mucha incertidumbre y miedo en el seno de sus comunidades\u201d.<\/p>\n<p>Esta liberaci\u00f3n y exilio de numerosos cl\u00e9rigos parece encajar en el modus operandi del r\u00e9gimen contra la Iglesia y sus miembros. En octubre de 2023, otros 12 sacerdotes fueron excarcelados y enviados al Vaticano, y anteriormente, en febrero de 2023, otro grupo tuvo que emprender un exilio forzado a Estados Unidos.<\/p>\n<p>La presi\u00f3n internacional, tanto pol\u00edtica (desde Washington hasta el Alto Comisionado de la ONU para los Derechos Humanos) como medi\u00e1tica se ha intensificado en las \u00faltimas semanas, en un contexto de represi\u00f3n que tiene pocos precedentes en Iberoam\u00e9rica.<\/p>\n<p>El Vaticano, por su parte, no ha emitido ninguna declaraci\u00f3n oficial. Su medio oficial, <em>Vatican News<\/em>, <a href=\"https:\/\/www.vaticannews.va\/en\/vatican-city\/news\/2024-01\/nicaraguan-bishops-alvarez-mora-and-priests-freed.html\" target=\"_blank\" rel=\"noopener\">anunci\u00f3 la liberaci\u00f3n<\/a>, pero el tono utilizado en el art\u00edculo contrasta radicalmente con el optimismo expresado en el comunicado de prensa del gobierno nicarag\u00fcense respecto a su relaci\u00f3n con la Santa Sede.<\/p>\n<h4><strong>Un clero menguante<\/strong><\/h4>\n<p>El exilio forzoso de este \u00faltimo grupo de sacerdotes se suma a la creciente lista de cl\u00e9rigos que han tenido que abandonar el pa\u00eds desde que <a href=\"https:\/\/acninternational.org\/es\/nicaragua-se-pone-a-la-cabeza-de-la-persecucion-religiosa-en-latinoamerica\/\" target=\"_blank\" rel=\"noopener\">el r\u00e9gimen iniciara su creciente opresi\u00f3n contra la Iglesia<\/a>, entre ellos el nuncio apost\u00f3lico Waldemar Stanislaw Sommertag, que fue expulsado en marzo de 2022.<\/p>\n<p>La expulsi\u00f3n de sacerdotes ya est\u00e1 planteando dificultades pastorales y administrativas en algunas di\u00f3cesis: \u201cTres di\u00f3cesis nicarag\u00fcenses tienen actualmente obispos exiliados: Matagalpa y Estel\u00ed, di\u00f3cesis dirigidas por Mons. \u00c1lvarez, y la di\u00f3cesis de Siuna. En 2019, el obispo auxiliar de Managua, Mons. Silvio B\u00e1ez Ortega, tambi\u00e9n se exili\u00f3 por correr peligro su seguridad personal. Otra di\u00f3cesis tiene un obispo que supera la edad de jubilaci\u00f3n, y el arzobispo de Managua, cardenal Leopoldo Brenes, cumplir\u00e1 75 a\u00f1os en marzo\u201d, informa Lynch.<\/p>\n<figure id=\"attachment_187982\" aria-describedby=\"caption-attachment-187982\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-187982 size-large\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/ACN-20190122-82614-1024x683.jpg\" alt=\"Monse\u00f1or Rolando Jos\u00e9 Alvarez Lagos, Obispo de Matagalpa, en las ruinas del local de C\u00e1ritas de Sebaco, incendiado por partidarios de Daniel Ortega.\" width=\"800\" height=\"534\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/ACN-20190122-82614-1024x683.jpg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/ACN-20190122-82614-300x200.jpg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/ACN-20190122-82614-768x512.jpg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/ACN-20190122-82614.jpg 1080w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-187982\" class=\"wp-caption-text\">Monse\u00f1or Rolando Jos\u00e9 Alvarez Lagos, Obispo de Matagalpa, en las ruinas del local de C\u00e1ritas de Sebaco, incendiado por partidarios de Daniel Ortega.<\/figcaption><\/figure>\n<p>Desde 2022, han sido detenidos por lo menos 50 sacerdotes en Nicaragua. Seg\u00fan algunas estimaciones, alrededor del 15% del clero del pa\u00eds vive ahora en el extranjero. Algunos se han exiliado por miedo a ser detenidos, otros fueron deportados por el r\u00e9gimen y a un tercer grupo se le neg\u00f3 entrar de nuevo en el pa\u00eds tras viajar al extranjero. El gobierno tambi\u00e9n ha deportado a religiosos y religiosas extranjeras, como las Hermanas de la Caridad, de\u00a0 la Madre Teresa de Calcuta, que se dedica a atender a los m\u00e1s pobres y necesitados.<\/p>\n<p>\u201cLa libertad religiosa es una de las piedras angulares de la libertad, y los reg\u00edmenes autocr\u00e1ticos siempre temen el testimonio y la voz de quienes dedican su vida a vivir y difundir el evangelio del amor. Las restricciones a la libertad religiosa contin\u00faan en un pa\u00eds donde cuatro de las nueve di\u00f3cesis actuales tienen obispos exiliados el extranjero. Recemos para que la Iglesia y el pueblo nicarag\u00fcenses sean alg\u00fan d\u00eda libres de decir lo que piensan y de practicar su fe sin miedo y sin repercusiones\u201d, concluye Regina Lynch.<\/p>\n<p>&nbsp;<\/p>\n<p>Por <strong>Filipe d\u2019Avillez<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diecinueve cl\u00e9rigos han sido liberados y expulsados del pa\u00eds, sum\u00e1ndose a las ya decenas de exiliados de los \u00faltimos a\u00f1os.<\/p>\n","protected":false},"author":4258341447,"featured_media":187991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[746,1254],"tags":[],"country":[419],"class_list":["post-188012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-news-es","country-nicaragua-es"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ACN se alegra por la liberaci\u00f3n de sacerdotes en Nicaragua, pero persiste la preocupaci\u00f3n por la falta de libertad religiosa | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACN se alegra por la liberaci\u00f3n de sacerdotes en Nicaragua, pero persiste la preocupaci\u00f3n por la falta de libertad religiosa\" \/>\n<meta property=\"og:description\" content=\"Diecinueve cl\u00e9rigos han sido liberados y expulsados del pa\u00eds, sum\u00e1ndose a las ya decenas de exiliados de los \u00faltimos a\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-16T00:20:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-11T09:48:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/heading_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"ACN se alegra por la liberaci\u00f3n de sacerdotes en Nicaragua, pero persiste la preocupaci\u00f3n por la falta de libertad religiosa\",\"datePublished\":\"2024-01-16T00:20:40+00:00\",\"dateModified\":\"2024-04-11T09:48:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/\"},\"wordCount\":1000,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/heading_web.jpg\",\"articleSection\":[\"NOTICIAS\",\"NOTICIAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/\",\"name\":\"ACN se alegra por la liberaci\u00f3n de sacerdotes en Nicaragua, pero persiste la preocupaci\u00f3n por la falta de libertad religiosa | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/heading_web.jpg\",\"datePublished\":\"2024-01-16T00:20:40+00:00\",\"dateModified\":\"2024-04-11T09:48:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/heading_web.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/heading_web.jpg\",\"width\":2000,\"height\":625,\"caption\":\"Bishop Rolando Alvarez released\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTICIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/news-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ACN se alegra por la liberaci\u00f3n de sacerdotes en Nicaragua, pero persiste la preocupaci\u00f3n por la falta de libertad religiosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ACN se alegra por la liberaci\u00f3n de sacerdotes en Nicaragua, pero persiste la preocupaci\u00f3n por la falta de libertad religiosa | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/","og_locale":"es_ES","og_type":"article","og_title":"ACN se alegra por la liberaci\u00f3n de sacerdotes en Nicaragua, pero persiste la preocupaci\u00f3n por la falta de libertad religiosa","og_description":"Diecinueve cl\u00e9rigos han sido liberados y expulsados del pa\u00eds, sum\u00e1ndose a las ya decenas de exiliados de los \u00faltimos a\u00f1os.","og_url":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2024-01-16T00:20:40+00:00","article_modified_time":"2024-04-11T09:48:19+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/heading_web.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"ACN Press Team","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"ACN se alegra por la liberaci\u00f3n de sacerdotes en Nicaragua, pero persiste la preocupaci\u00f3n por la falta de libertad religiosa","datePublished":"2024-01-16T00:20:40+00:00","dateModified":"2024-04-11T09:48:19+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/"},"wordCount":1000,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/heading_web.jpg","articleSection":["NOTICIAS","NOTICIAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/","url":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/","name":"ACN se alegra por la liberaci\u00f3n de sacerdotes en Nicaragua, pero persiste la preocupaci\u00f3n por la falta de libertad religiosa | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/heading_web.jpg","datePublished":"2024-01-16T00:20:40+00:00","dateModified":"2024-04-11T09:48:19+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/heading_web.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/01\/heading_web.jpg","width":2000,"height":625,"caption":"Bishop Rolando Alvarez released"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/acn-se-alegra-por-la-liberacion-de-sacerdotes-en-nicaragua-pero-persiste-la-preocupacion-por-la-falta-de-libertad-religiosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"NOTICIAS","item":"https:\/\/acninternational.org\/es\/category\/news-es\/"},{"@type":"ListItem","position":3,"name":"ACN se alegra por la liberaci\u00f3n de sacerdotes en Nicaragua, pero persiste la preocupaci\u00f3n por la falta de libertad religiosa"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/es\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/188012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=188012"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/188012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/187991"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=188012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=188012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=188012"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=188012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}