{"id":170412,"date":"2022-05-16T16:05:29","date_gmt":"2022-05-16T14:05:29","guid":{"rendered":"https:\/\/acninternational.org\/?p=170412"},"modified":"2022-05-16T16:22:28","modified_gmt":"2022-05-16T14:22:28","slug":"emergency-support-for-ukraine","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/","title":{"rendered":"Ucrania: Ayuda de emergencia para 144 religiosas"},"content":{"rendered":"<p>Desde el estallido de la guerra el 24 de febrero de 2022, m\u00e1s de 12 millones de ucranianos han huido de sus hogares, y m\u00e1s del ochenta por ciento son mujeres y ni\u00f1os. La mayor\u00eda han huido a Ucrania occidental, y una parte ha salido desde ah\u00ed al extranjero. Pero muchos se han quedado en esa regi\u00f3n con la esperanza de poder regresar a casa lo antes posible o porque no saben ad\u00f3nde ir.<\/p>\n<p>En la Archidi\u00f3cesis de Le\u00f3polis, todas las comunidades religiosas femeninas han abierto sus conventos para acoger a los desplazados y ofrecerles protecci\u00f3n y ayuda. Actualmente trabajan all\u00ed 144 religiosas de 23 comunidades. Algunas de ellas tambi\u00e9n han tenido que huir de otras partes del pa\u00eds y se han refugiado con sus compa\u00f1eras. Ahora, todas ellas est\u00e1n atendiendo a los que lo han perdido todo y que, a menudo, est\u00e1n desesperados.<\/p>\n<figure id=\"attachment_170401\" aria-describedby=\"caption-attachment-170401\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-170406 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/05\/pequenya-2.jpg\" alt=\" Religiosas con refugiados ucranianos\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/05\/pequenya-2.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/05\/pequenya-2-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-170401\" class=\"wp-caption-text\">Siervas de la Virgen Inmaculada con refugiados ucranianos<\/figcaption><\/figure>\n<p>As\u00ed, por ejemplo, en la parroquia de San Miguel de Le\u00f3polis, donde las Siervas de Mar\u00eda Inmaculada han acogido en el orfanato parroquial gestionado por ellas a desplazados procedentes de Mari\u00fapol, J\u00e1rkov, Kiev, Zaporiyia y otros lugares de Ucrania oriental: en total, a unas treinta personas. Las religiosas se ocupan de ellas, les proporcionan un alojamiento digno, les dan de comer, les facilitan ropa y productos de higiene, y a menudo les ayudan a realizar tr\u00e1mites oficiales. Adem\u00e1s, las Hermanas tambi\u00e9n intentan ayudar a los ni\u00f1os a superar sus experiencias traum\u00e1ticas.<\/p>\n<p>A estas personas tampoco se las deja solas espiritualmente. Las religiosas nos cuentan: \u201cPor la noche rezamos todos junto el Rosario en la capilla del convento. Y cuando suenan las sirenas de alarma y la gente se ve obligada a refugiarse en el s\u00f3tano ante la amenaza de ataques a\u00e9reos, nosotras vamos con ellos. Rezamos con ellos el Rosario y la Coronilla de la Divina Misericordia, para que la Providencia de Dios nos proteja a todos nosotros. Ante todo, el Se\u00f1or quiere darnos a todos \u2018un coraz\u00f3n nuevo y un esp\u00edritu nuevo\u2019, y la oraci\u00f3n se convierte en un espacio donde es posible abrirse a la luz de Dios\u201d.<\/p>\n<p>Tambi\u00e9n en el otro convento de estas religiosas en Krysowice, cerca del paso fronterizo, las Hermanas se ocupan de los desplazados, dej\u00e1ndoles pasar all\u00ed la noche y proporcion\u00e1ndoles atenci\u00f3n m\u00e9dica. Adem\u00e1s tambi\u00e9n alojan a m\u00e9dicos y otros voluntarios procedentes de Polonia que han acudido a Ucrania para ayudar.<\/p>\n<p>Nosotros apoyamos a las 144 Hermanas de las 23 comunidades religiosas de la Archidi\u00f3cesis de Le\u00f3polis con una ayuda de emergencia de 72.000 euros para que puedan seguir ayudando a los que lo han perdido todo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los refugiados ucranianos se han visto obligados a huir de sus hogares. En la archidi\u00f3cesis de Lviv todas las comunidades religiosas femeninas han ofrecido ayuda.<\/p>\n","protected":false},"author":4258341447,"featured_media":170400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[717,714],"tags":[],"country":[426],"class_list":["post-170412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emergencia-humanitaria","category-proyecto","country-ucrania"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ucrania: Ayuda de emergencia para religiosas | ACN International<\/title>\n<meta name=\"description\" content=\"Millones de refugiados ucranianos han huido. En la archidi\u00f3cesis de Lviv todas las comunidades religiosas femeninas han ofrecido ayuda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ucrania: Ayuda de emergencia para 144 religiosas\" \/>\n<meta property=\"og:description\" content=\"Millones de refugiados ucranianos han huido. En la archidi\u00f3cesis de Lviv todas las comunidades religiosas femeninas han ofrecido ayuda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-16T14:05:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-16T14:22:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/05\/heading-31-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Ucrania: Ayuda de emergencia para 144 religiosas\",\"datePublished\":\"2022-05-16T14:05:29+00:00\",\"dateModified\":\"2022-05-16T14:22:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/\"},\"wordCount\":480,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/heading-31-1.png\",\"articleSection\":[\"EMERGENCIA HUMANITARIA\",\"PROYECTO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/\",\"name\":\"Ucrania: Ayuda de emergencia para religiosas | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/heading-31-1.png\",\"datePublished\":\"2022-05-16T14:05:29+00:00\",\"dateModified\":\"2022-05-16T14:22:28+00:00\",\"description\":\"Millones de refugiados ucranianos han huido. En la archidi\u00f3cesis de Lviv todas las comunidades religiosas femeninas han ofrecido ayuda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/heading-31-1.png\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/heading-31-1.png\",\"width\":2000,\"height\":625,\"caption\":\"Religiosas con refugiados ucranianos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/emergency-support-for-ukraine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROYECTO\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/proyecto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ucrania: Ayuda de emergencia para 144 religiosas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ucrania: Ayuda de emergencia para religiosas | ACN International","description":"Millones de refugiados ucranianos han huido. En la archidi\u00f3cesis de Lviv todas las comunidades religiosas femeninas han ofrecido ayuda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/","og_locale":"es_ES","og_type":"article","og_title":"Ucrania: Ayuda de emergencia para 144 religiosas","og_description":"Millones de refugiados ucranianos han huido. En la archidi\u00f3cesis de Lviv todas las comunidades religiosas femeninas han ofrecido ayuda.","og_url":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2022-05-16T14:05:29+00:00","article_modified_time":"2022-05-16T14:22:28+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/05\/heading-31-1.png","type":"image\/png"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"ACN Press Team","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Ucrania: Ayuda de emergencia para 144 religiosas","datePublished":"2022-05-16T14:05:29+00:00","dateModified":"2022-05-16T14:22:28+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/"},"wordCount":480,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/05\/heading-31-1.png","articleSection":["EMERGENCIA HUMANITARIA","PROYECTO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/","url":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/","name":"Ucrania: Ayuda de emergencia para religiosas | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/05\/heading-31-1.png","datePublished":"2022-05-16T14:05:29+00:00","dateModified":"2022-05-16T14:22:28+00:00","description":"Millones de refugiados ucranianos han huido. En la archidi\u00f3cesis de Lviv todas las comunidades religiosas femeninas han ofrecido ayuda.","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/05\/heading-31-1.png","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/05\/heading-31-1.png","width":2000,"height":625,"caption":"Religiosas con refugiados ucranianos"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/emergency-support-for-ukraine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"PROYECTO","item":"https:\/\/acninternational.org\/es\/category\/proyecto\/"},{"@type":"ListItem","position":3,"name":"Ucrania: Ayuda de emergencia para 144 religiosas"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/es\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/170412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=170412"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/170412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/170400"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=170412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=170412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=170412"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=170412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}