{"id":166997,"date":"2022-02-17T09:58:14","date_gmt":"2022-02-17T08:58:14","guid":{"rendered":"https:\/\/acninternational.org\/?p=166997"},"modified":"2022-02-17T09:58:27","modified_gmt":"2022-02-17T08:58:27","slug":"monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/","title":{"rendered":"Monse\u00f1or Pasotto: uno de los art\u00edfices de la reconstrucci\u00f3n de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de la era comunista"},"content":{"rendered":"<p><em>Entrevista con Mons. Giuseppe Pasotto, sacerdote estigmatino italiano, que viene acompa\u00f1ando y guiando el rumbo de la peque\u00f1a Iglesia cat\u00f3lica en el C\u00e1ucaso desde la ca\u00edda del Tel\u00f3n de Acero, primero como misionero, entre 1996 y 2000 como administrador apost\u00f3lico y luego como obispo diocesano.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-166985\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120547-1024x683.jpeg\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120547-1024x683.jpeg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120547-300x200.jpeg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120547-768x512.jpeg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120547-1536x1024.jpeg 1536w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120547.jpeg 1920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><strong>\u00bfQu\u00e9 encontr\u00f3 cuando lleg\u00f3 a Georgia el a\u00f1o 1993? \u00bfQu\u00e9 quedaba de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de 70 a\u00f1os de r\u00e9gimen comunista?<\/strong><\/p>\n<p>\u00bfQue qu\u00e9 me encontr\u00e9? Es dif\u00edcil describir en pocas palabras c\u00f3mo era la situaci\u00f3n en 1993 cuando llegu\u00e9 aqu\u00ed. Georgia acababa de independizarse de Rusia y hab\u00eda roto todas las relaciones con este pa\u00eds, incluidas las econ\u00f3micas. Cuando llegu\u00e9 hab\u00eda gas, agua y electricidad; un mes y medio despu\u00e9s, llegamos a un punto en el que solo hab\u00eda electricidad dos horas al d\u00eda, agua cada dos d\u00edas y el suministro de gas estaba cortado por completo. En los mercados quedaban muy pocas cosas. Por poner un ejemplo: un d\u00eda necesitaba un lim\u00f3n y fui al mercado. No pude encontrar ning\u00fan lim\u00f3n hasta que me encontr\u00e9 con una mujer que ten\u00eda dos. Solo vend\u00eda estas dos frutas. Decid\u00ed comprar los dos, pero ella me dijo: \u201cle dar\u00e9 solo uno, pues otra persona podr\u00eda necesitar el otro\u201d. Qued\u00e9 asombrado y lleno de admiraci\u00f3n. Otra cosa que nunca olvidar\u00e9 es el grito de alegr\u00eda que se o\u00eda cuando volv\u00eda la electricidad por una o dos horas y se pod\u00edan apagar las velas o las l\u00e1mparas de gas.<\/p>\n<p>Llegu\u00e9 aqu\u00ed con otro sacerdote de mi peque\u00f1a congregaci\u00f3n de estigmatinos, que se fund\u00f3 en Verona. Durante este tiempo experimentamos nosotros mismos todas las dificultades de la gente, especialmente el fr\u00edo y las privaciones. Esto nos ayud\u00f3 a amar a\u00fan m\u00e1s a este pueblo y a comprender el significado de la libertad. A trav\u00e9s de nuestras conversaciones con los j\u00f3venes, comprendimos que se sufre por valores importantes y se debe mantener siempre la esperanza. Por \u00faltimo, al aprender la lengua georgiana, no precisamente f\u00e1cil, y casi sin material did\u00e1ctico, comprendimos a\u00fan mejor la vida de este pueblo. Tuvimos que aprender mucho sin importarnos las dificultades que nos rodeaban. Pero fue providencial vivir ese tiempo.<\/p>\n<p><strong>\u00bfCu\u00e1les fueron los primeros pasos que dieron usted y sus hermanos para reconstruir la comunidad cat\u00f3lica?<\/strong><\/p>\n<p>De la Iglesia cat\u00f3lica quedaba \u00fanicamente un solo lugar de culto abierto (la Iglesia de San Pedro y San Pablo en Tiflis); las parroquias dispersas por el campo estaban todas desiertas. Nuestro primer paso fue restablecer los contactos y buscar m\u00e1s sacerdotes de otros pa\u00edses e iglesias locales que pudieran venir a ayudarnos. Muy lentamente, empezamos a restaurar las estructuras principales.<\/p>\n<p>Pienso que la fe cat\u00f3lica, no solo en Georgia, sino en todos los pa\u00edses comunistas, se salv\u00f3 gracias al rezo del rosario. La gente se reun\u00eda en las casas para rezar, y las abuelas sent\u00edan esta responsabilidad. No se necesita ni sacerdote ni rosarios, se pueden contar las avemar\u00edas con los dedos de las manos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-166991\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120282-1024x682.jpeg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120282-1024x682.jpeg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120282-300x200.jpeg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120282-768x512.jpeg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120282.jpeg 1280w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>La primera tarea que nos propusimos fue formar catequistas. Para nuestro primer campamento de estudio de verano reunimos a unos 30 j\u00f3venes y les impartimos una formaci\u00f3n intensiva de diez d\u00edas, para que a su vez pudieran empezar a trabajar con los ni\u00f1os. Lo primero que se imprimi\u00f3 fue el Catecismo de la Iglesia Cat\u00f3lica&#8230; Poco a poco, se fueron abordando otras cosas.<\/p>\n<p><strong>\u00bfC\u00f3mo vivi\u00f3 la guerra del C\u00e1ucaso en 2008? \u00bfC\u00f3mo ayud\u00f3 la Iglesia en ese contexto?<\/strong><\/p>\n<p>La guerra lleg\u00f3 de forma totalmente inesperada; al menos yo no cre\u00eda que pudiera suceder algo as\u00ed. En muy poco tiempo, Rusia dej\u00f3 claro que no hab\u00eda esperanza para el ej\u00e9rcito georgiano y se acerc\u00f3 mucho a Tiflis con sus bombardeos. Por primera vez, vi a personas presas del p\u00e1nico. En nuestra sala de reuniones acogimos a refugiados de Gori durante todo un mes y nos ocupamos de ellos. Incluso hoy me env\u00edan cartas de agradecimiento con ocasi\u00f3n del aniversario de la guerra. C\u00e1ritas Georgia se involucr\u00f3 mucho con alimentos y ayuda a los desplazados. Todav\u00eda recuerdo c\u00f3mo, en cuanto fue posible, sali\u00f3 un cami\u00f3n con alimentos hacia Gori. La primera ayuda que lleg\u00f3 all\u00ed fue la nuestra y se le entreg\u00f3 al obispo ortodoxo para que los distribuyera seg\u00fan las necesidades.<\/p>\n<p><strong>\u00bfCu\u00e1les son los mayores retos para la Iglesia de Georgia en la actualidad? \u00bfQu\u00e9 queda por hacer despu\u00e9s de muchos a\u00f1os de servicio misionero? <\/strong><\/p>\n<p>El primer desaf\u00edo para el futuro sigue siendo la labor ecum\u00e9nica. Esta es nuestra primera tarea y es muy dif\u00edcil. La Iglesia ortodoxa sigue teniendo dificultades para abrirse en esta direcci\u00f3n debido a la herencia de su pasado. Los cat\u00f3licos no solo se sienten una minor\u00eda, sino que a menudo son discriminados y tratados injustamente. Basta pensar en las seis iglesias confiscadas que nunca fueron devueltas, pero tambi\u00e9n en la prohibici\u00f3n de los matrimonios entre personas de diversas confesiones. El camino ecum\u00e9nico requiere mucha paciencia para buscar constantemente nuevos y posibles puntos en com\u00fan y tejer relaciones que se conviertan en puentes. Nuestra universidad juega un papel importante, ya que la mayor\u00eda de los estudiantes no son cat\u00f3licos.<\/p>\n<p>La segunda tarea, en mi opini\u00f3n, es la formaci\u00f3n de nuestros fieles para que su fe sea cada vez m\u00e1s fuerte y segura. Aqu\u00ed, es donde los sacerdotes y religiosos est\u00e1n especialmente comprometidos en las parroquias. La tercera tarea es mostrar el rostro misericordioso y amoroso de Dios, sobre todo a las personas que se encuentran en especiales dificultades.<\/p>\n<p>Nos damos cuenta de que somos muy pocos, tambi\u00e9n porque los \u00e1mbitos de trabajo son cada vez m\u00e1s grandes y cambiantes en nuestro mundo, cada vez m\u00e1s complejo. Afortunadamente, hay j\u00f3venes que se preparan para el sacerdocio y la vida consagrada&#8230; pero el camino de la formaci\u00f3n es largo, lo cual es importante, porque debe ser una buena formaci\u00f3n. Es dif\u00edcil encontrar sacerdotes en el extranjero que quieran venir a trabajar con nosotros, tambi\u00e9n porque existe la barrera del idioma. Se necesita un largo estudio y muchos sacrificios para aprender georgiano, despu\u00e9s solo se puede utilizar el idioma aqu\u00ed. Pero el Se\u00f1or dispone y provee.<\/p>\n<p><strong>\u00bfC\u00f3mo ve el futuro de la Iglesia cat\u00f3lica en Georgia y de qu\u00e9 manera puede ACN acompa\u00f1ar sus pasos?<\/strong><\/p>\n<p>El apoyo prestado por ACN ha sido crucial durante estos a\u00f1os. Puedo decir que son muchos los que han contribuido a mantener nuestra Iglesia en funcionamiento, pero ACN siempre se ha distinguido por apoyar las obras de evangelizaci\u00f3n y formaci\u00f3n. Cada a\u00f1o, gracias a ACN, es decir, gracias al apoyo de miles de benefactores, hemos podido realizar iniciativas pastorales, especialmente los campamentos de verano para la formaci\u00f3n en la fe de ni\u00f1os y j\u00f3venes. Siempre he sido consciente y estoy profundamente agradecido por este camino que hemos compartido con ACN. No conocemos las caras de los benefactores de ACN, pero Dios los conoce a todos, los bendecir\u00e1 y los recompensar\u00e1. Para m\u00ed, siempre ha sido una gran ayuda sentir que las Iglesias hermanas nos han acompa\u00f1ado en el camino y nos han apoyado. En \u00faltimo t\u00e9rmino, nosotros solo hemos sido las manos que han hecho realidad lo que hab\u00eda en los corazones de tantos cat\u00f3licos de todo el mundo.<\/p>\n<p><strong>\u00bfHay algo que desee decir a nuestros benefactores?<\/strong><\/p>\n<p>Me gustar\u00eda aprovechar esta oportunidad para dar las gracias a ACN: gracias a los que colaboran con nosotros y son siempre pacientes con nosotros; nos sentimos realmente queridos. Se puede decir que nuestra Iglesia apenas tiene recursos econ\u00f3micos, pero es capaz de vivir cada d\u00eda confiando en Dios. Todos estamos llamados a anunciar el Evangelio, pero de diferentes maneras. Aqu\u00ed, en Georgia, he descubierto el valor de la palabra \u201ccat\u00f3lico\u201d. Es hermoso pensar que nosotros, los cat\u00f3licos, podemos mostrar a todas las Iglesias lo bueno que es tener un coraz\u00f3n que no conoce fronteras, que no distingue a nadie, que mira siempre m\u00e1s all\u00e1 de sus propias fronteras. Es hermoso dar testimonio de un Dios que nos ense\u00f1a a trav\u00e9s de su coraz\u00f3n a tener un horizonte amplio, a no centrarnos solo en nuestros intereses, sino a abrirnos cada vez m\u00e1s. Este es su amor por nosotros. Deber\u00eda ser lo que testimoniamos y lo que ense\u00f1amos. Este es el hermoso mensaje, el Evangelio. Y para m\u00ed, ese es el color del catolicismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevista con Mons. Giuseppe Pasotto, sacerdote estigmatino italiano, que viene acompa\u00f1ando y guiando el rumbo de la peque\u00f1a Iglesia cat\u00f3lica<\/p>\n","protected":false},"author":4258341447,"featured_media":166979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[745,798],"tags":[],"country":[882],"class_list":["post-166997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas","category-interviews-es","country-georgia"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Monse\u00f1or Pasotto: uno de los art\u00edfices de la reconstrucci\u00f3n de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de la era comunista | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monse\u00f1or Pasotto: uno de los art\u00edfices de la reconstrucci\u00f3n de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de la era comunista\" \/>\n<meta property=\"og:description\" content=\"Entrevista con Mons. Giuseppe Pasotto, sacerdote estigmatino italiano, que viene acompa\u00f1ando y guiando el rumbo de la peque\u00f1a Iglesia cat\u00f3lica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-17T08:58:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-17T08:58:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120334.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Monse\u00f1or Pasotto: uno de los art\u00edfices de la reconstrucci\u00f3n de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de la era comunista\",\"datePublished\":\"2022-02-17T08:58:14+00:00\",\"dateModified\":\"2022-02-17T08:58:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/\"},\"wordCount\":1512,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/ACN-20211201-120334.jpeg\",\"articleSection\":[\"ENTREVISTAS\",\"INTERVIEWS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/\",\"name\":\"Monse\u00f1or Pasotto: uno de los art\u00edfices de la reconstrucci\u00f3n de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de la era comunista | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/ACN-20211201-120334.jpeg\",\"datePublished\":\"2022-02-17T08:58:14+00:00\",\"dateModified\":\"2022-02-17T08:58:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/ACN-20211201-120334.jpeg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/ACN-20211201-120334.jpeg\",\"width\":1280,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/entrevistas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Monse\u00f1or Pasotto: uno de los art\u00edfices de la reconstrucci\u00f3n de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de la era comunista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Monse\u00f1or Pasotto: uno de los art\u00edfices de la reconstrucci\u00f3n de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de la era comunista | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/","og_locale":"es_ES","og_type":"article","og_title":"Monse\u00f1or Pasotto: uno de los art\u00edfices de la reconstrucci\u00f3n de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de la era comunista","og_description":"Entrevista con Mons. Giuseppe Pasotto, sacerdote estigmatino italiano, que viene acompa\u00f1ando y guiando el rumbo de la peque\u00f1a Iglesia cat\u00f3lica","og_url":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2022-02-17T08:58:14+00:00","article_modified_time":"2022-02-17T08:58:27+00:00","og_image":[{"width":1280,"height":700,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120334.jpeg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"ACN Press Team","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Monse\u00f1or Pasotto: uno de los art\u00edfices de la reconstrucci\u00f3n de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de la era comunista","datePublished":"2022-02-17T08:58:14+00:00","dateModified":"2022-02-17T08:58:27+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/"},"wordCount":1512,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120334.jpeg","articleSection":["ENTREVISTAS","INTERVIEWS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/","url":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/","name":"Monse\u00f1or Pasotto: uno de los art\u00edfices de la reconstrucci\u00f3n de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de la era comunista | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120334.jpeg","datePublished":"2022-02-17T08:58:14+00:00","dateModified":"2022-02-17T08:58:27+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120334.jpeg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/02\/ACN-20211201-120334.jpeg","width":1280,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/monsenor-pasotto-uno-de-los-artifices-de-la-reconstruccion-de-la-iglesia-catolica-en-georgia-despues-de-la-era-comunista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTAS","item":"https:\/\/acninternational.org\/es\/category\/entrevistas\/"},{"@type":"ListItem","position":3,"name":"Monse\u00f1or Pasotto: uno de los art\u00edfices de la reconstrucci\u00f3n de la Iglesia cat\u00f3lica en Georgia despu\u00e9s de la era comunista"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/es\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/166997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=166997"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/166997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/166979"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=166997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=166997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=166997"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=166997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}