{"id":166105,"date":"2022-01-19T09:13:10","date_gmt":"2022-01-19T08:13:10","guid":{"rendered":"https:\/\/acninternational.org\/?p=166105"},"modified":"2022-01-19T09:13:14","modified_gmt":"2022-01-19T08:13:14","slug":"armenia-iglesia-de-martires","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/","title":{"rendered":"Armenia: Iglesia de m\u00e1rtires"},"content":{"rendered":"<p><em>Marco Mencaglia es, desde hace a\u00f1o y medio, el responsable de los proyectos de \u2018Ayuda a la Iglesia Necesitada\u2019 en Armenia, entre otros. En cuanto la situaci\u00f3n de la pandemia \u00a0lo permiti\u00f3, visit\u00f3 Georgia y Armenia por primera vez. El prop\u00f3sito del viaje era conocer de primera mano la situaci\u00f3n en el pa\u00eds, as\u00ed como evaluar las posibles formas de colaboraci\u00f3n de \u2018Ayuda a la Iglesia Necesitada\u2019 con la Iglesia local.<\/em><\/p>\n<p><em>Kira von Bock-Iwaniuk lo entrevist\u00f3 a su regreso.<\/em><\/p>\n<p><strong>Armenia, un pa\u00eds que perteneci\u00f3 al antiguo mundo cristiano, es hoy un enclave cristiano en un entorno islamista cada vez m\u00e1s hostil. \u00bfHa podido encontrar muchas coincidencias entre Georgia y Armenia o\u00a0 la situaci\u00f3n en ambos pa\u00edses es completamente diferente? <\/strong><\/p>\n<p>Georgia y Armenia son\u00a0 pa\u00edses vecinos pero completamente diferentes en cuanto a historia, cultura, lengua e incluso alfabeto. Sin embargo, a nivel eclesi\u00e1stico podemos observar varias similitudes. En ambos, la Iglesia cat\u00f3lica representa a una peque\u00f1a minor\u00eda y su presencia institucional es relativamente joven, lo cual no le impide realizar una extraordinaria labor en el \u00e1mbito social a trav\u00e9s de C\u00e1ritas y las congregaciones religiosas. Adem\u00e1s, la historia de la fe cristiana es excepcionalmente rica en ambos pa\u00edses: Armenia y Georgia fueron los primeros pa\u00edses del mundo en adoptar el cristianismo como religi\u00f3n oficial ya en el siglo IV. Pese al avance de la secularizaci\u00f3n, ambos pa\u00edses siguen ocupando el primer lugar, entre los 34 pa\u00edses europeos, en cuanto al n\u00famero de adultos creyentes en relaci\u00f3n con la poblaci\u00f3n total, seg\u00fan un estudio del <em>Pew Research Center<\/em> de 2018.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-166097\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120525-1024x683.jpeg\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120525-1024x683.jpeg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120525-300x200.jpeg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120525-768x512.jpeg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120525.jpeg 1200w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Por \u00faltimo, ambos pa\u00edses est\u00e1n sometidos a una constante presi\u00f3n a ra\u00edz de los graves conflictos armados en Abjasia y Osetia del Sur y, m\u00e1s recientemente, en el Alto Karabaj. La dram\u00e1tica p\u00e9rdida de vidas y la necesidad de hacer frente al gran n\u00famero de refugiados han ocasionado serias dificultades a los respectivos Gobiernos.<\/p>\n<p><strong>\u00bfPodr\u00eda decirnos cu\u00e1l es el mayor desaf\u00edo para la Iglesia en Armenia?<br \/>\n<\/strong>La Iglesia cat\u00f3lica est\u00e1 presente en Armenia casi exclusivamente en las regiones del noroeste del pa\u00eds y tambi\u00e9n hay algunas parroquias en el suroeste de Georgia, al otro lado de la frontera. Se trata de zonas pobres e inh\u00f3spitas, ubicadas a m\u00e1s de 2.000 metros de altitud, donde los inviernos son duros y duran hasta seis meses. All\u00ed, la tasa de desempleo es muy alta y la emigraci\u00f3n, permanente o estacional, a los pa\u00edses vecinos es la \u00fanica opci\u00f3n para muchos. En un contexto as\u00ed, resulta comprensible que la Iglesia se dedique intensamente a la labor social en favor de los m\u00e1s vulnerables con el fin de infundir esperanza y ofrecer una alternativa al abandono del pa\u00eds.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-166103\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120419-1024x683.jpeg\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120419-1024x683.jpeg 1024w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120419-300x200.jpeg 300w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120419-768x512.jpeg 768w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120419.jpeg 1200w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>La Iglesia tambi\u00e9n promueve activamente las nuevas vocaciones, ya que el n\u00famero de sacerdotes y religiosas es muy limitado en comparaci\u00f3n con las necesidades reales de los fieles. Al igual que la Iglesia cat\u00f3lica georgiana, la de Armenia carece de seminario mayor propio, por lo que los futuros sacerdotes se reparten entre varios seminarios de Europa Occidental. El proyecto de un seminario en Gyumr\u00ed -la sede episcopal- est\u00e1 actualmente bloqueado por falta de fondos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Armenia no solo ha sufrido un genocidio, sino que tambi\u00e9n se ha visto sacudida por cat\u00e1strofes naturales -el devastador terremoto de 1988- y, m\u00e1s recientemente, por otra cat\u00e1strofe provocada por el hombre, como la expulsi\u00f3n de los armenios de Nagorno Karabaj. \u00bfTodav\u00eda se perciben repercusiones de ello? \u00bfQu\u00e9 hace la Iglesia para aliviar el sufrimiento? \u00bfPuede ACN prestarle alg\u00fan apoyo?<\/strong><\/p>\n<p>El terremoto de 1988 afect\u00f3 precisamente a las zonas habitadas por los cat\u00f3licos, en el noroeste del pa\u00eds. La respuesta de la Iglesia en el \u00e1mbito social ha sido, como ya he dicho antes, muy significativa. La crisis m\u00e1s reciente est\u00e1 relacionada, naturalmente, con la acogida de las familias huidas del Alto Karabaj: en la situaci\u00f3n de emergencia de oto\u00f1o de 2020, fueron m\u00e1s de 90.000 personas. La red de asistencia internacional pudo satisfacer las necesidades m\u00e1s urgentes en el primer a\u00f1o despu\u00e9s del conflicto. El problema surge ahora, que los ojos del mundo ya no est\u00e1n puestos en Armenia, porque el flujo de ayudas se ha reducido dr\u00e1sticamente. Muchas familias cristianas lo han perdido todo y la gran mayor\u00eda son madres\u00a0 con hijos que siguen viviendo en condiciones precarias. <a href=\"https:\/\/acninternational.org\/es\/armenia-los-refugiados-de-nagorno-karabaj-luchan-por-sobrevivir-acn-les-ayuda-2\/\">Tras el viaje, ACN ha aprobado una ayuda de emergencia para estas familias.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>ACN viene apoyando desde hace a\u00f1os las iniciativas pastorales del ordinariato cat\u00f3lico armenio para Europa del Este, especialmente los campamentos de verano para j\u00f3venes. Dado que el ordinariato, con sede en Armenia, es tambi\u00e9n responsable de los fieles cat\u00f3licos armenios de Georgia, Rusia, Ucrania y otros pa\u00edses de la regi\u00f3n, estas actividades tienen una dimensi\u00f3n internacional. Con m\u00e1s de 200.000 fieles, es la jurisdicci\u00f3n con mayor n\u00famero de fieles de toda la Iglesia cat\u00f3lica armenia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marco Mencaglia es, desde hace a\u00f1o y medio, el responsable de los proyectos de \u2018Ayuda a la Iglesia Necesitada\u2019 en<\/p>\n","protected":false},"author":4258341447,"featured_media":166129,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[746],"tags":[],"country":[879],"class_list":["post-166105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","country-armenia"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Armenia: Iglesia de m\u00e1rtires | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Armenia: Iglesia de m\u00e1rtires\" \/>\n<meta property=\"og:description\" content=\"Marco Mencaglia es, desde hace a\u00f1o y medio, el responsable de los proyectos de \u2018Ayuda a la Iglesia Necesitada\u2019 en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-19T08:13:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-19T08:13:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120435-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Armenia: Iglesia de m\u00e1rtires\",\"datePublished\":\"2022-01-19T08:13:10+00:00\",\"dateModified\":\"2022-01-19T08:13:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/\"},\"wordCount\":877,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ACN-20211201-120435-1.jpeg\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/\",\"name\":\"Armenia: Iglesia de m\u00e1rtires | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ACN-20211201-120435-1.jpeg\",\"datePublished\":\"2022-01-19T08:13:10+00:00\",\"dateModified\":\"2022-01-19T08:13:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ACN-20211201-120435-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/ACN-20211201-120435-1.jpeg\",\"width\":1200,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/armenia-iglesia-de-martires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTICIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/news-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Armenia: Iglesia de m\u00e1rtires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Armenia: Iglesia de m\u00e1rtires | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/","og_locale":"es_ES","og_type":"article","og_title":"Armenia: Iglesia de m\u00e1rtires","og_description":"Marco Mencaglia es, desde hace a\u00f1o y medio, el responsable de los proyectos de \u2018Ayuda a la Iglesia Necesitada\u2019 en","og_url":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2022-01-19T08:13:10+00:00","article_modified_time":"2022-01-19T08:13:14+00:00","og_image":[{"width":1200,"height":625,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120435-1.jpeg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"ACN Press Team","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Armenia: Iglesia de m\u00e1rtires","datePublished":"2022-01-19T08:13:10+00:00","dateModified":"2022-01-19T08:13:14+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/"},"wordCount":877,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120435-1.jpeg","articleSection":["NOTICIAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/","url":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/","name":"Armenia: Iglesia de m\u00e1rtires | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120435-1.jpeg","datePublished":"2022-01-19T08:13:10+00:00","dateModified":"2022-01-19T08:13:14+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120435-1.jpeg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/01\/ACN-20211201-120435-1.jpeg","width":1200,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/armenia-iglesia-de-martires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"NOTICIAS","item":"https:\/\/acninternational.org\/es\/category\/news-es\/"},{"@type":"ListItem","position":3,"name":"Armenia: Iglesia de m\u00e1rtires"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/es\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/166105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=166105"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/166105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/166129"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=166105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=166105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=166105"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=166105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}