{"id":158062,"date":"2021-08-16T16:15:49","date_gmt":"2021-08-16T14:15:49","guid":{"rendered":"https:\/\/acninternational.org\/?p=158062"},"modified":"2021-08-16T16:23:38","modified_gmt":"2021-08-16T14:23:38","slug":"historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/","title":{"rendered":"Historia de \u00e9xito: 6.000 ejemplares del catecismo juvenil YouCat en suajili"},"content":{"rendered":"<p>El <em>YouCat<\/em> es el catecismo de la Iglesia Cat\u00f3lica para adolescentes y j\u00f3venes adultos. En \u00e9l, los contenidos m\u00e1s importantes de la fe se resumen de forma breve y f\u00e1cilmente comprensible, en un formato de preguntas y respuestas. Las ilustraciones hacen a\u00fan m\u00e1s atractiva esta obra que ya se ha publicado en 58 idiomas.<\/p>\n<figure id=\"attachment_158043\" aria-describedby=\"caption-attachment-158043\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-158048 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili-3.jpg\" alt=\"\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili-3.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili-3-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-158043\" class=\"wp-caption-text\">La Hna. Olga Hassango entrega los libros de YOUCAT en swahili al Hermano Linus Scheutsen<\/figcaption><\/figure>\n<p>La orden de las Hijas de San Pablo ha traducido ahora el libro al suajili para hacerlo accesible a los j\u00f3venes de Tanzania y Kenia. A finales de 2019, la traducci\u00f3n estaba finalmente lista. La alegr\u00eda fue grande, pero luego lleg\u00f3 la pandemia, que lo hizo todo m\u00e1s dif\u00edcil. Las religiosas ten\u00edan grandes planes: quer\u00edan visitar las escuelas para presentar el libro a alumnos, maestros y padres, y tambi\u00e9n programaron encuentros con j\u00f3venes y numerosas iniciativas en el marco de la pastoral juvenil de las di\u00f3cesis. Por desgracia, el coronavirus bloque\u00f3 estas actividades. En cuanto la situaci\u00f3n lo permita, las religiosas reemprender\u00e1n esta labor.<\/p>\n<figure id=\"attachment_158049\" aria-describedby=\"caption-attachment-158049\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-158054 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili-4.jpg\" alt=\"\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili-4.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili-4-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-158049\" class=\"wp-caption-text\">El Hermano Linus Scheutsen firma la recepci\u00f3n de los ejemplares del YOUCAT para los presos<\/figcaption><\/figure>\n<p>Sin embargo, a pesar de estos obst\u00e1culos, muchos j\u00f3venes ya est\u00e1n disfrutando del libro, que es especialmente \u00fatil para la pastoral de prisiones. La Hna. Olga Massango de las Hermanas Paulinas nos escribe: \u201cEl Hno. Linus y el Hno. Pablo est\u00e1n muy contentos y consideran que estos libros son muy \u00fatiles para nuestras hermanas y hermanos presos. Estamos muy agradecidas a ACN por ayudarnos a llegar a los hermanos y hermanas que m\u00e1s necesitan la experiencia de la misericordia de Dios. Tengan la seguridad de que rezamos por ustedes y por todos los benefactores, especialmente en estos momentos en los que el coronavirus sigue sembrando el miedo y la inseguridad en el mundo\u201d.<\/p>\n<figure id=\"attachment_158037\" aria-describedby=\"caption-attachment-158037\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-158042 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili-2.jpg\" alt=\"\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili-2.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili-2-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-158037\" class=\"wp-caption-text\">\u00abLos presos tambi\u00e9n son personas\u00bb, y en Tanzania y Kenia tienen derecho a recibir sus copias del YOUCAT en swahili<\/figcaption><\/figure>\n<p>Gracias a vuestra ayuda hemos podido financiar la impresi\u00f3n de 6.000 ejemplares con 13.800 euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>6.000 ejemplares del catecismo juvenil YouCat en suajili accesible a los j\u00f3venes de Tanzania y Kenia <\/p>\n","protected":false},"author":66,"featured_media":158060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[718,935,714],"tags":[],"country":[434,429],"class_list":["post-158062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libros-religiosos","category-projects-es","category-proyecto","country-kenia-es","country-tanzania-es"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Historia de \u00e9xito: 6.000 ejemplares del catecismo juvenil YouCat en suajili | ACN International<\/title>\n<meta name=\"description\" content=\"6.000 ejemplares del catecismo juvenil YouCat en suajili accesible a los j\u00f3venes de Tanzania y Kenia. El YouCat es el catecismo de la Iglesia Cat\u00f3lica para adolescentes y j\u00f3venes adultos. En \u00e9l, los contenidos m\u00e1s importantes de la fe se resumen de forma breve y f\u00e1cilmente comprensible, en un formato de preguntas y respuestas. Las ilustraciones hacen a\u00fan m\u00e1s atractiva esta obra que ya se ha publicado en 58 idiomas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historia de \u00e9xito: 6.000 ejemplares del catecismo juvenil YouCat en suajili\" \/>\n<meta property=\"og:description\" content=\"6.000 ejemplares del catecismo juvenil YouCat en suajili accesible a los j\u00f3venes de Tanzania y Kenia. El YouCat es el catecismo de la Iglesia Cat\u00f3lica para adolescentes y j\u00f3venes adultos. En \u00e9l, los contenidos m\u00e1s importantes de la fe se resumen de forma breve y f\u00e1cilmente comprensible, en un formato de preguntas y respuestas. Las ilustraciones hacen a\u00fan m\u00e1s atractiva esta obra que ya se ha publicado en 58 idiomas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-16T14:15:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-16T14:23:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milena\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milena\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/\"},\"author\":{\"name\":\"Milena\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a2b2930ad4475e0aa0dade4e51d9474\"},\"headline\":\"Historia de \u00e9xito: 6.000 ejemplares del catecismo juvenil YouCat en suajili\",\"datePublished\":\"2021-08-16T14:15:49+00:00\",\"dateModified\":\"2021-08-16T14:23:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/\"},\"wordCount\":389,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili.jpg\",\"articleSection\":[\"LIBROS RELIGIOSOS\",\"PROJECTS\",\"PROYECTO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/\",\"name\":\"Historia de \u00e9xito: 6.000 ejemplares del catecismo juvenil YouCat en suajili | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili.jpg\",\"datePublished\":\"2021-08-16T14:15:49+00:00\",\"dateModified\":\"2021-08-16T14:23:38+00:00\",\"description\":\"6.000 ejemplares del catecismo juvenil YouCat en suajili accesible a los j\u00f3venes de Tanzania y Kenia. El YouCat es el catecismo de la Iglesia Cat\u00f3lica para adolescentes y j\u00f3venes adultos. En \u00e9l, los contenidos m\u00e1s importantes de la fe se resumen de forma breve y f\u00e1cilmente comprensible, en un formato de preguntas y respuestas. Las ilustraciones hacen a\u00fan m\u00e1s atractiva esta obra que ya se ha publicado en 58 idiomas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili.jpg\",\"width\":2000,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROJECTS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/projects-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Historia de \u00e9xito: 6.000 ejemplares del catecismo juvenil YouCat en suajili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a2b2930ad4475e0aa0dade4e51d9474\",\"name\":\"Milena\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/milena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Historia de \u00e9xito: 6.000 ejemplares del catecismo juvenil YouCat en suajili | ACN International","description":"6.000 ejemplares del catecismo juvenil YouCat en suajili accesible a los j\u00f3venes de Tanzania y Kenia. El YouCat es el catecismo de la Iglesia Cat\u00f3lica para adolescentes y j\u00f3venes adultos. En \u00e9l, los contenidos m\u00e1s importantes de la fe se resumen de forma breve y f\u00e1cilmente comprensible, en un formato de preguntas y respuestas. Las ilustraciones hacen a\u00fan m\u00e1s atractiva esta obra que ya se ha publicado en 58 idiomas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/","og_locale":"es_ES","og_type":"article","og_title":"Historia de \u00e9xito: 6.000 ejemplares del catecismo juvenil YouCat en suajili","og_description":"6.000 ejemplares del catecismo juvenil YouCat en suajili accesible a los j\u00f3venes de Tanzania y Kenia. El YouCat es el catecismo de la Iglesia Cat\u00f3lica para adolescentes y j\u00f3venes adultos. En \u00e9l, los contenidos m\u00e1s importantes de la fe se resumen de forma breve y f\u00e1cilmente comprensible, en un formato de preguntas y respuestas. Las ilustraciones hacen a\u00fan m\u00e1s atractiva esta obra que ya se ha publicado en 58 idiomas.","og_url":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2021-08-16T14:15:49+00:00","article_modified_time":"2021-08-16T14:23:38+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili.jpg","type":"image\/jpeg"}],"author":"Milena","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"Milena","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/"},"author":{"name":"Milena","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a2b2930ad4475e0aa0dade4e51d9474"},"headline":"Historia de \u00e9xito: 6.000 ejemplares del catecismo juvenil YouCat en suajili","datePublished":"2021-08-16T14:15:49+00:00","dateModified":"2021-08-16T14:23:38+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/"},"wordCount":389,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili.jpg","articleSection":["LIBROS RELIGIOSOS","PROJECTS","PROYECTO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/","url":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/","name":"Historia de \u00e9xito: 6.000 ejemplares del catecismo juvenil YouCat en suajili | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili.jpg","datePublished":"2021-08-16T14:15:49+00:00","dateModified":"2021-08-16T14:23:38+00:00","description":"6.000 ejemplares del catecismo juvenil YouCat en suajili accesible a los j\u00f3venes de Tanzania y Kenia. El YouCat es el catecismo de la Iglesia Cat\u00f3lica para adolescentes y j\u00f3venes adultos. En \u00e9l, los contenidos m\u00e1s importantes de la fe se resumen de forma breve y f\u00e1cilmente comprensible, en un formato de preguntas y respuestas. Las ilustraciones hacen a\u00fan m\u00e1s atractiva esta obra que ya se ha publicado en 58 idiomas.","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/08\/acn-internet-projects_6000-copies-of-the-youth-catechism-YOUCAT-in-Swahili.jpg","width":2000,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/historia-de-exito-6-000-ejemplares-del-catecismo-juvenil-youcat-en-suajili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"PROJECTS","item":"https:\/\/acninternational.org\/es\/category\/projects-es\/"},{"@type":"ListItem","position":3,"name":"Historia de \u00e9xito: 6.000 ejemplares del catecismo juvenil YouCat en suajili"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a2b2930ad4475e0aa0dade4e51d9474","name":"Milena","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/es\/author\/milena\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/158062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=158062"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/158062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/158060"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=158062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=158062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=158062"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=158062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}