{"id":155217,"date":"2021-07-05T09:52:39","date_gmt":"2021-07-05T07:52:39","guid":{"rendered":"https:\/\/acninternational.org\/?p=155217"},"modified":"2021-07-05T09:55:13","modified_gmt":"2021-07-05T07:55:13","slug":"burundi-un-centro-pastoral-para-la-diocesis-de-muyinga","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/","title":{"rendered":"Burundi:\u00a0Un centro pastoral para la Di\u00f3cesis de Muyinga\u00a0"},"content":{"rendered":"<p>Burundi, un pa\u00eds del \u00c1frica Oriental, es uno de los m\u00e1s pobres y subdesarrollados del mundo, y en su historia reciente ha sido repetidamente escenario de crisis de Estado, masacres, disturbios y conflictos sangrientos. Cientos de miles de personas han muerto o han huido de sus hogares. Especialmente la guerra civil entre 1993 y 2005 ha dejado profundas heridas, tanto en la sociedad en general como en los individuos.<\/p>\n<p>Las Hermanas de Mar\u00eda est\u00e1n presentes en Burundi desde 1962. Al principio se dedicaban sobre todo al cuidado de los enfermos y los pobres, pero luego se implicaron cada vez m\u00e1s en la pastoral familiar, juvenil y de la mujer, porque la necesidad de ayuda a las familias y acompa\u00f1amiento a los j\u00f3venes iba en aumento, y tambi\u00e9n porque urg\u00eda impulsar la catequesis y la profundizaci\u00f3n de la fe. Y es que, aunque all\u00ed la Iglesia sea joven y din\u00e1mica, a menudo se mezclan todav\u00eda elementos paganos en la pr\u00e1ctica de la fe, por lo que los fieles necesitan ayuda e instrucci\u00f3n en su camino de fe.<\/p>\n<figure id=\"attachment_155209\" aria-describedby=\"caption-attachment-155209\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-155209 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi2.jpg\" alt=\"Las Hermanas han decidido erigir un centro pastoral en el que puedan tener lugar las reuniones de los grupos, las jornadas de retiro, los talleres y dem\u00e1s actividades.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi2.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi2-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-155209\" class=\"wp-caption-text\">Las Hermanas han decidido erigir un centro pastoral en el que puedan tener lugar las reuniones de los grupos, las jornadas de retiro, los talleres y dem\u00e1s actividades.<\/figcaption><\/figure>\n<p>Entretanto, varios centenares de grupos para ni\u00f1os, j\u00f3venes, madres, mujeres solteras, licenciadas y estudiantes se han reunido bajo la direcci\u00f3n de las hermanas, cuyos miembros quieren crecer en la fe y sacar de ello la fuerza y la inspiraci\u00f3n para una vida plena.<\/p>\n<p>Desde hace tres a\u00f1os, tres religiosas nativas trabajan en la Di\u00f3cesis de Muyinga, en el norte del pa\u00eds, en una zona que es a\u00fan m\u00e1s pobre que el sur. No obstante, las religiosas no se desaniman, sino que se arremangan y ponen manos a la obra. Por el momento, se han instalado en un apartamento muy peque\u00f1o e inadecuado del que pronto tendr\u00e1n que mudarse porque que el propietario tiene otros planes para \u00e9l.<\/p>\n<p>Sin embargo, no necesitan en primera l\u00ednea un piso para ellas, sino tambi\u00e9n espacios adecuados para el trabajo con los grupos. Sin un lugar para los encuentros y eventos, el trabajo no funciona.<\/p>\n<figure id=\"attachment_155203\" aria-describedby=\"caption-attachment-155203\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-155203 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi3.jpg\" alt=\"Las Hermanas de Mar\u00eda est\u00e1n presentes en Burundi desde 1962.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi3.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi3-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-155203\" class=\"wp-caption-text\">Las Hermanas de Mar\u00eda est\u00e1n presentes en Burundi desde 1962.<\/figcaption><\/figure>\n<p>Por ello, las Hermanas han decidido erigir un centro pastoral en el que puedan tener lugar las reuniones de los grupos, las jornadas de retiro, los talleres y dem\u00e1s actividades. Adem\u00e1s, est\u00e1 previsto que el centro disponga de un jard\u00edn para que los participantes puedan refugiarse en el silencio o para que el trabajo en grupo pueda realizarse tambi\u00e9n al aire libre.<\/p>\n<p>A nosotros nos gustar\u00eda apoyar este proyecto con 200.000 euros.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Burundi, un pa\u00eds del \u00c1frica Oriental, es uno de los m\u00e1s pobres y subdesarrollados del mundo, y en su historia<\/p>\n","protected":false},"author":4258341447,"featured_media":155215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[721,935,714],"tags":[],"country":[822],"class_list":["post-155217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","category-projects-es","category-proyecto","country-burundi"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Burundi:\u00a0Un centro pastoral para la Di\u00f3cesis de Muyinga\u00a0 | ACN International<\/title>\n<meta name=\"description\" content=\"Por ello, las Hermanas han decidido erigir un centro pastoral en el que puedan tener lugar las reuniones de los grupos, las jornadas de retiro, los talleres y dem\u00e1s actividades. Adem\u00e1s, est\u00e1 previsto que el centro disponga de un jard\u00edn para que los participantes puedan refugiarse en el silencio o para que el trabajo en grupo pueda realizarse tambi\u00e9n al aire libre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Burundi:\u00a0Un centro pastoral para la Di\u00f3cesis de Muyinga\u00a0\" \/>\n<meta property=\"og:description\" content=\"Por ello, las Hermanas han decidido erigir un centro pastoral en el que puedan tener lugar las reuniones de los grupos, las jornadas de retiro, los talleres y dem\u00e1s actividades. Adem\u00e1s, est\u00e1 previsto que el centro disponga de un jard\u00edn para que los participantes puedan refugiarse en el silencio o para que el trabajo en grupo pueda realizarse tambi\u00e9n al aire libre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T07:52:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-05T07:55:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Burundi:\u00a0Un centro pastoral para la Di\u00f3cesis de Muyinga\u00a0\",\"datePublished\":\"2021-07-05T07:52:39+00:00\",\"dateModified\":\"2021-07-05T07:55:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/\"},\"wordCount\":490,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Burundi.jpg\",\"articleSection\":[\"CONSTRUCCI\u00d3N\",\"PROJECTS\",\"PROYECTO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/\",\"name\":\"Burundi:\u00a0Un centro pastoral para la Di\u00f3cesis de Muyinga\u00a0 | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Burundi.jpg\",\"datePublished\":\"2021-07-05T07:52:39+00:00\",\"dateModified\":\"2021-07-05T07:55:13+00:00\",\"description\":\"Por ello, las Hermanas han decidido erigir un centro pastoral en el que puedan tener lugar las reuniones de los grupos, las jornadas de retiro, los talleres y dem\u00e1s actividades. Adem\u00e1s, est\u00e1 previsto que el centro disponga de un jard\u00edn para que los participantes puedan refugiarse en el silencio o para que el trabajo en grupo pueda realizarse tambi\u00e9n al aire libre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Burundi.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Burundi.jpg\",\"width\":1400,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROJECTS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/projects-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Burundi:\u00a0Un centro pastoral para la Di\u00f3cesis de Muyinga\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Burundi:\u00a0Un centro pastoral para la Di\u00f3cesis de Muyinga\u00a0 | ACN International","description":"Por ello, las Hermanas han decidido erigir un centro pastoral en el que puedan tener lugar las reuniones de los grupos, las jornadas de retiro, los talleres y dem\u00e1s actividades. Adem\u00e1s, est\u00e1 previsto que el centro disponga de un jard\u00edn para que los participantes puedan refugiarse en el silencio o para que el trabajo en grupo pueda realizarse tambi\u00e9n al aire libre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/","og_locale":"es_ES","og_type":"article","og_title":"Burundi:\u00a0Un centro pastoral para la Di\u00f3cesis de Muyinga\u00a0","og_description":"Por ello, las Hermanas han decidido erigir un centro pastoral en el que puedan tener lugar las reuniones de los grupos, las jornadas de retiro, los talleres y dem\u00e1s actividades. Adem\u00e1s, est\u00e1 previsto que el centro disponga de un jard\u00edn para que los participantes puedan refugiarse en el silencio o para que el trabajo en grupo pueda realizarse tambi\u00e9n al aire libre.","og_url":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2021-07-05T07:52:39+00:00","article_modified_time":"2021-07-05T07:55:13+00:00","og_image":[{"width":1400,"height":438,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"ACN Press Team","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Burundi:\u00a0Un centro pastoral para la Di\u00f3cesis de Muyinga\u00a0","datePublished":"2021-07-05T07:52:39+00:00","dateModified":"2021-07-05T07:55:13+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/"},"wordCount":490,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi.jpg","articleSection":["CONSTRUCCI\u00d3N","PROJECTS","PROYECTO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/","url":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/","name":"Burundi:\u00a0Un centro pastoral para la Di\u00f3cesis de Muyinga\u00a0 | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi.jpg","datePublished":"2021-07-05T07:52:39+00:00","dateModified":"2021-07-05T07:55:13+00:00","description":"Por ello, las Hermanas han decidido erigir un centro pastoral en el que puedan tener lugar las reuniones de los grupos, las jornadas de retiro, los talleres y dem\u00e1s actividades. Adem\u00e1s, est\u00e1 previsto que el centro disponga de un jard\u00edn para que los participantes puedan refugiarse en el silencio o para que el trabajo en grupo pueda realizarse tambi\u00e9n al aire libre.","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/07\/Burundi.jpg","width":1400,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/burundi-un-centro-pastoral-para-la-diocesis-de-muyinga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"PROJECTS","item":"https:\/\/acninternational.org\/es\/category\/projects-es\/"},{"@type":"ListItem","position":3,"name":"Burundi:\u00a0Un centro pastoral para la Di\u00f3cesis de Muyinga\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/es\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/155217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=155217"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/155217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/155215"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=155217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=155217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=155217"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=155217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}