{"id":130159,"date":"2020-01-29T09:56:08","date_gmt":"2020-01-29T08:56:08","guid":{"rendered":"https:\/\/acninternational.org\/?p=130159"},"modified":"2020-01-29T10:00:04","modified_gmt":"2020-01-29T09:00:04","slug":"arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/","title":{"rendered":"Arzobispo Samir Nassar: \u201cSiria vive una Cuaresma anticipada\u201d"},"content":{"rendered":"<p><em>Seg\u00fan<\/em> <em>M<\/em><em>ons. <\/em><em>Samir <\/em><em>Nassar<\/em><em>, arzo<\/em><em>bispo<\/em><em> maronita de Damasco, <\/em><em>la continuidad de los proyectos de ayuda humanitaria en el pa\u00eds est\u00e1 en peligro <\/em><\/p>\n<p>La situaci\u00f3n econ\u00f3mica en Siria est\u00e1 empeorando. \u201cEsta crisis, que es algo diferente a lo experimentado durante los d\u00edas de guerra, ha obligado a la gente a vivir una especie de ayuno cuaresmal anticipado. Poder poner comida sobre la mesa se ha convertido en la pesadilla diaria,\u201d escribe Mons. Samir Nassar, arzobispo de Damasco, en un mensaje a la sede internacional de la fundaci\u00f3n pontificia ACN. Como consecuencia de la crisis econ\u00f3mica, resultado tanto del estado de guerra que afecta el pa\u00eds como\u00a0 del embargo impuesto por las potencias occidentales, la poblaci\u00f3n sufre diferentes tipos de racionamiento.\u00a0\u201cLa escasez de combustible, el suministro de gas dom\u00e9stico y la electricidad han sumido a los m\u00e1s vulnerables &#8211; entre ellos a los enfermos,\u00a0 ni\u00f1os y\u00a0 ancianos &#8211;\u00a0\u00a0 en la oscuridad, sufriendo tambi\u00e9n de las temperaturas de congelaci\u00f3n letales\u201d, lamenta Nassar.<\/p>\n<figure id=\"attachment_130143\" aria-describedby=\"caption-attachment-130143\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-130143 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/01\/Archbishop-Samir-Nassar.jpg\" alt=\"Mons. Samir Nassar, arzobispo maronita de Damasco.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/01\/Archbishop-Samir-Nassar.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/01\/Archbishop-Samir-Nassar-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-130143\" class=\"wp-caption-text\">Mons. Samir Nassar, arzobispo maronita de Damasco.<\/figcaption><\/figure>\n<p><strong>EL pueblo est\u00e1 viviendo la Pasi\u00f3n de Cristo antes de la Semana Santa <\/strong><\/p>\n<p>Por su parte la Hna. Maria L\u00facia Ferreira, de la Congregaci\u00f3n de Hermanas de la Unidad en Antioqu\u00eda, confirma\u00a0 a la oficina portuguesa de la fundaci\u00f3n pontificia ACN que \u201clas cosas est\u00e1n empeorando mucho\u201d.<\/p>\n<p>\u201cPor ejemplo, el gas se intercambia por vales,\u00a0 para cada familia hay [solo] una bombona al mes\u201d, explica la Hna. Maria L\u00facia, quien a\u00f1ade que la situaci\u00f3n es tan grave que \u201capenas se puede comprar comida\u201d. \u201cLos que llegan los \u00faltimos, se van de vac\u00edo&#8230;\u201d. De la misma manera, la religiosa explica que \u201chay escasez\u201d de combustible para calentar las casas, la electricidad falta casi todos los d\u00edas y el dinero vale cada vez menos.<\/p>\n<p>La religiosa se\u00f1ala la crisis del vecino L\u00edbano como una de las causas de esta situaci\u00f3n. A trav\u00e9s del L\u00edbano llegaba mucha financiaci\u00f3n que ahora es imposible.<\/p>\n<p>An\u00e1lisis en el que coincide Mons. Nassar, que asegura que la crisis bancaria del pa\u00eds vecino est\u00e1 trayendo graves dificultades a la ayuda humanitaria de varios pa\u00edses del mundo para Siria. Lo que el arzobispo denomina la \u201cruta de Sim\u00f3n de Cirene\u201d- la ruta de la solidaridad con el que carga la cruz \u2013 ha sido bloqueada sin compasi\u00f3n, lo que lleva a un empeoramiento total.<\/p>\n<p>La crisis en el L\u00edbano ha bloqueado las cuentas del pueblo sirio, tanto de empresas como las cuentas privadas, desde las que se llevaban lo que Nassar denomina \u2018movimientos de caridad\u2019.\u00a0 Seg\u00fan el prelado esta nueva situaci\u00f3n ha empobrecido tambi\u00e9n a la Iglesia, que no es otra cosa \u201cque un Muro de Lamentaci\u00f3n donde uno llega a llorar, a pedir ayuda y a buscar sin ostentaci\u00f3n y en silencio alg\u00fan consuelo, a vivir la Pasi\u00f3n de Cristo antes de la Semana Santa.\u201c<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan Mons. Samir Nassar, arzobispo maronita de Damasco, la continuidad de los proyectos de ayuda humanitaria en el pa\u00eds est\u00e1<\/p>\n","protected":false},"author":4258341447,"featured_media":130157,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[746],"tags":[],"country":[390],"class_list":["post-130159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","country-siria"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arzobispo Samir Nassar: \u201cSiria vive una Cuaresma anticipada\u201d<\/title>\n<meta name=\"description\" content=\"Seg\u00fan Mons. Samir Nassar, arzobispo maronita de Damasco, la continuidad de los proyectos de ayuda humanitaria en el pa\u00eds est\u00e1 en peligroLa situaci\u00f3n econ\u00f3mica en Siria est\u00e1 empeorando. \u201cEsta crisis, que es algo diferente a lo experimentado durante los d\u00edas de guerra, ha obligado a la gente a vivir una especie de ayuno cuaresmal anticipado. Poder poner comida sobre la mesa se ha convertido en la pesadilla diaria,\u201d escribe Mons. Samir Nassar, arzobispo de Damasco, en un mensaje a la sede internacional de la fundaci\u00f3n pontificia ACN.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arzobispo Samir Nassar: \u201cSiria vive una Cuaresma anticipada\u201d\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan Mons. Samir Nassar, arzobispo maronita de Damasco, la continuidad de los proyectos de ayuda humanitaria en el pa\u00eds est\u00e1 en peligroLa situaci\u00f3n econ\u00f3mica en Siria est\u00e1 empeorando. \u201cEsta crisis, que es algo diferente a lo experimentado durante los d\u00edas de guerra, ha obligado a la gente a vivir una especie de ayuno cuaresmal anticipado. Poder poner comida sobre la mesa se ha convertido en la pesadilla diaria,\u201d escribe Mons. Samir Nassar, arzobispo de Damasco, en un mensaje a la sede internacional de la fundaci\u00f3n pontificia ACN.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-29T08:56:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-29T09:00:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/01\/syria2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Arzobispo Samir Nassar: \u201cSiria vive una Cuaresma anticipada\u201d\",\"datePublished\":\"2020-01-29T08:56:08+00:00\",\"dateModified\":\"2020-01-29T09:00:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/\"},\"wordCount\":526,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/syria2.jpg\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/\",\"name\":\"Arzobispo Samir Nassar: \u201cSiria vive una Cuaresma anticipada\u201d\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/syria2.jpg\",\"datePublished\":\"2020-01-29T08:56:08+00:00\",\"dateModified\":\"2020-01-29T09:00:04+00:00\",\"description\":\"Seg\u00fan Mons. Samir Nassar, arzobispo maronita de Damasco, la continuidad de los proyectos de ayuda humanitaria en el pa\u00eds est\u00e1 en peligroLa situaci\u00f3n econ\u00f3mica en Siria est\u00e1 empeorando. \u201cEsta crisis, que es algo diferente a lo experimentado durante los d\u00edas de guerra, ha obligado a la gente a vivir una especie de ayuno cuaresmal anticipado. Poder poner comida sobre la mesa se ha convertido en la pesadilla diaria,\u201d escribe Mons. Samir Nassar, arzobispo de Damasco, en un mensaje a la sede internacional de la fundaci\u00f3n pontificia ACN.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/syria2.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/syria2.jpg\",\"width\":1400,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTICIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arzobispo Samir Nassar: \u201cSiria vive una Cuaresma anticipada\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arzobispo Samir Nassar: \u201cSiria vive una Cuaresma anticipada\u201d","description":"Seg\u00fan Mons. Samir Nassar, arzobispo maronita de Damasco, la continuidad de los proyectos de ayuda humanitaria en el pa\u00eds est\u00e1 en peligroLa situaci\u00f3n econ\u00f3mica en Siria est\u00e1 empeorando. \u201cEsta crisis, que es algo diferente a lo experimentado durante los d\u00edas de guerra, ha obligado a la gente a vivir una especie de ayuno cuaresmal anticipado. Poder poner comida sobre la mesa se ha convertido en la pesadilla diaria,\u201d escribe Mons. Samir Nassar, arzobispo de Damasco, en un mensaje a la sede internacional de la fundaci\u00f3n pontificia ACN.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/","og_locale":"es_ES","og_type":"article","og_title":"Arzobispo Samir Nassar: \u201cSiria vive una Cuaresma anticipada\u201d","og_description":"Seg\u00fan Mons. Samir Nassar, arzobispo maronita de Damasco, la continuidad de los proyectos de ayuda humanitaria en el pa\u00eds est\u00e1 en peligroLa situaci\u00f3n econ\u00f3mica en Siria est\u00e1 empeorando. \u201cEsta crisis, que es algo diferente a lo experimentado durante los d\u00edas de guerra, ha obligado a la gente a vivir una especie de ayuno cuaresmal anticipado. Poder poner comida sobre la mesa se ha convertido en la pesadilla diaria,\u201d escribe Mons. Samir Nassar, arzobispo de Damasco, en un mensaje a la sede internacional de la fundaci\u00f3n pontificia ACN.","og_url":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2020-01-29T08:56:08+00:00","article_modified_time":"2020-01-29T09:00:04+00:00","og_image":[{"width":1400,"height":438,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/01\/syria2.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"ACN Press Team","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Arzobispo Samir Nassar: \u201cSiria vive una Cuaresma anticipada\u201d","datePublished":"2020-01-29T08:56:08+00:00","dateModified":"2020-01-29T09:00:04+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/"},"wordCount":526,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/01\/syria2.jpg","articleSection":["NOTICIAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/","url":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/","name":"Arzobispo Samir Nassar: \u201cSiria vive una Cuaresma anticipada\u201d","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/01\/syria2.jpg","datePublished":"2020-01-29T08:56:08+00:00","dateModified":"2020-01-29T09:00:04+00:00","description":"Seg\u00fan Mons. Samir Nassar, arzobispo maronita de Damasco, la continuidad de los proyectos de ayuda humanitaria en el pa\u00eds est\u00e1 en peligroLa situaci\u00f3n econ\u00f3mica en Siria est\u00e1 empeorando. \u201cEsta crisis, que es algo diferente a lo experimentado durante los d\u00edas de guerra, ha obligado a la gente a vivir una especie de ayuno cuaresmal anticipado. Poder poner comida sobre la mesa se ha convertido en la pesadilla diaria,\u201d escribe Mons. Samir Nassar, arzobispo de Damasco, en un mensaje a la sede internacional de la fundaci\u00f3n pontificia ACN.","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/01\/syria2.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/01\/syria2.jpg","width":1400,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/arzobispo-samir-nassar-siria-vive-una-cuaresma-anticipada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"NOTICIAS","item":"https:\/\/acninternational.org\/es\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Arzobispo Samir Nassar: \u201cSiria vive una Cuaresma anticipada\u201d"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/es\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/130159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=130159"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/130159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/130157"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=130159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=130159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=130159"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=130159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}