{"id":122653,"date":"2019-09-19T00:00:00","date_gmt":"2019-09-18T22:00:00","guid":{"rendered":"https:\/\/acninternational.org\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/"},"modified":"2022-09-13T11:12:20","modified_gmt":"2022-09-13T09:12:20","slug":"campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/","title":{"rendered":"Campa\u00f1a de ACN para Siria: El Papa bendijo un icono mariano"},"content":{"rendered":"<p>El mismo d\u00eda en que se distribuyeron en las parroquias sirias los seis mil rosarios bendecidos por el Papa Francisco el pasado 15 de agosto, el Papa bendijo el icono de la Beata Virgen Mar\u00eda de los Dolores, consoladora de los sirios.<\/p>\n<p>Este es un nuevo gesto del Santo Padre de apoyo a la campa\u00f1a de oraci\u00f3n \u00abConsuela a mi pueblo\u201d, promovida por <em>Ayuda a la Iglesia Necesitada<\/em> junto con las Iglesias Cat\u00f3lica y Ortodoxa de Siria, en favor de los cristianos sirios cuyos familiares fueron secuestrados o asesinados en los ocho a\u00f1os de conflicto.<\/p>\n<figure id=\"attachment_56129\" aria-describedby=\"caption-attachment-56129\" style=\"width: 420px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-56129 size-medium\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/WEBSITE_template_gallery-12.jpg\" alt=\"El Papa Francisco se reuni\u00f3 con una delegaci\u00f3n de ACN encabezada por el Cardenal Mauro Piacenza.\" width=\"420\" height=\"280\" \/><figcaption id=\"caption-attachment-56129\" class=\"wp-caption-text\">El Papa Francisco se reuni\u00f3 con una delegaci\u00f3n de ACN encabezada por el Cardenal Mauro Piacenza.<\/figcaption><\/figure>\n<p>En la Casa Santa Marta, el Papa Francisco se reuni\u00f3 con una delegaci\u00f3n de ACN encabezada por el Cardenal Mauro Piacenza, presidente internacional de la Fundaci\u00f3n Pontificia, y bendijo un icono creado por un artista greco-ortodoxo para esta campa\u00f1a de oraci\u00f3n. Tambi\u00e9n formaron parte de la delegaci\u00f3n el creador del icono y algunos directores nacionales de ACN. Ya el 15 de agosto, el Pont\u00edfice hab\u00eda mostrado su apoyo a la iniciativa invitando excepcionalmente al director ejecutivo internacional de ACN, Thomas Heine-Geldern, a aparecer en el balc\u00f3n de su estudio al final del \u00c1ngelus, durante la bendici\u00f3n de los rosarios.<\/p>\n<p>Los seis mil rosarios bendecidos por el Santo Padre, realizados por artesanos cristianos de Bel\u00e9n y Damasco, se distribuyeron ayer en las parroquias de las 34 di\u00f3cesis sirias, tanto cat\u00f3licas como ortodoxas, con ocasi\u00f3n de la fiesta de los Siete Dolores de la Beat\u00edsima Virgen Mar\u00eda. Durante las Santas Misas y las diversas procesiones, los fieles rezaron por las personas asesinadas y secuestradas y por sus familias. <strong>Alrededor de 2.000 familias cristianas perdieron a uno de sus seres queridos durante el conflicto, y 800 fueron v\u00edctimas de un secuestro.<\/strong> Junto con los rosarios se distribuyeron Biblias en \u00e1rabe donadas por ACN y crucifijos de madera de olivo de Tierra Santa, bendecidas por el Patriarca siro-ortodoxo Efr\u00e9n II.<\/p>\n<figure id=\"attachment_56130\" aria-describedby=\"caption-attachment-56130\" style=\"width: 420px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-56130 size-medium\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/WEBSITE_template_gallery2-9.jpg\" alt=\"El Papa bendijo el icono de la Beata Virgen Mar\u00eda de los Dolores, consoladora de los sirios.\" width=\"420\" height=\"280\" \/><figcaption id=\"caption-attachment-56130\" class=\"wp-caption-text\">El Papa bendijo el icono de la Beata Virgen Mar\u00eda de los Dolores, consoladora de los sirios.<\/figcaption><\/figure>\n<p>El Papa Francisco se ha sumado repetidamente a las iniciativas de ACN en favor de la atormentada poblaci\u00f3n siria. As\u00ed, el domingo 2 de diciembre, despu\u00e9s del \u00c1ngelus, el Pont\u00edfice encendi\u00f3 una vela en el marco de la campa\u00f1a de oraci\u00f3n de la Fundaci\u00f3n Pontificia \u00abVelas por la Paz en Siria\u00bb.<\/p>\n<p>Despu\u00e9s del encuentro de ayer, el Cardenal Mauro Piacenza, con intensa gratitud hacia el Santo Padre por su afectuosa cercan\u00eda siempre que hay l\u00e1grimas que secar, resalt\u00f3 que el mundo tiene gran necesidad de compasi\u00f3n. La fiesta de Nuestra Se\u00f1ora de los Dolores nos da una lecci\u00f3n de verdadera y profunda compasi\u00f3n y de ternura maternal. Mar\u00eda sufre <strong>por<\/strong> Jes\u00fas, pero tambi\u00e9n sufre <strong>con<\/strong> Jes\u00fas, y la pasi\u00f3n de Cristo es compartir todo el dolor de los hombres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mismo d\u00eda en que se distribuyeron en las parroquias sirias los seis mil rosarios bendecidos por el Papa Francisco<\/p>\n","protected":false},"author":4258341447,"featured_media":89514,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[746],"tags":[],"country":[390],"class_list":["post-122653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","country-siria"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Campa\u00f1a de ACN para Siria: El Papa bendijo un icono mariano | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campa\u00f1a de ACN para Siria: El Papa bendijo un icono mariano\" \/>\n<meta property=\"og:description\" content=\"El mismo d\u00eda en que se distribuyeron en las parroquias sirias los seis mil rosarios bendecidos por el Papa Francisco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-18T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-13T09:12:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Campa%C3%B1a-de-ACN-para-Siria-El-Papa-bendecido-un-icono-mariano-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Campa\u00f1a de ACN para Siria: El Papa bendijo un icono mariano\",\"datePublished\":\"2019-09-18T22:00:00+00:00\",\"dateModified\":\"2022-09-13T09:12:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/\"},\"wordCount\":537,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Campa%C3%B1a-de-ACN-para-Siria-El-Papa-bendecido-un-icono-mariano-image.jpg\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/\",\"name\":\"Campa\u00f1a de ACN para Siria: El Papa bendijo un icono mariano | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Campa%C3%B1a-de-ACN-para-Siria-El-Papa-bendecido-un-icono-mariano-image.jpg\",\"datePublished\":\"2019-09-18T22:00:00+00:00\",\"dateModified\":\"2022-09-13T09:12:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Campa%C3%B1a-de-ACN-para-Siria-El-Papa-bendecido-un-icono-mariano-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Campa%C3%B1a-de-ACN-para-Siria-El-Papa-bendecido-un-icono-mariano-image.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Campa\u00f1a de ACN para Siria: El Papa bendecido un icono mariano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTICIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Campa\u00f1a de ACN para Siria: El Papa bendijo un icono mariano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Campa\u00f1a de ACN para Siria: El Papa bendijo un icono mariano | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/","og_locale":"es_ES","og_type":"article","og_title":"Campa\u00f1a de ACN para Siria: El Papa bendijo un icono mariano","og_description":"El mismo d\u00eda en que se distribuyeron en las parroquias sirias los seis mil rosarios bendecidos por el Papa Francisco","og_url":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2019-09-18T22:00:00+00:00","article_modified_time":"2022-09-13T09:12:20+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Campa%C3%B1a-de-ACN-para-Siria-El-Papa-bendecido-un-icono-mariano-image.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"ACN Press Team","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Campa\u00f1a de ACN para Siria: El Papa bendijo un icono mariano","datePublished":"2019-09-18T22:00:00+00:00","dateModified":"2022-09-13T09:12:20+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/"},"wordCount":537,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Campa%C3%B1a-de-ACN-para-Siria-El-Papa-bendecido-un-icono-mariano-image.jpg","articleSection":["NOTICIAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/","url":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/","name":"Campa\u00f1a de ACN para Siria: El Papa bendijo un icono mariano | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Campa%C3%B1a-de-ACN-para-Siria-El-Papa-bendecido-un-icono-mariano-image.jpg","datePublished":"2019-09-18T22:00:00+00:00","dateModified":"2022-09-13T09:12:20+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Campa%C3%B1a-de-ACN-para-Siria-El-Papa-bendecido-un-icono-mariano-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Campa%C3%B1a-de-ACN-para-Siria-El-Papa-bendecido-un-icono-mariano-image.jpg","width":1200,"height":628,"caption":"Campa\u00f1a de ACN para Siria: El Papa bendecido un icono mariano"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/campana-de-acn-para-siria-el-papa-bendecido-un-icono-mariano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"NOTICIAS","item":"https:\/\/acninternational.org\/es\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Campa\u00f1a de ACN para Siria: El Papa bendijo un icono mariano"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/es\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/122653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=122653"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/122653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/89514"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=122653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=122653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=122653"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=122653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}