{"id":117829,"date":"2018-08-01T00:00:00","date_gmt":"2018-07-31T22:00:00","guid":{"rendered":"https:\/\/acninternational.org\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/"},"modified":"2018-08-01T00:00:00","modified_gmt":"2018-07-31T22:00:00","slug":"una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/","title":{"rendered":"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda"},"content":{"rendered":"<p>El Vicariato Apost\u00f3lico de Gambella se encuentra en el extremo oeste de Etiop\u00eda, donde hace frontera con Sud\u00e1n del Sur. Es una zona subdesarrollada y pobre en la que se suceden, una y otra vez, la violencia, los disturbios y los conflictos. La mayor\u00eda de los habitantes siguen profesando las religiones tradicionales de las tribus y nunca han o\u00eddo hablar de Jesucristo. No obstante, est\u00e1n abiertos a la Iglesia Cat\u00f3lica, y en cuanto la Iglesia est\u00e1 presente en un lugar, la gente tambi\u00e9n pide ser asistida por un sacerdote.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_42584\" aria-describedby=\"caption-attachment-42584\" style=\"width: 690px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-42584\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-20131206-03318-post.jpg\" alt=\"Holy Mass in at Akado village.\" width=\"690\" height=\"452\" \/><figcaption id=\"caption-attachment-42584\" class=\"wp-caption-text\">Santa Misa en el pueblo de Akado.<\/figcaption><\/figure>\n<p>As\u00ed tambi\u00e9n ocurri\u00f3 cuando, hace ocho a\u00f1os, unos funcionarios civiles cat\u00f3licos fueron trasladados a la ciudad de Nyininyang, donde no hab\u00eda ni iglesia cat\u00f3lica ni sacerdote. Estos cat\u00f3licos empezaron a reunirse para rezar a la intemperie y escribieron cartas al Obispo para pedirle que les enviara a un sacerdote. El Obispo encarg\u00f3 la asistencia pastoral en la ciudad a un misionero italiano que, al principio, ni siquiera dispon\u00eda de un alojamiento fijo, pero que, incansable, se puso al servicio de la gente. Y as\u00ed surgi\u00f3 la parroquia de la Santa Cruz. Muy pronto, los habitantes de los pueblos circundantes quisieron saber m\u00e1s acerca de la Buena Nueva de Cristo. Pese al mal estado de las carreteras y los numerosos retos, el sacerdote comenz\u00f3 a asistir tambi\u00e9n a la gente de los alrededores que nunca hab\u00eda o\u00eddo hablar de la fe cat\u00f3lica. El n\u00famero de poblados que quer\u00edan ser instruidos en la fe fue en aumento, y este a\u00f1o se han vuelto a celebrar m\u00e1s de doscientos bautizos en la parroquia (!).<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_42585\" aria-describedby=\"caption-attachment-42585\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-42585\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-20131206-03322-post.jpg\" alt=\"Holy Mass in at Akado village.\" width=\"630\" height=\"430\" \/><figcaption id=\"caption-attachment-42585\" class=\"wp-caption-text\">Santa Misa en el pueblo de Akado.<\/figcaption><\/figure>\n<p>Uno de estos poblados es Tormorok. All\u00ed ya viven numerosos cat\u00f3licos, y cada vez m\u00e1s personas desean bautizarse. A los creyentes les gustar\u00eda tener una iglesia, pues para acceder a la sede parroquial tienen que recorrer un trayecto de seis horas a pie, lo cual no es posible ni para los ni\u00f1os ni para los ancianos. Hasta ahora, los creyentes vienen reuni\u00e9ndose en una caba\u00f1a con un techo de paja, pero el nuevo p\u00e1rroco, P. Mesert Tadesse, quiere ayudarlos para que por fin puedan erigir una capilla propia.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_42583\" aria-describedby=\"caption-attachment-42583\" style=\"width: 630px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-42583 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-20140220-05378-post.jpg\" alt=\"pueblo de Akado\" width=\"630\" height=\"400\" \/><figcaption id=\"caption-attachment-42583\" class=\"wp-caption-text\">Pueblo de Akado<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Vicariato Apost\u00f3lico de Gambella se encuentra en el extremo oeste de Etiop\u00eda, donde hace frontera con Sud\u00e1n del Sur.<\/p>\n","protected":false},"author":1,"featured_media":117830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[721,714],"tags":[],"country":[],"class_list":["post-117829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","category-proyecto"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Una capilla en el poblado remoto de Gambella, en Etiop\u00eda | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda\" \/>\n<meta property=\"og:description\" content=\"El Vicariato Apost\u00f3lico de Gambella se encuentra en el extremo oeste de Etiop\u00eda, donde hace frontera con Sud\u00e1n del Sur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-31T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Una-capilla-en-el-poblado-remoto-de-Gambella-en-Etiop%C3%ADa-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_acn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_acn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/\"},\"author\":{\"name\":\"admin_acn\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\"},\"headline\":\"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda\",\"datePublished\":\"2018-07-31T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/\"},\"wordCount\":430,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Una-capilla-en-el-poblado-remoto-de-Gambella-en-Etiop%C3%ADa-image.jpg\",\"articleSection\":[\"CONSTRUCCI\u00d3N\",\"PROYECTO\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/\",\"name\":\"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Una-capilla-en-el-poblado-remoto-de-Gambella-en-Etiop%C3%ADa-image.jpg\",\"datePublished\":\"2018-07-31T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Una-capilla-en-el-poblado-remoto-de-Gambella-en-Etiop%C3%ADa-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Una-capilla-en-el-poblado-remoto-de-Gambella-en-Etiop%C3%ADa-image.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROYECTO\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/proyecto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CONSTRUCCI\u00d3N\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/proyecto\\\/construccion\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\",\"name\":\"admin_acn\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/admin_acn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/","og_locale":"es_ES","og_type":"article","og_title":"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda","og_description":"El Vicariato Apost\u00f3lico de Gambella se encuentra en el extremo oeste de Etiop\u00eda, donde hace frontera con Sud\u00e1n del Sur.","og_url":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2018-07-31T22:00:00+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Una-capilla-en-el-poblado-remoto-de-Gambella-en-Etiop%C3%ADa-image.jpg","type":"image\/jpeg"}],"author":"admin_acn","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"admin_acn","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/"},"author":{"name":"admin_acn","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc"},"headline":"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda","datePublished":"2018-07-31T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/"},"wordCount":430,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Una-capilla-en-el-poblado-remoto-de-Gambella-en-Etiop%C3%ADa-image.jpg","articleSection":["CONSTRUCCI\u00d3N","PROYECTO"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/","url":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/","name":"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Una-capilla-en-el-poblado-remoto-de-Gambella-en-Etiop%C3%ADa-image.jpg","datePublished":"2018-07-31T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Una-capilla-en-el-poblado-remoto-de-Gambella-en-Etiop%C3%ADa-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Una-capilla-en-el-poblado-remoto-de-Gambella-en-Etiop%C3%ADa-image.jpg","width":1200,"height":628,"caption":"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/una-capilla-en-el-poblado-remoto-de-gambella-en-etiopia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"PROYECTO","item":"https:\/\/acninternational.org\/es\/category\/proyecto\/"},{"@type":"ListItem","position":3,"name":"CONSTRUCCI\u00d3N","item":"https:\/\/acninternational.org\/es\/category\/proyecto\/construccion\/"},{"@type":"ListItem","position":4,"name":"Una capilla en el poblado remoto de Gambella, en Etiop\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc","name":"admin_acn","url":"https:\/\/acninternational.org\/es\/author\/admin_acn\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/117829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=117829"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/117829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/117830"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=117829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=117829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=117829"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=117829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}