{"id":117792,"date":"2018-07-31T00:00:00","date_gmt":"2018-07-30T22:00:00","guid":{"rendered":"https:\/\/acninternational.org\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/"},"modified":"2018-07-31T00:00:00","modified_gmt":"2018-07-30T22:00:00","slug":"sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/","title":{"rendered":"Sacerdotes en la frontera: instrumentos de consuelo espiritual"},"content":{"rendered":"<p>\u201cMuchas personas llegan llorando, con graves problemas, preocupados o tristes porque se van del pa\u00eds, porque no tienen nada que comer, o les falta medicina, y nuestra misi\u00f3n es consolar a la luz de la Palabra de Dios, y con la oraci\u00f3n\u201d, manifiesta el sacerdote Esteban Galvis, p\u00e1rroco de la iglesia Nuestra Se\u00f1ora de Lourdes en la poblaci\u00f3n de Aguas Calientes (Venezuela), en la frontera colombo venezolana.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_42533\" aria-describedby=\"caption-attachment-42533\" style=\"width: 690px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-42533 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-20180717-73959-post.jpg\" alt=\"Fr. Esteban Galvis\" width=\"690\" height=\"540\" \/><figcaption id=\"caption-attachment-42533\" class=\"wp-caption-text\">P. Esteban Galvis, p\u00e1rroco de la iglesia Nuestra Se\u00f1ora de Lourdes en la poblaci\u00f3n de Aguas Calientes (Venezuela)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>La atenci\u00f3n a los migrantes en la frontera y tambi\u00e9n a la misma poblaci\u00f3n empobrecida de la frontera, no es s\u00f3lo material a pesar de las limitaciones, sino principalmente pastoral y espiritual.<\/p>\n<p>\u201cVivimos una realidad muy cruda, nos encontramos con una situaci\u00f3n particular \u2013dice el presb\u00edtero Estaban Galvis- por un lado, los inmigrantes que pasan por nuestras parroquias y por el otro lado la pobreza de las familias de la frontera, nuestra misma gente sigue siendo afectada por la situaci\u00f3n cr\u00edtica el pa\u00eds\u201d.<\/p>\n<p>\u201cSomos los pobres atendiendo a los pobres. Aunque sea con un vaso de agua panela\u201d, afirma.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_42534\" aria-describedby=\"caption-attachment-42534\" style=\"width: 690px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-42534 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-20180717-73954-post.jpg\" alt=\"Fr. Esteban Galvis. Holy Mass\" width=\"690\" height=\"460\" \/><figcaption id=\"caption-attachment-42534\" class=\"wp-caption-text\">P. Esteban Galvis en la Santa Misa<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Comenta el p\u00e1rroco de Aguas Calientes que \u201ccada persona o cada grupo familiar tiene su historia particular, pero todos conf\u00edan en Dios. Y buscan en el sacerdote y las parroquias un refugio para ser fortalecidos y consolados. Vienen a confesarse, y a colocarse en las manos de Dios\u201d.<\/p>\n<p>\u201cUna historia significativa ha sido la de Juan Carlos, que viaj\u00f3 con su esposa y su hijo desde el estado Falc\u00f3n, para ir a otro pa\u00eds, pero lleg\u00f3 ac\u00e1 sin dinero para continuar\u201d, relata el p\u00e1rroco Galvis.<\/p>\n<p>\u201cUn hombre que lloraba junto a su pareja porque no sab\u00edan qu\u00e9 hacer. Lo primero que he hecho es orar con ellos para pedir a Dios que nos iluminara, luego compart\u00ed con ellos el alimento. Y durante el d\u00eda, otra persona de la comunidad les ofreci\u00f3 donde pernoctar, ellos decidieron quedarse en la zona y van durante el d\u00eda a trabajar a C\u00facuta (Colombia). Poco a poco han ido solucionando con la ayuda de Dios\u201d.<\/p>\n<p>En las parroquias de las fronteras la pastoral social ha sido fortalecida principalmente con la atenci\u00f3n y el acompa\u00f1amiento espiritual, \u201ces ante todo nuestra principal misi\u00f3n. Muchas personas llegan llorando al templo, con sus problemas y preocupaciones. Y nos corresponde a nosotros ser instrumentos de Dios para consolar al pueblo\u201d, dice el sacerdote.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_42535\" aria-describedby=\"caption-attachment-42535\" style=\"width: 690px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-42535 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-20180717-73958-post.jpg\" alt=\"Fr. Esteban Galvis. Holy Mass\" width=\"690\" height=\"460\" \/><figcaption id=\"caption-attachment-42535\" class=\"wp-caption-text\">P. Esteban Galvis en la Santa Misa<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Como parte de la actividad pastoral la parroquia Nuestra Se\u00f1ora de Lourdes, en Aguas Calientes, organiza jornadas de Adoraci\u00f3n Eucar\u00edstica, y gu\u00eda espiritual permanente para las personas que buscan consuelo.<\/p>\n<p>\u201cDesde el cierre de la frontera \u2013se\u00f1ala le padre Galvis- motivamos campa\u00f1as de acci\u00f3n social compartiendo un poco de alimento, pero la inflaci\u00f3n nos va haciendo imposible ese trabajo. Seguimos ayudando, pero con los m\u00e1s m\u00ednimo, y principalmente a los ancianos y a los ni\u00f1os. Porque no nos alcanza para todos\u201d.<\/p>\n<p>En el Informe de Movilidad Humana Venezolana, publicado en mayo por el Servicio a Refugiados de los Jesuitas en Venezuela, advierte que las principales causas que han motivado a los venezolanos a cruzar la frontera ha sido la inseguridad, la preocupaci\u00f3n por lo que sucede en el pa\u00eds, el hambre, altos niveles de estr\u00e9s d\u00eda a d\u00eda, la incertidumbre de no saber que va pasar, y la falta de medicina para tratamientos m\u00e9dicos. El 83.6% ha emigrado buscando ambientes m\u00e1s seguros y 31.2% se vieron forzados a moverse de su sitio original.<\/p>\n<p>Recientemente se realiz\u00f3 la Asamblea de Laicos de la Frontera, que junto a sus sacerdotes y el Obispo de la Di\u00f3cesis de San Crist\u00f3bal refirmaron sus compromisos de servicio pastoral especial y permanente a la zona fronteriza.<\/p>\n<p>Enfatiza el padre Esteban Galvis que un compromiso urgente del cristiano debe ser \u201cla oraci\u00f3n y el ayuno, esto ayudar\u00e1 a salir de esta situaci\u00f3n\u201d.\u00a0 Y finalmente invita a unirse a esta tarea: \u201csomos el consuelo de quienes viven, y vienen a sufrir a la frontera, e invit\u00f3 a quienes se quieran sumar a esta tarea que oren por la situaci\u00f3n que se vive ac\u00e1, pues Dios es una nuestra \u00fanica fuerza\u201d.<\/p>\n<p><em>Aid to the Church in Need visit\u00f3 recientemente la ciudad de San Antonio de Tachira (Colombia) para ofrecer apoyo y solidaridad a las di\u00f3cesis fronterizas de Venezuela y Colombia en esta dif\u00edcil situaci\u00f3n que est\u00e1 pasando y estudiar futuras ayudas para una proyecto de la Casa del Migrante.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cMuchas personas llegan llorando, con graves problemas, preocupados o tristes porque se van del pa\u00eds, porque no tienen nada que<\/p>\n","protected":false},"author":1,"featured_media":117793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[760,713],"tags":[],"country":[],"class_list":["post-117792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-historias"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sacerdotes en la frontera: instrumentos de consuelo espiritual | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sacerdotes en la frontera: instrumentos de consuelo espiritual\" \/>\n<meta property=\"og:description\" content=\"\u201cMuchas personas llegan llorando, con graves problemas, preocupados o tristes porque se van del pa\u00eds, porque no tienen nada que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-30T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_acn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_acn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/\"},\"author\":{\"name\":\"admin_acn\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\"},\"headline\":\"Sacerdotes en la frontera: instrumentos de consuelo espiritual\",\"datePublished\":\"2018-07-30T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/\"},\"wordCount\":830,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual-image.jpg\",\"articleSection\":[\"DESTACADO\",\"HISTORIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/\",\"name\":\"Sacerdotes en la frontera: instrumentos de consuelo espiritual | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual-image.jpg\",\"datePublished\":\"2018-07-30T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual-image.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Sacerdotes en la frontera: instrumentos de consuelo espiritual\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DESTACADO\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/destacado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sacerdotes en la frontera: instrumentos de consuelo espiritual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\",\"name\":\"admin_acn\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/admin_acn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sacerdotes en la frontera: instrumentos de consuelo espiritual | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/","og_locale":"es_ES","og_type":"article","og_title":"Sacerdotes en la frontera: instrumentos de consuelo espiritual","og_description":"\u201cMuchas personas llegan llorando, con graves problemas, preocupados o tristes porque se van del pa\u00eds, porque no tienen nada que","og_url":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2018-07-30T22:00:00+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual-image.jpg","type":"image\/jpeg"}],"author":"admin_acn","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"admin_acn","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/"},"author":{"name":"admin_acn","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc"},"headline":"Sacerdotes en la frontera: instrumentos de consuelo espiritual","datePublished":"2018-07-30T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/"},"wordCount":830,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual-image.jpg","articleSection":["DESTACADO","HISTORIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/","url":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/","name":"Sacerdotes en la frontera: instrumentos de consuelo espiritual | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual-image.jpg","datePublished":"2018-07-30T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual-image.jpg","width":1200,"height":628,"caption":"Sacerdotes en la frontera: instrumentos de consuelo espiritual"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/sacerdotes-en-la-frontera-instrumentos-de-consuelo-espiritual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"DESTACADO","item":"https:\/\/acninternational.org\/es\/category\/destacado\/"},{"@type":"ListItem","position":3,"name":"Sacerdotes en la frontera: instrumentos de consuelo espiritual"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc","name":"admin_acn","url":"https:\/\/acninternational.org\/es\/author\/admin_acn\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/117792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=117792"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/117792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/117793"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=117792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=117792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=117792"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=117792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}