{"id":116718,"date":"2018-01-25T00:00:00","date_gmt":"2018-01-24T23:00:00","guid":{"rendered":"https:\/\/acninternational.org\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/"},"modified":"2018-01-25T00:00:00","modified_gmt":"2018-01-24T23:00:00","slug":"republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/","title":{"rendered":"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Mientras permanec\u00eda escondido junto a otros sacerdotes, el P. Yovane Cox, misionero chileno en Centro\u00e1frica, se contact\u00f3 con la Fundaci\u00f3n Ayuda a la Iglesia que Sufre (ACN) para pedir urgente nuestra oraci\u00f3n. \u201cLa catedral de Bangassou est\u00e1 siendo atacada\u201d, nos escribi\u00f3 el pasado viernes 19 de enero. \u201cLa situaci\u00f3n es bastante cr\u00edtica porque este ataque estaba ya anunciado y las fuerzas de la ONU que est\u00e1n a cargo de la seguridad aqu\u00ed no han hecho caso de lo que se les ha dicho. Pareciera de que hay una voluntad de que una masacre pase aqu\u00ed en la catedral y en el sitio donde viven los musulmanes\u201d, nos cuenta el sacerdote.<\/p>\n<p>En mayo de 2017, 2.000 musulmanes se refugiaron en el terreno de la Iglesia cat\u00f3lica (a 200 metros de la catedral, en el seminario menor de la di\u00f3cesis) en busca de protecci\u00f3n. Hoy quedan un poco menos que mil. \u201cDetr\u00e1s de todo este lugar, est\u00e1 rodeado de hombres armados esperando que alg\u00fan musulm\u00e1n salga para matarlo\u201d, cuenta el Padre Yovane mientras se refiere a las condiciones inhumanas en las que permanecen. \u201cLos musulmanes intentan salir del campo para ir a buscar le\u00f1a, otros para aprovechar de robar en las casas que han sido abandonadas alrededor del sitio (en busca del alimento necesario para sobrevivir)\u201d, dice. Ayer, uno de estos musulmanes fue atrapado por los antibalakas (grupo rebelde anti musulm\u00e1n) y asesinado en el pueblo. Eso exacerb\u00f3 much\u00edsimo los \u00e1nimos de los musulmanes que est\u00e1n refugiados en el terreno de la Iglesia. Seg\u00fan cuenta el Padre, si no fuera por el contingente camerun\u00e9s que se interpuso, se hubiera vivido una situaci\u00f3n a\u00fan m\u00e1s cr\u00edtica.<\/p>\n<p>Desde la misi\u00f3n cat\u00f3lica ven con impotencia c\u00f3mo, en cualquier minuto, los antibalakas van a entrar en el campamento con el objetivo de matar a los musulmanes que se encuentran refugiados. Esto, sin que nadie intervenga para impedirlo. \u201cLo que se est\u00e1 buscando con esta quietud de las autoridades del Estado y con esta quietud de las Naciones unidas al no querer movilizar a estos pocos musulmanes que quedan en este sitio, es buscar simplemente que haya un afrontamiento entre los grupos y que haya un ba\u00f1o de sangre. Eso es lo que estamos denunciando y lo que estamos pidiendo: que por favor deslocalicen el sitio porque es la \u00fanica manera de salvar a los que quedan, que son la mayor\u00eda mujeres y ni\u00f1os\u201d, nos dice el sacerdote chileno.<\/p>\n<p>Han pasado ya nueve meses desde que los enfrentamientos entre los rebeldes antibalakas y los musulmanes no dan tregua. En este pa\u00eds, cuya historia est\u00e1 marcada por la violencia y la guerra, hoy se vive uno de los cap\u00edtulos m\u00e1s duros. \u201cSe vive una situaci\u00f3n en la que ninguna persona tiene el control: ni el Gobierno, ni las Naciones Unidas, ni las autoridades locales y menos nosotros como Iglesia Cat\u00f3lica\u201d dice el Padre, quien tambi\u00e9n nos ha comentado que la Iglesia es la \u00fanica organizaci\u00f3n que permanece ah\u00ed para ayudar: \u201cno hay otro organismo, la mayor\u00eda se han ido. El \u00faltimo fue M\u00e9dicos sin Fronteras\u201d.<\/p>\n<p>Cuando le preguntamos sobre la situaci\u00f3n que viven los cristianos en la di\u00f3cesis nos cuenta que \u201clos cristianos viven en su mayor\u00eda escondidos en sus campos o en los barrios. Con mucho miedo de reunirse en las iglesias o en la catedral. La Misa se hace los domingos y los que vienen no superan las 15 personas. Los sacerdotes nos vemos limitados y las pastorales totalmente inactivas, una parte del clero se encuentra en la capital y el resto limitando nuestras actividades\u201d. Esto, debido a que hay una divisi\u00f3n muy grande entre las posiciones radicales de los musulmanes que ven a la Iglesia Cat\u00f3lica como c\u00f3mplice (junto a los antibalakas) y, por otro lado, los antibalakas que la ven como traidora al guardar a los musulmanes en su seno. \u201cHay una incomprensi\u00f3n, un antagonismo muy grande y la que se encuentra al medio es la Iglesia que, de un lado y de otro, es un cible (objetivo) perfecto para cualquiera que pierda las riendas de la situaci\u00f3n\u201d, cuenta con preocupaci\u00f3n el Padre.<\/p>\n<p>En estos momentos, solo dos de las ocho parroquias de la di\u00f3cesis est\u00e1n abiertas y la mayor\u00eda de los sacerdotes se encuentran en la catedral de Bangassou por razones de seguridad. La violencia en la zona ha obligado a cerrar las escuelas de la di\u00f3cesis. \u201cNo podemos tener a los ni\u00f1os en las escuelas sabiendo que hay una gran dificultad para poder tenerlos en seguridad en las salas\u201d, cuenta el Padre Yovane. As\u00ed, ha visto c\u00f3mo se posterga su sue\u00f1o de abrir un nuevo colegio en Bema -su parroquia- para educar a 400 ni\u00f1os.<\/p>\n<p>El llamado que nos hace es a rezar. \u201cSabemos que la \u00fanica seguridad es la que nos viene de Dios y en \u00c9l ponemos toda nuestra vida y nuestra confianza\u201d, dice. \u201cSentimos que la Iglesia diocesana de Bangassou est\u00e1 en medio de una pelea de hombres, tratando de poner un poco de paz y su voz apenas se escucha\u201d, es la sensaci\u00f3n que describe el sacerdote. Sin embargo, agradece a la Fundaci\u00f3n por \u201cser esa voz de los que aqu\u00ed nadie escucha; la voz de los que son olvidados&#8230;\u201d[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Mientras permanec\u00eda escondido junto a otros sacerdotes, el P. Yovane Cox, misionero chileno en Centro\u00e1frica, se contact\u00f3 con la Fundaci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":116719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[746],"tags":[],"country":[],"class_list":["post-116718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Mientras permanec\u00eda escondido junto a otros sacerdotes, el P. Yovane Cox, misionero chileno en Centro\u00e1frica, se contact\u00f3 con la Fundaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-24T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Rep%C3%BAblica-Centroafricana-Si-alguien-no-hace-algo-una-masacre-va-a-tener-lugar-en-Bangassou-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_acn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_acn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/\"},\"author\":{\"name\":\"admin_acn\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\"},\"headline\":\"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou\",\"datePublished\":\"2018-01-24T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/\"},\"wordCount\":943,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Rep%C3%BAblica-Centroafricana-Si-alguien-no-hace-algo-una-masacre-va-a-tener-lugar-en-Bangassou-image.jpg\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/\",\"name\":\"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Rep%C3%BAblica-Centroafricana-Si-alguien-no-hace-algo-una-masacre-va-a-tener-lugar-en-Bangassou-image.jpg\",\"datePublished\":\"2018-01-24T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Rep%C3%BAblica-Centroafricana-Si-alguien-no-hace-algo-una-masacre-va-a-tener-lugar-en-Bangassou-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Rep%C3%BAblica-Centroafricana-Si-alguien-no-hace-algo-una-masacre-va-a-tener-lugar-en-Bangassou-image.jpg\",\"width\":1980,\"height\":800,\"caption\":\"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTICIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\",\"name\":\"admin_acn\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/admin_acn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/","og_locale":"es_ES","og_type":"article","og_title":"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou","og_description":"[vc_row][vc_column][vc_column_text]Mientras permanec\u00eda escondido junto a otros sacerdotes, el P. Yovane Cox, misionero chileno en Centro\u00e1frica, se contact\u00f3 con la Fundaci\u00f3n","og_url":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2018-01-24T23:00:00+00:00","og_image":[{"width":1980,"height":800,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Rep%C3%BAblica-Centroafricana-Si-alguien-no-hace-algo-una-masacre-va-a-tener-lugar-en-Bangassou-image.jpg","type":"image\/jpeg"}],"author":"admin_acn","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"admin_acn","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/"},"author":{"name":"admin_acn","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc"},"headline":"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou","datePublished":"2018-01-24T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/"},"wordCount":943,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Rep%C3%BAblica-Centroafricana-Si-alguien-no-hace-algo-una-masacre-va-a-tener-lugar-en-Bangassou-image.jpg","articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/","url":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/","name":"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Rep%C3%BAblica-Centroafricana-Si-alguien-no-hace-algo-una-masacre-va-a-tener-lugar-en-Bangassou-image.jpg","datePublished":"2018-01-24T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Rep%C3%BAblica-Centroafricana-Si-alguien-no-hace-algo-una-masacre-va-a-tener-lugar-en-Bangassou-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Rep%C3%BAblica-Centroafricana-Si-alguien-no-hace-algo-una-masacre-va-a-tener-lugar-en-Bangassou-image.jpg","width":1980,"height":800,"caption":"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/republica-centroafricana-si-alguien-no-hace-algo-una-masacre-va-tener-lugar-en-bangassou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"NOTICIAS","item":"https:\/\/acninternational.org\/es\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Rep\u00fablica Centroafricana: Si alguien no hace algo, una masacre va a tener lugar en Bangassou"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc","name":"admin_acn","url":"https:\/\/acninternational.org\/es\/author\/admin_acn\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/116718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=116718"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/116718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/116719"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=116718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=116718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=116718"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=116718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}