{"id":115812,"date":"2016-09-20T00:00:00","date_gmt":"2016-09-19T22:00:00","guid":{"rendered":"https:\/\/acninternational.org\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/"},"modified":"2016-09-20T00:00:00","modified_gmt":"2016-09-19T22:00:00","slug":"en-las-garras-de-boko-haram-una-joven-relata-su-historia-2","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/","title":{"rendered":"En las garras de Boko Haram: una joven relata su historia"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<strong>Por el P. GIDEON OBASOGIE, para Ayuda a la Iglesia Necesitada\/Aid to the Church in Need \u00a0\u2013 9 de septiembre de 2016, K\u00f6nigstein\/Maidiguri<\/strong><\/p>\n<p><em>REBECA FUE CAUTIVA DE LOS TERRORISTAS DURANTE DOS A\u00d1OS. EL 5 DE SEPTIEMBRE, CUANDO VOLVI\u00d3 A MAIDUGURI PARA REUNIRSE CON SU MARIDO, LLEVABA CONSIGO A UN BEB\u00c9 DE UN MILICIANO DE BOKO HARAM.<\/em><\/p>\n<p><strong>BITRUS Y REBECA<\/strong><\/p>\n<p>La familia de Bitrus Zachariah y su esposa Rebeca comparten con nosotros su dolorosa historia, que comienza cuando unos milicianos de Boko Haram asaltaron su localidad el 21 de agosto de 2014, antes de la ofensiva masiva y total ocupaci\u00f3n de Baga por los terroristas en 2015.<\/p>\n<p>Con mirada seria y un sentimiento de profunda depresi\u00f3n, Rebecca relata su calvario al P. Gideon Obasogie, sacerdote y director de Comunicaciones de la di\u00f3cesis de Maiduguri en Nigeria. Cuando Boko Haram asalt\u00f3 la ciudad de Baga, en medio de una gran confusi\u00f3n ella, su marido y sus dos hijos (Zacar\u00edas de 3 a\u00f1os y Jonat\u00e1n de uno) huyeron de su amado hogar. Ella estaba embarazada, pero perdi\u00f3 al ni\u00f1o seis meses m\u00e1s tarde debido a las condiciones infrahumanas a las que estuvo sometida durante su cautividad. Cuando huyeron, el esposo no pod\u00eda correr r\u00e1pidamente porque llevaba a su hijo en brazos. Como consideraron que \u00e9l era el objetivo principal, Rebeca rog\u00f3 a su marido que corriera por su vida y que los dejara atr\u00e1s. Bitrus acept\u00f3 y corri\u00f3 a ocultarse en los matorrales mientras los terroristas de Boko Haram los persegu\u00edan y lanzaban disparos. Afortunadamente, como Bitrus narra con cierta nostalgia, no fue alcanzado por ninguna bala. Tras un rato, Bitrus prosigui\u00f3 la huida, pensando en lo que podr\u00eda ocurrirle a su mujer. Mientras relata su historia, mira a su mujer con el rostro avergonzado por no haber sido para ella un h\u00e9roe en aquellos momentos desesperados de sus vidas. Bitrus se fue a Mongonou con esperanzas renovadas, haciendo la promesa de volver a ponerse en contacto con su familia si Dios la conservaba viva. En Mongonou esper\u00f3 quince d\u00edas, con la esperanza puesta en que llegara su mujer. Mientras esperaba, ve\u00eda a mucha gente que ven\u00eda de Baga:\u00a0<em>\u201cLes preguntaba a todos si sab\u00edan algo de mi mujer, pero nadie me pudo dar alguna buena noticia. Me deprim\u00ed profundamente, sufr\u00eda una severa migra\u00f1a y la tensi\u00f3n se me subi\u00f3 mucho. Unos soldados me asistieron, me dieron cobijo para acostarme y tambi\u00e9n alg\u00fan dinero que utilic\u00e9 para desplazarme a Maiduguri. Mi t\u00edo de Maiduguri me rog\u00f3 que no perdiera el \u00e1nimo y me llev\u00f3 al hospital para que me medicaran. Intent\u00f3 infundirme esperanza, pero mis pesadillas y el dolor de cabeza no cesaron. Dejar atr\u00e1s a mi familia y todo lo que pose\u00eda no fue precisamente una experiencia f\u00e1cil de superar\u201d.<\/em><\/p>\n<p><strong>LA HISTORIA DE REBECA<\/strong><\/p>\n<p>\u201cCuando los milicianos de Boko Haram me encontraron, me dijeron: \u2026\u00a0<em>da mun kashe Mujin ki<\/em>\u2026\u00a0<em>da mun Sami lada\u2026 ama ton da Allah bai bari ba\u2026ke da yaran ki sai ku je ku yi aikin Allah<\/em>\u00a0(Si hubi\u00e9ramos matado a tu marido habr\u00edamos recibido la recompensa de Al\u00e1\u2026 pero como Al\u00e1 no lo ha permitido\u2026 t\u00fa y tus hijos vais a trabajar para Al\u00e1). Y despu\u00e9s me golpearon con un arma pesada y me sacaron de cuajo varios dientes\u201d.<\/p>\n<p>A la pregunta de qu\u00e9 pas\u00f3 despu\u00e9s, Rebeca rompe a llorar y me dirige una mirada penetrante que parece decir: \u201cPara qu\u00e9 querr\u00e1 este periodista escucharlo otra vez\u201d. Yo sonr\u00edo para animarla.<\/p>\n<p>Rebeca vuelve a tranquilizarse y cuenta que entonces comenz\u00f3 su pesadilla. Despu\u00e9s de matar a todos los hombres que hab\u00edan capturado, los terroristas de Boko Haram la trasladaron a ella y sus hijos al lago Chad. Cruzar el lago fue horrible, con el agua lleg\u00e1ndole hasta el cuello. Tardaron seis d\u00edas en cruzar el lago y recibieron galletas para comer. Al s\u00e9ptimo d\u00eda llegaron a un lugar llamado Kwalleram, rodeado de arbustos espinosos. All\u00ed permanecieron durante unos 53 d\u00edas. Los obligaron a lavar para sus mujeres, preparar pimiento dulce, limpiar los caminos para sus motocicletas y cocinar para los milicianos. \u201cDespu\u00e9s nos llevaron a m\u00ed y a mis hijos a Gurva, en Chad, por miedo a que escapara. En Gurva permanecimos setenta d\u00edas. Trabajamos el campo y cortamos le\u00f1a. En Gurva hab\u00eda unos dos mil milicianos\u201d.<\/p>\n<p><strong>EN TILMA<\/strong><\/p>\n<p>\u201cEn Tilma me marcaron en la espalda con el n\u00famero 69. No s\u00e9 qu\u00e9 significa y nunca pregunt\u00e9. Me vendieron a un hombre llamado Bage\u00a0Guduma. Con \u00e9l permanec\u00ed 55 d\u00edas. Me daban frutos de palmera, pero, gracias a Dios, no com\u00ed nada, porque podr\u00eda tratarse de un hechizo que me dejara hipnotizada y me hiciera perder el sentido. Yo me resist\u00ed siempre, en la mayor\u00eda de las noches en las que quer\u00eda tocarme yo frotaba las heces de mis hijos contra mi cuerpo, y eso lo mantuvo siempre alejado de m\u00ed, aunque sus hijos varones pod\u00edan pegarme sin piedad. Me hicieron cavar un agujero durante tres semanas hasta que di con agua. Cada d\u00eda me propinaban 98 golpes. Estuve enferma durante dos semanas. Me quitaron a Jonat\u00e1n, mi segundo hijo, y lo lanzaron al lago Chad, donde muri\u00f3 ahogado\u201d. Rebeca pronuncia estas palabras con gran sufrimiento mientras las l\u00e1grimas recorren sus mejillas. Estas terribles cosas le pasaron a Rebeca por negarse a entregar su cuerpo.<\/p>\n<p><strong>MALLA: EL PADRE DE MI NUEVO HIJO<\/strong><\/p>\n<p>Malla fue el segundo hombre al que me entregaron. Me obligaron a acostarme con \u00e9l, y cuando me resist\u00ed me introdujeron en su prisi\u00f3n, que era un profundo hoyo en el que me dejaron durante dos d\u00edas sin comida ni agua. Cuando me sacaron, Malla me viol\u00f3 varias veces. Cuando vi que no me llegaba el periodo, supe que estaba embarazada. Busqu\u00e9 Paracetamol y me tom\u00e9 diez pastillas de golpe para librarme del embarazo. Pero no lo logr\u00e9. Entonces una mujer, una mujer de un Pastor que hab\u00eda sido secuestrada en Gwoza, me suplic\u00f3 que no me quitara la vida por el embarazo. Ella ya ten\u00eda dos hijos de los terroristas. Me tranquilizaron para que mantuviera el embarazo hasta dar a luz. Casi me mor\u00ed de hambre. Di a luz en casa, sin nadie que me ayudara. Yo misma cort\u00e9 la placenta, sufriendo un gran dolor. No recib\u00ed ninguna atenci\u00f3n m\u00e9dica. Llamaron a mi hijo Ibrahim y lo aceptaron de buena gana por ser var\u00f3n: quieren que las mujeres den a luz a varones. Malla, el padre, era miembro de Boko Haram y estaba de viaje, regres\u00f3 seis semanas despu\u00e9s el alumbramiento. Yo ya no ten\u00eda nada que ver con \u00e9l, porque me prometieron que me vender\u00edan a otro hombre.<\/p>\n<p><strong>ESCENAS TERRIBLES<\/strong><\/p>\n<p>Ha visto cosas terribles y atemorizantes en los \u00faltimos dos a\u00f1os y algunos meses. Presenci\u00f3 c\u00f3mo mucha gente intent\u00f3 huir y acab\u00f3 muerta. All\u00ed estaba por ejemplo Benjam\u00edn, un var\u00f3n igbo que quiso escapar, pero al que, tras ser interceptado, le rompieron las dos piernas y lo dejaron atr\u00e1s sin ocuparse m\u00e1s de \u00e9l. Los obligaban a acompa\u00f1arlos en sus oraciones de 7 a 10 de la ma\u00f1ana, de 12 a 2 del mediod\u00eda y de 4 a 6 de la tarde. Mataron a algunos cristianos que se negaron a rezar con ellos. Violaron a ni\u00f1as de ocho y nueve a\u00f1os, asfixi\u00e1ndolas con objetos en la boca hasta matarlas.<\/p>\n<p><strong>LA HUIDA<\/strong><\/p>\n<p>En un d\u00eda afortunado, cuando la mayor\u00eda de los milicianos estaban fuera, una mujer de Boko Haram \u2013probablemente, la mujer del comandante\u2013permiti\u00f3 a Rebeca que fuera a visitar a una amiga en otra zona bajo el control de Boko Haram. As\u00ed se traslad\u00f3 a\u00a0<em>Maitele<\/em>, una peque\u00f1a comunidad tal vez situada en torno a Chad. Caminaron durante seis d\u00edas hacia la frontera nigeriana. Uno de sus hijos enferm\u00f3 por falta de agua y comida. Gracias a Dios, cay\u00f3 una tormenta que los renov\u00f3 y reaviv\u00f3 para seguir el viaje, un viaje en el que muchos otros se hab\u00edan encaminado antes hacia un destino incierto. Rebeca, en cambio, aun sin saber a ciencia cierta d\u00f3nde estaba, avanzaba persuadida de una gran esperanza en encontrar un lugar seguro. Llegaron a Diffa, donde se encontraron con soldados estadounidenses y de N\u00edger. Estos atendieron a su hijo y les dieron algo de pan. Al poco tiempo los llevaron a Damaturu, donde hab\u00eda soldados nigerianos. \u201cLos soldados fueron maravillosos: me llevaron directamente a la ciudad de Maiduguri, junto a mi marido\u201d.<\/p>\n<p><strong>MI NUEVO HIJO IBRAHIM:<\/strong><\/p>\n<p>Bitrus, el marido de Rebeca, cuenta en un tono tranquilo con el que no logra disimular que esta alterado: \u201cVer a mi esposa con un hijo de un padre de Boko Haram me da mucho miedo. Me alegr\u00e9 mucho de ver a mi mujer, pero el hijo me rompe el coraz\u00f3n. Ruego a Dios que me haga amarle\u2026 s\u00ed, el hijo de una serpiente\u2026\u201d. As\u00ed habla Bitrus con amargura.<\/p>\n<p>Rebeca, con sentimientos encontrados, dice que el peque\u00f1o Ibrahim es su hijo, a pesar de que el padre sea el malvado Malla. Intent\u00f3 en varias ocasiones entregar al ni\u00f1o al Gobierno, pero los soldados le pidieron que esperara, pues el peque\u00f1o Ibrahim solo tiene ocho meses de edad.<\/p>\n<p>Rebeca, cuyos padres se encuentran en Camer\u00fan, ha rogado a su marido que la acepte como es\u2026 y le ha dicho, desesperanzada, que si \u00e9l duda, \u201cle dejar\u00e9 a su hijo y yo me ir\u00e9 con mis padres\u201d.<\/p>\n<p><strong>EL PRESENTE<\/strong><\/p>\n<p>Bitrus y su familia se encuentran en la Di\u00f3cesis cat\u00f3lica de Maiduguri, y el Obispo, Mons. Oliver Dashe Doeme, se ocupa de ellos, pues se encuentran en un campo de desplazados donde hay m\u00e1s de 500 personas como ellos. Con oraciones y ayuda de urgencia pronto olvidar\u00e1n las maldades y los sufrimientos del pasado. La di\u00f3cesis ha facilitado a Rebeca asistencia alimentaria de emergencia, y esperan poder seguir ayud\u00e1ndola. En estos momentos, la familia se encuentra en una encrucijada moral. Ahora Rebeca necesita una buena atenci\u00f3n m\u00e9dica, v\u00edveres para comer, ropa para vestirse, un buen alojamiento y una cama en la que reposar su atribulada cabeza. El tiempo lo cura casi todo pero tambi\u00e9n es muy necesaria una sistem\u00e1tica atenci\u00f3n psicol\u00f3gica, y su hijo Zacar\u00edas, que ahora tiene seis a\u00f1os de edad, deber\u00eda ir a la escuela. \u00a1Realmente, es una mujer de fe fuerte![\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Por el P. GIDEON OBASOGIE, para Ayuda a la Iglesia Necesitada\/Aid to the Church in Need \u00a0\u2013 9 de septiembre<\/p>\n","protected":false},"author":1,"featured_media":113382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[713,746],"tags":[],"country":[],"class_list":["post-115812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias","category-noticias"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>En las garras de Boko Haram: una joven relata su historia | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En las garras de Boko Haram: una joven relata su historia\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Por el P. GIDEON OBASOGIE, para Ayuda a la Iglesia Necesitada\/Aid to the Church in Need \u00a0\u2013 9 de septiembre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-19T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/En-las-garras-de-boko-haram-una-joven-relata-su-historia-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1960\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_acn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_acn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/\"},\"author\":{\"name\":\"admin_acn\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\"},\"headline\":\"En las garras de Boko Haram: una joven relata su historia\",\"datePublished\":\"2016-09-19T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/\"},\"wordCount\":1804,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/En-las-garras-de-boko-haram-una-joven-relata-su-historia-image.jpg\",\"articleSection\":[\"HISTORIAS\",\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/\",\"name\":\"En las garras de Boko Haram: una joven relata su historia | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/En-las-garras-de-boko-haram-una-joven-relata-su-historia-image.jpg\",\"datePublished\":\"2016-09-19T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/En-las-garras-de-boko-haram-una-joven-relata-su-historia-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/En-las-garras-de-boko-haram-una-joven-relata-su-historia-image.jpg\",\"width\":1960,\"height\":600,\"caption\":\"En las garras de Boko Haram: una joven relata su historia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HISTORIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/historias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"En las garras de Boko Haram: una joven relata su historia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\",\"name\":\"admin_acn\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/admin_acn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"En las garras de Boko Haram: una joven relata su historia | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/","og_locale":"es_ES","og_type":"article","og_title":"En las garras de Boko Haram: una joven relata su historia","og_description":"[vc_row][vc_column][vc_column_text]Por el P. GIDEON OBASOGIE, para Ayuda a la Iglesia Necesitada\/Aid to the Church in Need \u00a0\u2013 9 de septiembre","og_url":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2016-09-19T22:00:00+00:00","og_image":[{"width":1960,"height":600,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/En-las-garras-de-boko-haram-una-joven-relata-su-historia-image.jpg","type":"image\/jpeg"}],"author":"admin_acn","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"admin_acn","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/"},"author":{"name":"admin_acn","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc"},"headline":"En las garras de Boko Haram: una joven relata su historia","datePublished":"2016-09-19T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/"},"wordCount":1804,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/En-las-garras-de-boko-haram-una-joven-relata-su-historia-image.jpg","articleSection":["HISTORIAS","NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/","url":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/","name":"En las garras de Boko Haram: una joven relata su historia | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/En-las-garras-de-boko-haram-una-joven-relata-su-historia-image.jpg","datePublished":"2016-09-19T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/En-las-garras-de-boko-haram-una-joven-relata-su-historia-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/En-las-garras-de-boko-haram-una-joven-relata-su-historia-image.jpg","width":1960,"height":600,"caption":"En las garras de Boko Haram: una joven relata su historia"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/en-las-garras-de-boko-haram-una-joven-relata-su-historia-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"HISTORIAS","item":"https:\/\/acninternational.org\/es\/category\/historias\/"},{"@type":"ListItem","position":3,"name":"En las garras de Boko Haram: una joven relata su historia"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc","name":"admin_acn","url":"https:\/\/acninternational.org\/es\/author\/admin_acn\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/115812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=115812"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/115812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/113382"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=115812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=115812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=115812"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=115812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}