{"id":115640,"date":"2017-09-05T00:00:00","date_gmt":"2017-09-04T22:00:00","guid":{"rendered":"https:\/\/acninternational.org\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/"},"modified":"2017-09-05T00:00:00","modified_gmt":"2017-09-04T22:00:00","slug":"acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/","title":{"rendered":"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Aid to the Church in Need (ACN) inform\u00f3 a Su Santidad el Papa Francisco sobre los esfuerzos de reconstrucci\u00f3n que est\u00e1 desarrollando esta fundaci\u00f3n, para ayudar a los cristianos que intentan regresar a sus hogares en la Llanura de N\u00ednive, Irak. Durante una audiencia privada concedida a la Red Internacional de Legisladores Cat\u00f3licos (ICLN por sus siglas en ingl\u00e9s) el pasado 27 de agosto, los representantes de Asuntos P\u00fablicos de ACN, Mark von Riedemann y Marcela Szymanski, explicaron al Santo Padre el alcance y las dimensiones del esfuerzo de reconstrucci\u00f3n, pidiendo sus oraciones para todos los involucrados.<\/p>\n<p>Al presentar mapas e informaci\u00f3n estad\u00edstica, los representantes de ACN subrayaron el alcance del da\u00f1o, la reconstrucci\u00f3n en curso y el n\u00famero de familias que regresan, as\u00ed como la naturaleza ecum\u00e9nica del \u201cComit\u00e9 de Reconstrucci\u00f3n de N\u00ednive\u201d, sobre la cual el Santo Padre expres\u00f3 un profundo inter\u00e9s.<\/p>\n<p>La asamblea anual de tres d\u00edas del ICLN reuni\u00f3 a m\u00e1s de 250 legisladores cat\u00f3licos de 30 pa\u00edses. Los representantes de Asuntos P\u00fablicos de ACN presentaron el Proyecto de Reconstrucci\u00f3n de N\u00ednive durante un panel especial sobre los cristianos perseguidos.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Aid to the Church in Need (ACN) inform\u00f3 a Su Santidad el Papa Francisco sobre los esfuerzos de reconstrucci\u00f3n que<\/p>\n","protected":false},"author":1,"featured_media":115641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[746],"tags":[],"country":[],"class_list":["post-115640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Aid to the Church in Need (ACN) inform\u00f3 a Su Santidad el Papa Francisco sobre los esfuerzos de reconstrucci\u00f3n que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-04T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-informa-al-Papa-Francisco-sobre-el-Proyecto-de-Reconstrucci%C3%B3n-en-N%C3%ADnive-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_acn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_acn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/\"},\"author\":{\"name\":\"admin_acn\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\"},\"headline\":\"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive\",\"datePublished\":\"2017-09-04T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/\"},\"wordCount\":232,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ACN-informa-al-Papa-Francisco-sobre-el-Proyecto-de-Reconstrucci%C3%B3n-en-N%C3%ADnive-image.jpg\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/\",\"name\":\"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ACN-informa-al-Papa-Francisco-sobre-el-Proyecto-de-Reconstrucci%C3%B3n-en-N%C3%ADnive-image.jpg\",\"datePublished\":\"2017-09-04T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ACN-informa-al-Papa-Francisco-sobre-el-Proyecto-de-Reconstrucci%C3%B3n-en-N%C3%ADnive-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ACN-informa-al-Papa-Francisco-sobre-el-Proyecto-de-Reconstrucci%C3%B3n-en-N%C3%ADnive-image.jpg\",\"width\":1980,\"height\":800,\"caption\":\"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTICIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\",\"name\":\"admin_acn\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/admin_acn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/","og_locale":"es_ES","og_type":"article","og_title":"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive","og_description":"[vc_row][vc_column][vc_column_text]Aid to the Church in Need (ACN) inform\u00f3 a Su Santidad el Papa Francisco sobre los esfuerzos de reconstrucci\u00f3n que","og_url":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2017-09-04T22:00:00+00:00","og_image":[{"width":1980,"height":800,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-informa-al-Papa-Francisco-sobre-el-Proyecto-de-Reconstrucci%C3%B3n-en-N%C3%ADnive-image.jpg","type":"image\/jpeg"}],"author":"admin_acn","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"admin_acn","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/"},"author":{"name":"admin_acn","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc"},"headline":"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive","datePublished":"2017-09-04T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/"},"wordCount":232,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-informa-al-Papa-Francisco-sobre-el-Proyecto-de-Reconstrucci%C3%B3n-en-N%C3%ADnive-image.jpg","articleSection":["NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/","url":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/","name":"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-informa-al-Papa-Francisco-sobre-el-Proyecto-de-Reconstrucci%C3%B3n-en-N%C3%ADnive-image.jpg","datePublished":"2017-09-04T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-informa-al-Papa-Francisco-sobre-el-Proyecto-de-Reconstrucci%C3%B3n-en-N%C3%ADnive-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ACN-informa-al-Papa-Francisco-sobre-el-Proyecto-de-Reconstrucci%C3%B3n-en-N%C3%ADnive-image.jpg","width":1980,"height":800,"caption":"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/acn-informa-al-papa-francisco-sobre-el-proyecto-de-reconstruccion-en-ninive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"NOTICIAS","item":"https:\/\/acninternational.org\/es\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"ACN informa al Papa Francisco sobre el Proyecto de Reconstrucci\u00f3n en N\u00ednive"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc","name":"admin_acn","url":"https:\/\/acninternational.org\/es\/author\/admin_acn\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/115640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=115640"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/115640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/115641"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=115640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=115640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=115640"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=115640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}