{"id":115328,"date":"2017-08-04T00:00:00","date_gmt":"2017-08-03T22:00:00","guid":{"rendered":"https:\/\/acninternational.org\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/"},"modified":"2017-08-04T00:00:00","modified_gmt":"2017-08-03T22:00:00","slug":"zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/","title":{"rendered":"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<em>Tony Zender responsable de proyectos en Zambia de la fundaci\u00f3n internacional ACN (Aid to the Church in Need) ha visitado este pa\u00eds africano para hacer balance de las ayudas de la organizaci\u00f3n durante los \u00faltimos a\u00f1os y estudiar las necesidades futuras de la iglesia local. <\/em><\/p>\n<p><em>La entrevista fue realizada por Maria Lozano.<\/em><\/p>\n<p><strong>Sr. Zender: usted acaba de volver de un viaje de trabajo a Zambia, donde ha visitado sobre todo proyectos de <\/strong><strong>Aid to the Church in Need<\/strong><strong>. \u00bfQu\u00e9 impresi\u00f3n general ha sacado del pa\u00eds?<br \/>\n<\/strong>Zambia es un pa\u00eds en v\u00edas de desarrollo estable en amplia medida. En el pasado se produjeron algunos des\u00f3rdenes pol\u00edticos debidos a la transici\u00f3n entre el gobierno del antiguo Presidente al actual; pero, en general, el pa\u00eds es estable. Las autoridades estatales funcionan \u2014en comparaci\u00f3n con otros pa\u00edses de esa regi\u00f3n\u2014 bastante bien. Zambia est\u00e1 en un buen camino, pero se trata de un proceso a\u00fan muy largo hasta conseguir un buen resultado para mejorar las condiciones de vida.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][bs_modal_gallery groupname=\u00bbzambia\u00bb images=\u00bb8299,8298,8297,8296,8295,8294,8293&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<strong>\u00bfC\u00f3mo est\u00e1 organizada la Iglesia en Zambia?<br \/>\n<\/strong>La Iglesia est\u00e1 dividida en once di\u00f3cesis y se encuentra presente entre las personas con muchas iniciativas y la administraci\u00f3n de los sacramentos. Est\u00e1 sensibilizada frente a la llegada del Islam. Pero m\u00e1s cr\u00edticamente ve a las sectas evang\u00e9licas, que se presentan con el siguiente mensaje: \u00abSi vienes con nosotros, recibir\u00e1s recompensa ya en esta vida; y cuando m\u00e1s reces, m\u00e1s rico te volver\u00e1s\u00bb. Esto es problem\u00e1tico, porque tambi\u00e9n se pierden muchos cat\u00f3licos; pero la Iglesia en Zambia intenta reaccionar.<\/p>\n<p>Los problemas fundamentales, para los que necesita nuestra ayuda, son la construcci\u00f3n de casas parroquiales, la motorizaci\u00f3n (autom\u00f3viles, motos), formaci\u00f3n permanente y continua, ejercicios espirituales\u2026 y tambi\u00e9n hay que mencionar que nos piden frecuentemente que financiemos proyectos espec\u00edficos para la protecci\u00f3n de las familias cat\u00f3licas.<\/p>\n<p><strong>\u00bfQu\u00e9 momento del viaje fue el que m\u00e1s le impresion\u00f3? \u00bfHay proyectos sobre los que pueda decir: \u00abgracias a Dios que en ACN decidimos hacer este proyecto&#8230;\u00bb?<br \/>\n<\/strong>Por lo que se refiere a nuestro viaje para ver proyectos, fue la visita a una parroquia bastante alejada de la di\u00f3cesis de Mansa. Se encuentra situada en la regi\u00f3n m\u00e1s pobre de Zambia, al norte del pa\u00eds. Nos recibieron en el centro de formaci\u00f3n de catequistas. La formaci\u00f3n dura dos a\u00f1os, durante los cuales los catequistas se trasladan con sus familias cada una a una casa peque\u00f1a. Durante esos dos a\u00f1os de formaci\u00f3n, los hombres se preparan para su servicio como catequistas y las mujeres acuden a cursos de perfeccionamiento para actuar como formadoras en las futuras comunidades, en el \u00e1mbito de la catequesis, pero tambi\u00e9n en la econom\u00eda dom\u00e9stica, por ejemplo costura. Me regalaron una camisa de colores que hab\u00edan hecho ellas mismas. Para m\u00ed, personalmente, fue una visita muy emocionante. Los sacerdotes, frecuentemente, solo est\u00e1n unos pocos d\u00edas al trimestre en las parroquias, a veces incluso solo unos d\u00edas al a\u00f1o. En ausencia del sacerdote, los catequistas hacen una muy buena labor de evangelizaci\u00f3n: atienden a las personas y tambi\u00e9n sirven de ejemplo con su familia&#8230; Cuando los sacerdotes ven esa decisi\u00f3n de sacrificarse por la Iglesia, tambi\u00e9n muchos de ellos se sienten motivados. Visitamos ese centro porque apoyamos directamente la formaci\u00f3n de los catequistas all\u00ed; ahora les hemos facilitado bicicletas para que tengan mayor libertad de movimientos y puedan cumplir mejor su tarea. Tambi\u00e9n queremos llevar a cabo reformas en el centro de formaci\u00f3n de catequistas. Se aprecia la gratitud que siente el Rector del centro y tambi\u00e9n de los formadores. Esperamos no solo apoyar el pr\u00f3ximo curso de formaci\u00f3n, sino tambi\u00e9n ayudar a los trabajos de reforma, porque el estado de los edificios es muy malo.<\/p>\n<p><strong>\u00bfNo puede prestar esa ayuda la propia poblaci\u00f3n? \u00bfEs muy pobre esa regi\u00f3n?<\/strong><\/p>\n<p>Esto es un problema. La Iglesia hace todo lo posible por ense\u00f1ar a las personas que todos los laicos est\u00e1n llamados a ayudar a la Iglesia, tambi\u00e9n econ\u00f3micamente, y que la situaci\u00f3n ha cambiado, que no es como cuando hab\u00eda misioneros y se repart\u00eda desde arriba hacia abajo, sino que ahora la Iglesia precisa la ayuda de todos los fieles. En algunas regiones de Zambia todav\u00eda hay una cierta presencia misionera de Polonia y tambi\u00e9n de algunas congregaciones de otros pa\u00edses, pero la Iglesia se est\u00e1 transformando cada vez m\u00e1s en una iglesia local. Esto es un proceso bueno y necesario, pero est\u00e1 naturalmente unido a un cambio de mentalidad. La gente tiene que aprender que est\u00e1n llamados por el Se\u00f1or a apoyar a la Iglesia y que todos y cada uno deben hacer su aportaci\u00f3n, independientemente de lo pobre que sea. No se puede ver solo el lado econ\u00f3mico, sino tambi\u00e9n todos los sacrificios que se hacen por la Iglesia. Si todos intentan construir unidos la Iglesia, si todos actuamos con esp\u00edritu de sacrificio y de decisi\u00f3n, mostraremos que somos nosotros los que queremos sostener la Iglesia; entonces, el Se\u00f1or de la Iglesia nos dar\u00e1 gracias que no recibir\u00edamos de otro modo. Y, adem\u00e1s, esto mismo vale para Europa.<\/p>\n<p><strong>\u00bfHubo alg\u00fan momento que le produjera tristeza o preocupaci\u00f3n?<br \/>\n<\/strong>Lo que siempre me ha impresionado es el modo tan ejemplar con que algunos sacerdotes cumplen su ministerio, que a veces viven en lugares sin electricidad, donde quiz\u00e1 tienen que sacar agua de un dep\u00f3sito y a veces tambi\u00e9n tienen que vivir completamente solos; me sirven de ejemplo en el sentido de que se enfrentan a su situaci\u00f3n. Veo muchas necesidades para nuestra ayuda, por ejemplo con trabajos de reformas, construcci\u00f3n de nuevas casas parroquiales y motorizaci\u00f3n. Queremos hacer llegar motos a sacerdotes j\u00f3venes, para llevar a las personas sacerdotes bien formados y con mucha vida espiritual. A algunos lugares, los sacerdotes apenas pueden acceder. Muchos tienen que llegar andando o los tienen que llevar all\u00ed. Las condiciones son adversas. En las temporadas de lluvia no suelen poder avanzar en autom\u00f3vil. Un ejemplo: hay un misionero alem\u00e1n de la di\u00f3cesis de Maguncia, el padre Thomas, con el que ya hemos llevado a cabo algunos proyectos. Durante nuestro viaje no pudimos verle porque estaba sustituyendo a otro sacerdote en una parroquia que durante la \u00e9poca de lluvias est\u00e1 completamente rodeada por el agua. El sacerdote que atiende esa zona no puede abandonar el terreno durante 3-4 meses, o solo en una barca. Cuando las carreteras vuelven a estar transitables, le sustituye alguien durante una o dos semanas; en uno de esos lugares es donde se encontraba ahora el padre Thomas. Es todo un modelo, pero tambi\u00e9n un ejemplo de lo dif\u00edcil que puede resultar moverse en Zambia.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Tony Zender responsable de proyectos en Zambia de la fundaci\u00f3n internacional ACN (Aid to the Church in Need) ha visitado<\/p>\n","protected":false},"author":1,"featured_media":115329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[745],"tags":[],"country":[],"class_list":["post-115328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Tony Zender responsable de proyectos en Zambia de la fundaci\u00f3n internacional ACN (Aid to the Church in Need) ha visitado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-03T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ZAMBIA-%C2%ABMe-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio%C2%BB-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_acn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_acn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/\"},\"author\":{\"name\":\"admin_acn\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\"},\"headline\":\"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb\",\"datePublished\":\"2017-08-03T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/\"},\"wordCount\":1243,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ZAMBIA-%C2%ABMe-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio%C2%BB-image.jpg\",\"articleSection\":[\"ENTREVISTAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/\",\"name\":\"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ZAMBIA-%C2%ABMe-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio%C2%BB-image.jpg\",\"datePublished\":\"2017-08-03T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ZAMBIA-%C2%ABMe-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio%C2%BB-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/ZAMBIA-%C2%ABMe-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio%C2%BB-image.jpg\",\"width\":1980,\"height\":800,\"caption\":\"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/entrevistas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\",\"name\":\"admin_acn\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/admin_acn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/","og_locale":"es_ES","og_type":"article","og_title":"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb","og_description":"[vc_row][vc_column][vc_column_text]Tony Zender responsable de proyectos en Zambia de la fundaci\u00f3n internacional ACN (Aid to the Church in Need) ha visitado","og_url":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2017-08-03T22:00:00+00:00","og_image":[{"width":1980,"height":800,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ZAMBIA-%C2%ABMe-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio%C2%BB-image.jpg","type":"image\/jpeg"}],"author":"admin_acn","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"admin_acn","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/"},"author":{"name":"admin_acn","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc"},"headline":"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb","datePublished":"2017-08-03T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/"},"wordCount":1243,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ZAMBIA-%C2%ABMe-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio%C2%BB-image.jpg","articleSection":["ENTREVISTAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/","url":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/","name":"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ZAMBIA-%C2%ABMe-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio%C2%BB-image.jpg","datePublished":"2017-08-03T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ZAMBIA-%C2%ABMe-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio%C2%BB-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/ZAMBIA-%C2%ABMe-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio%C2%BB-image.jpg","width":1980,"height":800,"caption":"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/zambia-me-ha-impresionado-mucho-el-modo-tan-ejemplar-con-que-muchos-sacerdotes-cumplen-su-ministerio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTAS","item":"https:\/\/acninternational.org\/es\/category\/entrevistas\/"},{"@type":"ListItem","position":3,"name":"ZAMBIA: \u00abMe ha impresionado mucho el modo tan ejemplar con que muchos sacerdotes cumplen su ministerio\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc","name":"admin_acn","url":"https:\/\/acninternational.org\/es\/author\/admin_acn\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/115328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=115328"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/115328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/115329"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=115328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=115328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=115328"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=115328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}