{"id":114206,"date":"2017-03-21T00:00:00","date_gmt":"2017-03-20T23:00:00","guid":{"rendered":"https:\/\/acninternational.org\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/"},"modified":"2017-03-21T00:00:00","modified_gmt":"2017-03-20T23:00:00","slug":"un-pozo-de-agua-brota-en-la-gloriosa-kinshasa","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/","title":{"rendered":"Un pozo de agua brota en la gloriosa Kinshasa"},"content":{"rendered":"<p>Por Murcadha O Flaherty<\/p>\n<p>&nbsp;<\/p>\n<p>Una comunidad contemplativa de religiosas en la Rep\u00fablica Democr\u00e1tica del Congo (RDC), que oran por los cristianos perseguidos, tendr\u00e1 su futuro asegurado por un nuevo pozo \u2013 despu\u00e9s de una cr\u00f3nica escasez de agua que hab\u00eda amenazado su supervivencia.<\/p>\n<p>\u201cNo sab\u00edamos c\u00f3mo \u00edbamos a sobrevivir despu\u00e9s del colapso de nuestro antiguo pozo hace un a\u00f1o\u201d, dijo a ACN la Hermana Mahele Mwamini, priora de las Carmelitas Descalzas en el convento de San Jos\u00e9 Glorioso en Kinshasa.<\/p>\n<p>ACN respondi\u00f3 a la solicitud urgente de las hermanas proporcionando una subvenci\u00f3n para permitir que el pozo se profundice para que alcance una nueva fuente de agua. Durante la temporada seca de 2017, el pozo se extender\u00e1 por otros 30 metros hasta una nueva profundidad de m\u00e1s de 50 metros para asegurar que se alcance suficiente agua para satisfacer las necesidades del convento.<\/p>\n<p>La Hna. Mwamini dijo: \u201cEstamos comprometidos a orar por la Iglesia, pero especialmente por aquellos que m\u00e1s necesitan nuestras oraciones: los sacerdotes y los cristianos perseguidos por su fe\u201d. En una s\u00faplica desesperada a ACN, ella describi\u00f3 la crisis que estaban haciendo frente: \u201cNo hemos tenido una sola gota desde febrero de 2016. Nuestro convento est\u00e1 sufriendo a causa de esta situaci\u00f3n. Anteriormente, vend\u00edamos algunas verduras para ayudar a la comunidad a ser m\u00e1s autosuficiente y ayudar a las madres desempleadas y a sus hijos con sus cuotas escolares. Pero ahora, con esta escasez de agua, no tenemos m\u00e1s verduras y nos vemos forzadas a comprarlas para la comunidad\u201d.<\/p>\n<p>A causa de la falta de agua, tampoco pueden seguir produciendo hostias, pero peores a\u00fan son las consecuencias para el huerto y la cr\u00eda de gallinas, cerdos y conejos, ambos necesarios para que las religiosas puedan ganarse su humilde sustento. \u201cNo sabemos c\u00f3mo vamos a sobrevivir\u201d.<\/p>\n<p>La escasez de agua significaba que el convento tuvo que dejar de organizar retiros espirituales: \u201cHab\u00eda gente que ven\u00eda a nosotros por un tiempo para sanar o retirarse, pero debido a la falta de agua potable nos vimos obligadas a decirles que ser\u00eda imposible.\u201d Pero la Hermana Mwamini ahora habla con optimismo: \u201cEl nuevo pozo garantizar\u00e1 el agua potable y por lo tanto la continuaci\u00f3n de nuestras actividades generadoras de recursos y cubrir\u00e1 nuestras necesidades de limpieza tanto dom\u00e9stica como de higiene personal.\u201d<\/p>\n<p>Tambi\u00e9n se beneficiar\u00e1n las \u201cmadres sin trabajo que compran verduras, pollos y cerdos para la reventa y sostener as\u00ed las necesidades de sus familias\u201d. El P. Saverio Cannistr\u00e0, Superior General de los Carmelitas Descalzos, afirma: \u201cEstamos agradecidos de que este proyecto asegure que estas monjas contemplativas puedan vivir en paz, que no sufran m\u00e1s por la falta de agua potable y puedan seguir apoyando a la Iglesia con sus oraciones.\u201d<\/p>\n<p><a href=\"http:\/\/africa.pontifical.acninternational.org\/es\/\">Agradeci\u00e9ndoles su apoyo a los benefactores de ACN<\/a>, la Hna. Mwamini dijo: \u201cQue el Se\u00f1or los bendiga y los colme de abundantes gracias\u2026 Esta ayuda que nos dan nos permite costearnos un pozo perforado\u201d. Hablando en nombre de las doce hermanas, cuyas edades oscilan entre los 32 y los 81 a\u00f1os, agreg\u00f3: \u201cNos sentimos conmovidas por el inter\u00e9s que han demostrado por nuestro sufrimiento y por su disposici\u00f3n a hacer todo lo que han hecho para ayudarnos. Que Dios les bendiga.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Murcadha O Flaherty &nbsp; Una comunidad contemplativa de religiosas en la Rep\u00fablica Democr\u00e1tica del Congo (RDC), que oran por<\/p>\n","protected":false},"author":26,"featured_media":114207,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[713],"tags":[],"country":[],"class_list":["post-114206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un pozo de agua brota en la gloriosa Kinshasa | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un pozo de agua brota en la gloriosa Kinshasa\" \/>\n<meta property=\"og:description\" content=\"Por Murcadha O Flaherty &nbsp; Una comunidad contemplativa de religiosas en la Rep\u00fablica Democr\u00e1tica del Congo (RDC), que oran por\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-20T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Un-pozo-de-agua-brota-en-la-gloriosa-Kinshasa-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1960\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un pozo de agua brota en la gloriosa Kinshasa\",\"datePublished\":\"2017-03-20T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/\"},\"wordCount\":568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Un-pozo-de-agua-brota-en-la-gloriosa-Kinshasa-image.jpg\",\"articleSection\":[\"HISTORIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/\",\"name\":\"Un pozo de agua brota en la gloriosa Kinshasa | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Un-pozo-de-agua-brota-en-la-gloriosa-Kinshasa-image.jpg\",\"datePublished\":\"2017-03-20T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Un-pozo-de-agua-brota-en-la-gloriosa-Kinshasa-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Un-pozo-de-agua-brota-en-la-gloriosa-Kinshasa-image.jpg\",\"width\":1960,\"height\":600,\"caption\":\"Un pozo de agua brota en la gloriosa Kinshasa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HISTORIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/historias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Un pozo de agua brota en la gloriosa Kinshasa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un pozo de agua brota en la gloriosa Kinshasa | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/","og_locale":"es_ES","og_type":"article","og_title":"Un pozo de agua brota en la gloriosa Kinshasa","og_description":"Por Murcadha O Flaherty &nbsp; Una comunidad contemplativa de religiosas en la Rep\u00fablica Democr\u00e1tica del Congo (RDC), que oran por","og_url":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2017-03-20T23:00:00+00:00","og_image":[{"width":1960,"height":600,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Un-pozo-de-agua-brota-en-la-gloriosa-Kinshasa-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/"},"author":{"name":"","@id":""},"headline":"Un pozo de agua brota en la gloriosa Kinshasa","datePublished":"2017-03-20T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/"},"wordCount":568,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Un-pozo-de-agua-brota-en-la-gloriosa-Kinshasa-image.jpg","articleSection":["HISTORIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/","url":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/","name":"Un pozo de agua brota en la gloriosa Kinshasa | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Un-pozo-de-agua-brota-en-la-gloriosa-Kinshasa-image.jpg","datePublished":"2017-03-20T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Un-pozo-de-agua-brota-en-la-gloriosa-Kinshasa-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Un-pozo-de-agua-brota-en-la-gloriosa-Kinshasa-image.jpg","width":1960,"height":600,"caption":"Un pozo de agua brota en la gloriosa Kinshasa"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/un-pozo-de-agua-brota-en-la-gloriosa-kinshasa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"HISTORIAS","item":"https:\/\/acninternational.org\/es\/category\/historias\/"},{"@type":"ListItem","position":3,"name":"Un pozo de agua brota en la gloriosa Kinshasa"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"","url":"https:\/\/acninternational.org\/es\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/114206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=114206"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/114206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/114207"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=114206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=114206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=114206"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=114206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}