{"id":113621,"date":"2016-12-09T00:00:00","date_gmt":"2016-12-08T23:00:00","guid":{"rendered":"https:\/\/acninternational.org\/eritrea-tiene-hambre-de-dios\/"},"modified":"2016-12-09T00:00:00","modified_gmt":"2016-12-08T23:00:00","slug":"eritrea-tiene-hambre-de-dios","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/","title":{"rendered":"\u00abEritrea tiene hambre de Dios\u00bb"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Entrevista acerca de las primeras impresiones del P. Andrzej Halemba en su reciente visita a Eritrea.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Por Maria Lozano <\/b><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Usted ha estado recientemente en Eritrea. \u00bfQu\u00e9 impresi\u00f3n le ha causado este pa\u00eds? <\/b><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Es la primera vez que he logrado ir all\u00ed, tras muchos a\u00f1os de intentar obtener el permiso para visitar el pa\u00eds. Casi el 50 % de la poblaci\u00f3n es cristiana, y la otra mitad, musulmana. La mayor\u00eda de los cristianos pertenecen a la Iglesia Ortodoxa. El Estado reconoce a las Iglesias Cat\u00f3lica, Ortodoxa y Protestante y tambi\u00e9n al Islam. En Eritrea hay unos 150.000 cat\u00f3licos. Sin lugar a dudas, podemos afirmar que este pa\u00eds est\u00e1 muy marcado por el Cristianismo. En \u00e9l hay iglesias impresionantes y hermosas, e incre\u00edbles campanarios. Pero tambi\u00e9n la espiritualidad de la gente es impactante, y esta espiritualidad tambi\u00e9n se refleja en sus rostros y en la ropa que llevan. All\u00ed se puede ver a mujeres vestidas de blanco, lo cual simboliza su adhesi\u00f3n a la espiritualidad, pues as\u00ed toman conciencia del cielo. Adem\u00e1s, estas ropas contribuyen de alguna manera a un ambiente espiritual.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>\u00bfC\u00f3mo es all\u00ed la vida de los cristianos? <\/b><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Pese a todas las dificultades que atraviesan, que son ampliamente conocidas, podemos afirmar que el Cristianismo est\u00e1 sobreviviendo en estos dif\u00edciles tiempos. Tambi\u00e9n cabe resaltar que la Iglesia Cat\u00f3lica est\u00e1 manteni\u00e9ndose a s\u00ed misma, que intenta ser autosuficiente y que dirige proyectos sociales. La Iglesia Cat\u00f3lica es la \u00fanica organizaci\u00f3n religiosa del pa\u00eds que gestiona jardines de infancia, escuelas, etc., y que tambi\u00e9n ofrece diferentes tipos de apoyo a la promoci\u00f3n de las mujeres, ofreci\u00e9ndoles instrumentos para ganarse ellas mismas el sustento. Esta labor de la Iglesia es especialmente notable, pues \u2013como todo el mundo sabe\u2013 muchos hombres de edad media est\u00e1n en el Ej\u00e9rcito, por lo que las mujeres tienen que hacerse cargo de familias generalmente numerosas. En Eritrea hay muchas familias mantenidas solo por mujeres. La Iglesia Cat\u00f3lica ha detectado esta situaci\u00f3n e intenta afrontar el problema mediante una oferta de cursos de higiene, cocina, bordado, costura y muchos m\u00e1s.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>\u00bfCu\u00e1les fueron los momentos m\u00e1s emocionantes del viaje?<\/b><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Hubo muchos momentos emocionantes, pero si, como sacerdote, tuviera que elegir uno, escoger\u00eda la gran determinaci\u00f3n de los j\u00f3venes sacerdotes y religiosas para aprender. Como la velocidad de Internet no es grande, tienen que permanecer despiertos hasta muy entrada la noche, hasta despu\u00e9s de la medianoche, para hacer sus deberes, descargarse archivos y preparar los documentos para el d\u00eda siguiente. Los he visto trabajar durante muchas horas y estudiar por la noche con el fin de obtener su licenciatura. Esto resulta sorprendente, y lo mismo vale para las religiosas. Tambi\u00e9n es hermoso ver cu\u00e1ntas personas est\u00e1n interesadas en convertirse en catequistas y en impartir Religi\u00f3n. Para ellos esto no es solo una fuente de ingresos, un salario, sino una vocaci\u00f3n que sienten en su interior.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Como es bien sabido, los sacerdotes no pueden celebrar la Misa en cualquier lugar, por lo que, en estos casos, son las religiosas las que se encargan de las parroquias. Son ellas las que preparan a la gente para la Primera Comuni\u00f3n y las que atienden a los enfermos. Recuerdo presenciar c\u00f3mo un anciano que acud\u00eda a ellas era tratado con gran familiaridad, como si fuera un abuelo. Era un albino y estaba claro que estaba enfermo y atravesaba otras dificultades. Sin embargo, con ellas se sent\u00eda como en casa, lo cual demuestra que las religiosas mantienen una gran cercan\u00eda con la gente.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Tambi\u00e9n me conmovi\u00f3 mucho ver c\u00f3mo las religiosas gestionan un orfanato. Fue hermoso presenciar c\u00f3mo las chicas j\u00f3venes y algo m\u00e1s mayores trataban a las Hermanas, y fue realmente bonito verlas danzar, impartir clases y todo lo dem\u00e1s.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Otra imagen que me viene a la mente es la de un sacerdote casi ciego que dirige un orfanato a donde trajeron un hombre discapacitado, pues el centro es para hu\u00e9rfanos, pero tambi\u00e9n para personas con minusval\u00edas. All\u00ed percib\u00ed que estos centros no son instituciones, sino que en ellos se forman algo as\u00ed como familias cuyos miembros se cuidan mutuamente.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>\u00bfQu\u00e9 cabe resaltar de la labor actual de AIN en Eritrea? <\/b><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Eritrea tiene hambre de Dios. Puedo afirmar que su determinaci\u00f3n y espiritualidad, su hambre de Biblias es realmente impactante. Seg\u00fan me aseguraron, la gente solo quiere leer obras relacionadas con la religi\u00f3n. Tambi\u00e9n me dijeron que les gustar\u00eda tener literatura religiosa, pero que no es f\u00e1cil de conseguir. Sin embargo, cuando hay una oferta, la gente compra, aunque le resulte caro. Adem\u00e1s, hay muchas vocaciones, tanto para el sacerdocio como para la vida religiosa. Cuando visit\u00e9 el seminario menor les pregunt\u00e9 a los chavales si quer\u00edan ser sacerdotes, y las repuestas eran maravillosas, de todo tipo, pero maravillosas: \u201cQuiero servir a Dios\u201d, \u201cQuiero dirigir a la gente\u201d o \u201cAmo a Dios y me gustar\u00eda que los dem\u00e1s tambi\u00e9n amaran a Dios\u201d. Evidentemente, no todos ellos se convertir\u00e1n en sacerdotes, porque, a veces, se encuentran solos con esta decisi\u00f3n. Por ejemplo, cuando son el \u00fanico hijo var\u00f3n de la familia y los padres no quieren que sean sacerdotes; otros realizan el servicio militar y no pueden abandonarlo. Ciertamente, hay obst\u00e1culos, pero las respuestas son maravillosas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevista acerca de las primeras impresiones del P. Andrzej Halemba en su reciente visita a Eritrea.<\/p>\n","protected":false},"author":1,"featured_media":113622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[713],"tags":[],"country":[],"class_list":["post-113621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Eritrea tiene hambre de Dios&quot; | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Eritrea tiene hambre de Dios&quot;\" \/>\n<meta property=\"og:description\" content=\"Entrevista acerca de las primeras impresiones del P. Andrzej Halemba en su reciente visita a Eritrea.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-08T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Eritrea-tiene-hambre-de-Dios-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1960\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_acn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_acn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/\"},\"author\":{\"name\":\"admin_acn\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\"},\"headline\":\"\u00abEritrea tiene hambre de Dios\u00bb\",\"datePublished\":\"2016-12-08T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/\"},\"wordCount\":933,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Eritrea-tiene-hambre-de-Dios-image.jpg\",\"articleSection\":[\"HISTORIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/\",\"name\":\"\\\"Eritrea tiene hambre de Dios\\\" | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Eritrea-tiene-hambre-de-Dios-image.jpg\",\"datePublished\":\"2016-12-08T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Eritrea-tiene-hambre-de-Dios-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Eritrea-tiene-hambre-de-Dios-image.jpg\",\"width\":1960,\"height\":600,\"caption\":\"\\\"Eritrea tiene hambre de Dios\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/eritrea-tiene-hambre-de-dios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HISTORIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/historias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00abEritrea tiene hambre de Dios\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\",\"name\":\"admin_acn\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/admin_acn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Eritrea tiene hambre de Dios\" | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/","og_locale":"es_ES","og_type":"article","og_title":"\"Eritrea tiene hambre de Dios\"","og_description":"Entrevista acerca de las primeras impresiones del P. Andrzej Halemba en su reciente visita a Eritrea.","og_url":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2016-12-08T23:00:00+00:00","og_image":[{"width":1960,"height":600,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Eritrea-tiene-hambre-de-Dios-image.jpg","type":"image\/jpeg"}],"author":"admin_acn","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"admin_acn","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/"},"author":{"name":"admin_acn","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc"},"headline":"\u00abEritrea tiene hambre de Dios\u00bb","datePublished":"2016-12-08T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/"},"wordCount":933,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Eritrea-tiene-hambre-de-Dios-image.jpg","articleSection":["HISTORIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/","url":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/","name":"\"Eritrea tiene hambre de Dios\" | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Eritrea-tiene-hambre-de-Dios-image.jpg","datePublished":"2016-12-08T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Eritrea-tiene-hambre-de-Dios-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Eritrea-tiene-hambre-de-Dios-image.jpg","width":1960,"height":600,"caption":"\"Eritrea tiene hambre de Dios\""},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/eritrea-tiene-hambre-de-dios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"HISTORIAS","item":"https:\/\/acninternational.org\/es\/category\/historias\/"},{"@type":"ListItem","position":3,"name":"\u00abEritrea tiene hambre de Dios\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc","name":"admin_acn","url":"https:\/\/acninternational.org\/es\/author\/admin_acn\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/113621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=113621"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/113621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/113622"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=113621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=113621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=113621"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=113621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}