{"id":113501,"date":"2016-11-01T00:00:00","date_gmt":"2016-10-31T23:00:00","guid":{"rendered":"https:\/\/acninternational.org\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/"},"modified":"2016-11-01T00:00:00","modified_gmt":"2016-10-31T23:00:00","slug":"mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/","title":{"rendered":"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d"},"content":{"rendered":"<p><strong>En Mogadiscio \u201clos cristianos arriesgan su vida\u201d <\/strong><\/p>\n<p><strong>El trabajo de la Iglesia en Yibuti se centra en las escuelas y en C\u00e1ritas, \u201cun misionero no est\u00e1 s\u00f3lo para los cat\u00f3licos\u201d<\/strong><\/p>\n<p>\u201cAunque sea en silencio, es mejor estar que no estar\u201d, as\u00ed explica Mons. Giorgio Bertin, administrador apost\u00f3lico de Mogadiscio y obispo de Yibuti, la presencia de la Iglesia Cat\u00f3lica en esta zona del <strong>Cuerno de \u00c1frica <\/strong>donde vive y trabaja desde hace casi 40 a\u00f1os. <strong>\u00a0<\/strong><\/p>\n<p>Al prelado italiano se le ilumina la cara cuando se le pregunta por la peque\u00f1a Iglesia de San Antonio de Padova, situada en la ciudad somalilandesa de Hargeisa, \u201cla construyeron los capuchinos en 1950, pero durante muchos a\u00f1os ha estado cerrada. Antes de las rebeliones contra las autoridades de Mogadiscio yo daba misa aqu\u00ed al menos tres veces al a\u00f1o, en Navidad, Pascua\u2026 Luego era muy peligroso\u201d. En 1996 un colaborador de C\u00e1ritas comenz\u00f3 a hacer obras, incluso hizo una tapia, pero era un riesgo estar all\u00ed, estaba cerrada y hab\u00eda un se\u00f1or que la vigilaba. \u201cEl pasado mes de enero habl\u00e9 con las autoridades de Hargeisa explic\u00e1ndoles que quer\u00edamos abrirla de nuevo y que ser\u00eda tambi\u00e9n un lugar donde llevar a cabo la actividad humanitaria con C\u00e1ritas. Lo aceptaron y consagr\u00e9 de nuevo la Iglesia\u201d, responde con una sonrisa de oreja a oreja en declaraciones a <em>Aid to the Church in Need<\/em> (ACN) en Roma, en un viaje rel\u00e1mpago a Italia. \u201cNo vienen muchas personas a misa, diez a los sumo, pero <strong>es importante\u201d.<\/strong><\/p>\n<p>La peque\u00f1a iglesia de Hargeisa es el \u00fanico lugar de culto cat\u00f3lico de toda <strong>Somalia\u00a0 <\/strong>actualmente, un pa\u00eds donde cada vez \u201chay m\u00e1s mezquitas por las ayudas que llegan de Arabia Saud\u00ed\u201d. \u201cEn Mogadiscio no hay ninguna posibilidad de estar presentes porque es muy peligroso, hay alg\u00fan cat\u00f3lico, pero si por ejemplo hacen cualquier actividad con C\u00e1ritas arriesgan su vida. S\u00f3lo podemos estar all\u00ed a trav\u00e9s de otras asociaciones somal\u00edes\u201d.<\/p>\n<p>La Santa Sede pidi\u00f3 a Mons. Bertin ser administrador apost\u00f3lico de Mogadiscio cuando asesinaron a <strong>Mons. Salvatore Colombo<\/strong> hace 27 a\u00f1os, despu\u00e9s de que los rebeldes destruyeran la gran totalidad de la capital somal\u00ed y toda la presencia f\u00edsica de la Iglesia Cat\u00f3lica. \u201cNos tomaron como punto de mira, pero no s\u00f3lo a nosotros, destruyeron todo, embajadas, instituciones p\u00fablicas\u2026\u201d. Una rebeli\u00f3n tal que marc\u00f3 un antes y un despu\u00e9s en la historia de Somalia donde todav\u00eda no se ha podido formar un Estado, sino que el pa\u00eds se ha divido en zonas y se han autoproclamado diversos estados aut\u00f3nomos, en su mayor\u00eda no reconocidos.<\/p>\n<p><strong>En Yibuti la Iglesia s\u00ed es respetada<\/strong><\/p>\n<p>Puntualiza Mons. Bert\u00edn que en el estado independiente de Yibuti donde \u00e9l vive habitualmente, es diferente que en Somalia, \u201call\u00ed estamos tranquilos, no hay peligros, la Iglesia es respetada\u201d. En esta excolonia francesa, viven actualmente 5.000 cat\u00f3licos, la mayor\u00eda extranjeros que est\u00e1n all\u00ed por trabajo, o franceses o personas que llegan desde Etiop\u00eda. \u201cTambi\u00e9n hay fieles aut\u00f3ctonos de Yibuti que son cat\u00f3licos, ya sea por tradici\u00f3n familiar o hu\u00e9rfanos que fueron acogidos por instituciones de la Iglesia, pero son los menos\u201d.<\/p>\n<p>\u201cEn Yibuti la labor m\u00e1s grande de la Iglesia son <strong>las escuelas y el trabajo de C\u00e1ritas<\/strong>\u201d, afirma el obispo italiano tocando la cruz de madera que lleva en el pecho, \u201cson como nuestros dos brazos\u201d. \u201cEl trabajo pastoral all\u00ed es muy reducido, y aunque no hagamos conversiones ni las sigamos, s\u00ed que llevamos la semilla del Evangelio a la gente, ya que el 99 % de los alumnos de nuestros colegios son musulmanes. Saben que somos serios, que les respetamos y ellos nos respetan a nosotros\u201d.<\/p>\n<p>En este pa\u00eds de mayor\u00eda musulmana, viven 30 religiosos aproximadamente, hay dos iglesias cat\u00f3licas y cuatro estaciones misioneras. \u201cUn sacerdote o una religiosa <strong>no est\u00e1n s\u00f3lo para los cat\u00f3licos<\/strong>, est\u00e1 presente en la sociedad, en contacto con las personas, abiertos a ellos, no nos podemos quedar cerrados en nuestras estructuras\u201d, detalla Mons. Giorgio Bertin, quien pis\u00f3 el Cuerno de \u00c1frica por primera vez en 1969, donde vive desde 1978.<\/p>\n<p>Hace poco el Papa Francisco recibi\u00f3 al entrevistado en audiencia, \u201cme escuch\u00f3, hablamos de las realidades de all\u00ed, nos agradeci\u00f3 por nuestra labor y tambi\u00e9n por el regalo que le llev\u00e9 que era incienso, \u00a1y me dijo que el incienso de Somalia era muy bueno!\u201d, explica ri\u00e9ndose, \u201cahora estamos esperando a la visita Ad Limina\u201d.<\/p>\n<p>La fundaci\u00f3n internacional <strong>ACN<\/strong> ha ayudado tanto en Somalia como en Yibuti en diferentes proyectos, por ejemplo en la traducci\u00f3n y la publicaci\u00f3n de diferentes libros como el catecismo. \u201cEstoy muy agradecido a <em>Aid to the Church in Need<\/em>, tenemos una buena relaci\u00f3n desde hace ya muchos a\u00f1os\u201d, afirma el obispo de Yibuti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Mogadiscio \u201clos cristianos arriesgan su vida\u201d  El trabajo de la Iglesia en Yibuti se centra en las escuelas<\/p>\n","protected":false},"author":1,"featured_media":113502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[713],"tags":[],"country":[],"class_list":["post-113501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d\" \/>\n<meta property=\"og:description\" content=\"En Mogadiscio \u201clos cristianos arriesgan su vida\u201d El trabajo de la Iglesia en Yibuti se centra en las escuelas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-31T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Mons.-Bertin-%E2%80%9CHemos-consagrado-de-nuevo-la-capilla-de-San-Antonio-%C3%BAnico-lugar-de-culto-en-Somalia%E2%80%9D-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1960\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_acn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_acn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/\"},\"author\":{\"name\":\"admin_acn\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\"},\"headline\":\"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d\",\"datePublished\":\"2016-10-31T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/\"},\"wordCount\":849,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Mons.-Bertin-%E2%80%9CHemos-consagrado-de-nuevo-la-capilla-de-San-Antonio-%C3%BAnico-lugar-de-culto-en-Somalia%E2%80%9D-image.jpg\",\"articleSection\":[\"HISTORIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/\",\"name\":\"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Mons.-Bertin-%E2%80%9CHemos-consagrado-de-nuevo-la-capilla-de-San-Antonio-%C3%BAnico-lugar-de-culto-en-Somalia%E2%80%9D-image.jpg\",\"datePublished\":\"2016-10-31T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Mons.-Bertin-%E2%80%9CHemos-consagrado-de-nuevo-la-capilla-de-San-Antonio-%C3%BAnico-lugar-de-culto-en-Somalia%E2%80%9D-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Mons.-Bertin-%E2%80%9CHemos-consagrado-de-nuevo-la-capilla-de-San-Antonio-%C3%BAnico-lugar-de-culto-en-Somalia%E2%80%9D-image.jpg\",\"width\":1960,\"height\":600,\"caption\":\"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HISTORIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/historias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\",\"name\":\"admin_acn\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/admin_acn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/","og_locale":"es_ES","og_type":"article","og_title":"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d","og_description":"En Mogadiscio \u201clos cristianos arriesgan su vida\u201d El trabajo de la Iglesia en Yibuti se centra en las escuelas","og_url":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2016-10-31T23:00:00+00:00","og_image":[{"width":1960,"height":600,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Mons.-Bertin-%E2%80%9CHemos-consagrado-de-nuevo-la-capilla-de-San-Antonio-%C3%BAnico-lugar-de-culto-en-Somalia%E2%80%9D-image.jpg","type":"image\/jpeg"}],"author":"admin_acn","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"admin_acn","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/"},"author":{"name":"admin_acn","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc"},"headline":"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d","datePublished":"2016-10-31T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/"},"wordCount":849,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Mons.-Bertin-%E2%80%9CHemos-consagrado-de-nuevo-la-capilla-de-San-Antonio-%C3%BAnico-lugar-de-culto-en-Somalia%E2%80%9D-image.jpg","articleSection":["HISTORIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/","url":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/","name":"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Mons.-Bertin-%E2%80%9CHemos-consagrado-de-nuevo-la-capilla-de-San-Antonio-%C3%BAnico-lugar-de-culto-en-Somalia%E2%80%9D-image.jpg","datePublished":"2016-10-31T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Mons.-Bertin-%E2%80%9CHemos-consagrado-de-nuevo-la-capilla-de-San-Antonio-%C3%BAnico-lugar-de-culto-en-Somalia%E2%80%9D-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Mons.-Bertin-%E2%80%9CHemos-consagrado-de-nuevo-la-capilla-de-San-Antonio-%C3%BAnico-lugar-de-culto-en-Somalia%E2%80%9D-image.jpg","width":1960,"height":600,"caption":"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/mons-bertin-hemos-consagrado-de-nuevo-la-capilla-de-san-antonio-unico-lugar-de-culto-en-somalia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"HISTORIAS","item":"https:\/\/acninternational.org\/es\/category\/historias\/"},{"@type":"ListItem","position":3,"name":"Mons. Bertin: \u201cHemos consagrado de nuevo la capilla de San Antonio, \u00fanico lugar de culto en Somalia\u201d"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc","name":"admin_acn","url":"https:\/\/acninternational.org\/es\/author\/admin_acn\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/113501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=113501"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/113501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/113502"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=113501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=113501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=113501"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=113501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}