{"id":113036,"date":"2017-01-17T00:00:00","date_gmt":"2017-01-16T23:00:00","guid":{"rendered":"https:\/\/acninternational.org\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/"},"modified":"2017-01-17T00:00:00","modified_gmt":"2017-01-16T23:00:00","slug":"iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/","title":{"rendered":"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n &#8211; El EI utiliz\u00f3 una iglesia como campo de tiro"},"content":{"rendered":"<p><em>por Jaco Klamer para Aid to the Church in Need <\/em><\/p>\n<p>\u00abNo entiendo c\u00f3mo los hombres pueden causar tantos da\u00f1os los unos a los otros\u00bb, dice suspirando Louis Petrus, un guardia de seguridad. Hoy, Louis ha regresado por primera vez a su tierra natal: la ciudad cristiana de Qaraqosh, cerca de Mosul. De all\u00ed tuvo que huir el 6 de agosto de 2014, cuando el EI ocup\u00f3 la ciudad. \u00abMire mi casa: est\u00e1 da\u00f1ada, la mayor parte de los muebles ha sido robada y mis efectos personales est\u00e1n rotos. Otras personas de Qaraqosh ya me hab\u00edan preparado comentando lo que me esperar\u00eda en la ciudad. Hab\u00eda o\u00eddo historias y visto im\u00e1genes de la destrucci\u00f3n causada por los yihadistas. Pero ahora que veo la ciudad con mis propios ojos, no s\u00e9 qu\u00e9 sentir. Los terroristas del EI han destruido muchas de mis posesiones; pero estoy bastante bien, comparado con el da\u00f1o que puedo ver en las casas de mis vecinos: muchas casas han sido incendiadas o incluso completamente destruidas. Me puedo considerar bendecido\u00bb.<\/p>\n<p><em>Tesoros escondidos <\/em><\/p>\n<p>Hoy, Fr. Sharbil Eeso, sacerdote cat\u00f3lico de 72 a\u00f1os de edad, ha vuelto a la ciudad liberada de Qaraqosh, que fue obligado a abandonar el 17 de agosto de 2014 por tercera y \u00faltima vez. En el seminario y sus oficinas anejas reina el caos: en busca de tesoros escondidos, los ocupantes derrumbaron los techos. Destruyeron estatuas y desperdigaron los papeles. \u00abTodav\u00eda no se nos permite poner orden\u00bb, dice mientras sacude el polvo de su birrete, recientemente recuperado. \u00abEn primer lugar tenemos que evaluar cuidadosamente los da\u00f1os y documentarlos minuciosamente; y no lo podemos hacer hasta que la ciudad est\u00e9 segura. La semana pasada, un yihadista sali\u00f3 de un sistema de t\u00faneles construido debajo de la ciudad por el EI. Efectivos del Ej\u00e9rcito le dispararon inmediatamente y lo mataron; era un muchacho de unos 13 a\u00f1os de edad\u00bb.<\/p>\n<p><em>Seguridad<\/em><\/p>\n<p>Los yihadistas utilizaron frecuentemente las iglesias de Qaraqosh, e incluso escribieron instrucciones de batalla en sus paredes. La iglesia cat\u00f3lica siria de San Jorge fue convertida en f\u00e1brica de bombas; estaba en pleno uso hasta la apresurada retirada del EI. All\u00ed se encuentran cientos de bombas y granadas, de todas las formas y tama\u00f1os, esperando a ser detonadas. Adem\u00e1s, la iglesia ha \u00abrecibido\u00bb recetas mortales, que \u2014si se usan en las proporciones adecuadas\u2014 pueden convertir los agentes qu\u00edmicos escondidos en la iglesia en explosivos de dimensiones catastr\u00f3ficas.<\/p>\n<p>\u00abA pesar de todos los da\u00f1os sufridos, tengo esperanza para el futuro\u00bb, dice sonriendo el padre Sharbil. \u00abSi se garantiza nuestra seguridad, los cristianos pueden seguir viviendo en Irak. Los cristianos europeos podr\u00edan hacer m\u00e1s para mantenernos seguros. Deseo volver a Qaraqosh cuando haya electricidad y agua de nuevo, aunque pienso que la seguridad es la principal condici\u00f3n para el regreso\u00bb.<\/p>\n<p>Tambi\u00e9n Louis Petrus tiene la firme intenci\u00f3n de volver a Qaraqosh: \u00abYo no quiero salir de Irak, a menos que todos los habitantes abandonen la ciudad. Pero si dos o tres familias regresan a Qaraqosh, yo tambi\u00e9n lo har\u00e9. Es mi pa\u00eds. Tan pronto como la ciudad sea segura y nos den el permiso para vivir aqu\u00ed de nuevo, deseo rehacer mi vida en Qaraqosh. Este es mi lugar, y aqu\u00ed permanecer\u00e9 hasta que muera\u00bb.<\/p>\n<p><em>Rectificaci\u00f3n de fronteras<\/em><\/p>\n<p>Yacoob G. Yaco, miembro asirio del Parlamento, viaja casi diariamente al territorio liberado, a fin de informarse sobre los progresos en el frente y la situaci\u00f3n de la seguridad. Tambi\u00e9n anima a los miembros del ej\u00e9rcito voluntario asirio (NPU). Hoy se ha reunido con el general Faris Abderlahad Yacub (54), encargado de coordinar las tareas del ej\u00e9rcito de voluntarios en la llanura de N\u00ednive. Ambos han perdido la confianza en el ej\u00e9rcito kurdo peshmerga, porque les abandonaron cuando el EI invadi\u00f3 sus ciudades y aldeas. Por esto estamos convencidos de la importancia de un\u00a0 ej\u00e9rcito de seguridad y de crear un oasis cristiano en la llanura de N\u00ednive.<\/p>\n<p>En su condici\u00f3n de uno de los cinco miembros cristianos permanentes en el Parlamento kurdo, Yacoob representa a la comunidad cristiana iraqu\u00ed. \u00abEntre los cristianos iraqu\u00edes reina un gran malestar \u2014nos comenta\u2014. Los kurdos apoyaron a Irak en su batalla contra el EI y en la reconquista de Mosul y de las ciudades y aldeas de sus alrededores. Los habitantes lo aprecian; pero muchos cristianos sospechan que el Gobierno iraqu\u00ed dar\u00e1 a los kurdos tierras en recompensa por esa ayuda. Los kurdos cavaron fosas profundas y construyeron vallas altas que \u2014seg\u00fan ellos\u2014 tienen como objetivo detener al EI. Entretanto, los kurdos y el Gobierno niegan que se hubiera prometido territorio por esa ayuda, y aseguran a los cristianos que no se hicieron negocios en relaci\u00f3n en la tierra. Pero los canales y las vallas no se hicieron en territorio kurdo, sino en la llanura de N\u00ednive. Muchos cristianos sospechan que esa fronteras no sean temporales, sino el comienzo de una rectificaci\u00f3n permanente de las fronteras\u00bb.<\/p>\n<p><em>Pasadizos secretos<\/em><\/p>\n<p>\u00abPor supuesto que queremos volver a Qaraqosh, con nuestros hijos\u00bb, dice el alcalde de esta ciudad, Nisan Karromi (59), quien regres\u00f3 a ella el 23 de octubre, cuando todav\u00eda no estaba decidida la batalla por la ciudad. Hoy, Nisan visita su oficina y concluye que los yihadistas no tuvieron ning\u00fan respeto de su cargo: la placa con su nombre est\u00e1 tirada en el suelo, da\u00f1ada; pr\u00e1cticamente todo el inventario de su oficina ha quedado destrozado. Supone que \u00abpasar\u00e1 mucho tiempo antes de que se hayan reparado todos los da\u00f1os\u00bb.<\/p>\n<p>\u00abAlgunos habitantes de la ciudad lo perdieron todo con la invasi\u00f3n del EI; otros han visto c\u00f3mo sus casas hab\u00edan sido incendiadas y otros tuvieron incluso menos fortuna; en cualquier caso, todos tuvieron que dejar la ciudad durante dos a\u00f1os. No solo tenemos que reconstruir y reedificar la ciudad, sino que debemos abonar compensaciones por los danos sufridos. Actualmente, el Gobierno iraqu\u00ed est\u00e1 en crisis; la comunidad internacional tendr\u00e1 que ayudar a hacer que Irak vuelva a ser habitable\u00bb.<\/p>\n<p>\u00abAntes de comenzar a recoger los pedazos, tendremos que registrar cuidadosamente los da\u00f1os \u2014expone el alcalde\u2014. Adem\u00e1s, no podemos comenzar con la reconstrucci\u00f3n porque el servicio de seguridad sospecha de que a\u00fan hay guerreros del EI en los pasadizos construidos en el subsuelo de la ciudad. Todav\u00eda no se ha registrado cada casa buscando pasadizos secretos. Recientemente, dos yihadistas de aspecto asi\u00e1tico fueron vistos en Qaraqosh; pero desaparecieron antes de que pudi\u00e9ramos detenerlos\u201c.<\/p>\n<p>Entretanto, Manal Matti visita la iglesia de la Inmaculada Concepci\u00f3n, completamente calcinada. Se muestra sorprendida por los maniqu\u00edes que se encuentran por todo el recinto de la iglesia, acribillados a disparos. \u00abLos yihadistas utilizaron la iglesia como campo de tiro, y los maniqu\u00edes como dianas\u00bb, nos dice, horrorizada. \u00abLos maniqu\u00edes han quedado completamente acribillados\u00bb. Manal Matti ten\u00eda un sal\u00f3n de belleza, a pocos pasos de la catedral. Dice: \u00abNo s\u00e9 si alg\u00fan d\u00eda los habitantes de Qaraqosh acudir\u00e1n de nuevo a mi sal\u00f3n de belleza\u00bb.<\/p>\n<p>Desde 2014, <em>ACN<\/em> ha prestado ayudas a los cristianos de Irak por un valor de m\u00e1s de 20 millones de euros, para proyectos de ayuda de emergencia, formaci\u00f3n escolar, alimentos y mantenimiento de los desplazados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Jaco Klamer para Aid to the Church in Need  \u00abNo entiendo c\u00f3mo los hombres pueden causar tantos da\u00f1os<\/p>\n","protected":false},"author":1,"featured_media":113037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[713],"tags":[],"country":[],"class_list":["post-113036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n - El EI utiliz\u00f3 una iglesia como campo de tiro | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n - El EI utiliz\u00f3 una iglesia como campo de tiro\" \/>\n<meta property=\"og:description\" content=\"por Jaco Klamer para Aid to the Church in Need \u00abNo entiendo c\u00f3mo los hombres pueden causar tantos da\u00f1os\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-16T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Iraq-los-habitantes-de-Qaraqosh-eval%C3%BAan-los-da%C3%B1os-causados-por-la-ocupaci%C3%B3n-El-EI-utiliz%C3%B3-una-iglesia-como-campo-de-tiro-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1960\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_acn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_acn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/\"},\"author\":{\"name\":\"admin_acn\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\"},\"headline\":\"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n &#8211; El EI utiliz\u00f3 una iglesia como campo de tiro\",\"datePublished\":\"2017-01-16T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/\"},\"wordCount\":1263,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Iraq-los-habitantes-de-Qaraqosh-eval%C3%BAan-los-da%C3%B1os-causados-por-la-ocupaci%C3%B3n-El-EI-utiliz%C3%B3-una-iglesia-como-campo-de-tiro-image.jpg\",\"articleSection\":[\"HISTORIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/\",\"name\":\"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n - El EI utiliz\u00f3 una iglesia como campo de tiro | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Iraq-los-habitantes-de-Qaraqosh-eval%C3%BAan-los-da%C3%B1os-causados-por-la-ocupaci%C3%B3n-El-EI-utiliz%C3%B3-una-iglesia-como-campo-de-tiro-image.jpg\",\"datePublished\":\"2017-01-16T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Iraq-los-habitantes-de-Qaraqosh-eval%C3%BAan-los-da%C3%B1os-causados-por-la-ocupaci%C3%B3n-El-EI-utiliz%C3%B3-una-iglesia-como-campo-de-tiro-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Iraq-los-habitantes-de-Qaraqosh-eval%C3%BAan-los-da%C3%B1os-causados-por-la-ocupaci%C3%B3n-El-EI-utiliz%C3%B3-una-iglesia-como-campo-de-tiro-image.jpg\",\"width\":1960,\"height\":600,\"caption\":\"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n - El EI utiliz\u00f3 una iglesia como campo de tiro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HISTORIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/historias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n &#8211; El EI utiliz\u00f3 una iglesia como campo de tiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\",\"name\":\"admin_acn\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/admin_acn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n - El EI utiliz\u00f3 una iglesia como campo de tiro | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/","og_locale":"es_ES","og_type":"article","og_title":"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n - El EI utiliz\u00f3 una iglesia como campo de tiro","og_description":"por Jaco Klamer para Aid to the Church in Need \u00abNo entiendo c\u00f3mo los hombres pueden causar tantos da\u00f1os","og_url":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2017-01-16T23:00:00+00:00","og_image":[{"width":1960,"height":600,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Iraq-los-habitantes-de-Qaraqosh-eval%C3%BAan-los-da%C3%B1os-causados-por-la-ocupaci%C3%B3n-El-EI-utiliz%C3%B3-una-iglesia-como-campo-de-tiro-image.jpg","type":"image\/jpeg"}],"author":"admin_acn","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"admin_acn","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/"},"author":{"name":"admin_acn","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc"},"headline":"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n &#8211; El EI utiliz\u00f3 una iglesia como campo de tiro","datePublished":"2017-01-16T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/"},"wordCount":1263,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Iraq-los-habitantes-de-Qaraqosh-eval%C3%BAan-los-da%C3%B1os-causados-por-la-ocupaci%C3%B3n-El-EI-utiliz%C3%B3-una-iglesia-como-campo-de-tiro-image.jpg","articleSection":["HISTORIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/","url":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/","name":"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n - El EI utiliz\u00f3 una iglesia como campo de tiro | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Iraq-los-habitantes-de-Qaraqosh-eval%C3%BAan-los-da%C3%B1os-causados-por-la-ocupaci%C3%B3n-El-EI-utiliz%C3%B3-una-iglesia-como-campo-de-tiro-image.jpg","datePublished":"2017-01-16T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Iraq-los-habitantes-de-Qaraqosh-eval%C3%BAan-los-da%C3%B1os-causados-por-la-ocupaci%C3%B3n-El-EI-utiliz%C3%B3-una-iglesia-como-campo-de-tiro-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Iraq-los-habitantes-de-Qaraqosh-eval%C3%BAan-los-da%C3%B1os-causados-por-la-ocupaci%C3%B3n-El-EI-utiliz%C3%B3-una-iglesia-como-campo-de-tiro-image.jpg","width":1960,"height":600,"caption":"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n - El EI utiliz\u00f3 una iglesia como campo de tiro"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/iraq-los-habitantes-de-qaraqosh-evaluan-los-danos-causados-por-la-ocupacion-el-ei-utilizo-una-iglesia-como-campo-de-tiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"HISTORIAS","item":"https:\/\/acninternational.org\/es\/category\/historias\/"},{"@type":"ListItem","position":3,"name":"Iraq: los habitantes de Qaraqosh eval\u00faan los da\u00f1os causados por la ocupaci\u00f3n &#8211; El EI utiliz\u00f3 una iglesia como campo de tiro"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc","name":"admin_acn","url":"https:\/\/acninternational.org\/es\/author\/admin_acn\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/113036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=113036"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/113036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/113037"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=113036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=113036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=113036"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=113036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}