{"id":112946,"date":"2016-10-21T00:00:00","date_gmt":"2016-10-20T22:00:00","guid":{"rendered":"https:\/\/acninternational.org\/alepo-no-podemos-mas\/"},"modified":"2016-10-21T00:00:00","modified_gmt":"2016-10-20T22:00:00","slug":"alepo-no-podemos-mas","status":"publish","type":"post","link":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/","title":{"rendered":"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb"},"content":{"rendered":"<p><b>Alepo, contin\u00faa recibiendo bombardeos, multiplicando las v\u00edctimas tanto en el este como en el oeste de la ciudad. Las religiosas del Carmelo de Alepo nos mandan esta carta, testigo de lo que sus habitantes viven a diario.<\/b><\/p>\n<p>AIN.- \u00abComo sab\u00e9is por la informaci\u00f3n que llega a Occidente,<b> los bombardeos sobre el este de Alepo son numerosos. <\/b>Pero la situaci\u00f3n en el oeste de la ciudad no es mucho mejor, a pesar de que los medios de comunicaci\u00f3n no se hacen eco de ello. Esta parcialidad en la informaci\u00f3n nos entristece, ya que somos cada d\u00eda testigos directos o indirectos, a trav\u00e9s de las noticias de sacerdotes o de personas cercanas y conocidas, de todos los sufrimientos que padecen en los diferentes barrios del oeste de la ciudad: obuses, misiles y armas cada vez m\u00e1s sofisticadas, sin citar la falta absoluta de agua y de electricidad (cortados por los grupos armados opositores) que provocan cada vez m\u00e1s v\u00edctimas; los muertos y los heridos se cuentan por decenas todos los d\u00edas.<\/p>\n<p><span style=\"color: #ff0000;\">\u00abDesde hace una semana, este sacerdote no deja de enterrar a civiles\u00bb <\/span><br \/>\nEl otro d\u00eda, un sacerdote que nos celebra la misa un d\u00eda por semana, lleg\u00f3 llorando: vive en <b>Midan,<\/b> un barrio sencillo que desde hace tres a\u00f1os, es<b>presa incesante de atentados.<\/b> <b>Desde hace una semana, este sacerdote no deja de enterrar a v\u00edctimas civiles.<\/b><\/p>\n<p>En otro <b>barrio obrero, pr\u00e1cticamente musulm\u00e1n en su totalidad,<\/b> cerca del hospital de San Luis regentado por las <b>hermanas de San Jos\u00e9 de la Aparici\u00f3n,<\/b> <b>los obuses provocaron hace algunos d\u00edas, una decena de muertos y m\u00e1s de 70 heridos.<\/b><\/p>\n<p>NO PODEMOS M\u00c1S y <b>pedimos INCESANTEMENTE EL FIN DE LOS COMBATES EN TODAS LAS ZONAS<\/b> de la ciudad, as\u00ed como un poco m\u00e1s de OBJETIVIDAD en la informaci\u00f3n, por simple respeto a todas estas personas pobres que est\u00e1n sufriendo (se trata en su mayor\u00eda de familias muy modestas, por no decir pobres o incluso miserables\u2026)<\/p>\n<p><span style=\"color: #ff0000;\">Contemplativas en el coraz\u00f3n de la violencia <\/span><br \/>\nDicho esto,<b> queremos conservar la confianza y creer que un d\u00eda la verdad triunfar\u00e1;<\/b> y que el mal, la mentira y la corrupci\u00f3n, sean de uno u otro bando, ser\u00e1n vencidos por la verdad, la reconciliaci\u00f3n y por verdaderos proyectos de paz, en definitiva por nuestra conversi\u00f3n al Se\u00f1or. \u00a1Somos las primeras en reconocer la necesidad de conversi\u00f3n en nuestro propio coraz\u00f3n!<\/p>\n<p>(\u2026) Gracias por rezar por todo lo que vivimos en la oscuridad de nuestra vida oculta o por nuestro pobre testimonio de contemplativas en pleno coraz\u00f3n de la violencia y de la guerra, para que sea vivido en la humildad, la paz y la verdad. <b>En este mes del Rosario, os conf\u00edo a todos bajo la protecci\u00f3n maternal de ternura y de misericordia de la Santa Madre de Dios, Madre Nuestra:<\/b> <b>\u00abque nos arrastre con su ejemplo y nos conceda amar con su propio coraz\u00f3n\u00bb<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alepo, contin\u00faa recibiendo bombardeos, multiplicando las v\u00edctimas tanto en el este como en el oeste de la ciudad. Las religiosas<\/p>\n","protected":false},"author":1,"featured_media":112947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[713],"tags":[],"country":[],"class_list":["post-112946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb\" \/>\n<meta property=\"og:description\" content=\"Alepo, contin\u00faa recibiendo bombardeos, multiplicando las v\u00edctimas tanto en el este como en el oeste de la ciudad. Las religiosas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-20T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Alepo-%C2%AB-%C2%A1No-podemos-m%C3%A1s-%C2%BB-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1960\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_acn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_acn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/\"},\"author\":{\"name\":\"admin_acn\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\"},\"headline\":\"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb\",\"datePublished\":\"2016-10-20T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/\"},\"wordCount\":518,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Alepo-%C2%AB-%C2%A1No-podemos-m%C3%A1s-%C2%BB-image.jpg\",\"articleSection\":[\"HISTORIAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/\",\"name\":\"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Alepo-%C2%AB-%C2%A1No-podemos-m%C3%A1s-%C2%BB-image.jpg\",\"datePublished\":\"2016-10-20T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Alepo-%C2%AB-%C2%A1No-podemos-m%C3%A1s-%C2%BB-image.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Alepo-%C2%AB-%C2%A1No-podemos-m%C3%A1s-%C2%BB-image.jpg\",\"width\":1960,\"height\":600,\"caption\":\"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/alepo-no-podemos-mas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HISTORIAS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/es\\\/category\\\/historias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/es\\\/#\\\/schema\\\/person\\\/5a7468d38fb12b1976b6eeda95c21ebc\",\"name\":\"admin_acn\",\"url\":\"https:\\\/\\\/acninternational.org\\\/es\\\/author\\\/admin_acn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/","og_locale":"es_ES","og_type":"article","og_title":"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb","og_description":"Alepo, contin\u00faa recibiendo bombardeos, multiplicando las v\u00edctimas tanto en el este como en el oeste de la ciudad. Las religiosas","og_url":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2016-10-20T22:00:00+00:00","og_image":[{"width":1960,"height":600,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Alepo-%C2%AB-%C2%A1No-podemos-m%C3%A1s-%C2%BB-image.jpg","type":"image\/jpeg"}],"author":"admin_acn","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Escrito por":"admin_acn","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/"},"author":{"name":"admin_acn","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc"},"headline":"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb","datePublished":"2016-10-20T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/"},"wordCount":518,"commentCount":0,"publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Alepo-%C2%AB-%C2%A1No-podemos-m%C3%A1s-%C2%BB-image.jpg","articleSection":["HISTORIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/","url":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/","name":"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Alepo-%C2%AB-%C2%A1No-podemos-m%C3%A1s-%C2%BB-image.jpg","datePublished":"2016-10-20T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Alepo-%C2%AB-%C2%A1No-podemos-m%C3%A1s-%C2%BB-image.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/Alepo-%C2%AB-%C2%A1No-podemos-m%C3%A1s-%C2%BB-image.jpg","width":1960,"height":600,"caption":"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/es\/alepo-no-podemos-mas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"HISTORIAS","item":"https:\/\/acninternational.org\/es\/category\/historias\/"},{"@type":"ListItem","position":3,"name":"Alepo: \u00ab \u00a1No podemos m\u00e1s! \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/es\/#website","url":"https:\/\/acninternational.org\/es\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/es\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/es\/#\/schema\/person\/5a7468d38fb12b1976b6eeda95c21ebc","name":"admin_acn","url":"https:\/\/acninternational.org\/es\/author\/admin_acn\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/112946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/comments?post=112946"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/posts\/112946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media\/112947"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/media?parent=112946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/categories?post=112946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/tags?post=112946"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/es\/wp-json\/wp\/v2\/country?post=112946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}