{"id":242638,"date":"2025-03-17T09:38:52","date_gmt":"2025-03-17T08:38:52","guid":{"rendered":"https:\/\/acninternational.org\/?p=242638"},"modified":"2025-08-12T10:16:19","modified_gmt":"2025-08-12T08:16:19","slug":"nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde","status":"publish","type":"post","link":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/","title":{"rendered":"Nigerianische Kirche trauert um 21-j\u00e4hrigen Seminaristen, der von Entf\u00fchrern ermordet wurde"},"content":{"rendered":"<p><em>Die Ermordung des Seminaristen Andrew Peter folgt auf den k\u00fcrzlichen Mord an Pfarrer Sylvester Okechukwu. In den ersten drei Monaten des Jahres 2025 hat Nigeria dreimal so viele Entf\u00fchrungen von Geistlichen und Ordensleuten zu verzeichnen wie im gleichen Zeitraum des Jahres 2024. <\/em><\/p>\n<p>Die Nachricht von der Ermordung des jungen Seminaristen Andrew Peter durch seine Entf\u00fchrer ersch\u00fcttert die nigerianische Kirche. Dies geht aus einer Erkl\u00e4rung hervor, die die Di\u00f6zese Auchi an das Hilfswerk Aid to the Church in Need (ACN) geschickt hat.<\/p>\n<figure id=\"attachment_242580\" aria-describedby=\"caption-attachment-242580\" style=\"width: 720px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-242580 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/03\/250317_Nigeria_Auchi_Seminarian_murdered.jpg\" alt=\"Andrew Peter wurde im M\u00e4rz von seinen Entf\u00fchrern ermordet\" width=\"720\" height=\"932\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/03\/250317_Nigeria_Auchi_Seminarian_murdered.jpg 720w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2025\/03\/250317_Nigeria_Auchi_Seminarian_murdered-232x300.jpg 232w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption id=\"caption-attachment-242580\" class=\"wp-caption-text\">Andrew Peter wurde im M\u00e4rz von seinen Entf\u00fchrern ermordet<\/figcaption><\/figure>\n<p>Die Ermordung von Andrew Peter folgt auf die erst k\u00fcrzliche <a href=\"https:\/\/acninternational.org\/priest-kidnapped-and-murdered-in-nigeria\/\" target=\"_blank\" rel=\"noopener\">brutale Ermordung von Pfarrer Sylvester Okechukwu<\/a> in der Di\u00f6zese Kafanchan; die Zahl der Entf\u00fchrungen und Angriffe auf katholische Geistliche im Land hat im Vergleich zum gleichen Zeitraum des Jahres 2024 alarmierend zugenommen.<\/p>\n<p>In den ersten drei Monaten des Jahres 2024 waren drei Priester entf\u00fchrt und alle innerhalb weniger Tage freigelassen worden. Doch zwei Wochen vor Ende M\u00e4rz dieses Jahres sind in Nigeria bereits zehn Entf\u00fchrungen, darunter zwei Morde, zu beklagen.<\/p>\n<p>Der Seminarist Andrew Peter war zusammen mit Pfarrer Philip Ekweli am 3. M\u00e4rz entf\u00fchrt worden. Pfarrer Ekweli kam zehn Tage sp\u00e4ter, am 13. M\u00e4rz, frei; doch der Seminarist wurde von den Entf\u00fchrern ermordet.<\/p>\n<p>\u201eDas Leben war f\u00fcr unser Volk in letzter Zeit die H\u00f6lle. Die Menschen sind nicht sicher auf den Stra\u00dfen, in ihren H\u00f6fen und nicht einmal in ihren H\u00e4usern\u201c, sagte Bischof Gabriel Dunia von Auchi in einer Erkl\u00e4rung, die ACN zugeschickt wurde und in der die Di\u00f6zese den Tod von Andrew Peter beklagt.<\/p>\n<p>Nigeria leidet in vielen Regionen unter akuter Unsicherheit. F\u00fcr die Entf\u00fchrungen von Priestern gibt es verschiedene Gr\u00fcnde, darunter L\u00f6segeldforderungen krimineller Banden, die damit finanzielle Gewinne anstreben, religi\u00f6se und ethnische Konflikte, an denen extremistische Gruppen wie Boko Haram und ISWAP beteiligt sind, und die Bedrohung der meist christlichen Bauern durch muslimische Hirten der Volksgruppe der Fulani. Einige Entf\u00fchrungen dienen als politisches Instrument, um die Regierung zu destabilisieren und ihr Versagen bei der Gew\u00e4hrleistung der Sicherheit zu entlarven, w\u00e4hrend andere auf lokale Streitigkeiten und Landkonflikte zur\u00fcckzuf\u00fchren sind.<\/p>\n<p>Laut einer Statistik des Katholischen Sekretariats von Nigeria wurden in den vergangenen zehn Jahren 145 Priester und Seminaristen entf\u00fchrt und elf von ihnen get\u00f6tet. Diese Zahlen wurden nach der Entf\u00fchrung von Pfarrer Philip Ekweli, jedoch vor seiner Freilassung und vor der Ermordung von Pfarrer Sylvester Okechukwu und dem Seminaristen Andrew Peter ver\u00f6ffentlicht.<\/p>\n<p>Das katholische Hilfswerk Aid to the Church in Need begleitet weiterhin das Leiden der nigerianischen Kirche und ruft zum Gebet und Handeln auf, um die Sicherheit aller nigerianischen Geistlichen und Laien zu gew\u00e4hrleisten, die unter dieser Unsicherheit und Gewalt leiden. ACN ruft seine Freunde und Wohlt\u00e4ter au\u00dferdem auf, f\u00fcr die Seelen von Pfarrer Sylvester Okechukwu und Seminarist Andrew Peter zu beten sowie f\u00fcr alle, die in Nigeria ihr Leben f\u00fcr den Dienst am Volk Gottes riskieren.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eDas Leben war f\u00fcr unser Volk in letzter Zeit die H\u00f6lle. Die Menschen sind nicht sicher auf den Stra\u00dfen, in ihren H\u00f6fen und nicht einmal in ihren H\u00e4usern\u201c<\/p>\n","protected":false},"author":4258341377,"featured_media":207795,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[918,954],"tags":[],"country":[116],"class_list":["post-242638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht","category-news-de","country-nigeria"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nigerianische Kirche trauert um 21-j\u00e4hrigen Seminaristen, der von Entf\u00fchrern ermordet wurde | ACN International<\/title>\n<meta name=\"description\" content=\"\u201eDas Leben war f\u00fcr unser Volk in letzter Zeit die H\u00f6lle. Die Menschen sind nicht sicher auf den Stra\u00dfen, in ihren H\u00f6fen und nicht einmal in ihren H\u00e4usern\u201c\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nigerianische Kirche trauert um 21-j\u00e4hrigen Seminaristen, der von Entf\u00fchrern ermordet wurde\" \/>\n<meta property=\"og:description\" content=\"\u201eDas Leben war f\u00fcr unser Volk in letzter Zeit die H\u00f6lle. Die Menschen sind nicht sicher auf den Stra\u00dfen, in ihren H\u00f6fen und nicht einmal in ihren H\u00e4usern\u201c\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-17T08:38:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T08:16:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/05\/ACN-20170328-52366.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filipe d\u2019Avillez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filipe d\u2019Avillez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/\"},\"author\":{\"name\":\"Filipe d\u2019Avillez\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7489225627ad784c8faa0f4616c1cbdf\"},\"headline\":\"Nigerianische Kirche trauert um 21-j\u00e4hrigen Seminaristen, der von Entf\u00fchrern ermordet wurde\",\"datePublished\":\"2025-03-17T08:38:52+00:00\",\"dateModified\":\"2025-08-12T08:16:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/\"},\"wordCount\":528,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ACN-20170328-52366.jpg\",\"articleSection\":[\"Nachricht\",\"Nachricht\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/\",\"name\":\"Nigerianische Kirche trauert um 21-j\u00e4hrigen Seminaristen, der von Entf\u00fchrern ermordet wurde | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ACN-20170328-52366.jpg\",\"datePublished\":\"2025-03-17T08:38:52+00:00\",\"dateModified\":\"2025-08-12T08:16:19+00:00\",\"description\":\"\u201eDas Leben war f\u00fcr unser Volk in letzter Zeit die H\u00f6lle. Die Menschen sind nicht sicher auf den Stra\u00dfen, in ihren H\u00f6fen und nicht einmal in ihren H\u00e4usern\u201c\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ACN-20170328-52366.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ACN-20170328-52366.jpg\",\"width\":1920,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachricht\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/category\\\/news-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nigerianische Kirche trauert um 21-j\u00e4hrigen Seminaristen, der von Entf\u00fchrern ermordet wurde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7489225627ad784c8faa0f4616c1cbdf\",\"name\":\"Filipe d\u2019Avillez\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/author\\\/filipe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nigerianische Kirche trauert um 21-j\u00e4hrigen Seminaristen, der von Entf\u00fchrern ermordet wurde | ACN International","description":"\u201eDas Leben war f\u00fcr unser Volk in letzter Zeit die H\u00f6lle. Die Menschen sind nicht sicher auf den Stra\u00dfen, in ihren H\u00f6fen und nicht einmal in ihren H\u00e4usern\u201c","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/","og_locale":"de_DE","og_type":"article","og_title":"Nigerianische Kirche trauert um 21-j\u00e4hrigen Seminaristen, der von Entf\u00fchrern ermordet wurde","og_description":"\u201eDas Leben war f\u00fcr unser Volk in letzter Zeit die H\u00f6lle. Die Menschen sind nicht sicher auf den Stra\u00dfen, in ihren H\u00f6fen und nicht einmal in ihren H\u00e4usern\u201c","og_url":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2025-03-17T08:38:52+00:00","article_modified_time":"2025-08-12T08:16:19+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/05\/ACN-20170328-52366.jpg","type":"image\/jpeg"}],"author":"Filipe d\u2019Avillez","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Verfasst von":"Filipe d\u2019Avillez","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/"},"author":{"name":"Filipe d\u2019Avillez","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7489225627ad784c8faa0f4616c1cbdf"},"headline":"Nigerianische Kirche trauert um 21-j\u00e4hrigen Seminaristen, der von Entf\u00fchrern ermordet wurde","datePublished":"2025-03-17T08:38:52+00:00","dateModified":"2025-08-12T08:16:19+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/"},"wordCount":528,"publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/05\/ACN-20170328-52366.jpg","articleSection":["Nachricht","Nachricht"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/","url":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/","name":"Nigerianische Kirche trauert um 21-j\u00e4hrigen Seminaristen, der von Entf\u00fchrern ermordet wurde | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/05\/ACN-20170328-52366.jpg","datePublished":"2025-03-17T08:38:52+00:00","dateModified":"2025-08-12T08:16:19+00:00","description":"\u201eDas Leben war f\u00fcr unser Volk in letzter Zeit die H\u00f6lle. Die Menschen sind nicht sicher auf den Stra\u00dfen, in ihren H\u00f6fen und nicht einmal in ihren H\u00e4usern\u201c","breadcrumb":{"@id":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/05\/ACN-20170328-52366.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2024\/05\/ACN-20170328-52366.jpg","width":1920,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/de\/nigerianische-kirche-trauert-um-21-jaehrigen-seminaristen-der-von-entfuehrern-ermordet-wurde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/de\/"},{"@type":"ListItem","position":2,"name":"Nachricht","item":"https:\/\/acninternational.org\/de\/category\/news-de\/"},{"@type":"ListItem","position":3,"name":"Nigerianische Kirche trauert um 21-j\u00e4hrigen Seminaristen, der von Entf\u00fchrern ermordet wurde"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/de\/#website","url":"https:\/\/acninternational.org\/de\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/de\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7489225627ad784c8faa0f4616c1cbdf","name":"Filipe d\u2019Avillez","url":"https:\/\/acninternational.org\/de\/author\/filipe\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/242638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/users\/4258341377"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/comments?post=242638"}],"version-history":[{"count":1,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/242638\/revisions"}],"predecessor-version":[{"id":245077,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/242638\/revisions\/245077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media\/207795"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media?parent=242638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/categories?post=242638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/tags?post=242638"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/country?post=242638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}