{"id":180469,"date":"2023-04-27T16:28:19","date_gmt":"2023-04-27T14:28:19","guid":{"rendered":"https:\/\/acninternational.org\/?p=180469"},"modified":"2023-04-27T16:38:30","modified_gmt":"2023-04-27T14:38:30","slug":"burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land","status":"publish","type":"post","link":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/","title":{"rendered":"Burkina Faso: \u201eDas B\u00f6se hat nicht das letzte Wort\u201c, sagt ein Priester \u00fcber die Gewalt gegen Christen in seinem Land"},"content":{"rendered":"<p><em>Die Kirchen m\u00fcssen bewacht werden, damit die Christen in Sicherheit beten k\u00f6nnen. Katholische Krankenschwestern verkleiden sich als Muslimas, damit sie in die D\u00f6rfer fahren k\u00f6nnen, um Patienten zu behandeln. Christliche M\u00e4dchen tragen Vollverschleierung, wenn sie zur Schule gehen, um nicht entf\u00fchrt zu werden. Der Widerstand gegen die Dschihadisten in Burkina Faso erfordere viel Mut, erkl\u00e4rt Pater Wenceslao Belem bei einer von Aid to the Church in Need Spanien (ACN) organisierten Veranstaltung in der Almudena-Kathedrale von Madrid.<\/em><\/p>\n<p>\u201eSeit den ersten Anschl\u00e4gen im Jahr 2015 hat sich die Situation ver\u00e4ndert f\u00fcr Christen, die ihre Religion frei aus\u00fcben wollen.\u201c Die Worte von Pater Wenceslao Belem in der Madrider Almudena-Kathedrale h\u00e4tten nicht deutlicher sein k\u00f6nnen. Der Priester wurde eingeladen, bei einer vom spanischen B\u00fcro von ACN organisierten Gebetswache zu sprechen. Er erz\u00e4hlte von einem Land, in dem Christen unter st\u00e4ndiger Bedrohung leben, ohne Freiheit, brutaler Gewalt durch Gruppen von Dschihadisten ausgesetzt, die den Islam als einzige Religion durchsetzen wollen und die Gesellschaft allm\u00e4hlich ihren Regeln und Auflagen unterwerfen.<\/p>\n<figure id=\"attachment_180452\" aria-describedby=\"caption-attachment-180452\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-180452 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/pequena-9-1.png\" alt=\"\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/pequena-9-1.png 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/pequena-9-1-300x179.png 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-180452\" class=\"wp-caption-text\">Pater Wenceslao Belem bei seiner Zeugenaussage in Spanien.<\/figcaption><\/figure>\n<p>\u201eSeit Beginn des Terrors sind \u00fcber 2000 Schulen geschlossen worden. Sie greifen moderne Schulen an und verwandeln sie in Koranschulen; sie greifen katholische Schulen an, t\u00f6ten oder entf\u00fchren Christen, vor allem Katecheten, Priester und engagierte Laien; und sie wollen Frauen zwingen, Vollverschleierung zu tragen, unabh\u00e4ngig von ihrer Religion. Viele christliche M\u00e4dchen m\u00fcssen in der Schule einen Schleier tragen, um nicht gebrandmarkt, verleumdet, geschlagen oder gar entf\u00fchrt zu werden.\u201c<\/p>\n<p>Die Bedrohung sei so allgegenw\u00e4rtig, dass \u201ean Sonn- und Feiertagen die Kirchen von Polizei, Milit\u00e4r oder Freiwilligen bewacht werden m\u00fcssen, damit wir in Ruhe beten und die Heilige Messe feiern k\u00f6nnen\u201c, erkl\u00e4rt Pater Wenceslao. \u201eDie Terroristen verminen die Stra\u00dfen, die zu den D\u00f6rfern f\u00fchren, um uns und dem Milit\u00e4r den Zugang zu verwehren. Auf diese Weise k\u00f6nnen sie die Bev\u00f6lkerung weiterhin isolieren und sie dem Hunger oder Entbehrungen aussetzen, wenn sie sich weigern, zum Islam zu konvertieren.\u201c<\/p>\n<p>In Burkina Faso sind f\u00fcnfzig Prozent des Landes <a href=\"https:\/\/acninternational.org\/de\/terrorismus-nimmt-in-burkina-faso-zu\/\">von terroristischen Gruppen besetzt<\/a>, und an vielen anderen Orten ist es sehr gef\u00e4hrlich, die D\u00f6rfer zu besuchen, um pastorale Unterst\u00fctzung zu leisten. \u201eBevor wir zu pastoralen Eins\u00e4tzen aufbrechen, beten wir intensiv, empfangen die Sakramente und gehen zur Beichte, f\u00fcr den Fall, dass wir nicht zur\u00fcckkehren.\u201c<\/p>\n<p>In seinem Zeugnis beschrieb Pater Wenceslao ein Land, das unter den Einfluss eines dschihadistischen Terrors geraten ist, der bereits in viele der an Burkina Faso angrenzenden L\u00e4nder wie Mali, Niger und Benin vorgedrungen ist. Etwa 60 Prozent der Bev\u00f6lkerung von Burkina Faso seien Muslime. Die Katholiken machten mit etwa 19 Prozent weniger als die H\u00e4lfte davon aus und seien zunehmend dazu gezwungen, die Messe und die Katechese \u00fcber das Radio zu h\u00f6ren, da es fast unm\u00f6glich geworden sei, die Pfarrkirchen zu erreichen.<\/p>\n<figure id=\"attachment_180446\" aria-describedby=\"caption-attachment-180446\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-180446 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/pequena-8-1.png\" alt=\"\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/pequena-8-1.png 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/pequena-8-1-300x179.png 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-180446\" class=\"wp-caption-text\">Binnenvertriebene im Lager Konean.<\/figcaption><\/figure>\n<p>\u201eIn Burkina Faso sind derzeit Tausende von Schulen geschlossen, viele Kirchengemeinden wurden vorerst geschlossen, und es gibt mehr als 1,7 Millionen Binnenvertriebene\u201c, f\u00fcgte er hinzu. Dieser Bedrohung zu begegnen, erfordere sowohl Mut als auch Erfindungsgeist, wie man an den Krankenschwestern sehen k\u00f6nne, die sich weiterhin um die Menschen k\u00fcmmerten, die medizinische Hilfe ben\u00f6tigen und oft in D\u00f6rfern ohne jegliche Ressourcen zur\u00fcckgelassen werden. \u201eWenn wir diese katholischen Krankenschwestern sehen, die sich ganz der Barmherzigkeit Gottes anvertrauen und sich als Muslimas verkleiden, um gef\u00e4hrliche und von Terroristen heimgesuchte Gebiete zu durchqueren, um Leben zu retten und Kranke zu versorgen, die nicht entkommen k\u00f6nnen, f\u00fchlen wir uns ermutigt und sagen, dass es Gott ist, der rettet\u201c, sagte Pater Wenceslao bei der ACN-Veranstaltung.<\/p>\n<h4><strong>N\u00e4hrboden f\u00fcr M\u00e4rtyrer<\/strong><\/h4>\n<p>Das Zeugnis des Priesters war auch gepr\u00e4gt von der Geschichte des Priesters <a href=\"https:\/\/acninternational.org\/priest-killed-by-terrorists-in-burkina-faso\/\">Jacques Yaro Zerbo<\/a>, der am 2. Januar 2023 ermordet wurde, als er zur Beerdigung eines Katecheten in ein Dorf fuhr. \u201eEr sollte mit einem Gemeindemitglied reisen, aber in letzter Minute entschied er sich, allein zu fahren. Auf dem Weg dorthin wurde er von Terroristen angehalten. Da sie ihn kannten und wussten, dass er sich wegen seines Glaubens nicht w\u00fcrde einsch\u00fcchtern lassen, brachten sie ihn bis auf wenige Meter an die Dorfkapelle heran, erschossen ihn und fuhren mit seinem Auto davon. Die Christen h\u00f6rten den L\u00e4rm, gingen nachsehen und entdeckten die Leiche von Pater Jacques\u201c, so Pater Wenceslao Belem.<\/p>\n<p>Die Kirche von Burkina Faso ist zu einer Keimzelle f\u00fcr M\u00e4rtyrer geworden \u2013 vieler \u00a0von ihnen wurde in der Almudena-Kathedrale gedacht. \u201eIm M\u00e4rz 2019 wurde Joel Yougbare, Pfarrer von Djibo in der Di\u00f6zese Dori, entf\u00fchrt. Seitdem haben wir nichts mehr von ihm geh\u00f6rt. Im Mai desselben Jahres wurde der Priester Pater Simeon Yampa zusammen mit f\u00fcnf Gemeindemitgliedern w\u00e4hrend der Sonntagsmesse ermordet. Im Jahr 2021 wurde ein weiterer Priester, der spanische Missionar Antonio Cesar Fernandez, ebenfalls ermordet. Andere Gemeindemitglieder wurden entf\u00fchrt, von denen einige freigelassen wurden, andere jedoch nicht.\u201c Sie alle bleiben in guter Erinnerung, in der Gewissheit, dass ihr Leben und ihre Opfer nicht vergeblich waren.<\/p>\n<figure id=\"attachment_180440\" aria-describedby=\"caption-attachment-180440\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-180440 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/pequena-10-1.png\" alt=\"\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/pequena-10-1.png 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/pequena-10-1-300x179.png 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-180440\" class=\"wp-caption-text\">Fl\u00fcchtlingslager in der N\u00e4he der Hauptstadt.<\/figcaption><\/figure>\n<h4><strong>Das Gebet: die leise, aber wirksame Waffe<\/strong><\/h4>\n<p>In seinem Zeugnis dankte Pater Wenceslao Belem ACN f\u00fcr die Hilfe, die es der verfolgten Kirche in seinem Land leistet. Er versicherte, dass die Christen in Burkina Faso der Gewalt und dem Terrorismus mit der einzigen Waffe, die sie haben, widerstehen werden: dem Gebet und dem Geist des Friedens.<\/p>\n<p>\u201eVielen Dank an Aid to the Church in Need f\u00fcr die Unterst\u00fctzung nachhaltiger Projekte rwie die Nahrungsmittelhilfe f\u00fcr die Opfer religi\u00f6ser Gewalt, die F\u00f6rderung des islamisch-christlichen Dialogs und der Priesterausbildung, damit diese dem Volk Gottes, das wegen seines Glaubens verfolgt wird, besser dienen k\u00f6nnen. Wir sind eine verfolgte Kirche, aber dank Ihnen sind wir nicht vergessen. Wir wissen, dass Sie uns mit Ihrem Gebet unterst\u00fctzen. Bei Gott gibt es immer Rettung\u201c, sagte er.<\/p>\n<p>\u201eWir glauben, dass das B\u00f6se nicht das letzte Wort hat. Wir k\u00e4mpfen weiterhin voller Hoffnung gegen den Terrorismus mit der einzigen \u201aKalaschnikow\u2018, die wir haben, unserer unsichtbaren, aber sehr wirksamen Waffe: dem Gebet, den Sakramenten, der heiligen Messe und dem Rosenkranz. Aus Liebe zu Gott und zu den anderen zu sterben, zerst\u00f6rt die Kr\u00e4fte des B\u00f6sen an den Wurzeln.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Churches have to be guarded so that Christians can pray in safety. Catholic nurses disguise themselves as Muslims so that<\/p>\n","protected":false},"author":4258341447,"featured_media":180460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[918],"tags":[],"country":[315],"class_list":["post-180469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht","country-burkina-faso"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Burkina Faso: \u201eDas B\u00f6se hat nicht das letzte Wort\u201c, sagt ein Priester \u00fcber die Gewalt gegen Christen in seinem Land | ACN International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Burkina Faso: \u201eDas B\u00f6se hat nicht das letzte Wort\u201c, sagt ein Priester \u00fcber die Gewalt gegen Christen in seinem Land\" \/>\n<meta property=\"og:description\" content=\"Churches have to be guarded so that Christians can pray in safety. Catholic nurses disguise themselves as Muslims so that\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-27T14:28:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-27T14:38:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/heading-4-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Burkina Faso: \u201eDas B\u00f6se hat nicht das letzte Wort\u201c, sagt ein Priester \u00fcber die Gewalt gegen Christen in seinem Land\",\"datePublished\":\"2023-04-27T14:28:19+00:00\",\"dateModified\":\"2023-04-27T14:38:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/\"},\"wordCount\":1107,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/heading-4-1.png\",\"articleSection\":[\"Nachricht\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/\",\"name\":\"Burkina Faso: \u201eDas B\u00f6se hat nicht das letzte Wort\u201c, sagt ein Priester \u00fcber die Gewalt gegen Christen in seinem Land | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/heading-4-1.png\",\"datePublished\":\"2023-04-27T14:28:19+00:00\",\"dateModified\":\"2023-04-27T14:38:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/heading-4-1.png\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/heading-4-1.png\",\"width\":2000,\"height\":625,\"caption\":\"Heiligtum der Muttergottes von Yagma.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachricht\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/category\\\/news-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Burkina Faso: \u201eDas B\u00f6se hat nicht das letzte Wort\u201c, sagt ein Priester \u00fcber die Gewalt gegen Christen in seinem Land\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Burkina Faso: \u201eDas B\u00f6se hat nicht das letzte Wort\u201c, sagt ein Priester \u00fcber die Gewalt gegen Christen in seinem Land | ACN International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/","og_locale":"de_DE","og_type":"article","og_title":"Burkina Faso: \u201eDas B\u00f6se hat nicht das letzte Wort\u201c, sagt ein Priester \u00fcber die Gewalt gegen Christen in seinem Land","og_description":"Churches have to be guarded so that Christians can pray in safety. Catholic nurses disguise themselves as Muslims so that","og_url":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2023-04-27T14:28:19+00:00","article_modified_time":"2023-04-27T14:38:30+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/heading-4-1.png","type":"image\/png"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Verfasst von":"ACN Press Team","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Burkina Faso: \u201eDas B\u00f6se hat nicht das letzte Wort\u201c, sagt ein Priester \u00fcber die Gewalt gegen Christen in seinem Land","datePublished":"2023-04-27T14:28:19+00:00","dateModified":"2023-04-27T14:38:30+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/"},"wordCount":1107,"publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/heading-4-1.png","articleSection":["Nachricht"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/","url":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/","name":"Burkina Faso: \u201eDas B\u00f6se hat nicht das letzte Wort\u201c, sagt ein Priester \u00fcber die Gewalt gegen Christen in seinem Land | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/heading-4-1.png","datePublished":"2023-04-27T14:28:19+00:00","dateModified":"2023-04-27T14:38:30+00:00","breadcrumb":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/heading-4-1.png","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2023\/04\/heading-4-1.png","width":2000,"height":625,"caption":"Heiligtum der Muttergottes von Yagma."},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/de\/burkina-faso-das-boese-hat-nicht-das-letzte-wort-sagt-ein-priester-ueber-die-gewalt-gegen-christen-in-seinem-land\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/de\/"},{"@type":"ListItem","position":2,"name":"Nachricht","item":"https:\/\/acninternational.org\/de\/category\/news-de\/"},{"@type":"ListItem","position":3,"name":"Burkina Faso: \u201eDas B\u00f6se hat nicht das letzte Wort\u201c, sagt ein Priester \u00fcber die Gewalt gegen Christen in seinem Land"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/de\/#website","url":"https:\/\/acninternational.org\/de\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/de\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/de\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/180469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/comments?post=180469"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/180469\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media\/180460"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media?parent=180469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/categories?post=180469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/tags?post=180469"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/country?post=180469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}