{"id":176821,"date":"2022-12-08T09:22:35","date_gmt":"2022-12-08T08:22:35","guid":{"rendered":"https:\/\/acninternational.org\/?p=176821"},"modified":"2022-12-08T09:47:48","modified_gmt":"2022-12-08T08:47:48","slug":"syrien-wir-legen-unser-schicksal-in-die-haende-gottes","status":"publish","type":"post","link":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/","title":{"rendered":"SYRIEN: \u201eWir legen unser Schicksal in die H\u00e4nde Gottes\u201c"},"content":{"rendered":"<h4><strong>Angst vor einer unmittelbar bevorstehenden t\u00fcrkischen Bodenoffensive <\/strong><\/h4>\n<p><em>Angriff auf Syrien: Seit dem 20. November ist Nord-Syrien wieder Ziel einer Reihe von Angriffen aus der T\u00fcrkei, die nach den Worten von Erdogan entschlossen ist, die kurdischen Milizen auszurotten, um \u201edie t\u00fcrkischen Grenzen zu sch\u00fctzen\u201c. ACN sprach mit Mgr Nidal Abdel Massih Thomas, Patriarchalvikar der chald\u00e4isch-katholischen Kirche in der Region Jazira.<\/em><\/p>\n<figure id=\"attachment_176808\" aria-describedby=\"caption-attachment-176808\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-176808 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-15.png\" alt=\"angriff auf syrien\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-15.png 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-15-300x179.png 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-176808\" class=\"wp-caption-text\">Ikonenwanderung mit der Schmerzensreichen Muttergottes in Syrien mit Mgr. Nidal<\/figcaption><\/figure>\n<h4><strong>Das armenisch-katholische Patriarchat hat k\u00fcrzlich zum Gebet aufgerufen, damit die t\u00fcrkischen milit\u00e4rischen Operationen gegen kurdische Ziele im Norden Syriens aufh\u00f6ren. Was geschieht dort genau? <\/strong><\/h4>\n<p>Seit dem 20. November hat die t\u00fcrkische Armee Drohnenangriffe auf bedeutende Stellungen der kurdischen Streitkr\u00e4fte, Standorte f\u00fcr die Gas- und Erd\u00f6lf\u00f6rderung auf dem Streifen von Al-Malikiyah und Al-Rumailan bis Ras Al-Ain geflogen. Diese Infrastrukturen (Erd\u00f6lraffinerien, Stromkraftwerke und Gasf\u00f6rderanlagen) wurden zerst\u00f6rt und vollst\u00e4ndig au\u00dfer Betrieb gesetzt. Es wurden auch manche grenznahen D\u00f6rfer bombardiert.<\/p>\n<p>Ziel der t\u00fcrkischen Milit\u00e4roperation innerhalb des syrischen Gebietes (n\u00f6rdlich von Aleppo und im Nordwesten Syriens) sind die Standorte der Demokratischen Kr\u00e4fte Syriens (SDF \u2013 Syrian Democratic Forces). Diese Angriffe dienen als Vergeltung f\u00fcr die Explosion auf dem Taksim-Platz in Istanbul (<em>A.d.R.: bei dem Attentat vom 13.11.2022 gab es sechs Tote und \u00fcber 80 Verletzte<\/em>).<\/p>\n<h4><strong>Welche St\u00e4dte werden angegriffen? Gibt es noch Christen in diesen Regionen? <\/strong><\/h4>\n<p>Ja, viele Christen leben noch in Al-Malikiya, in Amuda sind es ein oder zwei Familien, in Ad-Dirbasiyya zwanzig Familien, in Ra\u2018s al-\u2018Ain zehn Familien, in Tell Tamer leben 150 Assyrer\u2026 Insgesamt lebt noch eine ganze Reihe christlicher Familien in jeder dieser St\u00e4dte: Al-Malikiya, Qamischli, Al-Hasaka, Amuda, Tell Tamer und seine Vororte sowie Al-Qahtaniyya. Die meisten Familien leben in den St\u00e4dten Qamischli, gefolgt von Al-Hasaka, Al-Malikiya und Al-Qahtaniyya.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_176796\" aria-describedby=\"caption-attachment-176796\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-176796 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-16.png\" alt=\"angriff auf syrien\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-16.png 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-16-300x179.png 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-176796\" class=\"wp-caption-text\">Syrien, Hasaka (Jazira), Oktober 2022<\/figcaption><\/figure>\n<h4><strong>Ist die Zivilbev\u00f6lkerung ebenfalls Ziel dieser Angriffe?<\/strong><\/h4>\n<p>Sicherlich, denn es sind Zivilpersonen, die in diesen Infrastrukturen arbeiten und in den H\u00e4usern in deren Umgebung leben. Zahlreiche Zivilpersonen wurden in den Krankenh\u00e4usern von Qamischli und Al-Hasaka behandelt. Es wurden auch st\u00e4dtische Gebiete angegriffen, beispielsweise die Verbindungsstra\u00dfe zwischen Al-Hasaka und Qamischli, die Au\u00dfenbezirke von Amuda, von Al-Malikiya oder auch von Al-Qahtaniyya.<\/p>\n<h4><strong>Wie rechtfertigen die t\u00fcrkischen Streitkr\u00e4fte diese Angriffe?<\/strong><\/h4>\n<p>Die T\u00fcrkei rechtfertigt diese Interventionen mit der Notwendigkeit, ihre Grenzen innerhalb einer 30 km langen Sicherheitszone entlang der t\u00fcrkischen Grenze zu Syrien zu sch\u00fctzen. Die t\u00fcrkischen Streitkr\u00e4fte wollen auch verhindern, dass die PKK einen kurdischen Staat etabliert, der den t\u00fcrkischen Staat bedrohen w\u00fcrde und von dort Attentate in der T\u00fcrkei vorbereiten k\u00f6nnte.<\/p>\n<figure id=\"attachment_176802\" aria-describedby=\"caption-attachment-176802\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-176802 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-14.png\" alt=\"angriff auf syrien\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-14.png 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/pequena-14-300x179.png 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-176802\" class=\"wp-caption-text\">Beerdigungsmesse in der armenisch-katholischen Kirche in Qamishli.<\/figcaption><\/figure>\n<h4><strong>Kann die syrische Regierung denn reagieren, wenn doch diese Region als autonom gilt und von den Demokratischen Kr\u00e4ften Syriens (<\/strong><strong>SDF) verwaltet wird?<\/strong><\/h4>\n<p>Der syrische Staat will seine Gebiete zur\u00fcckbekommen und die kurdischen Streitkr\u00e4fte gehen nicht darauf ein. Es wurde mehrfach eine Vereinbarung getroffen, aufgrund derer sich die kurdischen Streitkr\u00e4fte zur\u00fcckgezogen haben und dabei den Vereinigten Staaten gehorchten. Der syrische Staat ist bereit, alle Gebiete zu sch\u00fctzen. Vergangenen Sonntag informierte der russische Vermittler den Oberbefehlshaber der SDF und forderte ihn auf, sich aus drei Gebieten zur\u00fcckzuziehen (Tall Rifaat, Manbidsch und Ayn Al-Arab), doch s\u00e4mtliche russischen Vorschl\u00e4ge wurden abgelehnt.<\/p>\n<h4><strong>Welche Perspektiven sehen Sie in den kommenden Monaten? <\/strong><\/h4>\n<p>Recep Tayyip Erdogan hat erkl\u00e4rt, dass die Bodenoffensive so bald wie m\u00f6glich beginnen wird, doch bisher ist dies nicht geschehen. Wenn die Kurden sich nicht aus den drei Gebieten zur\u00fcckziehen, deutet alles darauf hin, dass eine t\u00fcrkische Bodenoffensive im Norden Syriens unmittelbar bevorsteht, auch in Anbetracht der fortgesetzten t\u00e4glichen Bombardierungen durch Artillerie und Luftangriffe.<\/p>\n<p>In dieser Region findet bereits seit 2015 die gr\u00f6\u00dfte je dagewesene Auswanderungswelle statt; sie begann <a href=\"https:\/\/acninternational.org\/de\/10-jahre-krieg-bestandsaufnahme-der-hilfe-von-acn-in-syrien\/\">w\u00e4hrend der Jahre des Krieges in Syrien<\/a>. Wir wissen nicht, was die T\u00fcrkei machen wird, und legen unser Schicksal in die H\u00e4nde Gottes\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>,,Wir wissen nicht, was die T\u00fcrkei machen wird, und legen unser Schicksal in die H\u00e4nde Gottes\u2026&#8220;<\/p>\n","protected":false},"author":4258341447,"featured_media":176792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[929],"tags":[],"country":[852],"class_list":["post-176821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interview-2","country-syrien"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Angriff auf Syrien | ACN International<\/title>\n<meta name=\"description\" content=\"Angriff auf Syrien: Das Land ist Ziel aus der T\u00fcrkei, die entschlossen ist, kurdische K\u00e4mpfer auszul\u00f6schen, um &quot;ihre Grenzen zu sch\u00fctzen&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Angriff auf Syrien\" \/>\n<meta property=\"og:description\" content=\"Angriff auf Syrien: Das Land ist Ziel aus der T\u00fcrkei, die entschlossen ist, kurdische K\u00e4mpfer auszul\u00f6schen, um &quot;ihre Grenzen zu sch\u00fctzen&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-08T08:22:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-08T08:47:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/heading-7-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Angriff auf Syrien\" \/>\n<meta name=\"twitter:description\" content=\"Angriff auf Syrien: Das Land ist Ziel aus der T\u00fcrkei, die entschlossen ist, kurdische K\u00e4mpfer auszul\u00f6schen, um &quot;ihre Grenzen zu sch\u00fctzen&quot;.\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"SYRIEN: \u201eWir legen unser Schicksal in die H\u00e4nde Gottes\u201c\",\"datePublished\":\"2022-12-08T08:22:35+00:00\",\"dateModified\":\"2022-12-08T08:47:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/\"},\"wordCount\":694,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/heading-7-1.png\",\"articleSection\":[\"Interview\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/\",\"name\":\"Angriff auf Syrien | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/heading-7-1.png\",\"datePublished\":\"2022-12-08T08:22:35+00:00\",\"dateModified\":\"2022-12-08T08:47:48+00:00\",\"description\":\"Angriff auf Syrien: Das Land ist Ziel aus der T\u00fcrkei, die entschlossen ist, kurdische K\u00e4mpfer auszul\u00f6schen, um \\\"ihre Grenzen zu sch\u00fctzen\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/heading-7-1.png\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/heading-7-1.png\",\"width\":2000,\"height\":625,\"caption\":\"angriff auf syrien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/category\\\/interview-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SYRIEN: \u201eWir legen unser Schicksal in die H\u00e4nde Gottes\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Angriff auf Syrien | ACN International","description":"Angriff auf Syrien: Das Land ist Ziel aus der T\u00fcrkei, die entschlossen ist, kurdische K\u00e4mpfer auszul\u00f6schen, um \"ihre Grenzen zu sch\u00fctzen\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/","og_locale":"de_DE","og_type":"article","og_title":"Angriff auf Syrien","og_description":"Angriff auf Syrien: Das Land ist Ziel aus der T\u00fcrkei, die entschlossen ist, kurdische K\u00e4mpfer auszul\u00f6schen, um \"ihre Grenzen zu sch\u00fctzen\".","og_url":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2022-12-08T08:22:35+00:00","article_modified_time":"2022-12-08T08:47:48+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/heading-7-1.png","type":"image\/png"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_title":"Angriff auf Syrien","twitter_description":"Angriff auf Syrien: Das Land ist Ziel aus der T\u00fcrkei, die entschlossen ist, kurdische K\u00e4mpfer auszul\u00f6schen, um \"ihre Grenzen zu sch\u00fctzen\".","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Verfasst von":"ACN Press Team","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"SYRIEN: \u201eWir legen unser Schicksal in die H\u00e4nde Gottes\u201c","datePublished":"2022-12-08T08:22:35+00:00","dateModified":"2022-12-08T08:47:48+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/"},"wordCount":694,"publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/heading-7-1.png","articleSection":["Interview"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/","url":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/","name":"Angriff auf Syrien | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/heading-7-1.png","datePublished":"2022-12-08T08:22:35+00:00","dateModified":"2022-12-08T08:47:48+00:00","description":"Angriff auf Syrien: Das Land ist Ziel aus der T\u00fcrkei, die entschlossen ist, kurdische K\u00e4mpfer auszul\u00f6schen, um \"ihre Grenzen zu sch\u00fctzen\".","breadcrumb":{"@id":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/heading-7-1.png","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/12\/heading-7-1.png","width":2000,"height":625,"caption":"angriff auf syrien"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/de\/syrien-wir-legen-unser-schicksal-in-die-haende-gottes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/de\/"},{"@type":"ListItem","position":2,"name":"Interview","item":"https:\/\/acninternational.org\/de\/category\/interview-2\/"},{"@type":"ListItem","position":3,"name":"SYRIEN: \u201eWir legen unser Schicksal in die H\u00e4nde Gottes\u201c"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/de\/#website","url":"https:\/\/acninternational.org\/de\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/de\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/de\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/176821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/comments?post=176821"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/176821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media\/176792"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media?parent=176821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/categories?post=176821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/tags?post=176821"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/country?post=176821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}