{"id":175615,"date":"2022-11-02T10:59:11","date_gmt":"2022-11-02T09:59:11","guid":{"rendered":"https:\/\/acninternational.org\/?p=175615"},"modified":"2025-02-10T11:18:25","modified_gmt":"2025-02-10T10:18:25","slug":"erstes-katholisches-radio-in-bulgarien","status":"publish","type":"post","link":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/","title":{"rendered":"Kardinal Sandri: ,,Was ein gro\u00dfer Traum war, wurde jetzt Wirklichkeit&#8220;"},"content":{"rendered":"<h4>Erstes katholisches Radio in Bulgarien mit Unterst\u00fctzung des Hilfswerks ACN eingeweiht<\/h4>\n<p>Das Jahr 2022 steht f\u00fcr die katholische Kirche in Bulgarien im Zeichen verschiedener Feierlichkeiten: Gefeiert werden der 20. Jahrestag des Besuchs von Johannes Paul II. sowie der 70. Jahrestag der Ermordung von vier bulgarischen M\u00e4rtyrern, drei Assumptionisten-Priestern und einem Passionisten-Bischof, durch das kommunistische Regime. Im Rahmen dieser Feierlichkeiten wurde der erste bulgarische katholische Radiosender, ein wichtiges Instrument f\u00fcr die Evangelisierung und die \u00d6kumene im Land, in Anwesenheit von Kardinal Sandri als Gesandtem des Vatikans eingeweiht.<\/p>\n<p>Die bulgarische Kirche ist eine M\u00e4rtyrerkirche. W\u00e4hrend des diktatorischen kommunistischen Regimes zwischen 1946 und 1990wurden alle Priester irgendwann einmal inhaftiert, kirchliches Eigentum beschlagnahmt, ausl\u00e4ndische Priester ausgewiesen und Seminare geschlossen. Der heutige griechisch-katholische Bischof von Sofia und Vorsitzende der bulgarischen Bischofskonferenz Christo Proykov sagt in einem Interview mit ACN: \u201eIch wurde 1971 zum Priester geweiht. Ich war nach 19 Jahren der erste und einzige Priester; und es dauerte weitere f\u00fcnf Jahre, bis der n\u00e4chste geweiht wurde.\u201c<\/p>\n<figure id=\"attachment_175594\" aria-describedby=\"caption-attachment-175594\" style=\"width: 670px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-175594 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/pequena-23.png\" alt=\"Erstes katholisches Radio in Bulgarien\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/pequena-23.png 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/pequena-23-300x179.png 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-175594\" class=\"wp-caption-text\">Kardinal Leonardo Sandri und Bischof Christo Proykov bei der Einweihung von Radio Ave Maria in Sofia.<\/figcaption><\/figure>\n<p>Die katholische Kirche hat sich nach und nach erholt. Heute z\u00e4hlt sie 60 Priester, 100 Ordensm\u00e4nner und -frauen sowie mehrere geistliche Bewegungen, die im Land t\u00e4tig sind. \u201eEinige Geb\u00e4ude wurden restauriert, und mit Hilfe von ACN ist es uns gelungen, neue Kirchen zu errichten\u201c, so das Oberhaupt der griechisch-katholischen Kirche. \u201eEs gibt zwar eine Generation, die dank der Pfarreien und der Katecheten im Glauben gut ausgebildet ist, aber im Allgemeinen wurden die jungen Menschen nicht im Glauben erzogen, denn ihre Eltern haben nichts erhalten, was sie h\u00e4tten weitergeben k\u00f6nnen\u201c, f\u00fchrt Bischof Proykov aus.<\/p>\n<p>Daher die Bedeutung des Radiosenders, der gerade in Sofia dank des Beitrags der ACN-Wohlt\u00e4ter am Fest des heiligen Johannes Paul II. eingeweiht wurde. \u201eSeit Jahren bitten uns die Jugendlichen darum. Sie hatten bereits begonnen, bei sich zu Hause Material zu produzieren. Endlich konnten wir diese wunderbare Initiative ins Leben rufen, die ein Instrument des Gebets und der Erziehung f\u00fcr Jung und Alt sein wird\u201c. Radio Ave Maria wurde den Franziskanern anvertraut, \u201eweil sie aus Polen kommen und viel Erfahrung haben\u201c, so der Bischof.<\/p>\n<p><iframe loading=\"lazy\" title=\"First Catholic Radio in Bulgaria!\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/RoXUTa_lfEI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Bulgarien ist ein mehrheitlich christliches Land, in dem 85 % orthodox und nur 1 % Katholiken sind, die \u00fcber das ganze Land verstreut leben, einige davon bis zu drei Kilometer von der t\u00fcrkischen Grenze entfernt. Au\u00dferdem hat das Land einen Bev\u00f6lkerungsanteil von 10% Muslimen mit t\u00fcrkischen Wurzeln. Aus diesem Grund betont Bischof Proykov: \u201eAve Maria ist nicht nur f\u00fcr Katholiken. Es gibt viele Menschen, die danach suchen, es gibt einen Hunger nach geistlicher und religi\u00f6ser Bildung, aber auch nach kultureller Bildung mit Musik- und Geschichtsprogrammen. Es ist ein Projekt von allen und f\u00fcr alle.\u201c<\/p>\n<p>Anl\u00e4sslich des Jahrestages der apostolischen Reise des polnischen Papstes im Jahr 2002 ist Erzbischof Leonardo Sandri, Pr\u00e4fekt des Dikasteriums f\u00fcr die Ostkirchen, zu einer Reihe von Veranstaltungen nach Sofia gekommen. Als Erstes weihte er die Studios von \u201eRadio Ave Maria\u201c ein, die sich in dem k\u00fcrzlich restaurierten Haus des damaligen Apostolischen Delegierten Angelo Roncalli, des sp\u00e4teren Heiligen Johannes XXIII., befinden.<\/p>\n<figure id=\"attachment_175606\" aria-describedby=\"caption-attachment-175606\" style=\"width: 670px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-175606 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/pequena-24.png\" alt=\"Erstes katholisches Radio in Bulgarien\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/pequena-24.png 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/pequena-24-300x179.png 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-175606\" class=\"wp-caption-text\">Einweihung von Radio Ave Maria mit Bischof Christo Proykov<\/figcaption><\/figure>\n<p>\u201eRadio Ave Maria war ein gro\u00dfer Traum, jetzt ist er Wirklichkeit geworden. Das erste katholische Radio erlaubt es der katholischen Kirche , nicht nur in ihren Geb\u00e4uden t\u00e4tig zu sein, sondern auch au\u00dferhalb dieser Geb\u00e4ude,und mit allen Menschen zu arbeiten, besonders mit denen, die leiden oder die nicht die M\u00f6glichkeit haben, zur Kirche zu gehen\u201c, sagte Kardinal Sandri.<\/p>\n<p>Der Kardinal m\u00f6chte eine Dankbotschaft an die Wohlt\u00e4ter von ACN senden: \u201eEin besonderes Wort an unsere Freunde von ACN, die sich f\u00fcr die Br\u00fcderlichkeit in der Welt einsetzen, durch N\u00e4chstenliebe und den Dienst an allen, die leiden. Ihr alle, die Ihr mit ACN zusammenarbeitet, seid gro\u00dfe Protagonisten der N\u00e4chstenliebe, der Liebe und des Dienstes in der Kirche. Wir danken Euch f\u00fcr Eure Gro\u00dfz\u00fcgigkeit und Eure Anteilnahme. Ihr, die Ihr von euren L\u00e4ndern aus die Werke der N\u00e4chstenliebe unterst\u00fctzt, solltet wissen, dass Ihr in diesem Moment hier anwesend seid und dass Ihr gro\u00dfe Akteure der Kirche in Bulgarien seid.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kardinal Sandri er\u00f6ffnete das erste katholische Radio in Bulgarien, ein wichtiges Instrument f\u00fcr Evangelisierung.<\/p>\n","protected":false},"author":4258341447,"featured_media":175602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[918],"tags":[],"country":[1278],"class_list":["post-175615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht","country-bulgarien"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Erstes katholisches Radio in Bulgarien | ACN International<\/title>\n<meta name=\"description\" content=\"Kardinal Sandri er\u00f6ffnete das erste katholische Radio in Bulgarien, ein wichtiges Instrument f\u00fcr Evangelisierung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erstes katholisches Radio in Bulgarien\" \/>\n<meta property=\"og:description\" content=\"Kardinal Sandri er\u00f6ffnete das erste katholische Radio in Bulgarien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-02T09:59:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T10:18:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/heading-2022-11-02T105321.359-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Erstes katholisches Radio in Bulgarien\" \/>\n<meta name=\"twitter:description\" content=\"Kardinal Sandri er\u00f6ffnete das erste katholische Radio in Bulgarien.\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Kardinal Sandri: ,,Was ein gro\u00dfer Traum war, wurde jetzt Wirklichkeit&#8220;\",\"datePublished\":\"2022-11-02T09:59:11+00:00\",\"dateModified\":\"2025-02-10T10:18:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/\"},\"wordCount\":738,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/heading-2022-11-02T105321.359-1.png\",\"articleSection\":[\"Nachricht\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/\",\"name\":\"Erstes katholisches Radio in Bulgarien | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/heading-2022-11-02T105321.359-1.png\",\"datePublished\":\"2022-11-02T09:59:11+00:00\",\"dateModified\":\"2025-02-10T10:18:25+00:00\",\"description\":\"Kardinal Sandri er\u00f6ffnete das erste katholische Radio in Bulgarien, ein wichtiges Instrument f\u00fcr Evangelisierung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/heading-2022-11-02T105321.359-1.png\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/heading-2022-11-02T105321.359-1.png\",\"width\":2000,\"height\":625,\"caption\":\"Radio Ave Maria in Bulgarien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/erstes-katholisches-radio-in-bulgarien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachricht\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/category\\\/nachricht\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kardinal Sandri: ,,Was ein gro\u00dfer Traum war, wurde jetzt Wirklichkeit&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Erstes katholisches Radio in Bulgarien | ACN International","description":"Kardinal Sandri er\u00f6ffnete das erste katholische Radio in Bulgarien, ein wichtiges Instrument f\u00fcr Evangelisierung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/","og_locale":"de_DE","og_type":"article","og_title":"Erstes katholisches Radio in Bulgarien","og_description":"Kardinal Sandri er\u00f6ffnete das erste katholische Radio in Bulgarien.","og_url":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2022-11-02T09:59:11+00:00","article_modified_time":"2025-02-10T10:18:25+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/heading-2022-11-02T105321.359-1.png","type":"image\/png"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_title":"Erstes katholisches Radio in Bulgarien","twitter_description":"Kardinal Sandri er\u00f6ffnete das erste katholische Radio in Bulgarien.","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Verfasst von":"ACN Press Team","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Kardinal Sandri: ,,Was ein gro\u00dfer Traum war, wurde jetzt Wirklichkeit&#8220;","datePublished":"2022-11-02T09:59:11+00:00","dateModified":"2025-02-10T10:18:25+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/"},"wordCount":738,"publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/heading-2022-11-02T105321.359-1.png","articleSection":["Nachricht"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/","url":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/","name":"Erstes katholisches Radio in Bulgarien | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/heading-2022-11-02T105321.359-1.png","datePublished":"2022-11-02T09:59:11+00:00","dateModified":"2025-02-10T10:18:25+00:00","description":"Kardinal Sandri er\u00f6ffnete das erste katholische Radio in Bulgarien, ein wichtiges Instrument f\u00fcr Evangelisierung.","breadcrumb":{"@id":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/heading-2022-11-02T105321.359-1.png","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2022\/11\/heading-2022-11-02T105321.359-1.png","width":2000,"height":625,"caption":"Radio Ave Maria in Bulgarien"},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/de\/erstes-katholisches-radio-in-bulgarien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/de\/"},{"@type":"ListItem","position":2,"name":"Nachricht","item":"https:\/\/acninternational.org\/de\/category\/nachricht\/"},{"@type":"ListItem","position":3,"name":"Kardinal Sandri: ,,Was ein gro\u00dfer Traum war, wurde jetzt Wirklichkeit&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/de\/#website","url":"https:\/\/acninternational.org\/de\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/de\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/de\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/175615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/comments?post=175615"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/175615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media\/175602"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media?parent=175615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/categories?post=175615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/tags?post=175615"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/country?post=175615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}