{"id":154711,"date":"2021-06-28T14:22:31","date_gmt":"2021-06-28T12:22:31","guid":{"rendered":"https:\/\/acninternational.org\/?p=154711"},"modified":"2021-06-28T14:50:29","modified_gmt":"2021-06-28T12:50:29","slug":"junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert","status":"publish","type":"post","link":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/","title":{"rendered":"Junge christliche Frauen in Pakistan sind mit Diskriminierung, sozialer Ausgrenzung und Armut konfrontiert"},"content":{"rendered":"<p><strong><em>Ein ACN-Programm gibt ihnen neue Hoffnung und r\u00fcstet sie f\u00fcr den Kampf f\u00fcr eine bessere Zukunft<\/em><\/strong><\/p>\n<p>Das Leben f\u00fcr Christen in Pakistan ist nicht einfach. Als Angeh\u00f6rige einer religi\u00f6sen Minderheit sind sie h\u00e4ufig Opfer von Diskriminierung und sozialer Ausgrenzung. Die meisten Christen geh\u00f6ren zu den \u00e4rmsten Schichten der Gesellschaft und sind Fabrikarbeiter, Tagel\u00f6hner, Hausangestellte, Reinigungspersonal von Abfl\u00fcssen und Toiletten&#8230; Viele von ihnen finden sich ohne Zugang zu rechtlicher Unterst\u00fctzung wieder und werden von den Beh\u00f6rden ignoriert, wenn sie versuchen, ihre Menschenrechte zu verteidigen. Christliche Frauen sind in diesem Kontext noch verwundbarer und gr\u00f6\u00dferen Gefahren ausgesetzt. \u00d6ffentliche Berichte \u00fcber sexuellen Missbrauch und Zwangsverheiratungen werden immer zahlreicher, und doch ist die tats\u00e4chliche Zahl dieser F\u00e4lle wahrscheinlich noch h\u00f6her.<\/p>\n<p>Das Hilfswerk Aid to the Church Need f\u00f6rdert nun ein Programm, das junge christliche Frauen, die in diesen extrem schwierigen Verh\u00e4ltnissen leben, st\u00e4rken soll. Viele der jungen Frauen, die an dem Programm teilnehmen, sind Studentinnen oder Hausangestellte in den Au\u00dfenbezirken einer pakistanischen Gro\u00dfstadt. Um die Sicherheit der betroffenen jungen Frauen zu sch\u00fctzen und sie und die lokalen Projektpartner von ACN vor jeglicher Art der Repressalien zu bewahren, gibt die Hilfsorganisation weder Namen noch Orte bekannt. Sie teilt aber dennoch die Geschichten der Frauen, die \u00c4ngste und die Sorgen, mit denen sie konfrontiert sind. Es ist die Realit\u00e4t, von der so viele christliche Frauen in Pakistan betroffen sind.<\/p>\n<figure id=\"attachment_154695\" aria-describedby=\"caption-attachment-154695\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-154695 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/06\/Pakistan_women.jpg\" alt=\"Das Hilfswerk Aid to the Church Need f\u00f6rdert nun ein Programm, das junge christliche Frauen, die in diesen extrem schwierigen Verh\u00e4ltnissen leben, st\u00e4rken soll.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/06\/Pakistan_women.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/06\/Pakistan_women-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-154695\" class=\"wp-caption-text\">Das Hilfswerk Aid to the Church Need f\u00f6rdert nun ein Programm, das junge christliche Frauen, die in diesen extrem schwierigen Verh\u00e4ltnissen leben, st\u00e4rken soll.<\/figcaption><\/figure>\n<p>Eine dieser jungen Frauen ist \u201eSamia\u201c (Name ge\u00e4ndert). Sie lebt im Norden Pakistans zusammen mit ihren Eltern und vier Br\u00fcdern. Ihr Vater ist Fabrikarbeiter und ihre Mutter ist Hausfrau. Sie berichtet: \u201eDa ich zu einer christlichen Familie geh\u00f6re, haben meine Eltern mich immer ermahnt, niemals mit anderen Menschen \u00fcber religi\u00f6se Unterschiede zu sprechen. Sie haben uns beigebracht, jede Art von Diskriminierung einfach zu ertragen, da wir ohnehin keinen Einfluss haben, weil wir in einem muslimischen Land leben. Ich habe Angst von den Gesetzen diskriminiert zu werden; wir sind eine Minderheit in Pakistan, die nicht viel Unterst\u00fctzung hat. Wir leben in einem Zustand der Angst und des st\u00e4ndigen Drucks. Wir glauben, dass wir, wenn wir versuchen, unsere Rechte zu verteidigen, aufgrund falscher Anschuldigungen der Blasphemie oder anderer Vergehen beschuldigt werden, so wie es in der Vergangenheit schon h\u00e4ufiger vorgekommen ist.<\/p>\n<p>Dank meiner Teilnahme an dem von ACN International unterst\u00fctzten Frauenf\u00f6rderprogramm bin ich in meinem Glauben gest\u00e4rkt worden. Es hilft uns Frauen, uns unserer Verantwortung und unserer Rechte st\u00e4rker bewusst zu werden. Es ermutigt uns, stark zu bleiben, gegen Diskriminierung, Zwangsbekehrung, Bel\u00e4stigung und Gewalt zu k\u00e4mpfen und unsere gleichen Rechte zu verteidigen\u201c, erkl\u00e4rt die 20-j\u00e4hrige. Das Programm habe sie ermutigt, \u201ehart zu arbeiten, damit unsere Gemeinschaft eine bessere Zukunft haben kann\u201c.<\/p>\n<p><iframe loading=\"lazy\" title=\"&quot;Bericht Religonsfreiheit weltweit 2021&quot;\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/vyhsYct-6Ss?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Eine andere junge Frau, die an dem Programm teilnimmt, ist \u201eAshia\u201c (Name ge\u00e4ndert). Ihr Vater ist Stra\u00dfenkehrer und verdient gerade mal 10.000 Rupien (rund 53 Euro) im Monat. \u201eAls ich zur Universit\u00e4t ging, wurde ich von meinen Dozenten und Mitstudenten oft diskriminiert, und das ging so weit, so dass ich mich nicht mehr auf mein Studium konzentrieren konnte\u201c, berichtet die 17-j\u00e4hrige. Sie erz\u00e4hlte ihre Schwierigkeiten einer Freundin, die sie ermutigte, am ACN-Programm teilzunehmen. \u201eIch nahm an den Beratungsgespr\u00e4chen teil und sie gaben mir neue Hoffnung, mit meinen Umst\u00e4nden fertig zu werden. Ich habe mir fest vorgenommen, dass ich den Anderen keine weitere Gelegenheit geben werde, meine Zukunft zu zerst\u00f6ren. Ich werde flei\u00dfig studieren und den Menschen zeigen, dass unser Herr immer bei uns ist, dass er uns Kraft gibt und uns f\u00fchrt und besch\u00fctzt\u201c, schlie\u00dft sie.<\/p>\n<p>Paradigmatisch is der Fall von \u201eShazia\u201c (Name ge\u00e4ndert). Wie viele junge christliche Frauen hatte die 19-J\u00e4hrige gro\u00dfe Tr\u00e4ume. Ihr Vater, ein Rikschafahrer, war der Einzige, der f\u00fcr den Lebensunterhalt der Familie sorgte. Mit viel M\u00fche seitens ihrer Familie schaffte sie es, an der Universit\u00e4t Software Engineering zu studieren. Doch wegen der Finanzkrise musste sie das Studium im zweiten Jahr abbrechen. \u201eIch begann, in einer Fabrik zu arbeiten, um meinem Vater zu helfen, die Familie finanziell zu unterst\u00fctzen. Ich verdiente zwischen acht- und zehntausend pakistanische Rupien im Monat. Ich dachte, das ist mein Schicksal und das sollte meine Zukunft sein\u201c, erinnert sie sich. Sie hatte sich mit diesem \u00a0Schicksal abgefunden, bis sie das von ACN gesponserte F\u00f6rderprogramm kennenlernte. \u201eNeue Hoffnung keimte auf. Es entz\u00fcndete in mir den Funken der Hoffnung, dass es m\u00f6glich sein kann, etwas Anderes in unserem Leben zu tun, und das selbst verzweifelte junge Menschen wie ich es schaffen k\u00f6nnen, positive Ver\u00e4nderungen herbeizuf\u00fchren. Der Motivationsvortrag hat mich so sehr inspiriert, und mir wurde klar, dass Bildung das einzige Werkzeug und der Schl\u00fcssel zum Erfolg ist. Alles ist m\u00f6glich, wenn wir uns mit ganzem Herzen engagieren und uns mutig den Schwierigkeiten des Lebens stellen\u201c, sagt Shazia jetzt.<\/p>\n<p><iframe loading=\"lazy\" title=\"L\u00e4nderportr\u00e4t: Pakistan\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/8K6bLM3b4eE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Eine der j\u00fcngsten Teilnehmerinnen des Programms ist \u201eNasreen\u201c (Name ge\u00e4ndert). Diese junge Frau war gerade 15 Jahre alt und befand sich im neunten Schuljahr an einer staatlichen Schule, als die Pandemie ihr Leben zerst\u00f6rte. Ihr Vater ist Tagel\u00f6hner und befand sich durch den \u201eLockdown\u201c in gro\u00dfen finanziellen Schwierigkeiten, so dass er das Schulgeld und den Online-Unterricht in Zeiten der COVID-Pandemie nicht mehr bezahlen konnte. Zudem war Nasreen die einzige Christin in der Klasse. Am Ende wurde sie aus den Online-Kursen verwiesen. \u201eIch war sehr verletzt und aufgebracht, aber ich konnte dar\u00fcber mit meinen Eltern nicht sprechen, weil sie aufgrund der schwierigen finanziellen Situation in der Familie ohnehin schon sehr litten\u201c, erinnert sie sich. \u201eEs war nicht das erste Mal, dass ich von meinen Mitsch\u00fclern aufgrund unserer Religion Diskriminierungen und Vorurteilen gegen\u00fcber mir und meiner Familie ausgesetzt war. Ich war v\u00f6llig ratlos und verzweifelt \u00fcber das, was mir widerfahren ist\u201c, erz\u00e4hlt Nasreen. \u201eDann lernte ich das Team kennen, das das F\u00f6rderprojekt leitete und das einer Gruppe junger M\u00e4dchen wie mir die Teilnahme an einem Kurs anbot. Sie erkl\u00e4rten uns, dass eine Ausbildung unerl\u00e4sslich ist, um pers\u00f6nlich und spirituell wachsen zu k\u00f6nnen.\u201c Schlie\u00dflich besserte sich die Lage und Nasreens Vater konnte wieder arbeiten und ihr Schulgeld bezahlen. Aber es geht nicht nur um den wirtschaftlichen Aspekt. Die moralische Unterst\u00fctzung und Ermutigung, die die Kurse bieten, sind absolut notwendig, um diesen jungen christlichen Frauen zu helfen, die sich sonst angesichts ihres Schicksals oft \u00fcberfordert und verlassen f\u00fchlen. \u201eIch bin ACN so dankbar, dass es mir eine so gro\u00dfe Ver\u00e4nderung in meinem Leben erm\u00f6glicht hat. Jetzt erleuchtet die Kerze des Glaubens und der Hoffnung meinen Weg, und ich werde sie in Zukunft nicht durch irgendeine Art von Diskriminierung verl\u00f6schen lassen\u201c, sagt Nasreen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein ACN-Programm gibt ihnen neue Hoffnung und r\u00fcstet sie f\u00fcr den Kampf f\u00fcr eine bessere Zukunft Das Leben f\u00fcr Christen<\/p>\n","protected":false},"author":4258341447,"featured_media":154701,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[576,920],"tags":[],"country":[104],"class_list":["post-154711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projects","category-projekt","country-pakistan"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Junge christliche Frauen in Pakistan sind mit Diskriminierung, sozialer Ausgrenzung und Armut konfrontiert | ACN International<\/title>\n<meta name=\"description\" content=\"Das Hilfswerk Aid to the Church Need f\u00f6rdert nun ein Programm, das junge christliche Frauen, die in diesen extrem schwierigen Verh\u00e4ltnissen leben, st\u00e4rken soll. Viele der jungen Frauen, die an dem Programm teilnehmen, sind Studentinnen oder Hausangestellte in den Au\u00dfenbezirken einer pakistanischen Gro\u00dfstadt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Junge christliche Frauen in Pakistan sind mit Diskriminierung, sozialer Ausgrenzung und Armut konfrontiert\" \/>\n<meta property=\"og:description\" content=\"Das Hilfswerk Aid to the Church Need f\u00f6rdert nun ein Programm, das junge christliche Frauen, die in diesen extrem schwierigen Verh\u00e4ltnissen leben, st\u00e4rken soll. Viele der jungen Frauen, die an dem Programm teilnehmen, sind Studentinnen oder Hausangestellte in den Au\u00dfenbezirken einer pakistanischen Gro\u00dfstadt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-28T12:22:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-28T12:50:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/06\/Pakistan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Junge christliche Frauen in Pakistan sind mit Diskriminierung, sozialer Ausgrenzung und Armut konfrontiert\",\"datePublished\":\"2021-06-28T12:22:31+00:00\",\"dateModified\":\"2021-06-28T12:50:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/\"},\"wordCount\":1205,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Pakistan.jpg\",\"articleSection\":[\"Projects\",\"Projekt\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/\",\"name\":\"Junge christliche Frauen in Pakistan sind mit Diskriminierung, sozialer Ausgrenzung und Armut konfrontiert | ACN International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Pakistan.jpg\",\"datePublished\":\"2021-06-28T12:22:31+00:00\",\"dateModified\":\"2021-06-28T12:50:29+00:00\",\"description\":\"Das Hilfswerk Aid to the Church Need f\u00f6rdert nun ein Programm, das junge christliche Frauen, die in diesen extrem schwierigen Verh\u00e4ltnissen leben, st\u00e4rken soll. Viele der jungen Frauen, die an dem Programm teilnehmen, sind Studentinnen oder Hausangestellte in den Au\u00dfenbezirken einer pakistanischen Gro\u00dfstadt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Pakistan.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Pakistan.jpg\",\"width\":1400,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROJECTS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/category\\\/projects-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Junge christliche Frauen in Pakistan sind mit Diskriminierung, sozialer Ausgrenzung und Armut konfrontiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Junge christliche Frauen in Pakistan sind mit Diskriminierung, sozialer Ausgrenzung und Armut konfrontiert | ACN International","description":"Das Hilfswerk Aid to the Church Need f\u00f6rdert nun ein Programm, das junge christliche Frauen, die in diesen extrem schwierigen Verh\u00e4ltnissen leben, st\u00e4rken soll. Viele der jungen Frauen, die an dem Programm teilnehmen, sind Studentinnen oder Hausangestellte in den Au\u00dfenbezirken einer pakistanischen Gro\u00dfstadt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/","og_locale":"de_DE","og_type":"article","og_title":"Junge christliche Frauen in Pakistan sind mit Diskriminierung, sozialer Ausgrenzung und Armut konfrontiert","og_description":"Das Hilfswerk Aid to the Church Need f\u00f6rdert nun ein Programm, das junge christliche Frauen, die in diesen extrem schwierigen Verh\u00e4ltnissen leben, st\u00e4rken soll. Viele der jungen Frauen, die an dem Programm teilnehmen, sind Studentinnen oder Hausangestellte in den Au\u00dfenbezirken einer pakistanischen Gro\u00dfstadt.","og_url":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2021-06-28T12:22:31+00:00","article_modified_time":"2021-06-28T12:50:29+00:00","og_image":[{"width":1400,"height":438,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/06\/Pakistan.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Verfasst von":"ACN Press Team","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Junge christliche Frauen in Pakistan sind mit Diskriminierung, sozialer Ausgrenzung und Armut konfrontiert","datePublished":"2021-06-28T12:22:31+00:00","dateModified":"2021-06-28T12:50:29+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/"},"wordCount":1205,"publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/06\/Pakistan.jpg","articleSection":["Projects","Projekt"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/","url":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/","name":"Junge christliche Frauen in Pakistan sind mit Diskriminierung, sozialer Ausgrenzung und Armut konfrontiert | ACN International","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/06\/Pakistan.jpg","datePublished":"2021-06-28T12:22:31+00:00","dateModified":"2021-06-28T12:50:29+00:00","description":"Das Hilfswerk Aid to the Church Need f\u00f6rdert nun ein Programm, das junge christliche Frauen, die in diesen extrem schwierigen Verh\u00e4ltnissen leben, st\u00e4rken soll. Viele der jungen Frauen, die an dem Programm teilnehmen, sind Studentinnen oder Hausangestellte in den Au\u00dfenbezirken einer pakistanischen Gro\u00dfstadt.","breadcrumb":{"@id":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/06\/Pakistan.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/06\/Pakistan.jpg","width":1400,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/de\/junge-christliche-frauen-in-pakistan-sind-mit-diskriminierung-sozialer-ausgrenzung-und-armut-konfrontiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/de\/"},{"@type":"ListItem","position":2,"name":"PROJECTS","item":"https:\/\/acninternational.org\/de\/category\/projects-de\/"},{"@type":"ListItem","position":3,"name":"Junge christliche Frauen in Pakistan sind mit Diskriminierung, sozialer Ausgrenzung und Armut konfrontiert"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/de\/#website","url":"https:\/\/acninternational.org\/de\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/de\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/de\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/154711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/comments?post=154711"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/154711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media\/154701"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media?parent=154711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/categories?post=154711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/tags?post=154711"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/country?post=154711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}