{"id":151526,"date":"2021-05-19T10:47:35","date_gmt":"2021-05-19T08:47:35","guid":{"rendered":"https:\/\/acninternational.org\/?p=151526"},"modified":"2021-05-19T11:56:38","modified_gmt":"2021-05-19T09:56:38","slug":"katecheten-sind-das-rueckgrat-der-kirche","status":"publish","type":"post","link":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/","title":{"rendered":"\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c"},"content":{"rendered":"<p><em>\u201eKirche in Not\u201c unterst\u00fctzt Dienst von Laienverk\u00fcndigern weltweit<\/em><\/p>\n<p><strong>\u00a0<\/strong>\u201eDas j\u00fcngste Schreiben \u201aAntiquum ministerium\u2018 mit dem der Papst den \u201elaikalen Dienst\u201c des Katecheten mit eigener liturgischer Beauftragung eingef\u00fchrt hat, war eine gro\u00dfe Freude f\u00fcr uns\u201c, erkl\u00e4rt Regina Lynch, Direktorin der Projektabteilung des Hilfswerkes Aid to the Church in Need (ACN).<\/p>\n<p>\u201eDurch unsere Projektarbeit in mehr als 140 L\u00e4ndern wissen wir, dass Katechetinnen und Katecheten an vielen Orten der Welt das R\u00fcckgrat der Kirche sind\u201c, sagte Lynch. Gerade in entlegenen Gegenden, in die nur selten ein Priester kommen kann, oder in L\u00e4ndern, wo durch Krieg und Verfolgung die Gemeindearbeit erschwert ist, seien Katecheten Ansprechpartner, Helfer und Seelsorger in einem.<\/p>\n<p>\u201eDie Katecheten, die in Regionen, wo es keine Priester gibt, die Seelsorge leiten, bezahlen ihren Mut und ihre Hingabe bisweilen sogar mit dem Tod. Ein besonders ber\u00fchrendes Beispiel ist Philippe Yarga aus Diozese Dori in Burkina Faso\u201c. Yarga, der f\u00fcr die pastorale Koordination im Osten von Burkina Faso an der Grenze zu Niger zust\u00e4ndig war, wurde am 16. Februar 2020 von Terroristen ermordet. Er hinterlie\u00df sieben Kinder, von denen das j\u00fcngste sechs Wochen nach seinem Tod geboren wurde. \u201eDie Katecheten in Burkina Faso und anderen L\u00e4ndern der Sahelzone sehen sich unmittelbar der terroristischen Gefahr ausgesetzt und m\u00fcssen manchmal \u00fcber Nacht mit ihren Familien fliehen. Deshalb unterst\u00fctzt ACN zum Bespiel in Burkina Faso ein Hilfsprojekt zur Versorgung von 18 leitenden Katecheten und ihren Familien, die vertrieben wurden\u201c, erz\u00e4hlt Lynch.<\/p>\n<figure id=\"attachment_142750\" aria-describedby=\"caption-attachment-142750\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-142750 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Regina-Lynch.jpg\" alt=\"Regina Lynch, Direktorin der Projektabteilung des Hilfswerkes Aid to the Church in Need (ACN).\u00a0\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Regina-Lynch.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/09\/Regina-Lynch-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-142750\" class=\"wp-caption-text\">Regina Lynch, Direktorin der Projektabteilung des Hilfswerkes Aid to the Church in Need (ACN).<\/figcaption><\/figure>\n<p><strong>ACN f\u00f6rdert \u00fcber 18 000 Katecheten weltweit<\/strong><\/p>\n<p>Auch in zahlreichen anderen L\u00e4ndern weltweit unterst\u00fctzt ACN den Einsatz von Katecheten. \u201eAllein im Jahr 2020 haben wir \u00fcber 18 000 Katecheten auf allen Kontinenten gef\u00f6rdert \u2013 die meisten in Asien und Afrika\u201c, so Lynch. ACN hat im vergangenen Jahr 20 Projekte finanziert, um Katecheten f\u00fcr ihren Dienst technisch auszustatten oder sie mit Material f\u00fcr die Seelsorgearbeit und den Religionsunterricht zu versorgen. Hinzu kommen 35 Projekte zur Schulung und Weiterbildung von Katecheten in 18 L\u00e4ndern.<\/p>\n<figure id=\"attachment_151531\" aria-describedby=\"caption-attachment-151531\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-151531 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists3.jpg\" alt=\"\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists3.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists3-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-151531\" class=\"wp-caption-text\">\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c.<\/figcaption><\/figure>\n<p><strong>Ein Katechet in Uganda verk\u00fcndet Vers\u00f6hnung statt Rache<\/strong><\/p>\n<p>Hinter diesen Projekten stehen Menschen mit sehr beeindruckenden Geschichten. Einer der Katecheten, die ACN unterst\u00fctzt, ist zum Beispiel John Joseph Gazi aus Uganda. Urspr\u00fcnglich kommt er aus dem S\u00fcdsudan. In dem j\u00fcngsten Staat Afrikas, erst 2011 unabh\u00e4ngig geworden, herrscht ein brutaler Kampf, allen Friedensbem\u00fchungen zum Trotz. Es geht um Macht, um ethnische Konflikte. Johns Familie konnte dem Morden nicht entkommen. \u201eMein Vater, meine Schwester und mein Bruder wurden get\u00f6tet. Es geschah innerhalb weniger Minuten\u201c, erz\u00e4hlt er ACN.<\/p>\n<p>Er jedoch konnte ins Nachbarland Uganda fl\u00fcchten, wo \u00fcber eine Million Menschen in Fl\u00fcchtlingslagern hausen. Doch schlimmer als die himmelschreiende Not dort sind die Narben der Seele, vor allem unter den jungen Menschen: Denn viele wurden in den Auseinandersetzungen als Kindersoldaten missbraucht.<\/p>\n<p>Zu ihnen f\u00fchlt John sich besonders gesandt: \u201eViele tragen Hass und Rachegedanken in sich. Ich spreche zu ihnen \u00fcber Vergebung.\u201c Er hat fast alles verloren \u2013 aber nicht den Glauben an Gott. Darum hat er sich zum Katecheten ausbilden lassen. Er selber bevorzugt die Bezeichnung \u201eEvangelisierer\u201c: Den armen und verzweifelten Menschen die Frohe Botschaft bringen.<\/p>\n<figure id=\"attachment_151513\" aria-describedby=\"caption-attachment-151513\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-151513 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists2.jpg\" alt=\"\u201eAllein im Jahr 2020 haben wir \u00fcber 18 000 Katecheten auf allen Kontinenten gef\u00f6rdert \u2013 die meisten in Asien und Afrika\u201c, so Lynch.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists2.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists2-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-151513\" class=\"wp-caption-text\">\u201eAllein im Jahr 2020 haben wir \u00fcber 18 000 Katecheten auf allen Kontinenten gef\u00f6rdert \u2013 die meisten in Asien und Afrika\u201c, so Lynch.<\/figcaption><\/figure>\n<p><strong>\u201eSeelen zu Gott zur\u00fcckbringen\u201c<\/strong><\/p>\n<p>ACN hat seine Ausbildung finanziert, im Emmaus-Zentrum, nahe der ugandischen Hauptstadt Kampala. Dort werden junge Menschen geschult, die Wunden der Seelen ihrer Landsleute zu heilen und ihnen in verschiedenen N\u00f6ten beizustehen. Ein ganz anderer und aussichtsreicherer \u201eKampf\u201c als der verbitterte Krieg in seiner Heimat, bekennt John: \u201eIch bin jetzt ein Soldat f\u00fcr Jesus. Ich k\u00e4mpfe darum, die Seelen zu Gott zur\u00fcckzubringen.\u201c<\/p>\n<p>John besucht jetzt seine Landsleute, die sich in Uganda mehr schlecht als recht eine neue Existenz aufbauen \u2013 aber ohne Gewalt und Krieg. \u201eIch will das Leben zu den S\u00fcdsudanesen zur\u00fcckbringen.\u201c Er spricht vom Glauben, er spendet Trost, h\u00f6rt sich die schrecklichen Erz\u00e4hlungen der traumatisierten Menschen an und vermittelt Hilfe. John und seine Mitstreiter haben neben katechetischen auch psychologische Kenntnisse im Emmaus-Zentrum erworben. Denn zus\u00e4tzlich zu den Kriegserfahrungen, der Armut und Arbeitslosigkeit stellt auch der Alkoholmissbrauch ein Problem unter den Gefl\u00fcchteten dar.<\/p>\n<p>Der \u201eKampf\u201c gegen die Folgen des Krieges dauert an. Aber John ist sich sicher, dass es jede M\u00fche wert ist: \u201eDank meiner Ausbildung als Katechet mit der Unterst\u00fctzung von ACN, bringe ich nun Hoffnung und Liebe zu meinen Leuten.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eKirche in Not\u201c unterst\u00fctzt Dienst von Laienverk\u00fcndigern weltweit \u00a0\u201eDas j\u00fcngste Schreiben \u201aAntiquum ministerium\u2018 mit dem der Papst den \u201elaikalen Dienst\u201c<\/p>\n","protected":false},"author":4258341447,"featured_media":151519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[920],"tags":[],"country":[333],"class_list":["post-151526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projekt","country-international"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c<\/title>\n<meta name=\"description\" content=\"\u201eAllein im Jahr 2020 haben wir \u00fcber 18 000 Katecheten auf allen Kontinenten gef\u00f6rdert \u2013 die meisten in Asien und Afrika\u201c, so Lynch. ACN hat im vergangenen Jahr 20 Projekte finanziert, um Katecheten f\u00fcr ihren Dienst technisch auszustatten oder sie mit Material f\u00fcr die Seelsorgearbeit und den Religionsunterricht zu versorgen. Hinzu kommen 35 Projekte zur Schulung und Weiterbildung von Katecheten in 18 L\u00e4ndern.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c\" \/>\n<meta property=\"og:description\" content=\"\u201eAllein im Jahr 2020 haben wir \u00fcber 18 000 Katecheten auf allen Kontinenten gef\u00f6rdert \u2013 die meisten in Asien und Afrika\u201c, so Lynch. ACN hat im vergangenen Jahr 20 Projekte finanziert, um Katecheten f\u00fcr ihren Dienst technisch auszustatten oder sie mit Material f\u00fcr die Seelsorgearbeit und den Religionsunterricht zu versorgen. Hinzu kommen 35 Projekte zur Schulung und Weiterbildung von Katecheten in 18 L\u00e4ndern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-19T08:47:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-19T09:56:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c\",\"datePublished\":\"2021-05-19T08:47:35+00:00\",\"dateModified\":\"2021-05-19T09:56:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/\"},\"wordCount\":789,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/catechists.jpg\",\"articleSection\":[\"Projekt\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/\",\"name\":\"\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/catechists.jpg\",\"datePublished\":\"2021-05-19T08:47:35+00:00\",\"dateModified\":\"2021-05-19T09:56:38+00:00\",\"description\":\"\u201eAllein im Jahr 2020 haben wir \u00fcber 18 000 Katecheten auf allen Kontinenten gef\u00f6rdert \u2013 die meisten in Asien und Afrika\u201c, so Lynch. ACN hat im vergangenen Jahr 20 Projekte finanziert, um Katecheten f\u00fcr ihren Dienst technisch auszustatten oder sie mit Material f\u00fcr die Seelsorgearbeit und den Religionsunterricht zu versorgen. Hinzu kommen 35 Projekte zur Schulung und Weiterbildung von Katecheten in 18 L\u00e4ndern.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/catechists.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/catechists.jpg\",\"width\":1400,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/katecheten-sind-das-rueckgrat-der-kirche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROJECTS\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/category\\\/projects-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c","description":"\u201eAllein im Jahr 2020 haben wir \u00fcber 18 000 Katecheten auf allen Kontinenten gef\u00f6rdert \u2013 die meisten in Asien und Afrika\u201c, so Lynch. ACN hat im vergangenen Jahr 20 Projekte finanziert, um Katecheten f\u00fcr ihren Dienst technisch auszustatten oder sie mit Material f\u00fcr die Seelsorgearbeit und den Religionsunterricht zu versorgen. Hinzu kommen 35 Projekte zur Schulung und Weiterbildung von Katecheten in 18 L\u00e4ndern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/","og_locale":"de_DE","og_type":"article","og_title":"\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c","og_description":"\u201eAllein im Jahr 2020 haben wir \u00fcber 18 000 Katecheten auf allen Kontinenten gef\u00f6rdert \u2013 die meisten in Asien und Afrika\u201c, so Lynch. ACN hat im vergangenen Jahr 20 Projekte finanziert, um Katecheten f\u00fcr ihren Dienst technisch auszustatten oder sie mit Material f\u00fcr die Seelsorgearbeit und den Religionsunterricht zu versorgen. Hinzu kommen 35 Projekte zur Schulung und Weiterbildung von Katecheten in 18 L\u00e4ndern.","og_url":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2021-05-19T08:47:35+00:00","article_modified_time":"2021-05-19T09:56:38+00:00","og_image":[{"width":1400,"height":438,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Verfasst von":"ACN Press Team","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c","datePublished":"2021-05-19T08:47:35+00:00","dateModified":"2021-05-19T09:56:38+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/"},"wordCount":789,"publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists.jpg","articleSection":["Projekt"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/","url":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/","name":"\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists.jpg","datePublished":"2021-05-19T08:47:35+00:00","dateModified":"2021-05-19T09:56:38+00:00","description":"\u201eAllein im Jahr 2020 haben wir \u00fcber 18 000 Katecheten auf allen Kontinenten gef\u00f6rdert \u2013 die meisten in Asien und Afrika\u201c, so Lynch. ACN hat im vergangenen Jahr 20 Projekte finanziert, um Katecheten f\u00fcr ihren Dienst technisch auszustatten oder sie mit Material f\u00fcr die Seelsorgearbeit und den Religionsunterricht zu versorgen. Hinzu kommen 35 Projekte zur Schulung und Weiterbildung von Katecheten in 18 L\u00e4ndern.","breadcrumb":{"@id":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2021\/05\/catechists.jpg","width":1400,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/de\/katecheten-sind-das-rueckgrat-der-kirche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/de\/"},{"@type":"ListItem","position":2,"name":"PROJECTS","item":"https:\/\/acninternational.org\/de\/category\/projects-de\/"},{"@type":"ListItem","position":3,"name":"\u201eKatecheten sind das R\u00fcckgrat der Kirche\u201c"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/de\/#website","url":"https:\/\/acninternational.org\/de\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/de\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/de\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/151526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/comments?post=151526"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/151526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media\/151519"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media?parent=151526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/categories?post=151526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/tags?post=151526"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/country?post=151526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}