{"id":135208,"date":"2020-05-20T12:21:01","date_gmt":"2020-05-20T10:21:01","guid":{"rendered":"https:\/\/acninternational.org\/?p=135208"},"modified":"2020-05-20T12:28:50","modified_gmt":"2020-05-20T10:28:50","slug":"burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus","status":"publish","type":"post","link":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/","title":{"rendered":"Burkina Faso: ACN unterst\u00fctzt Opfer auf der Flucht vor dem Terrorismus"},"content":{"rendered":"<p>Die Sahelzone in Burkina Faso wird seit Jahren von Terroranschl\u00e4gen ersch\u00fcttert. Die letzten Anschl\u00e4ge liegen drei Monate zur\u00fcck und zwangen die betroffenen Menschen zu fliehen. Als Reaktion auf diese Notlage hat das Internationale Hilfswerk Aid to the Church in Need (ACN) gerade ein Projekt zur F\u00f6rderung der Eingliederung einiger der Binnenvertriebenen genehmigt. Konkret soll 18 leitenden Katecheten der Pfarrei Sebba und ihren Familien geholfen werden. Diese Pastoralkoordinatoren, die dort, wo es keine Priester gibt, ihre Gemeinden und die Seelsorge leiten, sehen sich unmittelbar der terroristischen Gefahr ausgesetzt. Die aus Sebba stammenden Katecheten mussten in Dori, der Hauptstadt des Departements und Sitz der Di\u00f6zese, Zuflucht nehmen.<\/p>\n<p>\u201eF\u00fcr die Di\u00f6zese Dori mit ihren begrenzten Ressoucen stellt die Situation eine Herausforderung dar. Seit 2015 ist sie stark von den Terroranschl\u00e4gen betroffen\u201c, erkl\u00e4rt der Ortsbischof, der f\u00fcr die Verwaltungsregion der Sahelzone in Burkina Faso zust\u00e4ndig ist. Bischof Laurent Dabir\u00e9 ist verantwortlich f\u00fcr die von der christlichen Gemeinschaft in Dori ergriffenen Ma\u00dfnahmen zur Aufnahme der Katecheten und ihrer Familien und f\u00fcr ihre Unterst\u00fctzung mit dem Lebensnotwendigsten. Denn die Menschen konnten nichts mitnehmen, als sie vor den Terroranschl\u00e4gen der letzten Monate flohen. Die Familien haben sich in die Stadt gefl\u00fcchtet, da die St\u00e4dte als sicherer gelten.<\/p>\n<p>Nach der ersten Nothilfe ist es heute dringend notwendig, \u201eihnen ein Existenzminimum zu sichern, solange sie hier in Dori bleiben\u201c, sagt der Bischof. Und das wird noch eine Weile n\u00f6tig sein. Zun\u00e4chst einmal, weil diese Familien ausschlie\u00dflich Gourmantch\u00e9 (Gurma) sprechen und aufgrund dieser Sprachbarriere nicht in andere Di\u00f6zesen des Landes umgesiedelt werden k\u00f6nnen. Zweitens, weil ihre Anwesenheit notwendig ist, um das missionarische Leben vor Ort zu gew\u00e4hrleisten und die Wiederaufnahme der Evangelisierung vorzubereiten, sobald die Bedingungen es erlauben.<\/p>\n<figure id=\"attachment_135196\" aria-describedby=\"caption-attachment-135196\" style=\"width: 670px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-135196 size-full\" src=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/05\/Burkina-Faso_Bishop-Laurent-Dabir%C3%A9.jpg\" alt=\"Bischof Laurent Dabir\u00e9.\" width=\"670\" height=\"400\" srcset=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/05\/Burkina-Faso_Bishop-Laurent-Dabir%C3%A9.jpg 670w, https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/05\/Burkina-Faso_Bishop-Laurent-Dabir%C3%A9-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption id=\"caption-attachment-135196\" class=\"wp-caption-text\">Bischof Laurent Dabir\u00e9.<\/figcaption><\/figure>\n<p>ACN hat beschlossen, die 18 Katecheten und ihre Familien bei ihrer sozialen Wiedereingliederung zu unterst\u00fctzen. Das mit 30.000 Euro ausgestattete Programm umfasst die Gesundheitsf\u00fcrsorge, von psychologischer Unterst\u00fctzung bis hin zur medizinischen Grundversorgung, Nahrungsmittelhilfen und Schulstipendien. Dar\u00fcber hinaus werden den Familien Mittel zur Verf\u00fcgung gestellt, die es ihnen erm\u00f6glichen, eine einkommensschaffende T\u00e4tigkeit wie Viehzucht oder Gartenbau auszu\u00fcben, damit sie sich mittelfristig selbst versorgen k\u00f6nnen.<\/p>\n<p><strong>\u00a0<\/strong>Im Osten der Di\u00f6zese Dori selbst, in deren Gebiet nur 1,8% der Bev\u00f6lkerung Christen (Katholiken und Protestanten) sind, haben sich gerade zwei Trag\u00f6dien ereignet. Die erste\u00a0 am 10. Februar, 50 km von Dori entfernt: \u201eBewaffnete M\u00e4nner drangen in die Stadt Sebba ein, die Hauptstadt einer meiner Pfarreien, wo sie einen Menschen t\u00f6teten und einen evangelischen Pfarrer sowie sechs junge Studenten entf\u00fchrten, die am n\u00e4chsten Tag kaltbl\u00fctig hingerichtet wurden. Nur zwei M\u00e4dchen wurden befreit\u201c, erkl\u00e4rt Bischof Dabir\u00e9. Der zweite Anschlag fand am 16. Februar 100 km von Dori entfernt statt. Die Terroristen fielen in das Dorf Pansi ein, das auf dem Gebiet der Pfarrei St. Antonius der Gro\u00dfe von Sebba liegt. Sie \u201epl\u00fcnderten den Ort und richteten dann 24 Menschen kaltbl\u00fctig hin\u201c. Unter ihnen befand sich Philippe Yarga, den die Presse f\u00e4lschlicherweise als evangelischen Pfarrer darstellte. Yarga war jedoch seit 2017 als leitender Katechet der Stadt f\u00fcr die pastorale Koordination des Gebiets zust\u00e4ndig.<\/p>\n<p>Er wurde 1975 geboren und hinterl\u00e4sst sieben Kinder, von denen das j\u00fcngste 43 Tage nach seinem Tod geboren wurde. Er sei ein \u201ebegeisterter\u201c Katechet gewesen, der \u201eseinen Dienst voller Liebe verrichtete\u201c, und ein \u201eguter Vater\u201c. Nach dem er bemerkt hatte, wie sich die Sicherheitslage in Pansi dramatisch verschlechterte, wollte er einen Kollegen in einem nahe gelegenen Dorf besuchen, um eine m\u00f6gliche Zuflucht in einer anderen Stadt zu pr\u00fcfen. Als er das Haus verlassen wollte, wurde er von unbekannten Bewaffneten \u00fcberrascht. Den Zeugenaussagen zufolge griffen die M\u00f6rder alle M\u00e4nner des Dorfes an, egal, unabh\u00e4ngig von ihrer religi\u00f6sen oder ethnischen Zugeh\u00f6rigkeit. Heute ist die Pfarrei Sebba geschlossen. Es ist die dritte Pfarrei in der Di\u00f6zese, die das gleiche Schicksal erleiden musste.<\/p>\n<p>Angesichts der zunehmenden Gewalt in Burkina Faso in den letzten f\u00fcnf Jahren hat ACN soeben beschlossen, mit insgesamt 100.000 Euro nicht nur das Projekt zur sozialen Wiedereingliederung der vertriebenen Familien in Dori, sondern auch sieben weitere Projekte in ganz Burkina Faso zu unterst\u00fctzen. Dazu geh\u00f6ren die Ausbildung von 83 Priesteramtskandidaten in den Di\u00f6zesen Dori, Kaya, Fada N&#8217;Gourma und Tenkodogo, Existenzhilfe f\u00fcr zehn Ordensschwestern, die im Bistum Dori t\u00e4tig sind, sowie die Unterst\u00fctzung von Radioprogrammen f\u00fcr Vertriebene und Menschen, die in schwierigen Gebieten im ganzen Land leben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Sahelzone in Burkina Faso wird seit Jahren von Terroranschl\u00e4gen ersch\u00fcttert. Die letzten Anschl\u00e4ge liegen drei Monate zur\u00fcck und zwangen<\/p>\n","protected":false},"author":4258341447,"featured_media":135190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_acn_coauthor_ids":[],"_acn_featured_article":false,"footnotes":""},"categories":[234],"tags":[],"country":[378],"class_list":["post-135208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","country-burkina-faso-es"],"acn_coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Burkina Faso: ACN unterst\u00fctzt Opfer auf der Flucht vor dem Terrorismus<\/title>\n<meta name=\"description\" content=\"Die Sahelzone in Burkina Faso wird seit Jahren von Terroranschl\u00e4gen ersch\u00fcttert. Die letzten Anschl\u00e4ge liegen drei Monate zur\u00fcck und zwangen die betroffenen Menschen zu fliehen. Als Reaktion auf diese Notlage hat das Internationale Hilfswerk Aid to the Church in Need (ACN) gerade ein Projekt zur F\u00f6rderung der Eingliederung einiger der Binnenvertriebenen genehmigt. Konkret soll 18 leitenden Katecheten der Pfarrei Sebba und ihren Familien geholfen werden. Diese Pastoralkoordinatoren, die dort, wo es keine Priester gibt, ihre Gemeinden und die Seelsorge leiten, sehen sich unmittelbar der terroristischen Gefahr ausgesetzt. Die aus Sebba stammenden Katecheten mussten in Dori, der Hauptstadt des Departements und Sitz der Di\u00f6zese, Zuflucht nehmen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Burkina Faso: ACN unterst\u00fctzt Opfer auf der Flucht vor dem Terrorismus\" \/>\n<meta property=\"og:description\" content=\"Die Sahelzone in Burkina Faso wird seit Jahren von Terroranschl\u00e4gen ersch\u00fcttert. Die letzten Anschl\u00e4ge liegen drei Monate zur\u00fcck und zwangen die betroffenen Menschen zu fliehen. Als Reaktion auf diese Notlage hat das Internationale Hilfswerk Aid to the Church in Need (ACN) gerade ein Projekt zur F\u00f6rderung der Eingliederung einiger der Binnenvertriebenen genehmigt. Konkret soll 18 leitenden Katecheten der Pfarrei Sebba und ihren Familien geholfen werden. Diese Pastoralkoordinatoren, die dort, wo es keine Priester gibt, ihre Gemeinden und die Seelsorge leiten, sehen sich unmittelbar der terroristischen Gefahr ausgesetzt. Die aus Sebba stammenden Katecheten mussten in Dori, der Hauptstadt des Departements und Sitz der Di\u00f6zese, Zuflucht nehmen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/\" \/>\n<meta property=\"og:site_name\" content=\"ACN International\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acninternationalorg\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-20T10:21:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-20T10:28:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/05\/Burkina-Faso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ACN Press Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@acn_int\" \/>\n<meta name=\"twitter:site\" content=\"@acn_int\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"ACN Press Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/\"},\"author\":{\"name\":\"ACN Press Team\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\"},\"headline\":\"Burkina Faso: ACN unterst\u00fctzt Opfer auf der Flucht vor dem Terrorismus\",\"datePublished\":\"2020-05-20T10:21:01+00:00\",\"dateModified\":\"2020-05-20T10:28:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/\"},\"wordCount\":774,\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Burkina-Faso.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/\",\"name\":\"Burkina Faso: ACN unterst\u00fctzt Opfer auf der Flucht vor dem Terrorismus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Burkina-Faso.jpg\",\"datePublished\":\"2020-05-20T10:21:01+00:00\",\"dateModified\":\"2020-05-20T10:28:50+00:00\",\"description\":\"Die Sahelzone in Burkina Faso wird seit Jahren von Terroranschl\u00e4gen ersch\u00fcttert. Die letzten Anschl\u00e4ge liegen drei Monate zur\u00fcck und zwangen die betroffenen Menschen zu fliehen. Als Reaktion auf diese Notlage hat das Internationale Hilfswerk Aid to the Church in Need (ACN) gerade ein Projekt zur F\u00f6rderung der Eingliederung einiger der Binnenvertriebenen genehmigt. Konkret soll 18 leitenden Katecheten der Pfarrei Sebba und ihren Familien geholfen werden. Diese Pastoralkoordinatoren, die dort, wo es keine Priester gibt, ihre Gemeinden und die Seelsorge leiten, sehen sich unmittelbar der terroristischen Gefahr ausgesetzt. Die aus Sebba stammenden Katecheten mussten in Dori, der Hauptstadt des Departements und Sitz der Di\u00f6zese, Zuflucht nehmen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Burkina-Faso.jpg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Burkina-Faso.jpg\",\"width\":1400,\"height\":438},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachricht\",\"item\":\"https:\\\/\\\/acninternational.org\\\/de\\\/category\\\/news-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Burkina Faso: ACN unterst\u00fctzt Opfer auf der Flucht vor dem Terrorismus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"name\":\"ACN International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acninternational.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#organization\",\"name\":\"Aid to the Church in Need International\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"contentUrl\":\"https:\\\/\\\/media.acninternational.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/acn_logo_blackvector.svg\",\"width\":232.6,\"height\":78,\"caption\":\"Aid to the Church in Need International\"},\"image\":{\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acninternationalorg\",\"https:\\\/\\\/x.com\\\/acn_int\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQ-077gS0TnVzkhHmf1opZw\",\"https:\\\/\\\/www.instagram.com\\\/acn_international\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acninternational.org\\\/de\\\/#\\\/schema\\\/person\\\/7f3dafb236b242fb2aa46be1411fd703\",\"name\":\"ACN Press Team\",\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.\",\"url\":\"https:\\\/\\\/acninternational.org\\\/de\\\/author\\\/acn-press-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Burkina Faso: ACN unterst\u00fctzt Opfer auf der Flucht vor dem Terrorismus","description":"Die Sahelzone in Burkina Faso wird seit Jahren von Terroranschl\u00e4gen ersch\u00fcttert. Die letzten Anschl\u00e4ge liegen drei Monate zur\u00fcck und zwangen die betroffenen Menschen zu fliehen. Als Reaktion auf diese Notlage hat das Internationale Hilfswerk Aid to the Church in Need (ACN) gerade ein Projekt zur F\u00f6rderung der Eingliederung einiger der Binnenvertriebenen genehmigt. Konkret soll 18 leitenden Katecheten der Pfarrei Sebba und ihren Familien geholfen werden. Diese Pastoralkoordinatoren, die dort, wo es keine Priester gibt, ihre Gemeinden und die Seelsorge leiten, sehen sich unmittelbar der terroristischen Gefahr ausgesetzt. Die aus Sebba stammenden Katecheten mussten in Dori, der Hauptstadt des Departements und Sitz der Di\u00f6zese, Zuflucht nehmen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/","og_locale":"de_DE","og_type":"article","og_title":"Burkina Faso: ACN unterst\u00fctzt Opfer auf der Flucht vor dem Terrorismus","og_description":"Die Sahelzone in Burkina Faso wird seit Jahren von Terroranschl\u00e4gen ersch\u00fcttert. Die letzten Anschl\u00e4ge liegen drei Monate zur\u00fcck und zwangen die betroffenen Menschen zu fliehen. Als Reaktion auf diese Notlage hat das Internationale Hilfswerk Aid to the Church in Need (ACN) gerade ein Projekt zur F\u00f6rderung der Eingliederung einiger der Binnenvertriebenen genehmigt. Konkret soll 18 leitenden Katecheten der Pfarrei Sebba und ihren Familien geholfen werden. Diese Pastoralkoordinatoren, die dort, wo es keine Priester gibt, ihre Gemeinden und die Seelsorge leiten, sehen sich unmittelbar der terroristischen Gefahr ausgesetzt. Die aus Sebba stammenden Katecheten mussten in Dori, der Hauptstadt des Departements und Sitz der Di\u00f6zese, Zuflucht nehmen.","og_url":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/","og_site_name":"ACN International","article_publisher":"https:\/\/www.facebook.com\/acninternationalorg","article_published_time":"2020-05-20T10:21:01+00:00","article_modified_time":"2020-05-20T10:28:50+00:00","og_image":[{"width":1400,"height":438,"url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/05\/Burkina-Faso.jpg","type":"image\/jpeg"}],"author":"ACN Press Team","twitter_card":"summary_large_image","twitter_creator":"@acn_int","twitter_site":"@acn_int","twitter_misc":{"Verfasst von":"ACN Press Team","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/#article","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/"},"author":{"name":"ACN Press Team","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703"},"headline":"Burkina Faso: ACN unterst\u00fctzt Opfer auf der Flucht vor dem Terrorismus","datePublished":"2020-05-20T10:21:01+00:00","dateModified":"2020-05-20T10:28:50+00:00","mainEntityOfPage":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/"},"wordCount":774,"publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"image":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/05\/Burkina-Faso.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/","url":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/","name":"Burkina Faso: ACN unterst\u00fctzt Opfer auf der Flucht vor dem Terrorismus","isPartOf":{"@id":"https:\/\/acninternational.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/#primaryimage"},"image":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/#primaryimage"},"thumbnailUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/05\/Burkina-Faso.jpg","datePublished":"2020-05-20T10:21:01+00:00","dateModified":"2020-05-20T10:28:50+00:00","description":"Die Sahelzone in Burkina Faso wird seit Jahren von Terroranschl\u00e4gen ersch\u00fcttert. Die letzten Anschl\u00e4ge liegen drei Monate zur\u00fcck und zwangen die betroffenen Menschen zu fliehen. Als Reaktion auf diese Notlage hat das Internationale Hilfswerk Aid to the Church in Need (ACN) gerade ein Projekt zur F\u00f6rderung der Eingliederung einiger der Binnenvertriebenen genehmigt. Konkret soll 18 leitenden Katecheten der Pfarrei Sebba und ihren Familien geholfen werden. Diese Pastoralkoordinatoren, die dort, wo es keine Priester gibt, ihre Gemeinden und die Seelsorge leiten, sehen sich unmittelbar der terroristischen Gefahr ausgesetzt. Die aus Sebba stammenden Katecheten mussten in Dori, der Hauptstadt des Departements und Sitz der Di\u00f6zese, Zuflucht nehmen.","breadcrumb":{"@id":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/#primaryimage","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/05\/Burkina-Faso.jpg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2020\/05\/Burkina-Faso.jpg","width":1400,"height":438},{"@type":"BreadcrumbList","@id":"https:\/\/acninternational.org\/de\/burkina-faso-acn-unterstuetzt-opfer-auf-der-flucht-vor-dem-terrorismus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acninternational.org\/de\/"},{"@type":"ListItem","position":2,"name":"Nachricht","item":"https:\/\/acninternational.org\/de\/category\/news-de\/"},{"@type":"ListItem","position":3,"name":"Burkina Faso: ACN unterst\u00fctzt Opfer auf der Flucht vor dem Terrorismus"}]},{"@type":"WebSite","@id":"https:\/\/acninternational.org\/de\/#website","url":"https:\/\/acninternational.org\/de\/","name":"ACN International","description":"","publisher":{"@id":"https:\/\/acninternational.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acninternational.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/acninternational.org\/de\/#organization","name":"Aid to the Church in Need International","url":"https:\/\/acninternational.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","contentUrl":"https:\/\/media.acninternational.org\/wp-content\/uploads\/2019\/11\/acn_logo_blackvector.svg","width":232.6,"height":78,"caption":"Aid to the Church in Need International"},"image":{"@id":"https:\/\/acninternational.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acninternationalorg","https:\/\/x.com\/acn_int","https:\/\/www.youtube.com\/channel\/UCQ-077gS0TnVzkhHmf1opZw","https:\/\/www.instagram.com\/acn_international\/"]},{"@type":"Person","@id":"https:\/\/acninternational.org\/de\/#\/schema\/person\/7f3dafb236b242fb2aa46be1411fd703","name":"ACN Press Team","description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.","url":"https:\/\/acninternational.org\/de\/author\/acn-press-team\/"}]}},"_links":{"self":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/135208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/users\/4258341447"}],"replies":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/comments?post=135208"}],"version-history":[{"count":0,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/posts\/135208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media\/135190"}],"wp:attachment":[{"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/media?parent=135208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/categories?post=135208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/tags?post=135208"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/acninternational.org\/de\/wp-json\/wp\/v2\/country?post=135208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}